{"id":9094,"date":"2019-09-11T18:16:14","date_gmt":"2019-09-11T18:16:14","guid":{"rendered":"https:\/\/blog.hostinger.io\/mx-tutoriales\/?p=9094"},"modified":"2024-10-11T13:51:04","modified_gmt":"2024-10-11T11:51:04","slug":"comando-unzip-linux","status":"publish","type":"post","link":"\/mx\/tutoriales\/comando-unzip-linux\/","title":{"rendered":"C\u00f3mo usar el comando Unzip de Linux"},"content":{"rendered":"<p>Para descomprimir, los usuarios de Linux pueden aplicar un comando de utilidad similar al de otros formatos de compresi&oacute;n, como <strong>tar <\/strong>y <strong>gzip<\/strong>.&nbsp;<\/p><p>Entender c&oacute;mo utilizar el comando <strong>unzip <\/strong>de Linux<strong> <\/strong>ayuda a mejorar la eficacia en diversas tareas, como la distribuci&oacute;n de software o el archivado de datos.<\/p><p>A diferencia de las dos utilidades, <strong>unzip <\/strong>no se instala por defecto. Tambi&eacute;n tiene distintas opciones para cambiar el comportamiento de extracci&oacute;n y es adecuado para un escenario de desarrollo concreto.<\/p><p>En este art&iacute;culo te explicamos c&oacute;mo instalar y utilizar <strong>unzip <\/strong>para extraer archivos zip en un <a href=\"\/mx\/servidor-vps\">servidor privado virtual (VPS)<\/a> con Linux. Tambi&eacute;n hablaremos de en qu&eacute; se diferencia de otros comandos de descompresi&oacute;n y de sus mejores pr&aacute;cticas.<\/p><figure class=\"wp-block-image size-large\"><a href=\"https:\/\/assets.hostinger.com\/content\/tutorials\/pdf\/Linux-Commands-Cheatsheet-ES.pdf\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"1024\" height=\"283\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/12\/Linux-cheat-sheet-ES.png\/w=1024,h=1024,fit=scale-down\" alt=\"\" class=\"wp-image-26004\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/12\/Linux-cheat-sheet-ES.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/12\/Linux-cheat-sheet-ES.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/12\/Linux-cheat-sheet-ES.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/12\/Linux-cheat-sheet-ES.png\/w=768,fit=scale-down 768w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/12\/Linux-cheat-sheet-ES.png\/w=1536,fit=scale-down 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><h2 class=\"wp-block-heading\" id=\"h-como-instalar-unzip-nbsp\">C&oacute;mo instalar Unzip<strong>&nbsp;<\/strong><\/h2><p>En esta secci&oacute;n, repasaremos los pasos para instalar <strong>unzip <\/strong>en <a href=\"\/mx\/tutoriales\/mejores-distribuciones-linux\/\">distribuciones populares de Linux<\/a> como <strong>Debian <\/strong>y <strong>CentOS<\/strong>. Para ejecutar los comandos de forma remota, con&eacute;ctate a tu VPS utilizando un <a href=\"\/mx\/tutoriales\/conectar-usando-terminal-putty-ssh\/\">cliente SSH como PuTTY<\/a>.<\/p><p><strong>Derivados de Debian<\/strong><\/p><p>Para los sistemas operativos basados en Debian, como <strong>Ubuntu<\/strong>, utiliza el gestor de paquetes APT para instalar <strong>unzip <\/strong>en Linux. Antes de hacerlo, actualiza y mejora el repositorio con el siguiente comando:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">sudo apt update &amp;&amp; sudo apt upgrade<\/pre><p>Luego, instala <strong>unzip <\/strong>usando esto:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">sudo apt install unzip<\/pre><p>Si utilizas un sistema operativo m&aacute;s antiguo, aplica en su lugar el siguiente comando:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">sudo apt-get install unzip<\/pre><p><strong>Derivados de Red Hat Linux Enterprise (RHEL)<\/strong><\/p><p>Los comandos para los sistemas operativos basados en RHEL como <strong>CentOS<\/strong>, <strong>AlmaLinux <\/strong>y <strong>Rocky Linux <\/strong>difieren seg&uacute;n su versi&oacute;n. Las versiones m&aacute;s antiguas utilizan el gestor de paquetes <strong>yum<\/strong>, mientras que las m&aacute;s recientes utilizan <strong>dnf<\/strong>.<\/p><p>Lee su documentaci&oacute;n o utiliza sitios web como <a href=\"https:\/\/distrowatch.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">DistroWatch<\/a> para comprobar el gestor de paquetes de tu sistema operativo. Dicho esto, los comandos son similares:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">sudo yum update &amp;&amp; sudo yum upgrade<\/pre><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">sudo dnf update &amp;&amp; sudo dnf upgrade<\/pre><p>Asimismo, los comandos de instalaci&oacute;n de la utilidad <strong>unzip <\/strong>son los siguientes:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">sudo yum install unzip<\/pre><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">sudo dnf install unzip<\/pre><p>Una vez finalizado el proceso, comprueba si <strong>unzip <\/strong>se ha instalado correctamente utilizando el siguiente comando. Es el mismo para todas las distribuciones:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip -v<\/pre><p>Si la utilidad est&aacute; configurada correctamente, tu interfaz de l&iacute;nea de comandos deber&iacute;a mostrar el n&uacute;mero de versi&oacute;n.<\/p><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"886\" height=\"60\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Utilizad-unzip.png\/public\" alt=\"Terminal muestra la versi&oacute;n de unzip instalada\" class=\"wp-image-39519\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Utilizad-unzip.png\/w=886,fit=scale-down 886w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Utilizad-unzip.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Utilizad-unzip.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Utilizad-unzip.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 886px) 100vw, 886px\" \/><\/figure><h2 class=\"wp-block-heading\" id=\"h-como-comprimir-y-descomprimir-archivos-en-linux\">C&oacute;mo comprimir y descomprimir archivos en Linux<\/h2><p>Una vez instalada la utilidad <strong>unzip<\/strong>, puedes empezar a extraer archivos en el sistema Linux. En esta secci&oacute;n, explicaremos c&oacute;mo utilizar la herramienta para varios casos de uso comunes.<\/p><p>\n\n\n\n<div><p class=\"important\"><strong>&iexcl;Importante!<\/strong> La configuraci&oacute;n del l&iacute;mite de tama&ntilde;o del sistema de archivos puede provocar un error al descomprimir un archivo en Linux. Si te encuentras con este problema, aumenta el l&iacute;mite en consecuencia.<\/p><\/div>\n\n\n\n<\/p><h3 class=\"wp-block-heading\" id=\"h-como-descomprimir-un-archivo\">C&oacute;mo descomprimir un archivo<\/h3><p>Para descomprimir un archivo en Linux, utiliza el comando con el nombre del elemento que quieras descomprimir. Recuerda que el archivo tambi&eacute;n debe estar en tu directorio actual. Aqu&iacute; tienes un ejemplo:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip archive_file.zip<\/pre><p>As&iacute; extraeras el contenido del archivo <strong>ZIP <\/strong>en el directorio de trabajo actual si tienes permisos de lectura-escritura.<\/p><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"734\" height=\"112\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/comando-unzip.png\/public\" alt=\"Extracci&oacute;n el contenido del archivo ZIP\" class=\"wp-image-39520\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/comando-unzip.png\/w=734,fit=scale-down 734w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/comando-unzip.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/comando-unzip.png\/w=150,fit=scale-down 150w\" sizes=\"(max-width: 734px) 100vw, 734px\" \/><\/figure>\n<\/div><p>Tambi&eacute;n puedes descomprimir archivos zip en un directorio diferente especificando la ruta como en el siguiente comando:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip path\/to\/the\/archive_file.zip<\/pre><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"844\" height=\"106\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Descomprimir-archivos-zip.png\/public\" alt=\"Descomprimir archivos desde otro lugar\" class=\"wp-image-39521\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Descomprimir-archivos-zip.png\/w=844,fit=scale-down 844w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Descomprimir-archivos-zip.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Descomprimir-archivos-zip.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Descomprimir-archivos-zip.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 844px) 100vw, 844px\" \/><\/figure><h3 class=\"wp-block-heading\" id=\"h-como-descomprimir-varios-archivos\">C&oacute;mo descomprimir varios archivos<\/h3><p>Para extraer simult&aacute;neamente varios archivos zip en la misma carpeta, utiliza un comod&iacute;n como el siguiente:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip \\*.zip<\/pre><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"636\" height=\"191\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/unzip-multiples-archivos.png\/public\" alt=\"Unzip multiples archivos\" class=\"wp-image-39522\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/unzip-multiples-archivos.png\/w=636,fit=scale-down 636w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/unzip-multiples-archivos.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/unzip-multiples-archivos.png\/w=150,fit=scale-down 150w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/figure>\n<\/div><p>El s&iacute;mbolo asterisco (*)<strong> <\/strong>representa cualquier car&aacute;cter. Por ejemplo, ejecuta lo siguiente para descomprimir archivos comprimidos con nombres similares, como <strong>file-1.zip<\/strong>, <strong>file-2.zip<\/strong>, etc:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip file-\\*.zip<\/pre><p>Cuando extraigas varios archivos <strong>ZIP <\/strong>utilizando un comod&iacute;n, aseg&uacute;rate de utilizar el car&aacute;cter de escape de la barra invertida (<strong>\\<\/strong>) para evitar que Terminal descomprima un archivo de otro.<\/p><h3 class=\"wp-block-heading\" id=\"h-como-extraer-archivos-a-un-directorio-especifico\">C&oacute;mo extraer archivos a un directorio espec&iacute;fico<\/h3><p>En lugar de utilizar el comando <strong>cd<\/strong>, utiliza la opci&oacute;n <strong>-d <\/strong>para descomprimir en una carpeta de otra ubicaci&oacute;n. Por ejemplo:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip archive_file.zip -d \/target\/folder\/destination<\/pre><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"884\" height=\"107\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/extraer-archvios-en-directorio-especifico.png\/public\" alt=\"Extrayendo archivos a un directorio espec&iacute;fico\" class=\"wp-image-39523\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/extraer-archvios-en-directorio-especifico.png\/w=884,fit=scale-down 884w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/extraer-archvios-en-directorio-especifico.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/extraer-archvios-en-directorio-especifico.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/extraer-archvios-en-directorio-especifico.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 884px) 100vw, 884px\" \/><\/figure><p>El destino puede ser absoluto o relativo al directorio de trabajo actual. Por ejemplo, si est&aacute;s en el directorio <strong>\/target<\/strong>, introduce lo siguiente para extraer el archivo comprimido al mismo destino:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip archive_file.zip -d \/directory\/destination<\/pre><p>Este comando tambi&eacute;n te permite descomprimir un archivo de una ubicaci&oacute;n a otra ruta de directorio sin moverte a ninguna de ellas. El comando tiene el siguiente aspecto:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip \/origin\/path\/archive_file.zip -d \/target\/folder\/destination<\/pre><h3 class=\"wp-block-heading\" id=\"h-como-hacer-una-extraccion-parcial-de-archivos-o-carpetas-especificos\">C&oacute;mo hacer una extracci&oacute;n parcial de archivos o carpetas espec&iacute;ficos<\/h3><p>Un archivo <strong>ZIP <\/strong>suele estar formado por varios archivos o carpetas. En Linux, puedes elegir extraer un elemento espec&iacute;fico especificando sus nombres despu&eacute;s del archivo <strong>ZIP <\/strong>como:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip file_archive.zip file1.txt<\/pre><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/extracci%C3%B3n-parcial-de-archivos-espec%C3%ADficos.png\/public\" alt=\"Extracci&oacute;n parcial de archivos o carpetas espec&iacute;ficos\" class=\"wp-image-39524\"><\/figure>\n<\/div><p>Para descomprimir varios archivos, simplemente enumera sus nombres despu&eacute;s del comando. Tambi&eacute;n puedes extraer una carpeta concreta:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip file_archive.zip folder_name<\/pre><p>Sin embargo, si quieres descomprimir una carpeta o archivo concreto dentro de un directorio, especifica la ruta completa. Por ejemplo, para extraer <strong>\/path<\/strong> dentro de la carpeta <strong>\/directory<\/strong>, introduce:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip file_archive.zip \/directory\/path<\/pre><p>Tambi&eacute;n puedes excluir determinados archivos de la extracci&oacute;n utilizando la opci&oacute;n <strong>-x<\/strong>. Por ejemplo, mantendremos archivados <strong>archive_1.txt <\/strong>y <strong>archive_2.txt <\/strong>utilizando este comando:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip file_archive.zip -x archive_1.txt archive_2.txt<\/pre><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/exclusi%C3%B3n-de-archivo-unzip.png\/public\" alt=\"\" class=\"wp-image-39525\"><\/figure>\n<\/div><p>Los administradores del servidor suelen excluir archivos si el archivo tiene mucho contenido. Tambi&eacute;n lo hacen para actualizar parcialmente un elemento concreto, con lo que el proceso es m&aacute;s eficaz al no tener que trabajar con muchos datos.<\/p><h3 class=\"wp-block-heading\" id=\"h-como-descomprimir-un-archivo-zip-protegido-con-contrasena\">C&oacute;mo descomprimir un archivo Zip protegido con contrase&ntilde;a<\/h3><p>Si descomprimes un archivo zip en linux protegido por contrase&ntilde;a sin introducir la clave de identificaci&oacute;n, Terminal te pedir&aacute; la credencial.<\/p><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/contrase%C3%B1a-archivo-unzip.png\/public\" alt=\"Descomprimir un archivo Zip protegido con contrase&ntilde;a\" class=\"wp-image-39526\"><\/figure>\n<\/div><p>Puedes escribir la contrase&ntilde;a manualmente y pulsar <strong>Intro<\/strong>. Sin embargo, el comando unzip de Linux te permite introducir las credenciales directamente mediante la opci&oacute;n <strong>-p<\/strong>:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip -p password file_archive.zip<\/pre><p>Hace que el proceso de extracci&oacute;n sea m&aacute;s eficaz. Sin embargo, te aconsejamos que evites este m&eacute;todo cuando varios usuarios trabajen en el mismo sistema, ya que expondr&aacute; credenciales sensibles en los registros de comandos.<\/p><p>La opci&oacute;n <strong>-p <\/strong>es &uacute;til si utilizas el comando <strong>unzip <\/strong>en scripts de automatizaci&oacute;n. Te permite extraer un archivo ZIP protegido por contrase&ntilde;a pasando las credenciales autom&aacute;ticamente en lugar de introducirlas a trav&eacute;s de la l&iacute;nea de comandos.<\/p><h3 class=\"wp-block-heading\" id=\"h-como-utilizar-unzip-en-scripts-de-automatizacion\">C&oacute;mo utilizar Unzip en scripts de automatizaci&oacute;n<\/h3><p>Los administradores de servidores suelen exportar los productos de procesos como las copias de seguridad o el registro de eventos como archivos <strong>ZIP <\/strong>para ahorrar espacio de almacenamiento. Deben descomprimir estos archivos para extraer los datos con otros fines.<\/p><p>Por ejemplo, extraer un registro <strong>ZIP <\/strong>te permite leer el historial de eventos o pasarlo a otro comando para filtrar los datos. En lugar de ejecutar <strong>unzip <\/strong>para cada archivo, utiliza un script de automatizaci&oacute;n para ejecutar el mismo comando en una sola ejecuci&oacute;n.<\/p><p>Para crear uno, <a href=\"\/mx\/tutoriales\/instalar-nano-text-editor\/\">utiliza un editor de texto como Nano<\/a>. Introduce el nombre con <strong>.sh <\/strong>como extensi&oacute;n de archivo, como en el siguiente ejemplo:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">sudo nano unzip_log.sh<\/pre><p>Introduce el comando dentro del archivo. Por ejemplo, el siguiente script descomprimir&aacute; un nuevo archivo de registro en una carpeta y eliminar&aacute; autom&aacute;ticamente los m&aacute;s antiguos cuando superen un n&uacute;mero determinado:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">#!\/bin\/bash\n#Log archive files location\nlog_archive=\"\/path\/to\/logs\/log_archive.zip\"\n\n#Destination for extracted files\nlog_destination=\"\/path\/to\/extracted\/logs\/\"\n\n#Maximum number of log files to keep\nmax_logs=5\n\n#Use the unzip command to extract files\nunzip \"$log_archive\" -d \"$log_destination\"\n\n#Log rotation\ncd \"$log_destination\" || exit\n\n# List and sort log files\nlog_files=($(ls -1t *.log))\n\n# Check if log rotation is needed\nif [ ${#log_files[@]} -gt $max_logs ]; then\n\n# Delete files and keep the recent ones\nexcess_logs=$(( ${#log_files[@]} - max_logs ))\nfor ((i = 0; i &lt; excess_logs; i++)); do\nrm \"${log_files[$i]}\"\ndone\nfi<\/pre><p>Pulsa <strong>Ctrl + X<\/strong>, <strong>Y <\/strong>e <strong>Intro <\/strong>para guardar los cambios. Ejecuta posteriormente estos comandos para hacer ejecutable el script y ejecutarlo:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">sudo chmod +x unzip_log.sh<\/pre><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">.\/unzip_log.sh<\/pre><p>Actualmente, el comando extrae el registro s&oacute;lo cuando lo ejecutas. Para ejecutarlo regularmente, establece un horario utilizando un <a href=\"\/mx\/tutoriales\/cron-job\/\">cronjob<\/a>. Por ejemplo, lo siguiente aplicar&aacute; el script diariamente a las 2 AM:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">0 2 * * * \/path\/to\/unzip_log.sh<\/pre><h3 class=\"wp-block-heading\" id=\"h-como-combinar-unzip-con-otros-comandos-de-linux\">C&oacute;mo combinar Unzip con otros comandos de Linux<\/h3><p>Linux te permite combinar varias utilidades para completar una tarea espec&iacute;fica en una sola ejecuci&oacute;n. Esto hace que la administraci&oacute;n del servidor sea m&aacute;s eficiente, ya que no necesitas ejecutar los comandos individualmente.<\/p><p>Por ejemplo, combina el comando <strong>unzip <\/strong>con <strong>find <\/strong>para localizar varios archivos y extraerlos simult&aacute;neamente. Aqu&iacute; tienes un ejemplo:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">find \/path\/to\/zips -type f -name \"*.zip\" -exec unzip {} -d \/path\/to\/destination\/ \\;<\/pre><p>En el fragmento, el comando <strong>find <\/strong>localiza archivos <strong>ZIP <\/strong>en el directorio <strong>\/ruta\/a\/zips<\/strong>. A continuaci&oacute;n, pasa los elementos recuperados al comando <strong>unzip<\/strong>, que representan las llaves.<\/p><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"961\" height=\"84\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/comandos-unzip-y-find.png\/public\" alt=\"Comandos find y unzip combinados\" class=\"wp-image-39527\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/comandos-unzip-y-find.png\/w=961,fit=scale-down 961w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/comandos-unzip-y-find.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/comandos-unzip-y-find.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/comandos-unzip-y-find.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 961px) 100vw, 961px\" \/><\/figure><p>Tambi&eacute;n puedes a&ntilde;adir el comando <strong>grep <\/strong>para descomprimir archivos que contengan un patr&oacute;n determinado. Considera el siguiente ejemplo:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip archive.zip $(unzip -l archive.zip | grep \"pattern\" | awk '{print $4}')<\/pre><p>En el comando, especificamos los elementos a extraer de <strong>archive.zip <\/strong>dentro de los par&eacute;ntesis. La opci&oacute;n <strong>-l <\/strong>lista todo el contenido del archivo <strong>ZIP, <\/strong>que <strong>grep <\/strong>filtrar&aacute; bas&aacute;ndose en el patr&oacute;n dado.<\/p><p>A continuaci&oacute;n, la tuber&iacute;a (<strong>|<\/strong>) pasa los elementos que contienen el patr&oacute;n al comando <strong>awk<\/strong>, extrayendo la cuarta columna que contiene el nombre del archivo.<\/p><p>Puedes incorporar <strong>unzip <\/strong>con otras utilidades espec&iacute;ficas para tus tareas. Lee nuestro art&iacute;culo de <a href=\"\/mx\/tutoriales\/linux-comandos\/\">comandos de Linux<\/a> y consulta su documentaci&oacute;n en el sitio web de <a href=\"https:\/\/www.gnu.org\/home.es.html\" target=\"_blank\" rel=\"noreferrer noopener\">GNU<\/a> para saber m&aacute;s sobre las posibles combinaciones.<\/p><h2 class=\"wp-block-heading\" id=\"h-comparacion-del-comando-unzip-con-metodos-alternativos\">Comparaci&oacute;n del comando Unzip con m&eacute;todos alternativos<\/h2><p>En Linux existen otros formatos de archivo y compresi&oacute;n, como <strong>tar <\/strong>y <strong>tar.gz<\/strong>. El <a href=\"\/mx\/tutoriales\/como-usar-comando-tar-linux\/\">comando tar<\/a> te permite crear un archivo sin reducir el tama&ntilde;o del fichero, mientras que <strong>gzip <\/strong>permite la compresi&oacute;n.<\/p><p>A diferencia del comando <strong>zip<\/strong>, estas dos utilidades no admiten la protecci&oacute;n mediante contrase&ntilde;a por defecto y pueden ser incompatibles con sistemas operativos que no sean UNIX, como Windows.<\/p><p>Dicho esto, estas compresiones son m&aacute;s habituales en los sistemas Linux, ya que est&aacute;n preinstaladas y la mayor&iacute;a de los paquetes de instalaci&oacute;n vienen en un archivo <strong>tar.gz <\/strong>o <strong>tar<\/strong>. Adem&aacute;s, estas utilidades ofrecen m&aacute;s modularidad y flexibilidad.<\/p><p>Para descomprimir un archivo <strong>tar.gz <\/strong>o <strong>tar<\/strong>, utiliza los siguientes comandos:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">tar -x archive.tar<\/pre><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">gunzip archive.tar.gz<\/pre><p>Para las distribuciones Linux de escritorio, tambi&eacute;n puedes utilizar un visor y extractor de archivos <strong>ZIP <\/strong>con una interfaz gr&aacute;fica de usuario como <a href=\"https:\/\/peazip.github.io\/\" target=\"_blank\" rel=\"noreferrer noopener\">PeaZip<\/a>.&nbsp;<\/p><p>Es m&aacute;s sencillo que la interfaz de l&iacute;nea de comandos, pero puede resultar ineficaz, ya que no puedes combinar utilidades ni utilizar la automatizaci&oacute;n de scripts.<\/p><h2 class=\"wp-block-heading\" id=\"h-buenas-practicas-para-gestionar-archivos-zip-en-linux\">Buenas pr&aacute;cticas para gestionar archivos Zip en Linux<\/h2><p>En esta secci&oacute;n, explicaremos c&oacute;mo gestionar archivos <strong>ZIP <\/strong>de<strong> <\/strong>forma segura y eficaz en un sistema Linux.<\/p><p><strong>Comprueba la integridad de los archivos comprimidos<\/strong><\/p><p>Los ciberdelincuentes suelen inyectar un archivo ZIP con c&oacute;digo malicioso o malware. Dado que un archivo <strong>ZIP <\/strong>se compone de varios elementos, los usuarios no suelen notar rarezas ni siquiera despu&eacute;s de descomprimir los archivos comprimidos.<\/p><p>Para evitar el riesgo de seguridad, lista el contenido de un archivo <strong>ZIP <\/strong>antes de descomprimirlo utilizando la opci&oacute;n <strong>-l<\/strong>:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip -l downloaded_file.zip<\/pre><p>Adem&aacute;s, aseg&uacute;rate de que la suma de comprobaci&oacute;n del archivo coincide con la de la fuente de descarga para garantizar su integridad. Para ello, ejecuta:&nbsp;<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">md5sum downloaded_file.zip<\/pre><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" width=\"592\" height=\"46\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/integralidad-de-archivos-terminal.png\/public\" alt=\"Terminal mostrando la integridad de los archivos descargados \" class=\"wp-image-39528\" style=\"width:592px;height:auto\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/integralidad-de-archivos-terminal.png\/w=592,fit=scale-down 592w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/integralidad-de-archivos-terminal.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/integralidad-de-archivos-terminal.png\/w=150,fit=scale-down 150w\" sizes=\"(max-width: 592px) 100vw, 592px\" \/><\/figure>\n<\/div><p>Utiliza tambi&eacute;n la opci&oacute;n <strong>-t <\/strong>para comprobar la coherencia estructural del archivo:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">uzip -t downloaded_file.zip<\/pre><p><strong>Conserva los archivos y permisos existentes<\/strong><\/p><p>La extracci&oacute;n puede sobrescribir archivos existentes con el mismo nombre en el destino, lo que provocar&iacute;a una p&eacute;rdida de datos. Utiliza la opci&oacute;n <strong>-n <\/strong>para forzar a <strong>unzip <\/strong>a omitir los elementos ya presentes:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip -n archive.zip<\/pre><p>No necesitas confirmar la extracci&oacute;n del archivo <strong>ZIP <\/strong>si ya existe el mismo elemento en la carpeta de destino, ya que <strong>unzip <\/strong>los omitir&aacute; autom&aacute;ticamente.<\/p><p>Adem&aacute;s de sobrescribirse, los permisos de los archivos o carpetas pueden diferir de los del archivo <strong>ZIP original <\/strong>tras la extracci&oacute;n.<\/p><p>Aunque puedes <a href=\"\/mx\/tutoriales\/cambiar-permisos-y-propietarios-linux-linea-de-comandos\/\">cambiar los permisos de los archivos manualmente utilizando chmod<\/a>, resulta ineficaz si extraes muchos archivos de un fichero <strong>ZIP<\/strong>. Para conservar estas propiedades, utiliza la opci&oacute;n <strong>-o<\/strong>:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">unzip -o archive.zip<\/pre><p><strong>Aprovecha el asistente con IA Kodee del VPS de Hostinger<\/strong><\/p><p>Para los principiantes en VPS, utilizar la interfaz de l&iacute;nea de comandos para descomprimir archivos en Linux puede resultar dif&iacute;cil debido a la falta de interfaz gr&aacute;fica de usuario.&nbsp;<\/p><p>Adem&aacute;s, escribir scripts de automatizaci&oacute;n o comandos espec&iacute;ficos para tareas concretas es complicado.<\/p><p>Con el alojamiento VPS de Hostinger, puedes utilizar a <strong>Kodee<\/strong>, nuestro <strong>asistente con IA <\/strong>para generar f&aacute;cilmente comandos <strong>unzip <\/strong>y scripts bash mediante sencillas instrucciones. Luego pueden copiar y pegar la salida para ahorrar tiempo y esfuerzo.<\/p><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Asistente-con-IA.png\/public\" alt=\"Asistente con IA de Hostinger\" class=\"wp-image-39529\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Asistente-con-IA.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Asistente-con-IA.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Asistente-con-IA.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Asistente-con-IA.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><p>Por ejemplo, introduce &ldquo;Genera un comando unzip de Linux para extraer archivos que contengan el patr&oacute;n <strong>&ldquo;log&rdquo;<\/strong> del fichero <strong>archivo.zip<\/strong> dentro de <strong>\/inicio\/log_extract&rdquo; <\/strong>o &ldquo;Escribe un script bash que descomprima autom&aacute;ticamente un registro archivado sin sobrescribir los archivos existentes&rdquo;.<\/p><p>Para acceder a la herramienta, haz clic en VPS en el men&uacute; superior de <strong>hPanel <\/strong>y selecciona <strong>Administrar <\/strong>en tu plan. Navega hasta la barra lateral &rarr; <strong>Kodee<\/strong>.<\/p><figure class=\"wp-block-image size-large\"><a href=\"\/mx\/servidor-vps\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=1024,h=1024,fit=scale-down\" alt=\"\" class=\"wp-image-29287\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=768,fit=scale-down 768w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=1536,fit=scale-down 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><h2 class=\"wp-block-heading\" id=\"h-conclusion\">Conclusi&oacute;n<\/h2><p>Al igual que <strong>tar <\/strong>y <strong>gunzip<\/strong>, el comando <strong>unzip <\/strong>te permite extraer un archivo comprimido en Linux. Sin embargo, debes instalarlo manualmente mediante un gestor de paquetes como <strong>APT <\/strong>para <strong>Debian <\/strong>o <strong>DNF <\/strong>para derivados de RHEL como <strong>CentOS<\/strong>.<\/p><p>Para descomprimir archivos, escribe sus nombres despu&eacute;s del comando. Por defecto, extraer&aacute; el contenido en tu carpeta actual, pero puedes especificar un directorio diferente utilizando la opci&oacute;n <strong>-d<\/strong>.&nbsp;<\/p><p>Adem&aacute;s, descomprime elementos concretos escribiendo sus nombres despu&eacute;s del archivo.<\/p><p>Puedes utilizar el comando <strong>unzip <\/strong>para una tarea espec&iacute;fica, integr&aacute;ndolo en un script bash o combin&aacute;ndolo con otras utilidades.&nbsp;<\/p><p>Antes de extraer, utiliza la opci&oacute;n <strong>-n <\/strong>para asegurarte de que no sobrescribes los archivos existentes y comprueba el contenido de un archivo <strong>ZIP <\/strong>utilizando <strong>-l <\/strong>para minimizar los riesgos de seguridad.<\/p><p>Con Hostinger, puedes simplemente preguntar y <strong>Kodee<\/strong> generar&aacute; comandos o scripts unzip<strong> <\/strong>para tareas espec&iacute;ficas. S&oacute;lo tienes que introducir las instrucciones, copiar y pegar el resultado en tu Terminal.<\/p><p>Esperamos que esta informaci&oacute;n te haya sido de utilidad. Si tienes comentarios o preguntas, escr&iacute;belas en la secci&oacute;n de abajo.&nbsp;<\/p><p>\n\n\n\n<div class=\"protip\">\n                    <p class=\"title\">M&aacute;s comandos de Linux para la gesti&oacute;n de archivos<\/p>\n                    <p><a href=\"\/mx\/tutoriales\/borrar-archivos-carpetas-linux\/\">C&oacute;mo eliminar archivos y directorios<\/a><br><a href=\"\/mx\/tutoriales\/usar-comando-touch-linux-ejemplos\/\">C&oacute;mo crear un archivo vac&iacute;o<\/a><br><a href=\"\/mx\/tutoriales\/como-usar-comando-find-locate-en-linux\/\">C&oacute;mo localizar un archivo<\/a><br><a href=\"\/mx\/tutoriales\/como-usar-comando-tar-linux\/\">C&oacute;mo comprimir un archivo con el comando tar<\/a><br><a href=\"\/mx\/tutoriales\/comando-chown-linux\/\">C&oacute;mo cambiar la propiedad de un archivo con el comando chown<\/a><br><a href=\"\/mx\/tutoriales\/cambiar-permisos-y-propietarios-linux-linea-de-comandos\/\">C&oacute;mo cambiar los permisos de un archivo con el comando chmod<\/a><br><a href=\"\/mx\/tutoriales\/renombrar-archivos-linux\/\">C&oacute;mo renombrar un archivo<\/a><br><a href=\"\/mx\/tutoriales\/crear-enlace-simbolico-linux\/\">C&oacute;mo crear un enlace simb&oacute;lico<\/a><\/p>\n                <\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para descomprimir, los usuarios de Linux pueden aplicar un comando de utilidad similar al de otros formatos de compresi&oacute;n, como tar y gzip.&nbsp; Entender c&oacute;mo utilizar el comando unzip de Linux ayuda a mejorar la eficacia en diversas tareas, como la distribuci&oacute;n de software o el archivado de datos. A diferencia de las dos utilidades, [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/mx\/tutoriales\/comando-unzip-linux\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":138,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_title":"C\u00f3mo utilizar el comando unzip de Linux en %currentyear%","rank_math_description":"Las opciones Zip y Unzip de Linux tienen muchos beneficios. En este tutorial te ense\u00f1amos a usarlos para aprovechar tu VPS al m\u00e1ximo.","rank_math_focus_keyword":"Unzip Linux","footnotes":""},"categories":[5700],"tags":[],"class_list":["post-9094","post","type-post","status-publish","format-standard","hentry","category-vps"],"hreflangs":[{"locale":"en-US","link":"https:\/\/www.hostinger.com\/tutorials\/how-to-unzip-files-linux","default":0},{"locale":"fr-FR","link":"https:\/\/www.hostinger.com\/fr\/tutoriels\/unzip-linux","default":0},{"locale":"es-ES","link":"https:\/\/www.hostinger.com\/es\/tutoriales\/comando-unzip-linux","default":0},{"locale":"id-ID","link":"https:\/\/www.hostinger.com\/id\/tutorial\/unzip-linux","default":0},{"locale":"en-GB","link":"https:\/\/www.hostinger.com\/uk\/tutorials\/how-to-unzip-files-linux","default":0},{"locale":"en-MY","link":"https:\/\/www.hostinger.com\/my\/tutorials\/how-to-unzip-files-linux\/","default":0},{"locale":"en-PH","link":"https:\/\/www.hostinger.com\/ph\/tutorials\/how-to-unzip-files-linux\/","default":0},{"locale":"es-MX","link":"https:\/\/www.hostinger.com\/mx\/tutoriales\/comando-unzip-linux","default":0},{"locale":"es-CO","link":"https:\/\/www.hostinger.com\/co\/tutoriales\/comando-unzip-linux","default":0},{"locale":"es-AR","link":"https:\/\/www.hostinger.com\/ar\/tutoriales\/comando-unzip-linux","default":0},{"locale":"en-IN","link":"https:\/\/www.hostinger.com\/in\/tutorials\/how-to-unzip-files-linux","default":0},{"locale":"en-CA","link":"https:\/\/www.hostinger.com\/ca\/tutorials\/how-to-unzip-files-linux","default":0},{"locale":"en-AU","link":"https:\/\/www.hostinger.com\/au\/tutorials\/how-to-unzip-files-linux","default":0},{"locale":"en-NG","link":"https:\/\/www.hostinger.com\/ng\/tutorials\/how-to-unzip-files-linux","default":0}],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts\/9094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/users\/138"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/comments?post=9094"}],"version-history":[{"count":15,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts\/9094\/revisions"}],"predecessor-version":[{"id":42720,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts\/9094\/revisions\/42720"}],"wp:attachment":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/media?parent=9094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/categories?post=9094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/tags?post=9094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}