{"id":7652,"date":"2018-11-16T08:59:13","date_gmt":"2018-11-16T08:59:13","guid":{"rendered":"https:\/\/blog.hostinger.io\/mx-tutoriales\/?p=7652"},"modified":"2026-03-10T16:28:49","modified_gmt":"2026-03-10T15:28:49","slug":"que-es-html","status":"publish","type":"post","link":"\/mx\/tutoriales\/que-es-html\/","title":{"rendered":"\u00bfQu\u00e9 es HTML? Explicaci\u00f3n de los fundamentos del Lenguaje de marcado de hipertexto"},"content":{"rendered":"<p>La definici&oacute;n de HTML es <strong>Lenguaje de Marcado de Hipertexto<\/strong>. Es un lenguaje de marcado est&aacute;ndar para la creaci&oacute;n de p&aacute;ginas web. Permite construir y estructurar secciones, p&aacute;rrafos y enlaces utilizando elementos HTML (los bloques de construcci&oacute;n de una p&aacute;gina web) como etiquetas y atributos.<\/p><p>HTML tiene muchos casos de uso como: <\/p><ul class=\"wp-block-list\">\n<li><strong>Desarrollo web<\/strong>: los desarrolladores utilizan c&oacute;digo HTML para dise&ntilde;ar la forma en que un navegador muestra los elementos de una p&aacute;gina web, como texto, hiperv&iacute;nculos y archivos multimedia.<\/li>\n\n\n\n<li><strong>Navegaci&oacute;n por Internet<\/strong>: los usuarios pueden navegar f&aacute;cilmente e insertar enlaces entre p&aacute;ginas y sitios web relacionados, ya que el HTML se utiliza mucho para incrustar hiperv&iacute;nculos.<\/li>\n\n\n\n<li><strong>Documentaci&oacute;n web<\/strong>: HTML permite organizar y dar formato a los documentos, de forma similar a Microsoft Word.<\/li>\n<\/ul><p>Tambi&eacute;n hay que se&ntilde;alar que HTML no se considera un lenguaje de programaci&oacute;n, ya que no puede crear funcionalidad din&aacute;mica, aunque ahora se considera un est&aacute;ndar web oficial. El Consorcio World Wide Web (W3C) mantiene y desarrolla las especificaciones HTML, adem&aacute;s de proporcionar actualizaciones peri&oacute;dicas.<\/p><p>Este art&iacute;culo repasar&aacute; los conceptos b&aacute;sicos de HTML, incluyendo c&oacute;mo funciona, sus ventajas y sus desventajas, y c&oacute;mo se relaciona con CSS y JavaScript.<\/p><p class=\"has-text-align-center\"><a href=\"https:\/\/assets.hostinger.com\/content\/ES-Web-Development-Glossary-for-Beginners.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Descarga la hoja de trucos HTML definitiva<\/a><\/p><h2 class=\"wp-block-heading\" id=\"h-que-es-el-html-nbsp-video\">&iquest;Qu&eacute; es el HTML?&nbsp; &ndash; Video<\/h2><p>&iquest;Tienes prisa? Mira este tutorial en video en su lugar y descubre m&aacute;s sobre HTML. <\/p><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"&iquest;Qu&eacute; es el HTML? | Explicado\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/pUjfXhQeSdc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure><p>\n  <div class=\"youtube-shortcode\">\n    <div class=\"row\">\n      <div class=\"col-7 col-sm-8 d-flex align-items-center\">\n        <img decoding=\"async\" class=\"channel-logo\" src=\"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-content\/themes\/tutorialsthemeuplift\/public\/images\/youtube-channels\/hostinger-spain.jpg\" alt=\"youtube channel logo\">\n        <div class=\"d-flex flex-column justify-content-between\">\n          <span class=\"slogan d-none d-sm-block\">Suscribirse \u00a1Para m\u00e1s videos educativos!<\/span>\n          <span class=\"channel-name\">Academia de Hostinger<\/span>\n                    <\/div>\n      <\/div>\n      <div class=\"col-5 col-sm-4 d-flex align-items-center justify-content-end\">\n        <a class=\"subscribe-button\" target=\"_blank\" rel=\"nofollow noopener noreferrer\" href=\"http:\/\/www.youtube.com\/channel\/UCYmKCu1yo_L0fqKe3U_oMnw?sub_confirmation=1\">\n          <img decoding=\"async\" src=\"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-content\/themes\/tutorialsthemeuplift\/public\/images\/icons\/youtube.svg\" alt=\"subscribe\">\n          <span>Suscribirse<\/span>\n        <\/a>\n      <\/div>\n    <\/div>\n  <\/div>\n\n    \n\n\n\n<\/p><h2 class=\"wp-block-heading\" id=\"h-como-funciona-html\">&iquest;C&oacute;mo funciona HTML?<\/h2><div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"2048\" height=\"3478\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/12\/ES_html_historical_milestones.png\/public\" alt=\"Funcionamiento de HTML \" class=\"wp-image-37147\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/12\/ES_html_historical_milestones.png\/w=2048,fit=scale-down 2048w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/12\/ES_html_historical_milestones.png\/w=177,fit=scale-down 177w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/12\/ES_html_historical_milestones.png\/w=603,fit=scale-down 603w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/12\/ES_html_historical_milestones.png\/w=88,fit=scale-down 88w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/12\/ES_html_historical_milestones.png\/w=707,fit=scale-down 707w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/12\/ES_html_historical_milestones.png\/w=706,fit=scale-down 706w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure><\/div><p>Un sitio web normal incluye varias p&aacute;ginas HTML diferentes. Por ejemplo, una <strong>p&aacute;gina de inicio<\/strong>, una <strong>p&aacute;gina de presentaci&oacute;n<\/strong> y una <strong>p&aacute;gina de contacto<\/strong> tienen archivos HTML distintos.<\/p><p>Los documentos HTML son archivos que terminan con una extensi&oacute;n <strong>.html<\/strong> o <strong>.htm<\/strong>. El navegador web lee el archivo HTML y muestra su contenido para que los usuarios de Internet puedan verlo.<\/p><p>Todas las p&aacute;ginas HTML cuentan con una serie de <strong>elementos HTML<\/strong>, formados por un conjunto de <strong>etiquetas<\/strong> y <strong>atributos<\/strong>. <\/p><p>Los elementos HTML son los bloques de construcci&oacute;n de una p&aacute;gina web. Una etiqueta indica al navegador d&oacute;nde empieza y termina un elemento, mientras que un atributo describe las caracter&iacute;sticas de un elemento.<\/p><p>Las tres partes principales de un elemento son:<\/p><ul class=\"wp-block-list\">\n<li><strong>Etiqueta de apertura:<\/strong> se utiliza para indicar d&oacute;nde empieza a tener efecto un elemento. Esta se envuelve con corchetes de apertura y cierre. Por ejemplo, usa la etiqueta de apertura <strong>&lt;p&gt;<\/strong> para crear un p&aacute;rrafo.<\/li>\n\n\n\n<li><strong>Contenido:<\/strong> ws el resultado que ven los dem&aacute;s usuarios.<\/li>\n\n\n\n<li><strong>Etiqueta de cierre:<\/strong> igual que la de apertura, pero con una barra inclinada antes del nombre del elemento. Por ejemplo, <strong>&lt;\/p&gt;<\/strong> para terminar un p&aacute;rrafo.<\/li>\n<\/ul><p>La combinaci&oacute;n de estas tres partes crear&aacute; un elemento HTML:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"null\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">&lt;p&gt;As&iacute; es como se a&ntilde;ade un p&aacute;rrafo en HTML.&lt;\/p&gt;<\/pre><p>Otra parte fundamental de un elemento HTML es su <strong>atributo<\/strong>, que tiene dos secciones: un <strong>nombre<\/strong> y un <strong>valor de atributo<\/strong>. El nombre identifica la informaci&oacute;n adicional que el usuario quiere a&ntilde;adir, mientras que el valor del atributo da m&aacute;s especificaciones.<\/p><p>Por ejemplo, un elemento de estilo que a&ntilde;ada el color p&uacute;rpura y la tipograf&iacute;a <strong>verdana<\/strong> tendr&aacute; el siguiente aspecto:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">&lt;p style=\"color:purple;font-family:verdana\"&gt;As&iacute;&nbsp;es&nbsp;como&nbsp;se&nbsp;a&ntilde;ade&nbsp;un&nbsp;p&aacute;rrafo&nbsp;en&nbsp;HTML.&lt;\/p&gt;<\/pre><p>Otro atributo, la clase, es el m&aacute;s importante para el desarrollo y la programaci&oacute;n. El atributo class a&ntilde;ade informaci&oacute;n de estilo que puede funcionar en diferentes elementos con el mismo valor de class.<\/p><p>Por ejemplo, usaremos el mismo estilo para un encabezado <strong>&lt;h1&gt;<\/strong> y un p&aacute;rrafo <strong>&lt;p&gt;<\/strong>. El estilo incluye el color de fondo, el color del texto, el borde, el margen y el relleno, bajo la clase <strong>.important<\/strong>. Para obtener el mismo estilo entre <strong>&lt;h1&gt;<\/strong> y<strong> &lt;p&gt;<\/strong>, a&ntilde;ada <strong>class=&rsquo;important&rsquo;<\/strong>&nbsp;despu&eacute;s de cada etiqueta de apertura:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">&lt;html&gt;\n&lt;head&gt;\n&lt;style&gt;\n.important {\n &nbsp;background-color: blue;\n &nbsp;color: white;\n &nbsp;border: 2px solid black;\n &nbsp;margin: 2px;\n &nbsp;padding: 2px;\n}\n&lt;\/style&gt;\n&lt;\/head&gt;\n&lt;body&gt;\n\n&lt;h1 class=\"important\"&gt;Esto es un t&iacute;tulo.&lt;\/h1&gt;\n&lt;p class=\"important\"&gt;Esto es un p&aacute;rrafo.&lt;\/p&gt;\n\n&lt;\/body&gt;\n&lt;\/html&gt;<\/pre><p>La mayor&iacute;a de los elementos tienen una etiqueta de apertura y otra de cierre, pero algunos elementos no necesitan las de cierre para funcionar, como los <strong>elementos vac&iacute;os<\/strong>. Estos elementos no utilizan una etiqueta de cierre porque no tienen contenido:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">&lt;img&nbsp;src=\"\/\"&nbsp;alt=\"Image\"&gt;<\/pre><p>Esta etiqueta de imagen tiene dos atributos: un atributo <strong>src<\/strong>, la ruta de la imagen, y un atributo <strong>alt<\/strong>, el texto descriptivo. Sin embargo, no tiene contenido ni etiqueta final.<\/p><p>Por &uacute;ltimo, todo documento HTML debe comenzar con una declaraci&oacute;n <strong>&lt;!DOCTYPE&gt;<\/strong> para informar al navegador sobre el tipo de documento. Con HTML5, la declaraci&oacute;n p&uacute;blica doctype HTML ser&aacute;:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">&lt;!DOCTYPE&nbsp;html&gt;<\/pre><h2 class=\"wp-block-heading\" id=\"h-las-etiquetas-y-elementos-html-mas-utilizados\">Las etiquetas y elementos HTML m&aacute;s utilizados<\/h2><p>Actualmente, existen 142 etiquetas HTML que nos permiten crear diversos elementos. Aunque los navegadores modernos ya no soportan algunas de estas etiquetas, aprender los diferentes elementos disponibles sigue siendo beneficioso.<\/p><p>En esta secci&oacute;n hablaremos de las etiquetas HTML m&aacute;s utilizadas y de dos elementos principales: los <strong>elementos de bloque<\/strong> y los <strong>elementos en l&iacute;nea<\/strong>.<\/p><h3 class=\"wp-block-heading\" id=\"h-elementos-de-bloque\">Elementos de bloque<\/h3><p>Un elemento de bloque ocupa todo el ancho de la p&aacute;gina. Siempre comienza una nueva l&iacute;nea en el documento. Por ejemplo, un elemento de <strong>encabezado<\/strong> estar&aacute; en una l&iacute;nea separada de un elemento de <strong>p&aacute;rrafo<\/strong>.<\/p><p>Todas las p&aacute;ginas HTML utilizan estas tres etiquetas:<\/p><ol class=\"wp-block-list\">\n<li>La etiqueta <strong>&lt;html&gt; <\/strong>es el elemento ra&iacute;z que define todo el documento HTML.<\/li>\n\n\n\n<li>La etiqueta <strong>&lt;head&gt; <\/strong>contiene informaci&oacute;n meta como el t&iacute;tulo y el conjunto de caracteres de la p&aacute;gina.<\/li>\n\n\n\n<li>La etiqueta <strong>&lt;body&gt;<\/strong>&nbsp;encierra todo el contenido que aparece en la p&aacute;gina.<\/li>\n<\/ol><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"null\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">&lt;html&gt;\n  &lt;head&gt;\n    &lt;!-- INFORMACION META--&gt;  \n  &lt;\/head&gt;\n  &lt;body&gt;\n    &lt;!-- CONTENIDO DE LA PAGINA --&gt;\n  &lt;\/body&gt;\n&lt;\/html&gt;<\/pre><p>Otras etiquetas de bloque populares son:<\/p><ul class=\"wp-block-list\">\n<li><strong>Etiquetas de encabezado<\/strong>: estas van desde <strong>&lt;h1&gt;<\/strong>&nbsp;a <strong>&lt;h6&gt;<\/strong>, donde h1 es el tama&ntilde;o m&aacute;s grande, disminuyendo a medida que se avanza hasta el h6.<\/li>\n\n\n\n<li><strong>Etiquetas de p&aacute;rrafo<\/strong>: todas se encierran utilizando la etiqueta <strong>&lt;p&gt;<\/strong>.<\/li>\n\n\n\n<li><strong>Etiquetas de listas:<\/strong> tienen distintas variaciones. Usa la etiqueta <strong>&lt;ol&gt;<\/strong> para las listas ordenadas y <strong>&lt;ul&gt;<\/strong> para las no ordenadas. Luego, encierra los elementos individuales de la lista con la etiqueta <strong>&lt;li&gt;<\/strong>.<\/li>\n<\/ul><h3 class=\"wp-block-heading\" id=\"h-elementos-en-linea\">Elementos en l&iacute;nea<\/h3><p>Un elemento en l&iacute;nea da formato al contenido interno de los elementos de bloque, agregando por ejemplo enlaces y texto enfatizado. Los elementos en l&iacute;nea se utilizan sobre todo para dar formato al texto sin romper el flujo del contenido.<\/p><p>Por ejemplo, una etiqueta <strong>&lt;strong&gt;<\/strong> muestra un elemento en negrita, mientras que la etiqueta <strong>&lt;em&gt;<\/strong> lo muestra en cursiva. Los hiperv&iacute;nculos tambi&eacute;n son elementos en l&iacute;nea que utilizan una etiqueta <strong>&lt;a&gt;<\/strong> y un atributo <strong>href<\/strong> para indicar el destino del enlace:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">&lt;a href=\"https:\/\/ejemplo.com\/\"&gt;Haz click aqu&iacute;&lt;\/a&gt;<\/pre><h2 class=\"wp-block-heading\" id=\"h-evolucion-de-html-cual-es-la-diferencia-entre-html-y-html5\">Evoluci&oacute;n de HTML: &iquest;Cu&aacute;l es la diferencia entre HTML y HTML5?<\/h2><p>La primera versi&oacute;n de HTML constaba de 18 etiquetas. Desde entonces, cada nueva versi&oacute;n trajo nuevas etiquetas y atributos a&ntilde;adidos al marcado. La actualizaci&oacute;n m&aacute;s significativa del lenguaje hasta ahora fue la introducci&oacute;n de <strong>HTML5<\/strong> en 2014.<\/p><p>La principal <a href=\"\/mx\/tutoriales\/diferencia-entre-html-y-html5\/\">diferencia entre HTML y HTML5<\/a> es que este &uacute;ltimo admite nuevos tipos de controles de formulario. HTML5 tambi&eacute;n introdujo varias etiquetas sem&aacute;nticas que describen claramente el contenido, como <strong>&lt;article&gt;<\/strong>, <strong>&lt;header&gt;<\/strong> y <strong>&lt;footer&gt;<\/strong>.<\/p><h2 class=\"wp-block-heading\" id=\"h-ventajas-y-desventajas-de-html\">Ventajas y desventajas de HTML<\/h2><p>Como cualquier otro lenguaje inform&aacute;tico, HTML tiene sus puntos fuertes y sus limitaciones.<\/p><p><strong>Ventajas de HTML:<\/strong><\/p><ul class=\"wp-block-list\">\n<li><strong>Para principiantes:<\/strong> HTML tiene un marcado limpio y consistente, as&iacute; como una curva de aprendizaje poco pronunciada.<\/li>\n\n\n\n<li><strong>Soporte:<\/strong> el lenguaje es ampliamente utilizado, con muchos recursos y una gran comunidad de apoyo.<\/li>\n\n\n\n<li><strong>Accesible:<\/strong> es de c&oacute;digo abierto y completamente gratuito. HTML se ejecuta de forma nativa en todos los navegadores web.<\/li>\n\n\n\n<li><strong>Flexible:<\/strong> HTML es f&aacute;cilmente integrable con lenguajes backend como <a href=\"\/mx\/tutoriales\/que-es-php\/\">PHP<\/a> y <a href=\"\/mx\/tutoriales\/instalar-node-js-ubuntu\/\">Node.js<\/a>.<\/li>\n<\/ul><p><strong>Desventajas de HTML:<\/strong><\/p><ul class=\"wp-block-list\">\n<li><strong>Est&aacute;tico:<\/strong> este lenguaje se utiliza principalmente para <a href=\"\/mx\/tutoriales\/pagina-web-estatica\/\">p&aacute;ginas web est&aacute;ticas<\/a>. Para una funcionalidad din&aacute;mica, puede ser necesario utilizar JavaScript o un lenguaje de back-end como PHP.<\/li>\n\n\n\n<li><strong>P&aacute;gina HTML independiente:<\/strong> los usuarios tienen que crear p&aacute;ginas web individuales para HTML, aunque los elementos sean los mismos.<\/li>\n\n\n\n<li><strong>Compatibilidad con los navegadores:<\/strong> algunos navegadores tardan en adoptar nuevas funciones. A veces, los navegadores m&aacute;s antiguos no reproducen las nuevas etiquetas.<\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-como-se-relacionan-html-css-y-javascript\">&iquest;C&oacute;mo se relacionan HTML, CSS y JavaScript?<\/h2><p>El HTML se utiliza para a&ntilde;adir elementos de texto y crear la estructura del contenido. Sin embargo, no es suficiente para construir un sitio web profesional y totalmente responsivo. <\/p><p>Por eso, HTML necesita la ayuda de las <a href=\"\/mx\/tutoriales\/codigos-css-cheat-sheet\/\">Hojas de Estilo en Cascada (CSS)<\/a> y de <a href=\"\/mx\/tutoriales\/que-es-javascript-introduccion-basica\/\">JavaScript<\/a> para crear la mayor parte del contenido del sitio web.<\/p><p>El CSS es responsable de estilos como el fondo, los colores, el dise&ntilde;o, el espaciado y las animaciones. Por otro lado, JavaScript&nbsp;a&ntilde;ade funcionalidades din&aacute;micas como sliders, pop-ups y galer&iacute;as de fotos. Estos tres lenguajes son los fundamentos del desarrollo front-end.<\/p><h2 class=\"wp-block-heading\" id=\"h-entender-html-y-mejorar-tus-conocimientos\">Entender HTML y mejorar tus conocimientos<\/h2><p><a href=\"\/mx\/tutoriales\/html\/\">Aprender sobre HTML<\/a> es un gran primer paso para quienes quieren <a href=\"\/mx\/tutoriales\/como-ser-programador-web\/\">convertirse en desarrolladores web<\/a>.<\/p><p>Hay un mont&oacute;n de <a href=\"\/mx\/tutoriales\/mejores-sitios-para-aprender-a-programar-gratis\/\">cursos disponibles online<\/a> para aprender a programar, pero hemos enumerado tres de las mejores plataformas de cursos sobre HTML:<\/p><ul class=\"wp-block-list\">\n<li><strong>W3Schools<\/strong>. Tiene recursos, ejemplos y ejercicios para aprender HTML b&aacute;sico de forma <strong>gratuita<\/strong>. Tambi&eacute;n hay un tutorial de HTML a tu ritmo y proporciona un certificado oficial.<\/li>\n\n\n\n<li><strong>Codecademy<\/strong>. Ofrece cursos introductorios <strong>gratuitos<\/strong> con tutoriales interactivos. Codecademy utiliza una pantalla dividida que muestra autom&aacute;ticamente el resultado de tu c&oacute;digo en un archivo HTML. Aunque la mayor parte del contenido es gratis, tambi&eacute;n hay contenido exclusivo disponible. <\/li>\n\n\n\n<li><strong>Coursera<\/strong>. Ofrece varios cursos con explicaciones detalladas y ejemplos de la vida real. El precio de la suscripci&oacute;n varia en funci&oacute;n de tus necesidades y del plan que elijas. <\/li>\n<\/ul><p>Sin ir m&aacute;s lejos, puedes aprender c&oacute;mo crear una web en HTML con nuestro video de la Academia de Hostinger.<\/p><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"&iquest;C&oacute;mo Crear una Web en HTML? (2024) | Paso a Paso y F&aacute;cil\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/DQCjcExU79s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure><p>\n  <div class=\"youtube-shortcode\">\n    <div class=\"row\">\n      <div class=\"col-7 col-sm-8 d-flex align-items-center\">\n        <img decoding=\"async\" class=\"channel-logo\" src=\"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-content\/themes\/tutorialsthemeuplift\/public\/images\/youtube-channels\/hostinger-spain.jpg\" alt=\"youtube channel logo\">\n        <div class=\"d-flex flex-column justify-content-between\">\n          <span class=\"slogan d-none d-sm-block\">Suscribirse \u00a1Para m\u00e1s videos educativos!<\/span>\n          <span class=\"channel-name\">Academia de Hostinger<\/span>\n                    <\/div>\n      <\/div>\n      <div class=\"col-5 col-sm-4 d-flex align-items-center justify-content-end\">\n        <a class=\"subscribe-button\" target=\"_blank\" rel=\"nofollow noopener noreferrer\" href=\"http:\/\/www.youtube.com\/channel\/UCYmKCu1yo_L0fqKe3U_oMnw?sub_confirmation=1\">\n          <img decoding=\"async\" src=\"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-content\/themes\/tutorialsthemeuplift\/public\/images\/icons\/youtube.svg\" alt=\"subscribe\">\n          <span>Suscribirse<\/span>\n        <\/a>\n      <\/div>\n    <\/div>\n  <\/div>\n\n    \n<\/p><h2 class=\"wp-block-heading\" id=\"h-conclusion\">Conclusi&oacute;n<\/h2><p>HTML es el principal lenguaje de marcado de Internet. Cada p&aacute;gina HTML tiene una serie de elementos que crean la estructura del contenido de una p&aacute;gina web o aplicaci&oacute;n.<\/p><p>HTML es un lenguaje apto para principiantes con gran apoyo y se utiliza principalmente para p&aacute;ginas web est&aacute;ticas. HTML funciona mejor junto con CSS para el estilo y JavaScript para la funcionalidad.<\/p><p>Tambi&eacute;n hemos incluido algunos de los mejores cursos disponibles en l&iacute;nea que te ayudar&aacute;n a mejorar tus conocimientos de HTML y te dar&aacute;n una visi&oacute;n b&aacute;sica de este lenguaje.<\/p><p>Haznos saber en la secci&oacute;n de comentarios si tienes alg&uacute;n otro recurso favorito para aprender HTML. &iexcl;Buena suerte!<\/p><figure class=\"wp-block-image size-large\"><a href=\"\/mx\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=1024,h=1024,fit=scale-down\" alt=\"\" class=\"wp-image-29291\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=768,fit=scale-down 768w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=1536,fit=scale-down 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><h2 class=\"wp-block-heading\" id=\"h-que-es-html-y-para-que-sirve-preguntas-frecuentes\">&iquest;Qu&eacute; es HTML y para qu&eacute; sirve? &ndash; Preguntas frecuentes<\/h2><p>A continuaci&oacute;n algunas de las preguntas m&aacute;s comunes sobre el lenguaje HTML.<\/p><div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-6944760d28931\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">&iquest;Para qu&eacute; se utiliza HTML?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>El lenguaje de marcado de hipertexto o HTML es un lenguaje de programaci&oacute;n utilizado para describir la estructura de las p&aacute;ginas web. HTML permite crear p&aacute;ginas est&aacute;ticas con texto, encabezados, tablas, listas, im&aacute;genes, enlaces, etc.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-6944760d28935\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">&iquest;C&oacute;mo funciona HTML?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Al estar basado en texto, HTML indica al navegador c&oacute;mo mostrar todos los elementos de la p&aacute;gina, como texto, im&aacute;genes y otros elementos multimedia, en una p&aacute;gina web individual.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-6944760d28936\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">&iquest;Es f&aacute;cil aprender HTML?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>S&iacute;, probablemente sea el lenguaje de programaci&oacute;n front-end m&aacute;s f&aacute;cil de aprender. Adem&aacute;s, gracias a la gran cantidad de recursos y herramientas gratuitas disponibles en Internet, es un lenguaje relativamente r&aacute;pido de aprender.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-6944760d28937\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">&iquest;Qu&eacute; tipo de lenguaje es HTML?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>HTML es un lenguaje de codificaci&oacute;n de marcas. Ordena los datos que se han categorizado con etiquetas HTML, lo que permite definirlos y describir su prop&oacute;sito en una p&aacute;gina web. u003cbr \/u003eu003cbr \/u003eHTML le dice a un navegador web esencialmente qu&eacute; son los diferentes elementos de la p&aacute;gina y d&oacute;nde deben ir cuando se carga la p&aacute;gina.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La definici&oacute;n de HTML es Lenguaje de Marcado de Hipertexto. Es un lenguaje de marcado est&aacute;ndar para la creaci&oacute;n de p&aacute;ginas web. Permite construir y estructurar secciones, p&aacute;rrafos y enlaces utilizando elementos HTML (los bloques de construcci&oacute;n de una p&aacute;gina web) como etiquetas y atributos. HTML tiene muchos casos de uso como: Tambi&eacute;n hay que [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/mx\/tutoriales\/que-es-html\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":85,"featured_media":46898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_title":"HTML: definici\u00f3n, funciones y ejemplos pr\u00e1cticos de uso","rank_math_description":"Descubre qu\u00e9 es HTML, c\u00f3mo usarlo para personalizar tu sitio web y comienza a aprender con nuestra gu\u00eda f\u00e1cil para principiantes.","rank_math_focus_keyword":"qu\u00e9 es html","footnotes":""},"categories":[9166],"tags":[7821],"class_list":["post-7652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-html","tag-html"],"hreflangs":[{"locale":"en-US","link":"https:\/\/www.hostinger.com\/tutorials\/what-is-html","default":0},{"locale":"pt-BR","link":"https:\/\/www.hostinger.com\/br\/tutoriais\/o-que-e-html-conceitos-basicos","default":0},{"locale":"es-ES","link":"https:\/\/www.hostinger.com\/es\/tutoriales\/que-es-html","default":0},{"locale":"id-ID","link":"https:\/\/www.hostinger.com\/id\/tutorial\/apa-itu-html","default":0},{"locale":"nl-NL","link":"https:\/\/www.hostinger.com\/nl\/tutorials\/wat-is-html","default":0},{"locale":"en-GB","link":"https:\/\/www.hostinger.com\/uk\/tutorials\/what-is-html","default":0},{"locale":"en-MY","link":"https:\/\/www.hostinger.com\/my\/tutorials\/what-is-html","default":0},{"locale":"en-PH","link":"https:\/\/www.hostinger.com\/ph\/tutorials\/what-is-html","default":0},{"locale":"es-MX","link":"https:\/\/www.hostinger.com\/mx\/tutoriales\/que-es-html","default":0},{"locale":"es-CO","link":"https:\/\/www.hostinger.com\/co\/tutoriales\/que-es-html","default":0},{"locale":"es-AR","link":"https:\/\/www.hostinger.com\/ar\/tutoriales\/que-es-html","default":0},{"locale":"pt-PT","link":"https:\/\/www.hostinger.com\/pt\/tutoriais\/o-que-e-html-conceitos-basicos","default":0},{"locale":"en-IN","link":"https:\/\/www.hostinger.com\/in\/tutorials\/what-is-html","default":0},{"locale":"en-CA","link":"https:\/\/www.hostinger.com\/ca\/tutorials\/what-is-html","default":0},{"locale":"en-AU","link":"https:\/\/www.hostinger.com\/au\/tutorials\/what-is-html","default":0},{"locale":"en-NG","link":"https:\/\/www.hostinger.com\/ng\/tutorials\/what-is-html","default":0}],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts\/7652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/users\/85"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/comments?post=7652"}],"version-history":[{"count":27,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts\/7652\/revisions"}],"predecessor-version":[{"id":46897,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts\/7652\/revisions\/46897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/media\/46898"}],"wp:attachment":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/media?parent=7652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/categories?post=7652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/tags?post=7652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}