{"id":5843,"date":"2018-01-30T08:59:24","date_gmt":"2018-01-30T08:59:24","guid":{"rendered":"https:\/\/blog.hostinger.io\/mx-tutoriales\/?p=5843"},"modified":"2025-02-20T12:53:03","modified_gmt":"2025-02-20T11:53:03","slug":"como-configurar-servidor-ftp-en-ubuntu","status":"publish","type":"post","link":"\/mx\/tutoriales\/como-configurar-servidor-ftp-en-ubuntu\/","title":{"rendered":"C\u00f3mo configurar el servidor FTP en Ubuntu VPS"},"content":{"rendered":"<p>En este art&iacute;culo, aprender&aacute;s a configurar un servidor FTP en un VPS de Ubuntu. Usaremos un servidor<a href=\"https:\/\/security.appspot.com\/vsftpd.html\" target=\"_blank\" rel=\"noreferrer noopener\"> vsftpd<\/a>, que es ampliamente considerado como el servidor FTP m&aacute;s r&aacute;pido y seguro para sistemas similares a UNIX.<\/p><figure class=\"wp-block-image size-large\"><a href=\"https:\/\/assets.hostinger.com\/content\/tutorials\/pdf\/Linux-Commands-Cheatsheet-ES.pdf\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"1024\" height=\"283\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/12\/Linux-cheat-sheet-ES.png\/w=1024,h=1024,fit=scale-down\" alt=\"\" class=\"wp-image-26004\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/12\/Linux-cheat-sheet-ES.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/12\/Linux-cheat-sheet-ES.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/12\/Linux-cheat-sheet-ES.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/12\/Linux-cheat-sheet-ES.png\/w=768,fit=scale-down 768w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/12\/Linux-cheat-sheet-ES.png\/w=1536,fit=scale-down 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><h2 class=\"wp-block-heading\" id=\"h-que-es-ftp\">&iquest;Qu&eacute; es FTP?<\/h2><p><strong>FTP<\/strong> o <strong>F<\/strong>ile <strong>T<\/strong>ransfer <strong>P<\/strong>rotocol, por sus siglas en ingl&eacute;s, es un medio para enviar y recibir archivos a trav&eacute;s de una conexi&oacute;n de red. Utilizando un marco de referencia de cliente\/servidor y seguridad SSL\/TLS, FTP le permite a los usuarios compartir archivos con (y recibir desde) computadoras remotas a trav&eacute;s de una transferencia de datos segura, eficiente y confiable (usando los protocolos TCP\/IP).<\/p><p>FTP funciona de la misma manera que <a href=\"https:\/\/es.wikipedia.org\/wiki\/Protocolo_de_transferencia_de_hipertexto\" target=\"_blank\" rel=\"noreferrer noopener\">HTTP<\/a> (HypertText Transfer Protocol) o <a href=\"\/mx\/tutoriales\/puerto-smtp\/\">SMTP<\/a> (Simple Mail Transfer Protocol). La diferencia es que el FTP se encarga de transportar archivos a trav&eacute;s de Internet, mientras que el HTTP y el SMTP se encargan de transferir p&aacute;ginas web y correos electr&oacute;nicos, respectivamente.<\/p><p>Antes de empezar, ten en cuenta que te guiaremos en la configuraci&oacute;n de un servidor FTP en <a href=\"\/mx\/tutoriales\/que-es-ubuntu\/\">Ubuntu<\/a> 22.04. Por lo tanto, debes asegurarte de que tu VPS se ejecuta en ese sistema operativo concreto.<\/p><h2 class=\"wp-block-heading\" id=\"h-como-configurar-un-servidor-ftp-en-ubuntu\">C&oacute;mo configurar un servidor FTP en Ubuntu<\/h2><p>Este tutorial requiere que sepas c&oacute;mo conectarte a un servidor a trav&eacute;s de SSH. Si tienes el <a href=\"\/mx\/servidor-vps\">hosting VPS de Hostinger<\/a>, los datos de acceso est&aacute;n disponibles en la pesta&ntilde;a Servidor del hPanel.<\/p><h3 class=\"wp-block-heading\" id=\"h-paso-1-instalar-vsftpd\">Paso 1 &ndash; Instalar Vsftpd<\/h3><ol class=\"wp-block-list\">\n<li>Primero que nada, obtengamos las actualizaciones de nuestros paquetes antes de continuar con la instalaci&oacute;n del <strong>vsftpd<\/strong>. Para comenzar, ejecuta el siguiente comando:<\/li>\n<\/ol><pre class=\"wp-block-preformatted\">sudo apt-get update<\/pre><p>Espera a que se completen todos los procesos y ver&aacute;s una confirmaci&oacute;n tan pronto como finalice la actualizaci&oacute;n.<\/p><ol class=\"wp-block-list\" start=\"2\">\n<li>Cuando termines con esto, instala el daemon vsftpd usando el siguiente comando:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">sudo apt-get install vsftpd<\/pre><p>Ahora ver&aacute;s un mensaje de confirmaci&oacute;n en el que tendr&aacute;s que escribir <strong>Y<\/strong> y presionar <strong>Enter<\/strong> para continuar con la instalaci&oacute;n.<\/p><ol class=\"wp-block-list\" start=\"4\">\n<li>Una vez completada la instalaci&oacute;n, haz una copia de seguridad del archivo original para que podamos comenzar nuestro trabajo con un archivo de configuraci&oacute;n en blanco:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">sudo cp \/etc\/vsftpd.conf \/etc\/vsftpd.conf.original<\/pre><p>Ahora estamos listos para dar el siguiente paso y configurar el firewall.<\/p><h3 class=\"wp-block-heading\" id=\"h-paso-2-permitir-el-trafico-ftp-desde-el-firewall\">Paso 2 &ndash; Permitir el tr&aacute;fico FTP desde el firewall<\/h3><ol class=\"wp-block-list\">\n<li>Para permitir que el servidor FTP de Ubuntu se comunique a trav&eacute;s del Internet, tiene que atravesar el firewall. Primero veamos si el firewall est&aacute; activado en la m&aacute;quina o no. Simplemente ejecuta el siguiente comando para verificar el estado:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">sudo ufw status<\/pre><p>Si ves el siguiente mensaje:<\/p><pre class=\"wp-block-preformatted lang:default decode:true\">ufw: command not found<\/pre><p>Significa que el firewall no est&aacute; instalado. Puedes instalarlo y habilitarlo escribiendo:<\/p><pre class=\"wp-block-preformatted\">sudo apt-get install ufw\nsudo ufw enable<\/pre><ol class=\"wp-block-list\" start=\"2\">\n<li>Si ya est&aacute; activo, todav&iacute;a tienes que asegurarte de que el tr&aacute;fico FTP est&aacute; permitido. Para ello, ejecuta los siguientes comandos uno a uno:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">sudo ufw allow 20\/tcp\nsudo ufw allow 21\/tcp\nsudo ufw allow 990\/tcp\nsudo ufw allow 40000:50000\/tcp<\/pre><p>Esta serie de comandos abrir&aacute; varios puertos:<\/p><ul class=\"wp-block-list\">\n<li><strong>OpenSSH<\/strong> es necesario si todav&iacute;a quieres acceder a tu servidor a trav&eacute;s de SSH. A veces, esta opci&oacute;n est&aacute; activada por defecto.<\/li>\n\n\n\n<li>los puertos <strong>20<\/strong> y <strong>21<\/strong> para el tr&aacute;fico FTP.<\/li>\n\n\n\n<li>los puertos <strong>40000:50000<\/strong> se reservar&aacute;n para el rango de puertos pasivos que eventualmente se establecer&aacute; en el archivo de configuraci&oacute;n.<\/li>\n\n\n\n<li>el puerto <strong>990<\/strong> se utilizar&aacute; cuando se active el TLS.<\/li>\n<\/ul><ol class=\"wp-block-list\" start=\"3\">\n<li>Ahora veamos el estado de nuevo:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">sudo ufw status<\/pre><p>El resultado deber&iacute;a ser algo as&iacute;:<\/p><pre class=\"wp-block-preformatted lang:default decode:true\">Status: active\n\nTo&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Action From\n\n--&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ------&nbsp; ----\n\n990\/tcp&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ALLOW Anywhere\n\n20\/tcp&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ALLOW Anywhere\n\n21\/tcp&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ALLOW&nbsp;Anywhere\n\n40000:50000\/tcp&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;ALLOW&nbsp;Anywhere\n\n20\/tcp (v6)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ALLOW&nbsp;Anywhere (v6)\n\n21\/tcp (v6)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ALLOW&nbsp;Anywhere (v6)\n\n990\/tcp (v6)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ALLOW&nbsp;Anywhere (v6)\n\n40000:50000\/tcp (v6)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ALLOW&nbsp;Anywhere (v6)<\/pre><h3 class=\"wp-block-heading\" id=\"h-paso-3-crear-el-directorio-de-usuarios\">Paso 3 &ndash; Crear el directorio de usuarios<\/h3><ol class=\"wp-block-list\">\n<li>Una vez configurado el firewall, debemos crear el usuario que va a utilizar el acceso FTP. Para crearlo, usa el siguiente comando:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">sudo adduser hostinger<\/pre><p>Recuerda cambiar el nombre de usuario seg&uacute;n tus preferencias.<\/p><ol class=\"wp-block-list\" start=\"2\">\n<li>Cuando el sistema te pregunte, ingresa una contrase&ntilde;a para el usuario y completa todos los dem&aacute;s detalles. Lo ideal es que el FTP se restrinja a un directorio espec&iacute;fico por motivos de seguridad. <strong>Vsftpd<\/strong> usa <strong>jaulas chroot <\/strong>para lograr esto. Con chroot habilitado, un usuario local est&aacute; restringido a su directorio de inicio (por defecto). Sin embargo, es posible que debido a la seguridad de <strong>vsftpd<\/strong>, un usuario no pueda escribir en el directorio. No eliminaremos los privilegios de escritura de la carpeta de inicio; en su lugar, crearemos un directorio ftp que actuar&aacute; como <strong>chroot<\/strong> junto con un directorio de archivos modificables que ser&aacute; responsable de mantener los archivos pertinentes. <\/li>\n\n\n\n<li>Usa el siguiente comando para crear la carpeta FTP:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">sudo mkdir \/home\/hostinger\/ftp<\/pre><p>Establece la propiedad usando:<\/p><pre class=\"wp-block-preformatted lang:default decode:true\">sudo chown nobody:nogroup \/home\/hostinger\/ftp<\/pre><p>Finalmente, elimina los permisos de escritura:<\/p><pre class=\"wp-block-preformatted lang:default decode:true\">sudo chmod a-w \/home\/hostinger\/ftp<\/pre><p>Ahora, usa el siguiente comando para verificar los permisos:<\/p><pre class=\"wp-block-preformatted lang:default decode:true\">sudo ls -la \/home\/hostinger\/ftp<\/pre><p>El resultado deber&iacute;a ser algo as&iacute;:<\/p><pre class=\"wp-block-preformatted lang:default decode:true\">total 8\ndr-xr-xr-x 2 nobody nogroup 4096 Jun 29 11:32 .\ndrwxr-xr-x 3 hostinger&nbsp;hostinger&nbsp;4096 Jun 29 11:32 ..<\/pre><ol class=\"wp-block-list\" start=\"4\">\n<li>Como paso siguiente, crearemos el directorio contenedor de archivos y asignaremos la propiedad:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">sudo mkdir \/home\/hostinger\/ftp\/files\nsudo chown hostinger:hostinger \/home\/hostinger\/ftp\/files<\/pre><p>Finalmente, agrega un archivo de prueba al directorio el cual se usar&aacute; cuando probemos todo m&aacute;s adelante:<\/p><pre class=\"wp-block-preformatted lang:default decode:true\">echo \"vsftpd sample file\" | sudo tee \/home\/hostinger\/ftp\/files\/sample.txt<\/pre><h3 class=\"wp-block-heading\" id=\"h-paso-4-configurar-vsftpd\">Paso 4 &ndash; Configurar vsftpd<\/h3><p>El siguiente paso en nuestra apuesta por configurar un servidor FTP en Ubuntu VPS, es configurar vsftpd y nuestro acceso FTP. En este tutorial, permitiremos que un solo usuario se conecte con FTP utilizando una cuenta shell local. Las dos configuraciones clave requeridas para esto ya est&aacute;n establecidas en el archivo de configuraci&oacute;n (<strong>vsftpd.conf<\/strong>). <\/p><ol class=\"wp-block-list\">\n<li>En primer lugar, verifica que el archivo de configuraci&oacute;n tenga una configuraci&oacute;n que coincida con las mencionadas a continuaci&oacute;n <a href=\"\/mx\/tutoriales\/instalar-nano-text-editor\/\">utilizando el comando nano<\/a>:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">sudo nano \/etc\/vsftpd.conf<\/pre><p>Comprueba que el contenido tiene una configuraci&oacute;n similar a &eacute;sta:<\/p><pre class=\"wp-block-preformatted lang:default decode:true\">. . .\n# Allow anonymous FTP? (Disabled by default).\nanonymous_enable=NO\n#\n# Uncomment this to allow local users to log in.\nlocal_enable=YES\n. . .<\/pre><p>En el mismo archivo, procederemos a eliminar <strong>#<\/strong> y a habilitar el <strong>write_enable<\/strong>:<\/p><pre class=\"wp-block-preformatted lang:default decode:true\">. . .\nwrite_enable=YES\n. . ..<\/pre><ol class=\"wp-block-list\" start=\"2\">\n<li><strong>Chroot<\/strong> tampoco se comentar&aacute;<strong> <\/strong>para asegurarte de que el usuario FTP s&oacute;lo accede a los archivos dentro del directorio permitido. Cambia tambi&eacute;n el valor <strong>NO<\/strong> por <strong>S&Iacute;<\/strong>. Ten en cuenta que hay dos l&iacute;neas como &eacute;sta, y tienes que descomentar ambas.<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">. . .\nchroot_local_user=YES\n. . .<\/pre><ol class=\"wp-block-list\" start=\"3\">\n<li>Hay algunos valores nuevos que tambi&eacute;n debes a&ntilde;adir al final del archivo. En primer lugar, se agregar&aacute; un <strong>user_sub_token<\/strong> en la <strong>ruta del directorio local_root<\/strong>. Esto permitir&aacute; que la configuraci&oacute;n funcione con el usuario actual y con cualquier otro usuario que se agregue posteriormente:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">user_sub_token=$USER\nlocal_root=\/home\/$USER\/ftp<\/pre><ol class=\"wp-block-list\" start=\"4\">\n<li>Para garantizar que haya una cantidad considerable de conexiones disponibles, limitaremos la cantidad de puertos utilizados en el archivo de configuraci&oacute;n:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">pasv_min_port=40000\npasv_max_port=50000<\/pre><ol class=\"wp-block-list\" start=\"5\">\n<li>En este tutorial, planeamos permitir el acceso caso por caso, as&iacute; que ajustemos la configuraci&oacute;n de forma tal que el acceso solo se otorgue a los usuarios que se hayan agregado expl&iacute;citamente a una lista:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">userlist_enable=YES\nuserlist_file=\/etc\/vsftpd.userlist\nuserlist_deny=NO<\/pre><p>El flag <strong>userlist_deny<\/strong> es el responsable de alternar la l&oacute;gica; cuando se establece en <strong>NO<\/strong>, solo se permitir&aacute; el acceso a los usuarios especificados en la lista. Una vez hecho esto, haz clic en <strong>CTRL+X<\/strong> y confirma los cambios del archivo.<\/p><ol class=\"wp-block-list\" start=\"6\">\n<li>Por &uacute;ltimo, procederemos con la creaci&oacute;n y adici&oacute;n de nuestro usuario al archivo:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">echo \"hostinger\" | sudo tee -a \/etc\/vsftpd.userlist<\/pre><p>Verifica que el usuario est&eacute; realmente activo ejecutando el siguiente comando:<\/p><pre class=\"wp-block-preformatted lang:default decode:true\">cat \/etc\/vsftpd.userlist<\/pre><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"458\" height=\"40\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/user-list-vsftpd.png\/public\" alt=\"\" class=\"wp-image-22382\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/user-list-vsftpd.png\/w=458,fit=scale-down 458w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/user-list-vsftpd.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/user-list-vsftpd.png\/w=150,fit=scale-down 150w\" sizes=\"(max-width: 458px) 100vw, 458px\" \/><\/figure>\n<\/div><p>El resultado debe ser &ldquo;hostinger&rdquo; como se muestra en esta captura de pantalla:<\/p><ol class=\"wp-block-list\" start=\"7\">\n<li>Reinicia el daemon utilizando el siguiente comando para cargar los cambios de configuraci&oacute;n:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">sudo systemctl restart vsftpd<\/pre><h3 class=\"wp-block-heading\" id=\"h-paso-5-hacer-que-el-ftp-sea-seguro\">Paso 5 &ndash; Hacer que el FTP sea seguro<\/h3><ol class=\"wp-block-list\">\n<li>Por defecto, FTP no hace ninguna encriptaci&oacute;n de datos, por eso utilizaremos <strong>TTL\/SSL<\/strong> para garantizar la seguridad. En primer lugar, debemos crear el certificado SSL y usarlo para proteger el servidor FTP de Ubuntu. Para comenzar, usa el siguiente comando:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">sudo openssl req -x509 -nodes -days 365 -newkey rsa:2048 -keyout \/etc\/ssl\/private\/vsftpd.pem -out \/etc\/ssl\/private\/vsftpd.pem<\/pre><p>El flag <strong>-days<\/strong> hace que el certificado sea v&aacute;lido por un a&ntilde;o y hemos incluido una clave privada <strong>RSA<\/strong> de <strong>2048 bits<\/strong> en el mismo comando. <\/p><ol class=\"wp-block-list\" start=\"2\">\n<li>Una vez sean solicitados, ingresa los datos personales correspondientes en el campo provisto.<\/li>\n\n\n\n<li>Cuando termines de crear el certificado, abre nuevamente el archivo de configuraci&oacute;n:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">sudo nano \/etc\/vsftpd.conf<\/pre><p>El final del archivo debe contener dos l&iacute;neas que comiencen con &ldquo;<strong>_rsa<\/strong>&ldquo;. Comenta ambas l&iacute;neas as&iacute;:<\/p><pre class=\"wp-block-preformatted lang:default decode:true\"># rsa_cert_file=\/etc\/ssl\/certs\/ssl-cert-snakeoil.pem\n# rsa_private_key_file=\/etc\/ssl\/private\/ssl-cert-snakeoil.key<\/pre><p>En lugar de eso, apuntemos el archivo de configuraci&oacute;n al certificado que acabamos de crear. A&ntilde;ade los siguientes direcciones justo debajo de las l&iacute;neas anteriores:<\/p><pre class=\"wp-block-preformatted lang:default decode:true\">rsa_cert_file=\/etc\/ssl\/private\/vsftpd.pem\nrsa_private_key_file=\/etc\/ssl\/private\/vsftpd.pem<\/pre><ol class=\"wp-block-list\" start=\"4\">\n<li>Ahora habilitaremos SSL y nos aseguraremos de que solo los clientes que tengan SSL habilitados nos puedan contactar. Cambia el valor de <strong>ssl_enable<\/strong> a <strong>YES<\/strong>:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">ssl_enable=YES<\/pre><p>A continuaci&oacute;n agrega las siguientes l&iacute;neas para prohibir cualquier conexi&oacute;n an&oacute;nima a trav&eacute;s de SSK<\/p><pre class=\"wp-block-preformatted lang:default decode:true\">allow_anon_ssl=NO\nforce_local_data_ssl=YES\nforce_local_logins_ssl=YES<\/pre><p>Configura el servidor para usar TLS usando:<\/p><pre class=\"wp-block-preformatted lang:default decode:true\">ssl_tlsv1=YES\nssl_sslv2=NO\nssl_sslv3=NO<\/pre><p>Ahora cambiaremos 2 opciones m&aacute;s. En primer lugar, no ser&aacute; necesario <strong>reutilizar SSL<\/strong> porque puede ocasionar que muchos clientes de FTP se aver&iacute;en. En segundo lugar, utilizaremos suites de encriptaci&oacute;n de alto cifrado, lo que significa que las longitudes de claves son iguales o superiores a 128 bits.<\/p><pre class=\"wp-block-preformatted lang:default decode:true\">require_ssl_reuse=NO\nssl_ciphers=HIGH<\/pre><p>Vuelve a guardar el archivo pulsando <strong>CTRL+X<\/strong> seguido de <strong>Y,<\/strong> y luego pulsa Intro.<\/p><ol class=\"wp-block-list\" start=\"6\">\n<li>Vamos a reiniciar <strong>vsftpd<\/strong> una vez m&aacute;s para aplicar las nuevas configuraciones:<\/li>\n<\/ol><pre class=\"wp-block-preformatted lang:default decode:true\">sudo systemctl restart vsftpd<\/pre><p>&iexcl;Buen trabajo! Has configurado el servidor FTP en tu VPS de Ubuntu para que funcione con el protocolo SSL\/TLS.<\/p><h2 class=\"wp-block-heading\" id=\"h-paso-6-prueba-de-conexiones-con-filezilla\">Paso 6 &ndash; Prueba de conexiones con FileZilla<\/h2><p>Hoy en d&iacute;a, la mayor&iacute;a de los clientes de FTP admiten configuraciones de cifrado TLS, por lo que es una excelente manera de comprobar si tu servidor FTP de Ubuntu funciona seg&uacute;n lo previsto. Para probar la conexi&oacute;n, utilizaremos un <a href=\"\/mx\/tutoriales\/configurar-filezilla\/\">cliente FTP de FileZilla<\/a>. <\/p><ol class=\"wp-block-list\">\n<li>Para comenzar inicia <strong>FileZilla <\/strong>y haz clic en el icono de&nbsp;<strong>Site Manager<\/strong>. Luego haz clic en el bot&oacute;n <strong>New Site<\/strong> en la ventana que aparece para comenzar a ingresar los detalles del servidor FTP de Ubuntu.<\/li>\n<\/ol><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"779\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/filezilla.png\/public\" alt=\"an&#771;adir-ubuntu-servidor-ftp-en-filezilla\" class=\"wp-image-22383\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/filezilla.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/filezilla.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/filezilla.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/filezilla.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><ol class=\"wp-block-list\" start=\"2\">\n<li>Completa todos los detalles requeridos con tu informaci&oacute;n del servidor FTP de Ubuntu reci&eacute;n creada. Como lo configuramos para usar TLS, tambi&eacute;n podemos marcar el cifrado para que sea <strong>expl&iacute;citamente FTP sobre TLS<\/strong>. La configuraci&oacute;n final deber&iacute;a verse as&iacute;:<\/li>\n<\/ol><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"922\" height=\"618\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/connecting-ftp-filezilla-1.jpeg\/public\" alt=\"configuracio&#769;n-final-filezilla-para-servidor-ftp\" class=\"wp-image-22385\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/connecting-ftp-filezilla-1.jpeg\/w=922,fit=scale-down 922w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/connecting-ftp-filezilla-1.jpeg\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/connecting-ftp-filezilla-1.jpeg\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/connecting-ftp-filezilla-1.jpeg\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 922px) 100vw, 922px\" \/><\/figure><ol class=\"wp-block-list\" start=\"3\">\n<li>Cuando est&eacute; listo, haz clic en <strong>Connect<\/strong> y aparecer&aacute; una pantalla que te pedir&aacute; ingresar la contrase&ntilde;a del usuario de FTP.<\/li>\n<\/ol><ol class=\"wp-block-list\" start=\"4\">\n<li>Finalmente, tendr&aacute;s que verificar el certificado SSL de tu servidor FTP en Ubuntu VPS.<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"781\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/ubuntu-ftp-server-connection.jpeg\/w=1024,h=1024,fit=scale-down\" alt=\"confirmar-certificado-de-servidor-ftp\" class=\"wp-image-22386\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/ubuntu-ftp-server-connection.jpeg\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/ubuntu-ftp-server-connection.jpeg\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/ubuntu-ftp-server-connection.jpeg\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/08\/ubuntu-ftp-server-connection.jpeg\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><p>Despu&eacute;s de confirmar, el directorio ra&iacute;z con el archivo de prueba deber&iacute;a aparecer en tu pantalla.<\/p><p>&iexcl;Eso es todo! Ahora puedes realizar transferencias de archivos desde tu computadora al servidor FTP de Ubuntu y viceversa.<\/p><h2 class=\"wp-block-heading\" id=\"h-conclusion\">Conclusi&oacute;n<\/h2><p>Tener un servidor FTP Ubuntu te facilita compartir archivos entre tu VPS\/servidor de Ubuntu y tu ordenador. Es un m&eacute;todo seguro y fiable de transferencia de datos, gracias a la seguridad SSL\/TLS y al <a href=\"\/mx\/tutoriales\/protocolo-tcp\/\">protocolo TCP\/IP<\/a>.<\/p><p>En este tutorial, has aprendido a configurar un servidor FTP en Ubuntu utilizando <a href=\"https:\/\/security.appspot.com\/vsftpd.html\" target=\"_blank\" rel=\"noreferrer noopener\">vsftpd<\/a>. Hay cinco pasos que debes seguir. Vamos a verlos una vez m&aacute;s.<\/p><ol class=\"wp-block-list\">\n<li>Instala <strong>vsftpd <\/strong>en tu servidor Ubuntu y haz una copia de seguridad del archivo de configuraci&oacute;n original.<\/li>\n\n\n\n<li>Permite las conexiones FTP a trav&eacute;s del cortafuegos.<\/li>\n\n\n\n<li>Crea un directorio de usuarios al que s&oacute;lo puedan acceder los usuarios especificados.<\/li>\n\n\n\n<li>Configura <strong>vsftpd<\/strong>.<\/li>\n\n\n\n<li>Asegura el servidor FTP.<\/li>\n\n\n\n<li>Prueba tu conexi&oacute;n FTP con FileZilla.<\/li>\n<\/ol><p>Buena suerte, y no dejes de consultar nuestros otros tutoriales sobre VPS.<\/p><figure class=\"wp-block-image size-large\"><a href=\"\/mx\/servidor-vps\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=1024,h=1024,fit=scale-down\" alt=\"\" class=\"wp-image-29287\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=768,fit=scale-down 768w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=1536,fit=scale-down 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><p>\n\n\n\n<div class=\"protip\">\n                    <p class=\"title\">Aprende m&aacute;s sobre Ubuntu<\/p>\n                    <p><a href=\"\/mx\/tutoriales\/instalar-python-pip-ubuntu\/\">C&oacute;mo instalar Python Pip en Ubuntu<\/a><br><a href=\"\/mx\/tutoriales\/como-instalar-java-en-ubuntu\/\">C&oacute;mo instalar Java en Ubuntu<\/a><br><a href=\"\/mx\/tutoriales\/instalar-node-js-ubuntu\/\">C&oacute;mo instalar Node en Ubuntu<\/a><\/p><p><a href=\"\/mx\/tutoriales\/que-es-un-vps\/\">Qu&eacute; es un VPS<\/a><\/p>\n                <\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este art&iacute;culo, aprender&aacute;s a configurar un servidor FTP en un VPS de Ubuntu. Usaremos un servidor vsftpd, que es ampliamente considerado como el servidor FTP m&aacute;s r&aacute;pido y seguro para sistemas similares a UNIX. &iquest;Qu&eacute; es FTP? FTP o File Transfer Protocol, por sus siglas en ingl&eacute;s, es un medio para enviar y recibir [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/mx\/tutoriales\/como-configurar-servidor-ftp-en-ubuntu\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":85,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_title":"C\u00f3mo Configurar un Servidor FTP en Ubuntu VPS %page%","rank_math_description":"Lee este art\u00edculo para aprender c\u00f3mo configurar un servidor FTP en Ubuntu, para transferir archivos entre computadoras a trav\u00e9s de Internet.","rank_math_focus_keyword":"ftp ubuntu","footnotes":""},"categories":[5700],"tags":[14182],"class_list":["post-5843","post","type-post","status-publish","format-standard","hentry","category-vps","tag-ftp-ubuntu"],"hreflangs":[{"locale":"en-US","link":"https:\/\/www.hostinger.com\/tutorials\/how-to-setup-ftp-server-on-ubuntu-vps","default":0},{"locale":"es-ES","link":"https:\/\/www.hostinger.com\/es\/tutoriales\/como-configurar-servidor-ftp-en-ubuntu","default":0},{"locale":"id-ID","link":"https:\/\/www.hostinger.com\/id\/tutorial\/cara-membuat-ftp-server","default":0},{"locale":"en-GB","link":"https:\/\/www.hostinger.com\/uk\/tutorials\/how-to-setup-ftp-server-on-ubuntu-vps","default":0},{"locale":"en-MY","link":"https:\/\/www.hostinger.com\/my\/tutorials\/how-to-setup-ftp-server-on-ubuntu-vps\/","default":0},{"locale":"en-PH","link":"https:\/\/www.hostinger.com\/ph\/tutorials\/how-to-setup-ftp-server-on-ubuntu-vps\/","default":0},{"locale":"en-IN","link":"https:\/\/www.hostinger.com\/in\/tutorials\/how-to-setup-ftp-server-on-ubuntu-vps","default":0},{"locale":"en-CA","link":"https:\/\/www.hostinger.com\/ca\/tutorials\/how-to-setup-ftp-server-on-ubuntu-vps","default":0},{"locale":"es-AR","link":"https:\/\/www.hostinger.com\/ar\/tutoriales\/como-configurar-servidor-ftp-en-ubuntu","default":0},{"locale":"es-MX","link":"https:\/\/www.hostinger.com\/mx\/tutoriales\/como-configurar-servidor-ftp-en-ubuntu","default":0},{"locale":"es-CO","link":"https:\/\/www.hostinger.com\/co\/tutoriales\/como-configurar-servidor-ftp-en-ubuntu","default":0},{"locale":"en-AU","link":"https:\/\/www.hostinger.com\/au\/tutorials\/how-to-setup-ftp-server-on-ubuntu-vps","default":0},{"locale":"en-NG","link":"https:\/\/www.hostinger.com\/ng\/tutorials\/how-to-setup-ftp-server-on-ubuntu-vps","default":0}],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts\/5843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/users\/85"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/comments?post=5843"}],"version-history":[{"count":24,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts\/5843\/revisions"}],"predecessor-version":[{"id":39510,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts\/5843\/revisions\/39510"}],"wp:attachment":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/media?parent=5843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/categories?post=5843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/tags?post=5843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}