{"id":47599,"date":"2026-05-28T08:01:21","date_gmt":"2026-05-28T06:01:21","guid":{"rendered":"\/mx\/tutoriales\/como-solucionar-err-connection-refused"},"modified":"2026-05-28T08:01:21","modified_gmt":"2026-05-28T06:01:21","slug":"como-solucionar-err-connection-refused","status":"publish","type":"post","link":"\/mx\/tutoriales\/como-solucionar-err-connection-refused\/","title":{"rendered":"C\u00f3mo solucionar el error ERR_CONNECTION_REFUSED"},"content":{"rendered":"<p class=\"wp-block-paragraph\">ERR_CONNECTION_REFUSED es un error de Google Chrome que impide que el navegador se conecte al servidor de un sitio web. Puedes probar alguno de estos 11 m&eacute;todos para identificar y solucionar el problema:<\/p><ul class=\"wp-block-list\">\n<li>Comprueba si el sitio web est&aacute; online<\/li>\n\n\n\n<li>Reinicia el router para restablecer la conexi&oacute;n<\/li>\n\n\n\n<li>Ejecuta el solucionador de problemas de red de tu sistema<\/li>\n\n\n\n<li>Desactiva o elimina las extensiones problem&aacute;ticas de Chrome<\/li>\n\n\n\n<li>Borra la cach&eacute; y las cookies del navegador<\/li>\n\n\n\n<li>Restablece o reinstala Google Chrome<\/li>\n\n\n\n<li>Desactiva temporalmente el antivirus y el firewall<\/li>\n\n\n\n<li>Desconecta la VPN y vuelve a intentarlo<\/li>\n\n\n\n<li>Borra la cach&eacute; DNS<\/li>\n\n\n\n<li>Desactiva o ajusta la configuraci&oacute;n del proxy<\/li>\n\n\n\n<li>Cambia a un servidor DNS p&uacute;blico<\/li>\n<\/ul><p class=\"wp-block-paragraph\">A continuaci&oacute;n, te guiaremos paso a paso por cada m&eacute;todo de soluci&oacute;n, todos f&aacute;ciles de aplicar y compatibles tanto con Windows como con macOS. Tambi&eacute;n explicaremos qu&eacute; causa este error del navegador, qu&eacute; hacer si el problema persiste y c&oacute;mo evitar que ERR_CONNECTION_REFUSED vuelva a aparecer.<\/p><h2 class=\"wp-block-heading\" id=\"h-what-is-the-err-connection-refused-error\">&iquest;Qu&eacute; es el error ERR_CONNECTION_REFUSED?<\/h2><p class=\"wp-block-paragraph\">El error ERR_CONNECTION_REFUSED significa que <strong>tu navegador intent&oacute; conectarse a una web, pero el servidor rechaz&oacute; activamente la solicitud<\/strong>. A diferencia de los errores del servidor que ocurren despu&eacute;s de que se establece una conexi&oacute;n, este se produce cuando el navegador ni siquiera puede llegar al servidor.<\/p><p class=\"wp-block-paragraph\">ERR_CONNECTION_REFUSED se debe a problemas como que el servidor est&eacute; offline o bloquee las solicitudes entrantes, a una configuraci&oacute;n incorrecta de la red, como el proxy, la VPN o el DNS, o a interferencias de extensiones del navegador, firewalls o software antivirus.<\/p><p class=\"wp-block-paragraph\">En algunos casos, tu proveedor de servicios de internet (ISP) o las restricciones de tu red local tambi&eacute;n pueden bloquear el acceso a ciertas p&aacute;ginas web.<\/p><p>        <div class=\"protip\">\n            <div class=\"protip__heading\">\n                <svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M1.49234 23.5024C1.23229 23.5024 0.972242 23.4024 0.782206 23.2123C0.562165 22.9923 0.452144 22.6822 0.502153 22.3722C0.562165 21.9221 1.14227 17.9113 3.00262 16.351C3.63274 15.8209 4.43289 15.5509 5.26305 15.5609C6.09321 15.5909 6.87335 15.9109 7.47347 16.4911C8.6937 17.6913 8.76371 19.6717 7.6435 20.9919C6.0832 22.8523 2.08245 23.4324 1.63237 23.4924C1.59236 23.4924 1.54235 23.4924 1.50234 23.4924L1.49234 23.5024ZM5.16303 17.5613C4.84297 17.5613 4.53291 17.6713 4.29287 17.8813C3.60274 18.4614 3.07264 19.9317 2.75258 21.242C4.06282 20.9219 5.5331 20.3918 6.11321 19.7017C6.55329 19.1716 6.54329 18.3814 6.0832 17.9213C5.85316 17.7013 5.5431 17.5713 5.20304 17.5613C5.19304 17.5613 5.17303 17.5613 5.16303 17.5613ZM11.7243 21.8821C11.4942 21.8821 11.2642 21.8021 11.0841 21.652C10.8541 21.462 10.7241 21.1819 10.7241 20.8819V15.9109L8.08358 13.2705H3.11264C2.81259 13.2705 2.53254 13.1404 2.3425 12.9104C2.15246 12.6803 2.07245 12.3803 2.12246 12.0902C2.19247 11.7102 2.84259 8.36953 4.70294 7.12929C6.33325 6.04909 8.96375 6.49918 10.244 6.80923C11.5442 4.96889 13.2546 3.4286 15.2349 2.33839C17.4553 1.11816 19.9858 0.518051 22.4963 0.498047C23.0464 0.498047 23.4865 0.948132 23.4865 1.49824C23.4865 5.0389 22.3763 9.97983 17.1753 13.7605C17.4853 15.0408 17.9354 17.6613 16.8552 19.2816C15.615 21.1419 12.2744 21.7921 11.8943 21.8621C11.8343 21.8721 11.7743 21.8821 11.7143 21.8821H11.7243ZM12.7245 16.181V19.6016C13.7146 19.2916 14.7948 18.7915 15.2049 18.1814C15.675 17.4812 15.605 16.091 15.385 14.9008C14.5248 15.3808 13.6346 15.8109 12.7245 16.181ZM9.66388 12.0302L11.9643 14.3307C13.1845 13.8306 14.3648 13.2204 15.485 12.5103C19.9358 9.51974 21.2361 5.60901 21.4561 2.53843C19.6157 2.67846 17.8254 3.20856 16.2051 4.09872C14.2847 5.14892 12.6544 6.68921 11.4942 8.54956C10.7841 9.65977 10.174 10.82 9.66388 12.0302ZM4.39289 11.2701H7.81353C8.1936 10.3599 8.63368 9.46974 9.11377 8.60957C7.92355 8.38953 6.51329 8.31952 5.81315 8.78961C5.19304 9.19968 4.70294 10.3099 4.39289 11.2701Z\" fill=\"#673DE6\"\/>\n                <\/svg>\n                <p class=\"protip__title\">\n                    &#128218; Lectura sugerida                <\/p>\n            <\/div>\n            <p class=\"protip__content\">Si ves el <a href=\"\/mx\/tutoriales\/error-localhost-ha-rechazado-la-conexion\/\">error ERR_CONNECTION_REFUSED en localhost<\/a>, significa que el servidor local al que intentas acceder no est&aacute; en funcionamiento, est&aacute; escuchando en un puerto diferente o est&aacute; bloqueado por un firewall. Aunque el error parece el mismo, la soluci&oacute;n depende de tu entorno local, no de un servidor remoto.<\/p>\n                    <\/div>\n        \n\n\n\n<\/p><h2 class=\"wp-block-heading\" id=\"h-how-to-solve-the-err-connection-refused-error\">&iquest;C&oacute;mo solucionar el error ERR_CONNECTION_REFUSED?<\/h2><div class=\"wp-block-image\"><figure data-wp-context='{\"imageId\":\"6a984fb08998c\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a984fb08998c\" class=\"aligncenter size-full wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2026\/05\/pagina-de-error-err-connection-refused-de-google-chrome.png\/public\" alt=\"La p&aacute;gina de error ERR_CONNECTION_REFUSED en Google Chrome.\" class=\"wp-image-53422\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" data-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.thisImage.buttonRight\" data-wp-style--top=\"state.thisImage.buttonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div><p class=\"wp-block-paragraph\">Para corregir el error del navegador ERR_CONNECTION_REFUSED, <strong>tendr&aacute;s que revisar tanto tu conexi&oacute;n local como la configuraci&oacute;n de tu navegador<\/strong>. El problema puede deberse a configuraciones incorrectas de Chrome, errores de DNS o restricciones de red, pero la mayor&iacute;a se pueden resolver f&aacute;cilmente.<\/p><p class=\"wp-block-paragraph\">A continuaci&oacute;n, te explicaremos paso a paso las formas m&aacute;s eficaces de revisar e reparar tu conexi&oacute;n.<\/p><h3 class=\"wp-block-heading\" id=\"h-1-check-the-website-status\">1. Revisa el estado de la web<\/h3><p class=\"wp-block-paragraph\">Empieza por comprobar si la web est&aacute; realmente online. Es posible que el error ERR_CONNECTION_REFUSED no sea un problema del navegador en absoluto: podr&iacute;a significar que el servidor de la web est&aacute; temporalmente fuera de l&iacute;nea o bloqueando solicitudes.<\/p><p class=\"wp-block-paragraph\">Usa herramientas gratuitas como Website Planet, Site24x7 o Host Tracker para comprobar el estado de la web. Solo ingresa la URL y comprueba si la conexi&oacute;n funciona para otras personas.<\/p><div class=\"wp-block-image\"><figure data-wp-context='{\"imageId\":\"6a984fb08c4ad\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a984fb08c4ad\" class=\"aligncenter size-full wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2026\/05\/herramienta-de-website-planet-para-saber-si-tu-web-esta-caida-ahora-mismo.png\/public\" alt=\"\" class=\"wp-image-53423\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" data-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.thisImage.buttonRight\" data-wp-style--top=\"state.thisImage.buttonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div><p class=\"wp-block-paragraph\">Si la web no funciona para nadie, es un problema del servidor e y no hay nada que t&uacute; puedas hacer para solucionarlo por tu cuenta. Si a otras personas les funciona, sigue los pasos a continuaci&oacute;n para solucionar el problema de conexi&oacute;n por tu parte.<\/p><figure class=\"wp-block-image size-large\"><a href=\"\/mx\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=1024,h=1024,fit=scale-down\" alt=\"\" class=\"wp-image-29291\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=768,fit=scale-down 768w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=1536,fit=scale-down 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><h3 class=\"wp-block-heading\" id=\"h-2-restart-your-network-router\">2. Reinicia tu router de red<\/h3><p class=\"wp-block-paragraph\">Reiniciar tu router puede ayudarte a solucionar problemas temporales de red que podr&iacute;an causar errores de conexi&oacute;n en Chrome, incluido ERR_CONNECTION_REFUSED.<\/p><p class=\"wp-block-paragraph\">Desconecta tu router de la corriente e espera de 10 a 30 segundos antes de volver a conectarlo. Cuando termine de reiniciarse por completo, vuelve a conectar tu dispositivo a internet e intenta cargar la web de nuevo.<\/p><h3 class=\"wp-block-heading\" id=\"h-3-troubleshoot-the-internet-connection\">3. Soluciona los problemas de la conexi&oacute;n a internet<\/h3><p class=\"wp-block-paragraph\">Si sigues viendo el error ERR_CONNECTION_REFUSED, prueba a usar las herramientas integradas de soluci&oacute;n de problemas de red de tu sistema. Estas pueden ayudarte a detectar e solucionar problemas de conexi&oacute;n autom&aacute;ticamente.<\/p><p class=\"wp-block-paragraph\"><strong>En Windows<\/strong>:<\/p><ol class=\"wp-block-list\">\n<li>Presiona <strong>Windows + I<\/strong> para abrir <strong>Configuraci&oacute;n<\/strong>.<\/li>\n\n\n\n<li>Ve a <strong>Red e internet<\/strong>.<\/li>\n\n\n\n<li>Haz clic en el bot&oacute;n <strong>Obtener ayuda<\/strong> (en algunas versiones de Windows, esta opci&oacute;n puede encontrarse en <strong>Configuraci&oacute;n avanzada de red<\/strong>).<\/li>\n<\/ol><div class=\"wp-block-image\"><figure data-wp-context='{\"imageId\":\"6a984fb08fde3\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a984fb08fde3\" class=\"aligncenter size-full wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2026\/05\/windows-red-internet-obtener-ayuda-resaltado.png\/public\" alt=\"El bot&oacute;n Obtener ayuda en el men&uacute; Red e internet de Windows\" class=\"wp-image-53424\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" data-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.thisImage.buttonRight\" data-wp-style--top=\"state.thisImage.buttonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div><ol start=\"4\" class=\"wp-block-list\">\n<li>Selecciona el adaptador de red que quieres diagnosticar y haz clic en <strong>Siguiente<\/strong>.<\/li>\n\n\n\n<li>Aplica las correcciones sugeridas e reinicia tu computadora.<\/li>\n<\/ol><p class=\"wp-block-paragraph\"><strong>En macOS<\/strong>:<\/p><ol class=\"wp-block-list\">\n<li>Desconecta todos los dispositivos externos excepto el monitor e el teclado.<\/li>\n\n\n\n<li>Apaga tu Mac y luego enci&eacute;ndela mientras mantienes presionadas las teclas <strong>Comando + D<\/strong>.<\/li>\n\n\n\n<li>Elige tu idioma y espera a que se ejecute <strong>Apple Diagnostics<\/strong>.<\/li>\n\n\n\n<li>Aplica las correcciones sugeridas e reinicia el sistema.<\/li>\n<\/ol><p class=\"wp-block-paragraph\">Una vez que hayas completado los diagn&oacute;sticos, vuelve a cargar la web para ver si se resolvi&oacute; el problema de conexi&oacute;n.<\/p><h3 class=\"wp-block-heading\" id=\"h-4-check-google-chrome-extensions\">4. Revisa las extensiones de Google Chrome<\/h3><p class=\"wp-block-paragraph\">Algunas extensiones de Chrome pueden interferir con tu conexi&oacute;n y causar errores como ERR_CONNECTION_REFUSED, especialmente si est&aacute;n desactualizadas o mal programadas.<\/p><p class=\"wp-block-paragraph\">Para comprobar r&aacute;pidamente si una extensi&oacute;n es el problema, abre la web en modo inc&oacute;gnito (<strong>Ctrl + Shift + N<\/strong>). Chrome desactiva las extensiones all&iacute; de forma predeterminada. Si la web carga, es probable que una de tus extensiones est&eacute; causando el problema.<\/p><p class=\"wp-block-paragraph\">Para gestionar o eliminar extensiones:<\/p><ol class=\"wp-block-list\">\n<li>Haz clic en el <strong>men&uacute; de tres puntos<\/strong> e intenta <strong>Extensiones<\/strong>.<\/li>\n\n\n\n<li>Desactiva las extensiones una por una e intenta abrir la web despu&eacute;s de cada cambio.<\/li>\n\n\n\n<li>Despu&eacute;s de encontrar al responsable, elim&iacute;nalo de Chrome.<\/li>\n\n\n\n<li>Reinicia Chrome e abre la web que quieras.<\/li>\n<\/ol><div class=\"wp-block-image\"><figure data-wp-context='{\"imageId\":\"6a984fb0913a0\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a984fb0913a0\" class=\"aligncenter size-full wp-lightbox-container\"><img decoding=\"async\" width=\"406\" height=\"163\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/03\/grammarly.png\/public\" alt=\"\" class=\"wp-image-17965\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/03\/grammarly.png\/w=406,fit=scale-down 406w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/03\/grammarly.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/03\/grammarly.png\/w=150,fit=scale-down 150w\" sizes=\"(max-width: 406px) 100vw, 406px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" data-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.thisImage.buttonRight\" data-wp-style--top=\"state.thisImage.buttonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div><div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"h-5-clear-browser-cache\">5. Borra la cach&eacute; del navegador<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una cach&eacute; del navegador desactualizada o da&ntilde;ada puede causar el error ERR_CONNECTION_REFUSED porque carga datos antiguos de la web en lugar de conectarse al servidor activo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para solucionar esto, borra la cach&eacute; de tu navegador en Chrome:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Haz clic en el <strong>men&uacute; de tres puntos<\/strong> &rarr; <strong>Configuraci&oacute;n <\/strong>&rarr; <strong>Privacidad y seguridad <\/strong>&rarr; <strong>Eliminar datos de navegaci&oacute;n<\/strong>.<\/li>\n\n\n\n<li>En el men&uacute; desplegable <strong>Intervalo de tiempo<\/strong>, selecciona <strong>Todo el tiempo<\/strong>.<\/li>\n\n\n\n<li>Marca <strong>Historial de navegaci&oacute;n<\/strong>, <strong>Cookies e informaci&oacute;n de otras webs<\/strong> e <strong>Im&aacute;genes y archivos almacenados en cach&eacute;<\/strong>.<\/li>\n\n\n\n<li>Haz clic en <strong>Borrar datos<\/strong>.<\/li>\n<\/ol>\n\n\n<div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a984fb092464\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a984fb092464\" class=\"aligncenter size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"450\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2018\/04\/borrar-datos-chrome.png\/public\" alt=\"Borrar datos de navegaci&oacute;n en Chrome\" class=\"wp-image-15823\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2018\/04\/borrar-datos-chrome.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2018\/04\/borrar-datos-chrome.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2018\/04\/borrar-datos-chrome.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2018\/04\/borrar-datos-chrome.png\/w=768,fit=scale-down 768w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2018\/04\/borrar-datos-chrome.png\/w=1536,fit=scale-down 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" data-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.thisImage.buttonRight\" data-wp-style--top=\"state.thisImage.buttonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Tambi&eacute;n puedes intentar abrir la web en modo inc&oacute;gnito para omitir temporalmente la cach&eacute;. Si el error persiste, contin&uacute;a con el siguiente m&eacute;todo.<\/p>\n<\/div><\/div><h3 class=\"wp-block-heading\" id=\"h-6-reset-or-reinstall-chrome\">6. Restablece o reinstala Chrome<\/h3><p class=\"wp-block-paragraph\">Si sigues viendo el error ERR_CONNECTION_REFUSED, es posible que el propio Chrome est&eacute; mal configurado o da&ntilde;ado. Primero, prueba restablecerlo. Si eso no ayuda, reinstala el navegador por completo.<\/p><p class=\"wp-block-paragraph\">Para restablecer la configuraci&oacute;n de Chrome:<\/p><ol class=\"wp-block-list\">\n<li>Abre Chrome e haz clic en el <strong>men&uacute; de tres puntos &rarr; Configuraci&oacute;n<\/strong>.<\/li>\n\n\n\n<li>Selecciona <strong>Restablecer configuraci&oacute;n &rarr; Restaurar la configuraci&oacute;n a sus valores predeterminados originales<\/strong>.<\/li>\n\n\n\n<li>Confirma haciendo clic en <strong>Restablecer configuraci&oacute;n<\/strong>.<\/li>\n<\/ol><p class=\"wp-block-paragraph\">Si el error persiste, prueba a reinstalar el navegador Chrome.<\/p><p class=\"wp-block-paragraph\"><strong>En Windows<\/strong>:<\/p><ol class=\"wp-block-list\">\n<li>Descarga la <a href=\"https:\/\/www.google.com\/chrome\/\" target=\"_blank\" rel=\"noopener\">versi&oacute;n m&aacute;s reciente de Chrome<\/a>.<\/li>\n\n\n\n<li>Abre <strong>Configuraci&oacute;n &rarr; Aplicaciones &rarr; Aplicaciones instaladas<\/strong>.<\/li>\n\n\n\n<li>Busca <strong>Google Chrome<\/strong>, haz clic en los <strong>tres puntos<\/strong> e selecciona <strong>Desinstalar<\/strong>.<\/li>\n\n\n\n<li>Una vez eliminado, ejecuta el instalador que descargaste antes.<\/li>\n<\/ol><div class=\"wp-block-image\"><figure data-wp-context='{\"imageId\":\"6a984fb0971b9\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a984fb0971b9\" class=\"aligncenter size-large is-resized wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2026\/05\/windows-desinstalar-google-chrome.png\/w=1024,h=1024,fit=scale-down\" alt=\"\" class=\"wp-image-53425\" style=\"width:840px;height:127px\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" data-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.thisImage.buttonRight\" data-wp-style--top=\"state.thisImage.buttonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div><p class=\"wp-block-paragraph\"><strong>En macOS<\/strong>:<\/p><ol class=\"wp-block-list\">\n<li>Abre la carpeta <strong>Aplicaciones<\/strong>.<\/li>\n\n\n\n<li>Encuentra <strong>Google Chrome<\/strong> y arr&aacute;stralo a la <strong>Papelera<\/strong>.<\/li>\n\n\n\n<li>Ve a la p&aacute;gina oficial de Chrome para descargar la versi&oacute;n m&aacute;s reciente.<\/li>\n\n\n\n<li>Abre el archivo <strong>.dmg<\/strong> e arrastra <strong>Chrome<\/strong> de nuevo a la carpeta <strong>Aplicaciones<\/strong>.<\/li>\n<\/ol><h3 class=\"wp-block-heading\" id=\"h-7-disable-antivirus-and-firewall\">7. Desactiva el antivirus y el firewall<\/h3><p class=\"wp-block-paragraph\">A veces, el antivirus o el software de firewall pueden bloquear por error p&aacute;ginas web seguras, lo que provoca problemas de conexi&oacute;n como el error ERR_CONNECTION_REFUSED. Para comprobar si ese es el caso, desactiva temporalmente tus herramientas de protecci&oacute;n e intenta volver a cargar la web.<\/p><p><div class=\"announcement-block announcement-block--important\">\n            <span class=\"announcement-block__heading\">\n                <svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path fill-rule=\"evenodd\" clip-rule=\"evenodd\"\n                          d=\"M12 22.5C17.799 22.5 22.5 17.799 22.5 12C22.5 6.20101 17.799 1.5 12 1.5C6.20101 1.5 1.5 6.20101 1.5 12C1.5 17.799 6.20101 22.5 12 22.5ZM13.637 7.65198C13.637 6.74791 12.9041 6.01501 12 6.01501C11.0959 6.01501 10.363 6.74791 10.363 7.65198C10.5335 9.53749 10.875 13.383 10.875 13.383C10.875 14.0043 11.3787 14.508 12 14.508C12.6213 14.508 13.125 14.0043 13.125 13.383V13.38L13.637 7.65198ZM11.9927 15.714C11.3714 15.714 10.8677 16.2177 10.8677 16.839C10.8677 17.4603 11.3714 17.964 11.9927 17.964H12.0073C12.6286 17.964 13.1323 17.4603 13.1323 16.839C13.1323 16.2177 12.6286 15.714 12.0073 15.714H11.9927Z\"\n                          fill=\"#FEA419\"\/>\n                <\/svg>\n                Important\n            <\/span>\n            <p class=\"announcement-block__content\">\n                <strong>&iexcl;Importante!<\/strong> Este m&eacute;todo es solo para pruebas. Vuelve a activar tu antivirus y tu firewall justo despu&eacute;s de revisar la conexi&oacute;n para evitar exponer tu sistema a amenazas.\n            <\/p><\/div>\n\n\n\n<\/p><p class=\"wp-block-paragraph\"><strong>En Windows (con Microsoft Defender)<\/strong>:<\/p><ol class=\"wp-block-list\">\n<li>Ve a <strong>Configuraci&oacute;n &rarr; Privacidad e seguridad &rarr; Seguridad de Windows<\/strong>.<\/li>\n\n\n\n<li>Haz clic en <strong>Protecci&oacute;n contra virus e amenazas &rarr; luego en Administrar la configuraci&oacute;n<\/strong> e inhabilita la <strong>Protecci&oacute;n en tiempo real<\/strong>.<\/li>\n<\/ol><div class=\"wp-block-image\"><figure data-wp-context='{\"imageId\":\"6a984fb09816c\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a984fb09816c\" class=\"aligncenter size-full is-resized wp-lightbox-container\"><img decoding=\"async\" width=\"398\" height=\"121\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/03\/Proteccion-en-tiempo-real.png\/public\" alt=\"El interruptor de la protecci&oacute;n en tiempo real en Windows.\" class=\"wp-image-17971\" style=\"object-fit:cover;width:538px;height:auto\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/03\/Proteccion-en-tiempo-real.png\/w=398,fit=scale-down 398w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/03\/Proteccion-en-tiempo-real.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/03\/Proteccion-en-tiempo-real.png\/w=150,fit=scale-down 150w\" sizes=\"(max-width: 398px) 100vw, 398px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" data-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.thisImage.buttonRight\" data-wp-style--top=\"state.thisImage.buttonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div><ol start=\"3\" class=\"wp-block-list\">\n<li>Luego ve a <strong>Firewall y protecci&oacute;n de red<\/strong>.<\/li>\n\n\n\n<li>Abre cada perfil de red (<strong>Dominio<\/strong>, <strong>Privado<\/strong>, <strong>P&uacute;blico<\/strong>) e inhabilita <strong>Microsoft Defender Firewall<\/strong>.<\/li>\n<\/ol><div class=\"wp-block-image\"><figure data-wp-context='{\"imageId\":\"6a984fb09a979\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a984fb09a979\" class=\"aligncenter size-full wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2026\/03\/Firewall-de-Microsoft-Defender.jpg\/public\" alt=\"El interruptor del Firewall de Microsoft Defender en Windows.\" class=\"wp-image-52109\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" data-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.thisImage.buttonRight\" data-wp-style--top=\"state.thisImage.buttonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div><p class=\"wp-block-paragraph\"><strong>En macOS<\/strong>:<\/p><ol class=\"wp-block-list\">\n<li>Haz clic en el <strong>logo de Apple <\/strong>en la esquina superior izquierda.<\/li>\n\n\n\n<li>Selecciona <strong>Configuraci&oacute;n del sistema<\/strong> <strong>&rarr;<\/strong> <strong>Red<\/strong> <strong>&rarr;<\/strong> <strong>Firewall<\/strong>.<\/li>\n\n\n\n<li>Desliza el interruptor hacia la izquierda para apagarlo.<\/li>\n<\/ol><p class=\"wp-block-paragraph\">Si usas software de seguridad de terceros, sigue la documentaci&oacute;n del desarrollador para desactivarlo de forma segura.<\/p><h3 class=\"wp-block-heading\" id=\"h-8-deactivate-your-vpn\">8. Desactiva tu VPN<\/h3><p class=\"wp-block-paragraph\">Algunas webs o proveedores de servicios de internet bloquean el tr&aacute;fico de las VPN, lo que puede provocar problemas de conexi&oacute;n como ERR_CONNECTION_REFUSED. Una configuraci&oacute;n incorrecta de la VPN tambi&eacute;n puede afectar la capacidad de Chrome para conectarse a ciertos servidores.<\/p><p class=\"wp-block-paragraph\">Descon&eacute;ctate temporalmente de tu VPN e intenta cargar la web de nuevo. La mayor&iacute;a de las apps de VPN incluyen una opci&oacute;n para pausarla o desconectarla r&aacute;pidamente.<\/p><p class=\"wp-block-paragraph\">Por ejemplo, as&iacute; puedes pausar <strong>NordVPN<\/strong>:<\/p><ol class=\"wp-block-list\">\n<li>Abre la app de NordVPN.<\/li>\n\n\n\n<li>Si est&aacute;s conectado, haz clic en el bot&oacute;n <strong>Desconectar<\/strong>.<\/li>\n\n\n\n<li>Cierra la app y luego abre la web sin una VPN.<\/li>\n<\/ol><p class=\"wp-block-paragraph\">Despu&eacute;s de probar la conexi&oacute;n, recuerda volver a conectar tu VPN para recuperar tu privacidad e seguridad.<\/p><h3 class=\"wp-block-heading\" id=\"h-9-flush-dns-cache\">9. Vac&iacute;a la cach&eacute; de DNS<\/h3><p class=\"wp-block-paragraph\">Tu sistema operativo almacena datos DNS de forma local para acelerar el acceso a la web. Si esa cach&eacute; se desactualiza o se da&ntilde;a, puede provocar el error ERR_CONNECTION_REFUSED. <a href=\"\/mx\/tutoriales\/como-hacer-un-flush-dns\/\">Vaciar la cach&eacute; de DNS<\/a> hace que tu sistema obtenga la informaci&oacute;n de DNS actualizada.<\/p><p class=\"wp-block-paragraph\"><strong>En Windows<\/strong>:<\/p><ol class=\"wp-block-list\">\n<li>Abre el men&uacute; <strong>Inicio<\/strong>, busca <strong>S&iacute;mbolo del sistema<\/strong>, luego <strong>haz clic derecho<\/strong> e <strong>inicia como administrador<\/strong>.<\/li>\n\n\n\n<li>Ejecuta los siguientes comandos uno por uno:<\/li>\n<\/ol><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">netsh winsock reset catalog<\/pre><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">ipconfig \/flushdns<\/pre><p class=\"wp-block-paragraph\"><strong>En macOS<\/strong>:<\/p><ol class=\"wp-block-list\">\n<li>Pulsa <strong>Comando + Espacio<\/strong>, escribe <strong>Terminal<\/strong> y pulsa <strong>Enter<\/strong>.<\/li>\n\n\n\n<li>Ejecuta este comando e introduce tu contrase&ntilde;a si se te solicita:<\/li>\n<\/ol><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">sudo dscacheutil -flushcache; sudo killall -HUP mDNSResponder<\/pre><p class=\"wp-block-paragraph\">Una vez que se borre la cach&eacute; de DNS, intenta acceder de nuevo a la web para comprobar si el error se ha resuelto.<\/p><h3 class=\"wp-block-heading\" id=\"h-10-configure-proxy-server-settings\">10. Configura los ajustes del servidor proxy<\/h3><p class=\"wp-block-paragraph\">Una configuraci&oacute;n del proxy incorrecta o desactualizada puede impedir que Chrome se conecte a internet y provocar errores como ERR_CONNECTION_REFUSED. Esto puede ocurrir si el proxy est&aacute; offline, est&aacute; mal configurado o el servidor de la web lo bloquea.<\/p><p class=\"wp-block-paragraph\">Para descartar esta posibilidad, prueba desactivar la configuraci&oacute;n del proxy en tu dispositivo.<\/p><p class=\"wp-block-paragraph\"><strong>En Windows:<\/strong> <\/p><ol class=\"wp-block-list\">\n<li>Abre el <strong>panel de control<\/strong>.<\/li>\n\n\n\n<li>Ve a <strong>Red e Internet<\/strong> &rarr; <strong>Opciones de Internet<\/strong> &rarr; <strong>Conexiones<\/strong> &rarr; <strong>Configuraci&oacute;n de LAN<\/strong>.<\/li>\n\n\n\n<li>Desmarca tanto <strong>Detectar la configuraci&oacute;n autom&aacute;ticamente<\/strong> como <strong>Usar un servidor proxy para tu LAN<\/strong>.<\/li>\n\n\n\n<li>Haz clic en <strong>Aceptar<\/strong> para guardar.<\/li>\n<\/ol><div class=\"wp-block-image\"><figure data-wp-context='{\"imageId\":\"6a984fb09dfea\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a984fb09dfea\" class=\"aligncenter size-full wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2026\/03\/red-de-area-local.png\/public\" alt=\"La configuraci&oacute;n de red de &aacute;rea local (LAN) en Windows.\" class=\"wp-image-52110\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" data-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.thisImage.buttonRight\" data-wp-style--top=\"state.thisImage.buttonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div><p class=\"wp-block-paragraph\"><strong>En macOS<\/strong>:<\/p><ol class=\"wp-block-list\">\n<li>Haz clic en el <strong>logo de Apple &rarr; Configuraci&oacute;n del Sistema &rarr; Wi-Fi<\/strong>.<\/li>\n\n\n\n<li>Selecciona tu conexi&oacute;n activa y luego haz clic en <strong>Detalles<\/strong> &rarr; <strong>Proxies<\/strong>.<\/li>\n\n\n\n<li>Desactiva todos los protocolos proxy de la lista.<\/li>\n\n\n\n<li>Haz clic en <strong>OK<\/strong> para guardar los cambios.<\/li>\n<\/ol><div class=\"wp-block-image\"><figure data-wp-context='{\"imageId\":\"6a984fb0a0e72\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a984fb0a0e72\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2026\/05\/macos-wi-fi-proxies-seleccionados.png\/w=1024,h=1024,fit=scale-down\" alt=\"La pesta&ntilde;a Proxies en macOS\" class=\"wp-image-53426\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" data-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.thisImage.buttonRight\" data-wp-style--top=\"state.thisImage.buttonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div><p class=\"wp-block-paragraph\">Una vez que hayas desactivado el proxy, vuelve a cargar la web para ver si se resolvi&oacute; el problema de conexi&oacute;n.<\/p><h3 class=\"wp-block-heading\" id=\"h-11-change-dns-server\">11. Cambia el servidor DNS<\/h3><p class=\"wp-block-paragraph\">Un servidor DNS sobrecargado o que no responde puede provocar el error ERR_CONNECTION_REFUSED al no resolver correctamente las direcciones de la web.<\/p><p class=\"wp-block-paragraph\">En lugar de usar el DNS predeterminado de tu proveedor de servicios de internet, cambia a un servicio de DNS p&uacute;blico confiable como:<\/p><ul class=\"wp-block-list\">\n<li><strong>DNS p&uacute;blico de Google<\/strong>: <strong>8.8.8.8<\/strong> y <strong>8.8.4.4<\/strong> <\/li>\n\n\n\n<li><strong>DNS de Cloudflare<\/strong>: <strong>1.1.1.1<\/strong> y <strong>1.0.0.1<\/strong> <\/li>\n<\/ul><p class=\"wp-block-paragraph\"><strong>En Windows<\/strong>:<\/p><ol class=\"wp-block-list\">\n<li>Abre <strong>Configuraci&oacute;n<\/strong> &rarr; <strong>Red e internet<\/strong>.<\/li>\n\n\n\n<li>Selecciona tu conexi&oacute;n activa, como Wi&#8209;Fi, y luego haz clic en <strong>Propiedades de hardware<\/strong>.<\/li>\n\n\n\n<li>Junto a <strong>la asignaci&oacute;n del servidor DNS<\/strong>, haz clic en <strong>Editar<\/strong> e ind&iacute;cala como <strong>Manual<\/strong>.<\/li>\n\n\n\n<li>Activa <strong>IPv4<\/strong> e introduce los servidores DNS que prefieras.\n<ul class=\"wp-block-list\">\n<li><strong>Preferido<\/strong>: 8.8.8.8<\/li>\n\n\n\n<li><strong>Alternativo<\/strong>: 8.8.4.4<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Configura el cifrado como <strong>Cifrado preferido, sin cifrar permitido<\/strong>.<\/li>\n\n\n\n<li>Haz clic en <strong>Guardar<\/strong>.<\/li>\n<\/ol><div class=\"wp-block-image\"><figure data-wp-context='{\"imageId\":\"6a984fb0a3b63\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a984fb0a3b63\" class=\"aligncenter size-full wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2026\/05\/editar-configuracion-de-DNS.png\/public\" alt=\"Editar la configuraci&oacute;n de DNS en Windows.\" class=\"wp-image-53427\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" data-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.thisImage.buttonRight\" data-wp-style--top=\"state.thisImage.buttonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div><p class=\"wp-block-paragraph\"><strong>En macOS<\/strong>:<\/p><ol class=\"wp-block-list\">\n<li>Ve a <strong>Ajustes del sistema<\/strong> &rarr; <strong>Wi-Fi<\/strong>.<\/li>\n\n\n\n<li>Selecciona tu red activa y luego haz clic en <strong>Detalles<\/strong> &rarr; <strong>DNS<\/strong>.<\/li>\n\n\n\n<li>Elimina los registros DNS existentes y luego haz clic en <strong>+<\/strong> para a&ntilde;adir otros nuevos.<\/li>\n\n\n\n<li>Ingresa <strong>8.8.8.8<\/strong> y <strong>8.8.4.4<\/strong> y luego haz clic en <strong>Aceptar<\/strong>.<\/li>\n<\/ol><div class=\"wp-block-image\"><figure data-wp-context='{\"imageId\":\"6a984fb0a698e\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a984fb0a698e\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2026\/05\/macos-wi-fi-dns-seleccionado.png\/w=1024,h=1024,fit=scale-down\" alt=\"La pesta&ntilde;a DNS en macOS\" class=\"wp-image-53428\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" data-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.thisImage.buttonRight\" data-wp-style--top=\"state.thisImage.buttonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div><p class=\"wp-block-paragraph\">Si ya usas un DNS personalizado e igual sigues viendo el error, intenta volver a la configuraci&oacute;n original de tu proveedor de internet. A veces, esto tambi&eacute;n puede resolver el problema.<\/p><h2 class=\"wp-block-heading\" id=\"h-next-steps-if-the-err-connection-refused-error-persists\">Siguientes pasos si el error ERR_CONNECTION_REFUSED persiste<\/h2><p class=\"wp-block-paragraph\">Si ya probaste todos los m&eacute;todos anteriores e el error ERR_CONNECTION_REFUSED sigue apareciendo, a&uacute;n hay algunas cosas m&aacute;s que puedes hacer para solucionar el problema o descartar fallas m&aacute;s profundas.<\/p><p class=\"wp-block-paragraph\"><strong>Prueba otras soluciones b&aacute;sicas<\/strong>:<\/p><ul class=\"wp-block-list\">\n<li><strong>Usa un navegador diferente<\/strong> para descartar problemas espec&iacute;ficos del navegador.<\/li>\n\n\n\n<li><strong>Reinicia tu dispositivo<\/strong> para solucionar fallos temporales del sistema.<\/li>\n\n\n\n<li><strong>Revisa tu archivo hosts<\/strong> en Windows y macOS para asegurarte de que la web no est&eacute; bloqueada por accidente.<\/li>\n\n\n\n<li><strong>Restablece tu pila TCP\/IP<\/strong> en Windows para recuperar la configuraci&oacute;n de red predeterminada ejecutando el siguiente comando:<\/li>\n<\/ul><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">netsh int ip reset<\/pre><p class=\"wp-block-paragraph\"><strong>Contacta con el equipo de soporte adecuado<\/strong>:<\/p><ul class=\"wp-block-list\">\n<li><strong>Tu proveedor de internet<\/strong>, si el problema afecta a varias webs.<\/li>\n\n\n\n<li><strong>El propietario de la web<\/strong>, si el error aparece solo en su web.<\/li>\n\n\n\n<li><strong>Tu proveedor de Hosting<\/strong> si la web que no est&aacute; disponible es la tuya.<\/li>\n<\/ul><p class=\"wp-block-paragraph\"><strong>Comprueba si hay actualizaciones pendientes<\/strong>:<\/p><p class=\"wp-block-paragraph\">Aseg&uacute;rate de que tu navegador y tu sistema operativo est&eacute;n actualizados. El software desactualizado puede provocar problemas de compatibilidad de red o errores que afecten la conectividad.<\/p><p class=\"wp-block-paragraph\"><strong>Evita ERR_CONNECTION_REFUSED en el futuro<\/strong>:<\/p><p class=\"wp-block-paragraph\">Como usuario final, puedes reducir las probabilidades de volver a ver el error ERR_CONNECTION_REFUSED si mantienes tu navegador e sistema operativo actualizados, evitas las extensiones de navegador sospechosas o desactualizadas e intentas mantener una conexi&oacute;n a internet estable.<\/p><p class=\"wp-block-paragraph\">Si alojas tu propia web, aseg&uacute;rate de que tu servidor est&eacute; en funcionamiento, las reglas del firewall est&eacute;n configuradas correctamente e los registros DNS sean correctos. Estas configuraciones incorrectas suelen ser causas comunes de que se rechace la conexi&oacute;n.<\/p><p class=\"wp-block-paragraph\">No te preocupes, ERR_CONNECTION_REFUSED es un error que se puede solucionar. Con un poco de paciencia y los pasos adecuados, retomar&aacute;s el rumbo en poco tiempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ERR_CONNECTION_REFUSED es un error de Google Chrome que impide que el navegador se conecte al servidor de un sitio web. Puedes probar alguno de estos 11 m&eacute;todos para identificar y solucionar el problema: A continuaci&oacute;n, te guiaremos paso a paso por cada m&eacute;todo de soluci&oacute;n, todos f&aacute;ciles de aplicar y compatibles tanto con Windows como [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/mx\/tutoriales\/como-solucionar-err-connection-refused\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":190,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_title":"C\u00f3mo solucionar el error ERR_CONNECTION_REFUSED","rank_math_description":"El error ERR_CONNECTION_REFUSED puede ser frustrante. Descubre 11 m\u00e9todos efectivos para solucionarlo y recuperar el acceso a tu web r\u00e1pidamente.","rank_math_focus_keyword":"err_connection_refused","footnotes":""},"categories":[],"tags":[],"class_list":["post-47599","post","type-post","status-publish","format-standard","hentry"],"hreflangs":[{"locale":"es-ES","link":"https:\/\/www.hostinger.com\/es\/tutoriales\/como-solucionar-err-connection-refused","default":1},{"locale":"es-AR","link":"https:\/\/www.hostinger.com\/ar\/tutoriales\/como-solucionar-err-connection-refused","default":0},{"locale":"es-MX","link":"https:\/\/www.hostinger.com\/mx\/tutoriales\/como-solucionar-err-connection-refused","default":0},{"locale":"es-CO","link":"https:\/\/www.hostinger.com\/co\/tutoriales\/como-solucionar-err-connection-refused","default":0}],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts\/47599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/users\/190"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/comments?post=47599"}],"version-history":[{"count":0,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts\/47599\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/media?parent=47599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/categories?post=47599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/tags?post=47599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}