{"id":10491,"date":"2020-05-12T19:36:14","date_gmt":"2020-05-12T17:36:14","guid":{"rendered":"https:\/\/blog.hostinger.io\/mx-tutoriales\/?p=10491"},"modified":"2026-03-10T16:28:32","modified_gmt":"2026-03-10T15:28:32","slug":"litespeed-cache-plugin","status":"publish","type":"post","link":"\/mx\/tutoriales\/litespeed-cache-plugin\/","title":{"rendered":"Maximiza el rendimiento de tu sitio de WordPress con LiteSpeed Cache: Gu\u00eda completa"},"content":{"rendered":"<p>La optimizaci&oacute;n de la velocidad debe ser una prioridad para todos los propietarios de sitios web, ya que esta afecta directamente al SEO en WordPress. <\/p><p>Adem&aacute;s, cuanto m&aacute;s tiempo tarda en cargar un sitio web, mayor es su tasa de rebote. Esto puede evitar que generes conversiones y que llegue tr&aacute;fico a tu sitio.<\/p><p>Con las herramientas y configuraciones adecuadas, el almacenamiento en cach&eacute; de tu sitio web puede aumentar significativamente su rendimiento. Por esta raz&oacute;n, te mostraremos c&oacute;mo optimizar la puntuaci&oacute;n de tu p&aacute;gina utilizando el mejor plugin de cach&eacute; de LiteSpeed &#8203;&#8203;Technologies.&nbsp;<\/p><p>Hemos probado el plugin LiteSpeed &#8203;&#8203;Cache y configurado los ajustes en tres sitios web diferentes. Este art&iacute;culo te guiar&aacute; a trav&eacute;s de la configuraci&oacute;n que aplicamos para obtener los mejores resultados.&nbsp;<\/p><p>Antes de sumergirnos en la configuraci&oacute;n, comencemos con una breve descripci&oacute;n general del plugin de cach&eacute; LiteSpeed.<\/p><p><div class=\"protip\">\n                    <h2 class=\"featured-snippet title\">&iquest;Qu&eacute; es LiteSpeed?<\/h2>\n                    <p>LiteSpeed &#8203;&#8203;es un software de servidor web dise&ntilde;ado para acelerar el rendimiento de un sitio web. Construido con una arquitectura basada en eventos, el servidor LiteSpeed &#8203;&#8203;puede manejar un mayor tr&aacute;fico con menos procesos, lo que reduce el uso de recursos y mejora la velocidad de la p&aacute;gina.<\/p>\n                <\/div><\/p><p>El servidor LiteSpeed &#8203;&#8203;tambi&eacute;n tiene incorporado un reemplazo para <a href=\"\/mx\/tutoriales\/que-es-apache\/\">Apache<\/a> con soporte<strong> .htaccess<\/strong>, lo que permite a los usuarios cambiarse de Apache y utilizar las configuraciones existentes. <\/p><p>Adem&aacute;s, LiteSpeed funciona con varios paneles de control de hosting populares, como WHM, DirectAdmin y Plesk.&nbsp;<\/p><p>Existen dos ediciones del servidor web LiteSpeed &#8203;&#8203;disponibles:<\/p><ul class=\"wp-block-list\">\n<li><strong>LiteSpeed &#8203;&#8203;Enterprise<\/strong>: es adecuado para alojar varios sitios web o un entorno de alojamiento compartido. Este detecta autom&aacute;ticamente los cambios en el archivo <strong>.htaccess<\/strong> y ajusta la configuraci&oacute;n sin reiniciar el servidor.&nbsp;<\/li>\n\n\n\n<li><strong>OpenLiteSpeed<\/strong>: es una versi&oacute;n de c&oacute;digo abierto de LiteSpeed &#8203;&#8203;Enterprise que tiene todas sus caracter&iacute;sticas esenciales. Esta requiere un reinicio cada vez que carga un nuevo archivo<strong> .htaccess<\/strong>. Por eso, este servidor web generalmente se utiliza para sitios web personales.<\/li>\n<\/ul><p>Al <a href=\"\/mx\/tutoriales\/mejorar-velocidad-wordpress\/\">optimizar la velocidad<\/a> y el rendimiento de un sitio, LiteSpeed &#8203;&#8203;utiliza un cach&eacute; de nivel de servidor incorporado conocido como LiteSpeed &#8203;&#8203;Cache.&nbsp;<\/p><p>LiteSpeed &#8203;&#8203;Cache es un producto de LiteSpeed &#8203;&#8203;Technologies que optimiza el contenido din&aacute;mico en las p&aacute;ginas web. Este viene con funciones avanzadas de almacenamiento en cach&eacute; y optimizaci&oacute;n. LiteSpeed &#8203;&#8203;Cache tambi&eacute;n est&aacute; disponible como plugin en varias plataformas, incluida WordPress.<\/p><p>LiteSpeed &#8203;&#8203;Cache para WordPress (LSCWP) funciona almacenando una copia del contenido del sitio web para futuras solicitudes. Como resultado, el servidor tiene que procesar menos solicitudes y puede mostrar p&aacute;ginas web m&aacute;s r&aacute;pido.&nbsp;<\/p><p>Ten en cuenta que las funciones que requieren el almacenamiento en cach&eacute; del servidor solo est&aacute;n disponibles en el servidor LiteSpeed. Por otro lado, las funciones de optimizaci&oacute;n se pueden utilizar con cualquier servidor web, incluidos OpenLiteSpeed, Apache y Nginx. <\/p><p>Estas funciones incluyen la optimizaci&oacute;n de im&aacute;genes, la integraci&oacute;n de <a href=\"\/mx\/tutoriales\/que-es-cdn\/\">CDN (red de entrega de contenido)<\/a> y la modificaci&oacute;n de CSS\/JS.<\/p><p>Antes de continuar, echemos un vistazo a las puntuaciones que Google PageSpeed &#8203;&#8203;Insights otorg&oacute; a las versiones m&oacute;vil y de escritorio del sitio web analizado antes de configurar LiteSpeed &#8203;&#8203;Cache.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"900\" height=\"400\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/page-speed-insight.png\/public\" alt=\"Puntuaciones de Google PageSpeed &#8203;&#8203;Insights antes de configurar LiteSpeed &#8203;&#8203;Cache\" class=\"wp-image-20086\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/page-speed-insight.png\/w=900,fit=scale-down 900w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/page-speed-insight.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/page-speed-insight.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/page-speed-insight.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><\/div><p>Una vez que se configur&oacute; LiteSpeed &#8203;&#8203;Cache para WordPress, ambas versiones mejoraron la puntuaci&oacute;n.<\/p><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"950\" height=\"386\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/pagespeed-puntuacion.png\/public\" alt=\"Puntuaci&oacute;n en Pagespeed luego de optimizar\" class=\"wp-image-20178\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/pagespeed-puntuacion.png\/w=950,fit=scale-down 950w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/pagespeed-puntuacion.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/pagespeed-puntuacion.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/pagespeed-puntuacion.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/figure><h2 class=\"wp-block-heading\" id=\"h-rendimiento-del-plugin-litespeed-cache-en-openlitespeed-el-servidor-web-litespeed-nginx-y-apache\">Rendimiento del plugin LiteSpeed Cache &#8203;&#8203;en OpenLiteSpeed, el servidor web LiteSpeed, Nginx y Apache<\/h2><p>Aunque el plugin de cach&eacute; LiteSpeed puede funcionar fuera del entorno de LiteSpeed, su funcionalidad difiere seg&uacute;n el servidor web que est&eacute;s utilizando. Por lo tanto, las mediciones de procesos y resultados tambi&eacute;n ser&aacute;n diferentes.&nbsp;<\/p><p>Por esta raz&oacute;n, hemos realizado pruebas de estr&eacute;s a peque&ntilde;a y gran escala comparando el servidor web LiteSpeed, <a href=\"\/mx\/tutoriales\/que-es-nginx\/\">Nginx<\/a> y Apache. Aqu&iacute; te mostraremos tres m&eacute;tricas de su rendimiento: el tiempo de procesamiento completo, las solicitudes por segundo y los megabytes por segundo.&nbsp;<\/p><p><div><p class=\"important\">&iexcl;<strong>Importante<\/strong>! Las pruebas de estr&eacute;s se realizaron desde Lituania en servidores ubicados en EE. UU.<\/p><\/div><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"980\" height=\"1200\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-03.jpg\/public\" alt=\"Comparaci&oacute;n de servidores\" class=\"wp-image-38071\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-03.jpg\/w=980,fit=scale-down 980w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-03.jpg\/w=245,fit=scale-down 245w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-03.jpg\/w=837,fit=scale-down 837w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-03.jpg\/w=123,fit=scale-down 123w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-03.jpg\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/figure><\/p><p>Como vimos anteriormente, los servidores web LiteSpeed &#8203;&#8203;obtuvieron la mejor puntuaci&oacute;n. Vincular el servidor web LiteSpeed &#8203;&#8203;con LiteSpeed &#8203;&#8203;Cache para WordPress sin duda le dar&aacute; a tu sitio web el rendimiento m&aacute;s &oacute;ptimo.<\/p><h3 class=\"wp-block-heading\" id=\"h-instalacion-del-plugin-litespeed-cache\">Instalaci&oacute;n del plugin LiteSpeed Cache<\/h3><p>Afortunadamente, el plugin LiteSpeed &#8203;&#8203;Cache viene preinstalado con todas las cuentas de Hostinger. Por lo tanto, los usuarios de Hostinger pueden continuar y omitir el paso de <a href=\"\/mx\/tutoriales\/plugins-en-wordpress-gratis\/\">instalaci&oacute;n del plugin<\/a>. <\/p><p>Sin embargo, si est&aacute;s utilizando un servidor web diferente, sigue las instrucciones a continuaci&oacute;n para instalar LiteSpeed &#8203;&#8203;Cache para WordPress.<\/p><ol class=\"wp-block-list\">\n<li>Inicia sesi&oacute;n en tu panel de control de WordPress y ve a la secci&oacute;n <strong>Plugins<\/strong>.&nbsp;<\/li>\n\n\n\n<li>Busca <strong>LiteSpeed &#8203;&#8203;Cache<\/strong>, haz clic en <strong>Instalar ahora<\/strong> y luego en <strong>Activar<\/strong>.<\/li>\n\n\n\n<li>Actualiza la p&aacute;gina: la secci&oacute;n LiteSpeed &#8203;&#8203;Cache aparecer&aacute; en tu escritorio.<\/li>\n<\/ol><p>Una vez instalado el plugin de WordPress, tendr&aacute;s que configurarlo. <\/p><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"\/mx\/hosting-wordpress\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/06\/ES-New-WP_in-text-banner.png\/public\" alt=\"\" class=\"wp-image-40615\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/06\/ES-New-WP_in-text-banner.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/06\/ES-New-WP_in-text-banner.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/06\/ES-New-WP_in-text-banner.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/06\/ES-New-WP_in-text-banner.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div><h2 class=\"wp-block-heading\" id=\"h-como-configurar-el-plugin-litespeed-cache-para-wordpress\">C&oacute;mo configurar el plugin LiteSpeed &#8203;&#8203;Cache para WordPress<\/h2><p>Hemos probado esta configuraci&oacute;n de LiteSpeed &#8203;&#8203;Cache en tres sitios con <a href=\"\/mx\/hosting-web\">alojamiento web<\/a> compartido: un sitio de blog simple, un sitio web de comercio electr&oacute;nico y un portfolio en l&iacute;nea.<\/p><p><div><p class=\"important\">&iexcl;<strong>Importante<\/strong>! Cuando pruebes el rendimiento en GTmetrix, hazlo varias veces independientemente del plugin de cach&eacute; que est&eacute;s utilizando, ya que es posible que no se acceda al cach&eacute; la primera vez o que este   no se cargue. Adem&aacute;s, aseg&uacute;rate de purgar el cach&eacute; antes de probar cualquier configuraci&oacute;n nueva.<\/p><\/div><\/p><p>Los clientes de hosting WordPress de Hostinger pueden utilizar los<strong> perfiles de optimizaci&oacute;n de LiteSpeed <\/strong>para optimizar el rendimiento de su sitio web con un solo clic. Estos perfiles tienen ajustes preconfigurados para optimizar diferentes aspectos de tu sitio web, eliminando el proceso de las configuraciones manuales.<\/p><p>Ten en cuenta que esta funci&oacute;n s&oacute;lo funciona con el plugin LiteSpeed Cache para optimizar sitios web de WordPress activos.<\/p><p>Sigue estos pasos para configurar los perfiles de optimizaci&oacute;n de LiteSpeed para mejorar el rendimiento de WordPress:<\/p><ol class=\"wp-block-list\">\n<li>Navega a <strong>WordPress <\/strong>&rarr; <strong>Vista general <\/strong>desde hPanel.<\/li>\n\n\n\n<li>Despl&aacute;zate hasta la secci&oacute;n <strong>N&uacute;cleo <\/strong>y aseg&uacute;rate de que la opci&oacute;n <strong>LiteSpeed <\/strong>est&aacute; activada.<\/li>\n<\/ol><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"833\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Nucleo-litespeed.png\/public\" alt=\"Vista general de WP en hPanel\" class=\"wp-image-39847\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Nucleo-litespeed.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Nucleo-litespeed.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Nucleo-litespeed.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Nucleo-litespeed.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><ol start=\"3\" class=\"wp-block-list\">\n<li>Selecciona <strong>Cambiar ajustes <\/strong>&rarr; <strong>Aplicar ajustes <\/strong>en uno de los tres perfiles de optimizaci&oacute;n:<\/li>\n<\/ol><ul class=\"wp-block-list\">\n<li><strong>B&aacute;sico:<\/strong> implementa optimizaciones b&aacute;sicas para mejorar los tiempos de carga y la experiencia del usuario.<\/li>\n\n\n\n<li><strong>Avanzado:<\/strong> el perfil recomendado para optimizar todo tipo de sitios web.<\/li>\n\n\n\n<li><strong>Agresivo<\/strong>: realiza optimizaciones avanzadas para obtener el mejor rendimiento posible.<\/li>\n<\/ul><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"644\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Austes-de-LiteSpeed-.png\/public\" alt=\"Ajustes de optimizaci&oacute;n de LiteSpeed\" class=\"wp-image-39849\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Austes-de-LiteSpeed-.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Austes-de-LiteSpeed-.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Austes-de-LiteSpeed-.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Austes-de-LiteSpeed-.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><ol start=\"4\" class=\"wp-block-list\">\n<li>Lee la cl&aacute;usula de exenci&oacute;n de responsabilidad y pulsa <strong>Aplicar <\/strong>para confirmar.<\/li>\n\n\n\n<li>La secci&oacute;n <strong>Registro de cambios en la configuraci&oacute;n<\/strong>, debajo de las opciones del perfil, realiza un seguimiento de cada cambio a un nuevo preajuste de optimizaci&oacute;n. Haz clic en <strong>Restaurar <\/strong>para restablecer la configuraci&oacute;n de la Cach&eacute; de LiteSpeed a su estado anterior si es necesario.<\/li>\n<\/ol><figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/05\/Registro-de-cambios-de-configuraci%C3%B3n.png\/public\" alt=\"Registro de cambios de configuraci&oacute;n de LiteSpeed\" class=\"wp-image-39850\"><\/figure><p>Tambi&eacute;n puedes consultar el siguiente proceso para configurar manualmente el plugin LiteSpeed Cache. Cada ajuste incluir&aacute; una descripci&oacute;n detallada para ayudarte a decidir si necesitas modificarlo.<\/p><h3 class=\"wp-block-heading\" id=\"h-1-completa-la-configuracion-basica\">1. Completa la configuraci&oacute;n b&aacute;sica<\/h3><p>Antes de entrar en los pasos para completar la configuraci&oacute;n b&aacute;sica del plugin LiteSpeed Cache, comparemos los resultados de las pruebas de rendimiento de los tres sitios web.&nbsp;<\/p><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"702\" height=\"1200\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-01-scaled.jpg\/public\" alt=\"Comparaci&oacute;n de sitios web con y sin Litespeed \" class=\"wp-image-38073\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-01-scaled.jpg\/w=702,fit=scale-down 702w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-01-scaled.jpg\/w=175,fit=scale-down 175w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-01-scaled.jpg\/w=599,fit=scale-down 599w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-01-scaled.jpg\/w=88,fit=scale-down 88w\" sizes=\"(max-width: 702px) 100vw, 702px\" \/><\/figure><p>El gr&aacute;fico anterior muestra una mejora significativa en el rendimiento del sitio web despu&eacute;s de activar y configurar el plugin LiteSpeed &#8203;&#8203;Cache.&nbsp;<\/p><p>Por esta raz&oacute;n, te guiaremos a trav&eacute;s de las caracter&iacute;sticas y funcionalidades de este plugin, junto con las mejores configuraciones que puedes aplicar. Comencemos con la p&aacute;gina <strong>Ajustes generales<\/strong>.<\/p><p>La primera opci&oacute;n en esta p&aacute;gina es <strong>Actualizar autom&aacute;ticamente<\/strong>. Como sugiere el nombre, cambiar este bot&oacute;n a <strong>On <\/strong>(activado) har&aacute; que el sistema instale la &uacute;ltima versi&oacute;n del plugin LiteSpeed Cache.&nbsp;<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1016\" height=\"102\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/actualizar-automaticamente.png\/public\" alt=\"Ajustes generales de LiteSpeed Cache, secci&oacute;n Actualizar autom&aacute;ticamente\" class=\"wp-image-20040\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/actualizar-automaticamente.png\/w=1016,fit=scale-down 1016w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/actualizar-automaticamente.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/actualizar-automaticamente.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/actualizar-automaticamente.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1016px) 100vw, 1016px\" \/><\/figure><\/div><p>A continuaci&oacute;n, hay un campo para agregar tu clave de dominio, tambi&eacute;n conocida como clave API. Es importante tener esto si deseas utilizar las <a href=\"https:\/\/quic.cloud\/quic-cloud-services-and-features\/\" target=\"_blank\" rel=\"noreferrer noopener\">funciones y los servicios<\/a> de <strong>QUIC.cloud<\/strong>. Simplemente haz clic en el bot&oacute;n <strong>Solicitar clave de dominio<\/strong>.<\/p><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"862\" height=\"66\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/clave-de-dominio-2.png\/public\" alt=\"Ajustes generales de LiteSpeed Cache, secci&oacute;n Clave de dominio\" class=\"wp-image-20047\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/clave-de-dominio-2.png\/w=862,fit=scale-down 862w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/clave-de-dominio-2.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/clave-de-dominio-2.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/clave-de-dominio-2.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 862px) 100vw, 862px\" \/><\/figure><p>Hablaremos m&aacute;s sobre la configuraci&oacute;n de <strong>QUIC.cloud<\/strong> en la siguiente secci&oacute;n. Ahora, dir&iacute;gete a la siguiente secci&oacute;n y ver&aacute;s el <strong>Modo de invitado<\/strong>.&nbsp;<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1101\" height=\"170\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/modo-de-invitado-1.png\/w=1024,h=1024,fit=scale-down\" alt=\"Ajustes generales de LiteSpeed Cache, secci&oacute;n Modo de invitado\" class=\"wp-image-20048\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/modo-de-invitado-1.png\/w=1101,fit=scale-down 1101w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/modo-de-invitado-1.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/modo-de-invitado-1.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/modo-de-invitado-1.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/modo-de-invitado-1.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1101px) 100vw, 1101px\" \/><\/figure><\/div><p>Esta opci&oacute;n proporciona una p&aacute;gina de destino en cach&eacute; autom&aacute;tica para la primera solicitud de un visitante. <\/p><p>Cuando habilitas el modo de invitado, el servidor no tendr&aacute; que obtener la informaci&oacute;n de los visitantes y, en su lugar, les entregar&aacute; la p&aacute;gina en cach&eacute; predeterminada. Como resultado, el tiempo de carga de la p&aacute;gina ser&aacute; menor.&nbsp;<\/p><p>Una vez que se entregan las p&aacute;ginas almacenadas en cach&eacute;, el servidor realizar&aacute; una llamada Ajax para obtener la versi&oacute;n adecuada de las p&aacute;ginas web que solicitaron los visitantes. Para habilitar el modo de invitado, simplemente cambia el bot&oacute;n a <strong>ON<\/strong>.&nbsp;<\/p><p>Para optimizar el modo de invitado, utiliza la opci&oacute;n <strong>Optimizaci&oacute;n para invitados<\/strong>.&nbsp;<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1105\" height=\"157\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/optimizacion-para-invitados.png\/w=1024,h=1024,fit=scale-down\" alt=\"Ajustes generales de LiteSpeed Cache, secci&oacute;n Optimizaci&oacute;n para invitados\" class=\"wp-image-20049\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/optimizacion-para-invitados.png\/w=1105,fit=scale-down 1105w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/optimizacion-para-invitados.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/optimizacion-para-invitados.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/optimizacion-para-invitados.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/optimizacion-para-invitados.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1105px) 100vw, 1105px\" \/><\/figure><\/div><p>Cuando habilitas esta configuraci&oacute;n, el servidor no solo entregar&aacute; la p&aacute;gina en cach&eacute; predeterminada, sino que tambi&eacute;n realizar&aacute; la optimizaci&oacute;n de im&aacute;genes y p&aacute;ginas incluso si estas funciones est&aacute;n deshabilitadas.&nbsp;<\/p><p>Sin embargo, la optimizaci&oacute;n del modo de invitado puede consumir algunos de los recursos de tu sitio web de WordPress, por lo que es mejor consultar a tu proveedor de alojamiento web antes de activar esta configuraci&oacute;n.&nbsp;<\/p><p>Debajo de esto, te encontrar&aacute;s con el campo <strong>IP del servidor<\/strong> para la <a href=\"\/mx\/tutoriales\/que-es-una-direccion-ip\/\">direcci&oacute;n IP<\/a> de tu sitio. Incluir tu direcci&oacute;n IP permitir&aacute; que el crawler recupere recursos directamente de tu servidor, mejorando el rendimiento del sitio.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1105\" height=\"191\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ip-del-servidor-1.png\/w=1024,h=1024,fit=scale-down\" alt=\"Ajustes generales de LiteSpeed Cache, secci&oacute;n IP del servidor\" class=\"wp-image-20050\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ip-del-servidor-1.png\/w=1105,fit=scale-down 1105w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ip-del-servidor-1.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ip-del-servidor-1.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ip-del-servidor-1.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ip-del-servidor-1.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1105px) 100vw, 1105px\" \/><\/figure><\/div><p>P&oacute;nte en contacto con tu proveedor de alojamiento web para obtener informaci&oacute;n sobre la direcci&oacute;n IP de tu sitio web. Los usuarios de Hostinger pueden acceder al escritorio de<strong> <\/strong><a href=\"\/mx\/tutoriales\/tutorial-hpanel\/\">hPanel<\/a> e ir a <strong>Hosting -&gt; Administrar -&gt; Detalles<\/strong>.&nbsp;<\/p><p>M&aacute;s abajo, encontrar&aacute;s la configuraci&oacute;n de <strong>Avisos<\/strong>. Al habilitarla, obtendr&aacute;s la informaci&oacute;n m&aacute;s reciente sobre el desarrollo del plugin LiteSpeed Cache, incluidas las promociones y los nuevos lanzamientos. <\/p><figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1101\" height=\"114\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/avisos-1.png\/w=1024,h=1024,fit=scale-down\" alt=\"Ajustes generales de LiteSpeed Cache, secci&oacute;n Avisos\" class=\"wp-image-20051\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/avisos-1.png\/w=1101,fit=scale-down 1101w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/avisos-1.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/avisos-1.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/avisos-1.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/avisos-1.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1101px) 100vw, 1101px\" \/><\/figure><p>Aseg&uacute;rate de guardar los cambios despu&eacute;s de realizar los ajustes.<\/p><h3 class=\"wp-block-heading\" id=\"h-2-ajusta-la-configuracion-de-cache\">2. Ajusta la configuraci&oacute;n de cach&eacute;<\/h3><p>La p&aacute;gina de configuraci&oacute;n de cach&eacute; LiteSpeed &#8203;&#8203;incluye caracter&iacute;sticas que se aplican principalmente a los servidores web LiteSpeed &#8203;&#8203;o al CDN de QUIC.cloud. <\/p><p>Esta p&aacute;gina cuenta con m&uacute;ltiples configuraciones: esta secci&oacute;n cubrir&aacute; todas las funciones de almacenamiento en cach&eacute; para ayudarte a elegir el mejor enfoque.<\/p><ul class=\"wp-block-list\">\n<li><strong>Activa cach&eacute;: ON.<\/strong> Habilitar esta opci&oacute;n har&aacute; que el sistema almacene autom&aacute;ticamente tu sitio de WordPress en cach&eacute;. Aunque desactivar esta funci&oacute;n no afectar&aacute; el contenido del sitio, todos los archivos almacenados en cach&eacute; se eliminar&aacute;n. Recomendamos mantener la configuraci&oacute;n predeterminada para mejorar los tiempos de carga.&nbsp;<\/li>\n<\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"998\" height=\"104\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/activa-cache.png\/public\" alt=\"P&aacute;gina de configuraci&oacute;n de Cach&eacute; de LiteSpeed, secci&oacute;n Activa cache\" class=\"wp-image-20024\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/activa-cache.png\/w=998,fit=scale-down 998w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/activa-cache.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/activa-cache.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/activa-cache.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 998px) 100vw, 998px\" \/><\/figure><\/div><ul class=\"wp-block-list\">\n<li><strong>Cachear usuarios con sesi&oacute;n iniciada: OFF<\/strong>. Esta configuraci&oacute;n almacena autom&aacute;ticamente en cach&eacute; las p&aacute;ginas web para los usuarios que han iniciado sesi&oacute;n. Sin embargo, habilitar esta configuraci&oacute;n consumir&aacute; recursos del servidor. Es mejor mantener esta opci&oacute;n deshabilitada a menos que tengas un sitio web de membres&iacute;a.&nbsp;<\/li>\n<\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1097\" height=\"94\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-usuarios-sesion-iniciada.png\/w=1024,h=1024,fit=scale-down\" alt=\"P&aacute;gina de configuraci&oacute;n de Cach&eacute; de LiteSpeed, secci&oacute;n Cachear usuarios con sesi&oacute;n iniciada\" class=\"wp-image-20071\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-usuarios-sesion-iniciada.png\/w=1097,fit=scale-down 1097w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-usuarios-sesion-iniciada.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-usuarios-sesion-iniciada.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-usuarios-sesion-iniciada.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-usuarios-sesion-iniciada.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1097px) 100vw, 1097px\" \/><\/figure><\/div><ul class=\"wp-block-list\">\n<li><strong>Cachear comentaristas: OFF<\/strong>. El resultado de esta funci&oacute;n depende de la configuraci&oacute;n de moderaci&oacute;n de comentarios. Si se habilitan tanto la opci&oacute;n de cachear comentaristas como la  moderaci&oacute;n, los usuarios no ver&aacute;n sus comentarios inmediatamente. Por el contrario, si la funci&oacute;n de cachear comentaristas est&aacute; deshabilitada, los usuarios ver&aacute;n sus comentarios pendientes.&nbsp;<\/li>\n<\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1105\" height=\"120\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-comentaristas-1.png\/w=1024,h=1024,fit=scale-down\" alt=\"P&aacute;gina de configuraci&oacute;n de Cach&eacute; de LiteSpeed, secci&oacute;n Cachear comentaristas\" class=\"wp-image-20052\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-comentaristas-1.png\/w=1105,fit=scale-down 1105w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-comentaristas-1.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-comentaristas-1.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-comentaristas-1.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-comentaristas-1.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1105px) 100vw, 1105px\" \/><\/figure><\/div><ul class=\"wp-block-list\">\n<li><strong>Cachear API REST: ON<\/strong>. Esto te permite almacenar en cach&eacute; las solicitudes de las llamadas de la <a href=\"\/mx\/tutoriales\/guia-para-principiantes-api-rest-wordpress\/\">API REST de WordPress<\/a>. Estas llamadas generalmente las realizan aplicaciones web de terceros integradas con WordPress, incluidos temas, plugins y el <a href=\"\/mx\/tutoriales\/gutenberg-wordpress\/\">editor de bloques<\/a>.<\/li>\n<\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1028\" height=\"86\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-api-rest.png\/w=1024,h=1024,fit=scale-down\" alt=\"P&aacute;gina de configuraci&oacute;n de Cach&eacute; de LiteSpeed, secci&oacute;n Cachear API REST\" class=\"wp-image-20027\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-api-rest.png\/w=1028,fit=scale-down 1028w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-api-rest.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-api-rest.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-api-rest.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-api-rest.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1028px) 100vw, 1028px\" \/><\/figure><\/div><ul class=\"wp-block-list\">\n<li><strong>Cachear p&aacute;gina de acceso: ON.<\/strong> Esta opci&oacute;n muestra versiones en cach&eacute; de las p&aacute;ginas de inicio de sesi&oacute;n. Es mejor dejar esta opci&oacute;n habilitada, ya que har&aacute; que tu sitio de WordPress se cargue m&aacute;s r&aacute;pido cada vez que llegue un visitante.&nbsp;<\/li>\n<\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1019\" height=\"90\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-pagina-de-acceso.png\/public\" alt=\"P&aacute;gina de configuraci&oacute;n de Cach&eacute; de LiteSpeed, secci&oacute;n Cachear p&aacute;gina de acceso\" class=\"wp-image-20028\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-pagina-de-acceso.png\/w=1019,fit=scale-down 1019w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-pagina-de-acceso.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-pagina-de-acceso.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-pagina-de-acceso.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1019px) 100vw, 1019px\" \/><\/figure><\/div><ul class=\"wp-block-list\">\n<li><strong>Cachear favicon.ico: ON.<\/strong> Mantener esta funci&oacute;n habilitada ayudar&aacute; a evitar llamadas PHP innecesarias y har&aacute; que la respuesta del servidor sea m&aacute;s r&aacute;pida. De lo contrario, el sistema buscar&aacute; el archivo <strong>favicon.ico <\/strong>y forzar&aacute; la ejecuci&oacute;n del backend PHP de WordPress, lo que ralentizar&aacute; tu sitio web.&nbsp;<\/li>\n<\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1035\" height=\"104\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-favicon-ico.png\/w=1024,h=1024,fit=scale-down\" alt=\"P&aacute;gina de configuraci&oacute;n de Cach&eacute; de LiteSpeed, secci&oacute;n Cachear favicon.ico\" class=\"wp-image-20031\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-favicon-ico.png\/w=1035,fit=scale-down 1035w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-favicon-ico.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-favicon-ico.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-favicon-ico.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachear-favicon-ico.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1035px) 100vw, 1035px\" \/><\/figure><\/div><ul class=\"wp-block-list\">\n<li><strong>Cachear recursos de PHP: ON<\/strong>. Esta funci&oacute;n almacena en cach&eacute; elementos est&aacute;ticos, incluidos los archivos CSS y JS generados por temas de WordPress. Mant&eacute;n esta configuraci&oacute;n habilitada para acelerar el rendimiento y evitar scripts PHP innecesarios.&nbsp;<\/li>\n<\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1021\" height=\"110\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachaer-recursos-php.png\/public\" alt=\"P&aacute;gina de configuraci&oacute;n de Cach&eacute; de LiteSpeed, secci&oacute;n Cachear recursos PHP\" class=\"wp-image-20033\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachaer-recursos-php.png\/w=1021,fit=scale-down 1021w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachaer-recursos-php.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachaer-recursos-php.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cachaer-recursos-php.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1021px) 100vw, 1021px\" \/><\/figure><\/div><ul class=\"wp-block-list\">\n<li><strong>Cach&eacute; m&oacute;vil: ON<\/strong>. Esta opci&oacute;n te permite entregar diferentes contenidos en cach&eacute; para dispositivos m&oacute;viles y de escritorio. A menos que tengas una versi&oacute;n <a href=\"\/mx\/tutoriales\/como-configurar-amp-wordpress\/\">AMP (p&aacute;ginas m&oacute;viles aceleradas)<\/a> de tu sitio de WordPress, te recomendamos que la mantengas desactivada.&nbsp;<\/li>\n<\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1010\" height=\"104\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cache-movil.png\/public\" alt=\"P&aacute;gina de configuraci&oacute;n de Cach&eacute; de LiteSpeed, secci&oacute;n Cach&eacute; m&oacute;vil\" class=\"wp-image-20034\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cache-movil.png\/w=1010,fit=scale-down 1010w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cache-movil.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cache-movil.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cache-movil.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1010px) 100vw, 1010px\" \/><\/figure><\/div><ul class=\"wp-block-list\">\n<li><strong>Lista de User Agents m&oacute;viles. <\/strong>Esta configuraci&oacute;n solo est&aacute; disponible si activas la funci&oacute;n de cach&eacute; m&oacute;vil. Puedes agregar una lista de agentes de usuarios m&oacute;viles en un formato compatible con reglas de reescritura. Por ejemplo, se puede escribir un agente de usuario en cada l&iacute;nea.&nbsp;<\/li>\n<\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1094\" height=\"225\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/lista-user-agents-moviles-1.png\/w=1024,h=1024,fit=scale-down\" alt=\"P&aacute;gina de configuraci&oacute;n de Cach&eacute; de LiteSpeed, secci&oacute;n Lista user agents m&oacute;viles\" class=\"wp-image-20053\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/lista-user-agents-moviles-1.png\/w=1094,fit=scale-down 1094w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/lista-user-agents-moviles-1.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/lista-user-agents-moviles-1.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/lista-user-agents-moviles-1.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/lista-user-agents-moviles-1.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1094px) 100vw, 1094px\" \/><\/figure><\/div><ul class=\"wp-block-list\">\n<li><strong>URIs cacheadas privadamente<\/strong>. Contiene rutas que se almacenar&aacute;n en cach&eacute; de forma privada. Sin embargo, esta funci&oacute;n es similar a la opci&oacute;n de <strong>cachear usuarios registrados<\/strong> que tambi&eacute;n maneja URIs cacheadas privadamente. A menos que desees cachear de forma privada p&aacute;ginas espec&iacute;ficas que no est&aacute;n relacionadas con el usuario, deja este campo vac&iacute;o.&nbsp;<\/li>\n<\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1027\" height=\"173\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/URIS-cacheadas-privadamente.png\/w=1024,h=1024,fit=scale-down\" alt=\"P&aacute;gina de configuraci&oacute;n de Cach&eacute; de LiteSpeed, secci&oacute;n URIs cacheadas privadamente\" class=\"wp-image-20036\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/URIS-cacheadas-privadamente.png\/w=1027,fit=scale-down 1027w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/URIS-cacheadas-privadamente.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/URIS-cacheadas-privadamente.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/URIS-cacheadas-privadamente.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/URIS-cacheadas-privadamente.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1027px) 100vw, 1027px\" \/><\/figure><\/div><ul class=\"wp-block-list\">\n<li><strong>Forzar URLs en cach&eacute;<\/strong>. El sistema forzar&aacute; el cacheo de todas las rutas escritas en el campo proporcionado, independientemente de los ajustes de no cacheables. En general, no tendr&aacute;s que preocuparte por esta funci&oacute;n ya que no necesitas forzar el cach&eacute; para la mayor&iacute;a de tus p&aacute;ginas.&nbsp;<\/li>\n<\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"201\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/forzar-urls-en-cache.png\/w=1024,h=1024,fit=scale-down\" alt=\"P&aacute;gina de configuraci&oacute;n de Cach&eacute; de LiteSpeed, secci&oacute;n Forzar URLs en cach&eacute;\" class=\"wp-image-20037\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/forzar-urls-en-cache.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/forzar-urls-en-cache.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/forzar-urls-en-cache.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/forzar-urls-en-cache.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><ul class=\"wp-block-list\">\n<li><strong>Forzar URIs de cach&eacute; p&uacute;blica<\/strong>. Esta funci&oacute;n hace que tipos de contenido espec&iacute;ficos se almacenen en cach&eacute; como p&uacute;blicos, independientemente de su configuraci&oacute;n.&nbsp;<\/li>\n<\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1096\" height=\"240\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/forzar-uris-de-cache-publica.png\/w=1024,h=1024,fit=scale-down\" alt=\"P&aacute;gina de configuraci&oacute;n de Cach&eacute; de LiteSpeed, secci&oacute;n Forzar URIs de cach&eacute; p&uacute;blica\" class=\"wp-image-20054\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/forzar-uris-de-cache-publica.png\/w=1096,fit=scale-down 1096w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/forzar-uris-de-cache-publica.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/forzar-uris-de-cache-publica.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/forzar-uris-de-cache-publica.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/forzar-uris-de-cache-publica.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1096px) 100vw, 1096px\" \/><\/figure><\/div><ul class=\"wp-block-list\">\n<li><strong>Ignorar cadenas de consulta<\/strong>. Ignora cualquier cadena de consulta agregada en el campo y acelera el tiempo de carga del sitio web. La configuraci&oacute;n predeterminada ya enumera algunas de las cadenas generadas con m&aacute;s frecuencia. Sin embargo, siempre puedes agregar m&aacute;s cadenas de consulta si es necesario.<\/li>\n<\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1022\" height=\"166\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ignorar-cadenas-de-consulta.png\/public\" alt=\"P&aacute;gina de configuraci&oacute;n de Cach&eacute; de LiteSpeed, secci&oacute;n Ignorar cadenas de consulta\" class=\"wp-image-20038\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ignorar-cadenas-de-consulta.png\/w=1022,fit=scale-down 1022w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ignorar-cadenas-de-consulta.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ignorar-cadenas-de-consulta.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ignorar-cadenas-de-consulta.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1022px) 100vw, 1022px\" \/><\/figure><\/div><p>En general, el plugin LiteSpeed Cache aplica configuraciones predeterminadas adecuadas para la mayor&iacute;a de los sitios web de WordPress. Dicho esto, te recomendamos ajustarlas de acuerdo con tus necesidades.<\/p><p>Adem&aacute;s de la p&aacute;gina de configuraci&oacute;n de cach&eacute; de LiteSpeed, vamos a repasar brevemente las otras secciones disponibles junto con sus funcionalidades principales:<\/p><ul class=\"wp-block-list\">\n<li><strong>TTL (Tiempo de vida)<\/strong>: esta funci&oacute;n controla cu&aacute;nto tiempo se almacenan tipos de contenido espec&iacute;ficos en la memoria cach&eacute;. La configuraci&oacute;n predeterminada deber&iacute;a funcionar bien, pero puedes reducir o aumentar los n&uacute;meros seg&uacute;n sea necesario.<\/li>\n\n\n\n<li><strong>Vaciar<\/strong>: proporciona todas las configuraciones para eliminar ciertos tipos de contenido en cach&eacute;. Recomendamos habilitar el vaciado en todas las actualizaciones para permitir que el sistema <a href=\"\/mx\/tutoriales\/cache-wordpress\/\">borre la cach&eacute; obsoleta de WordPress<\/a> cada vez que haya una actualizaci&oacute;n disponible. Si tienes suficientes recursos, habilita la opci&oacute;n Servir contenido rancio para un mejor rendimiento.<\/li>\n\n\n\n<li><strong>Excluir<\/strong>: esta opci&oacute;n te ayuda a especificar qu&eacute; tipos de contenido deseas excluir del cach&eacute;. Hay varios campos para completar, incluidos los URIs del sitio y las cadenas de consulta. Completa las cadenas en campo provisto y el sistema evitar&aacute; que se almacenen en cach&eacute;.<\/li>\n\n\n\n<li><strong>ESI (Edge Side Includes)<\/strong>: esta opci&oacute;n separa partes espec&iacute;ficas de la p&aacute;gina de un sitio web en fragmentos. Puedes elegir almacenar estas partes en un cach&eacute; p&uacute;blico o privado. Una vez habilitada, el sistema volver&aacute; a ensamblar las p&aacute;ginas antes de enviarlas al navegador.<\/li>\n\n\n\n<li><strong>Objeto<\/strong>: reduce la carga de la base de datos para aplicaciones web din&aacute;micas. El sistema de <a href=\"\/mx\/tutoriales\/que-es-la-cache-de-objetos\/\">cach&eacute; de objetos<\/a> de LiteSpeed almacena los resultados de las consultas a la base de datos y recupera la informaci&oacute;n de la cach&eacute; en lugar de recargarla.<\/li>\n<\/ul><p><div class=\"protip\">\n                    <p class=\"title\">Consejo Profesional<\/p>\n                    <p>Hostinger ofrece la funci&oacute;n de cach&eacute; de objetos en planes seleccionados. Puedes encontrarla en la secci&oacute;n <b>N&uacute;cleo<\/b> del panel de control de hPanel. Despu&eacute;s de habilitar <b>LiteSpeed<\/b>, haz clic en el bot&oacute;n de alternancia junto a <b>Object cache<\/b> para habilitar la configuraci&oacute;n de Memcached.<\/p>\n                <\/div>\n\n\n\n<\/p><ul class=\"wp-block-list\">\n<li><strong>Navegador<\/strong>: habilitar el almacenamiento en cach&eacute; del navegador permite que el sistema almacene autom&aacute;ticamente contenido din&aacute;mico de tu sitio de WordPress en el cach&eacute; del navegador de los usuarios. El servidor procesar&aacute; menos solicitudes del navegador y mostrar&aacute; las p&aacute;ginas de manera m&aacute;s eficiente.<\/li>\n\n\n\n<li><strong>Avanzado<\/strong>: la configuraci&oacute;n de esta pesta&ntilde;a est&aacute; dise&ntilde;ada para usuarios avanzados. Aqu&iacute; puedes habilitar la funcionalidad HTTP\/HTTPS para evitar conflictos con las cookies de inicio de sesi&oacute;n. Adem&aacute;s, encontrar&aacute;s una funci&oacute;n de clic instant&aacute;neo que puede cargar una p&aacute;gina web en segundo plano tan pronto como tus visitantes pasen el cursor sobre ella.<\/li>\n<\/ul><h3 class=\"wp-block-heading\" id=\"h-3-configura-las-opciones-de-optimizacion-de-pagina-e-imagenes\">3. Configura las opciones de optimizaci&oacute;n de p&aacute;gina e im&aacute;genes<\/h3><p>El plugin LiteSpeed &#8203;&#8203;Cache incluye herramientas de optimizaci&oacute;n para contenido din&aacute;mico en sitios de WordPress, incluidas im&aacute;genes y p&aacute;ginas web. Es importante tomarse el tiempo para configurar estos ajustes, ya que pueden afectar el SEO de tu sitio web.<\/p><p>Esta secci&oacute;n te guiar&aacute; a trav&eacute;s de las funciones y configuraciones de cada pesta&ntilde;a de optimizaci&oacute;n.<\/p><p><strong>Optimizaci&oacute;n de im&aacute;genes<\/strong><\/p><p>Cada vez que los visitantes acceden a tu sitio de WordPress, el navegador solicita recursos y descarga las im&aacute;genes antes de mostrarlas. Por lo tanto, el navegador tardar&aacute; m&aacute;s en cargar, cambiar el tama&ntilde;o y mostrar im&aacute;genes no optimizadas.<\/p><p>Afortunadamente, el plugin LiteSpeed &#8203;&#8203;Cache puede optimizar tus im&aacute;genes individualmente o en masa al cambiarles el tama&ntilde;o.<\/p><p class=\"warning\"><strong>&iexcl;Advertencia!<\/strong> No utilices otro plugin de optimizaci&oacute;n mientras utilizas LiteSpeed &#8203;&#8203;Cache, ya que esto podr&iacute;a desencadenar errores del sistema y de procesamiento.<\/p><p>Al ingresar a la p&aacute;gina de optimizaci&oacute;n de im&aacute;genes, ver&aacute;s la pesta&ntilde;a <strong>Resumen de la optimizaci&oacute;n de im&aacute;genes<\/strong>. Esta pesta&ntilde;a monitorea m&uacute;ltiples m&eacute;tricas, como la reducci&oacute;n de tama&ntilde;o y la cantidad total de im&aacute;genes extra&iacute;das de tu sitio web.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1164\" height=\"382\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/resumen-de-optimizacion-de-imagenes-1.png\/w=1024,h=1024,fit=scale-down\" alt=\"P&aacute;gina de optimizaci&oacute;n de im&aacute;genes\" class=\"wp-image-20055\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/resumen-de-optimizacion-de-imagenes-1.png\/w=1164,fit=scale-down 1164w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/resumen-de-optimizacion-de-imagenes-1.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/resumen-de-optimizacion-de-imagenes-1.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/resumen-de-optimizacion-de-imagenes-1.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/resumen-de-optimizacion-de-imagenes-1.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1164px) 100vw, 1164px\" \/><\/figure><\/div><p>Adem&aacute;s, aqu&iacute; puedes encontrar algunas otras funciones, como:<\/p><ul class=\"wp-block-list\">\n<li><strong>Recopilar datos de las im&aacute;genes<\/strong>: esta opci&oacute;n estar&aacute; disponible despu&eacute;s de cargar nuevas im&aacute;genes. Una vez hecho esto, aparecer&aacute; el bot&oacute;n <strong>Enviar solicitud de optimizaci&oacute;n<\/strong>, lo que te permitir&aacute; enviar las im&aacute;genes al servidor en la nube de LiteSpeed.<\/li>\n<\/ul><p><div><p class=\"important\"><strong>&iexcl;Importante!<\/strong> Esta funcionalidad solo est&aacute; disponible despu&eacute;s de haber agregado tu clave de dominio y activado el CDN de QUIC.Cloud.<\/p><\/div><\/p><ul class=\"wp-block-list\">\n<li><strong>Descargar im&aacute;genes<\/strong>: esta opci&oacute;n extrae tus im&aacute;genes optimizadas desde la nube a tu sitio de WordPress.<\/li>\n\n\n\n<li><strong>Limpiar datos no finalizados<\/strong>: esta funci&oacute;n borra los procesos inconclusos y los vuelve a iniciar cada vez que el proceso de optimizaci&oacute;n se atasca.<\/li>\n\n\n\n<li><strong>Calcular espacio en disco de las copias de seguridad<\/strong>: esta opci&oacute;n calcula el espacio en disco disponible para los archivos de copia de seguridad.<\/li>\n\n\n\n<li><strong>Eliminar copias de seguridad de las im&aacute;genes originales<\/strong>: elimina las copias de seguridad de las im&aacute;genes originales para liberar espacio en el disco. Recomendamos descargar las copias de seguridad a tu ordenador local antes de optar por esta funci&oacute;n. No podr&aacute;s revertir la configuraci&oacute;n de optimizaci&oacute;n despu&eacute;s de eliminar todas las copias de seguridad.<\/li>\n\n\n\n<li><strong>Reexaminar nuevas miniaturas<\/strong>: escanea im&aacute;genes reci&eacute;n agregadas en tu sitio web y env&iacute;a solicitudes de optimizaci&oacute;n al sistema.<\/li>\n\n\n\n<li><strong>Usar archivos originales \/ Usar archivos optimizados<\/strong>: brinda opciones para cambiar entre las im&aacute;genes no optimizadas y optimizadas en tu sitio web.<\/li>\n\n\n\n<li><strong>Destruir todos los datos de optimizaci&oacute;n<\/strong>: elimina todos los datos y revierte todas las configuraciones a los valores originales.<\/li>\n<\/ul><p>Ahora, pasemos a la siguiente pesta&ntilde;a y apliquemos los mejores ajustes de optimizaci&oacute;n para tu sitio web de WordPress. Simplemente haz clic en <strong>Ajustes de optimizaci&oacute;n de im&aacute;genes<\/strong> y ver&aacute;s m&uacute;ltiples funcionalidades para modificar:<\/p><ul class=\"wp-block-list\">\n<li><strong>Cron de petici&oacute;n autom&aacute;tica<\/strong>: <strong>ON<\/strong>. Esta funci&oacute;n env&iacute;a autom&aacute;ticamente solicitudes de optimizaci&oacute;n a trav&eacute;s un <a href=\"\/mx\/tutoriales\/como-configurar-wordpress-cron-job\/\">trabajo cron de WordPress<\/a> cada vez que se cargan nuevas im&aacute;genes.<\/li>\n\n\n\n<li><strong>Cron de obtenci&oacute;n autom&aacute;tica: ON<\/strong>. Funciona junto con la opci&oacute;n anterior. Por lo tanto, debes habilitar ambas funciones. De lo contrario, deber&aacute;s enviar todas las im&aacute;genes cargadas recientemente mediante el bot&oacute;n <strong>Descargar im&aacute;genes<\/strong>.<\/li>\n\n\n\n<li><strong>Optimizar im&aacute;genes originales<\/strong>: <strong>ON<\/strong>. Siempre debes mantener esta funci&oacute;n activada, ya que esta optimiza las im&aacute;genes .png y .jpg y genera los archivos de respaldo. Solo desact&iacute;vala si no deseas optimizar las im&aacute;genes.<\/li>\n\n\n\n<li><strong>Eliminar copias de seguridad del original: OFF<\/strong>. Ten en cuenta que esta funci&oacute;n es irreversible. Habilitarla borrar&aacute; todas las copias de seguridad, lo que te impedir&aacute; revertir cualquier configuraci&oacute;n de optimizaci&oacute;n.<\/li>\n\n\n\n<li><strong>Optimizar sin p&eacute;rdidas: ON<\/strong>. Esto optimizar&aacute; tus im&aacute;genes utilizando la compresi&oacute;n sin p&eacute;rdidas.<\/li>\n\n\n\n<li><strong>Conservar datos EXIF\/XMP: OFF<\/strong>. Este ajuste est&aacute; activado por defecto. Sin embargo, conservar los datos EXIF\/XMP podr&iacute;a aumentar el tama&ntilde;o de las im&aacute;genes optimizadas. Por lo tanto, es mejor desactivar esta funci&oacute;n.<\/li>\n\n\n\n<li><strong>Crear versiones de WebP: ON<\/strong>. Activar esta funci&oacute;n generar&aacute; <a href=\"\/mx\/tutoriales\/que-es-webp\/\">archivos .webp<\/a> de tus im&aacute;genes. Esto da como resultado una mayor reducci&oacute;n de tama&ntilde;o, de hasta un 30%, acelerando los tiempos de carga del sitio web.<\/li>\n\n\n\n<li><strong>Reemplazo de imagen WebP: ON<\/strong>. Si has habilitado la configuraci&oacute;n anterior, tambi&eacute;n debes activar esta opci&oacute;n, ya que esta reemplaza las im&aacute;genes <strong>.jpg<\/strong> y <strong>.png<\/strong> con archivos <strong>.webp<\/strong>.<\/li>\n\n\n\n<li><strong>Atributo WebP a reemplazar<\/strong>: controla qu&eacute; <a href=\"\/mx\/tutoriales\/formatos-de-imagen\/\">formatos de imagen<\/a> reemplazar con <strong>.webp<\/strong>. Simplemente ingresa un atributo de imagen por l&iacute;nea dentro del cuadro.<\/li>\n\n\n\n<li><strong>WebP para src estra:<\/strong> <strong>ON<\/strong>. Funciona para entregar c&oacute;digo personalizado con elementos <strong>srcset <\/strong>como versiones <strong>.webp<\/strong>.<\/li>\n\n\n\n<li><strong>Control de calidad de imagen de WordPress<\/strong>: la calidad de imagen predeterminada deber&iacute;a funcionar bien. Puedes modificar la configuraci&oacute;n seg&uacute;n lo necesites, pero recuerda mantener el valor por debajo de 100.<\/li>\n<\/ul><p><strong>Optimizaci&oacute;n de p&aacute;gina<\/strong><\/p><p>Una vez que hayas establecido los ajustes de optimizaci&oacute;n de imagen de LiteSpeed Cache, el siguiente paso es ajustar las funciones de optimizaci&oacute;n de p&aacute;gina. Si no lo haces, es probable que los tiempos de carga sean m&aacute;s lentos y los puntajes del sitio sean peores.<\/p><p>Afortunadamente, cuando se trata de la optimizaci&oacute;n de p&aacute;ginas, el plugin LiteSpeed &#8203;&#8203;Cache ofrece m&uacute;ltiples opciones para mejorar el rendimiento de tu sitio de WordPress. Esta p&aacute;gina contiene las configuraciones m&aacute;s importantes para optimizar los archivos HTML, CSS y JS.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1136\" height=\"581\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ajustes-css.png\/w=1024,h=1024,fit=scale-down\" alt=\"P&aacute;gina de ajustes de CSS\" class=\"wp-image-20056\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ajustes-css.png\/w=1136,fit=scale-down 1136w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ajustes-css.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ajustes-css.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ajustes-css.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ajustes-css.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1136px) 100vw, 1136px\" \/><\/figure><\/div><p>La secci&oacute;n de optimizaci&oacute;n de la p&aacute;gina tiene varias secciones; revisaremos cada una junto con sus funcionalidades.<\/p><p><strong>Ajustes de CSS<\/strong><\/p><ul class=\"wp-block-list\">\n<li><strong>Minificar CSS: ON<\/strong>. Esta configuraci&oacute;n elimina elementos innecesarios, como espacios en blanco adicionales y saltos de l&iacute;nea de los archivos CSS.<\/li>\n\n\n\n<li><strong>Combinar CSS: OFF. <\/strong>Habilitar esta opci&oacute;n har&aacute; que el sistema combine todos los archivos CSS<strong> <\/strong>individuales en un solo archivo CSS. Sin embargo, recomendamos desactivarla a menos que tengas espacio adicional, ya que esta funci&oacute;n puede consumir recursos.<\/li>\n\n\n\n<li><strong>Generar UCSS: OFF.<\/strong> Esta configuraci&oacute;n funciona de la mano con la funci&oacute;n de <strong>combinar CSS<\/strong>. Por lo tanto, si decides deshabilitar la funci&oacute;n anterior, tambi&eacute;n debes mantener esta configuraci&oacute;n desactivada.<\/li>\n\n\n\n<li><strong>UCSS integrado: OFF.<\/strong> Reduce la carga adicional de archivos CSS al almacenar el UCSS integrado con el HTML. Este ajuste tambi&eacute;n funciona en colaboraci&oacute;n con <strong>Combinar CSS<\/strong>, as&iacute; que habil&iacute;tala solo si has activado la configuraci&oacute;n anterior. Adem&aacute;s, habilitar esto omitir&aacute; la opci&oacute;n <strong>Cargar CSS as&iacute;ncronamente.<\/strong><\/li>\n\n\n\n<li><strong>Combinaci&oacute;n CSS externo e integrado: OFF<\/strong>. Esta opci&oacute;n ayuda a combinar archivos CSS externos con los que se encuentran con los elementos HTML integrados. Para evitar errores, habilita esta opci&oacute;n junto con la de <strong>Combinar CSS<\/strong>.<\/li>\n\n\n\n<li><strong>Cargar CSS as&iacute;ncronamente: OFF.<\/strong> Activar esta opci&oacute;n permite que tus elementos CSS y HTML se carguen al mismo tiempo. Sin embargo, es posible que se carguen sin formatear. Esto puede resultar en un cambio de dise&ntilde;o o un destello de contenido sin estilo (FOUC).<\/li>\n\n\n\n<li><strong>CCSS por URL: OFF<\/strong>. Desactivar esta funci&oacute;n generar&aacute; CSS cr&iacute;tico para cada tipo de entrada en lugar de para p&aacute;ginas individuales. Esto ahorrar&aacute; la cuota CCSS y el espacio en disco.<\/li>\n\n\n\n<li><strong>Biblioteca de CSS integrado as&iacute;ncrono: ON.<\/strong> Esta opci&oacute;n evita el bloqueo de procesamiento al incorporar la biblioteca CSS as&iacute;ncrona.<\/li>\n\n\n\n<li><strong>Optimizaci&oacute;n de visualizaci&oacute;n de fuentes<\/strong>: mant&eacute;n el valor predeterminado, ya que la modificaci&oacute;n de esta configuraci&oacute;n puede causar problemas de FOUC.<\/li>\n<\/ul><p><strong>Ajustes de JS<\/strong><\/p><ul class=\"wp-block-list\">\n<li><strong>Minificar JS: ON.<\/strong> Esta opci&oacute;n elimina scripts innecesarios para la optimizaci&oacute;n de JS.<\/li>\n\n\n\n<li><strong>Combinar JS: OFF. <\/strong>Esto compila todos los archivos JS individuales en un solo archivo.<\/li>\n\n\n\n<li><strong>Combinaci&oacute;n de JS externo e integrado: OFF. <\/strong>Esta funci&oacute;n opera de manera similar a las opciones de combinaci&oacute;n de CSS externo e integrado. Habilita esto solo si tambi&eacute;n has activado la funci&oacute;n anterior.<\/li>\n\n\n\n<li><strong>Deferir carga de JS: depende. <\/strong>Antes de modificar esta opci&oacute;n, realiza algunas pruebas, ya que los resultados pueden variar. Si eliges <strong>Diferido<\/strong>, el sistema cargar&aacute; JS justo despu&eacute;s del HTML. Mientras tanto, con la opci&oacute;n <strong>Retrasado<\/strong>, esto solo se iniciar&aacute; si el sistema detecta actividad por parte del usuario.<\/li>\n<\/ul><p><strong>Ajustes HTML&nbsp;<\/strong><\/p><ul class=\"wp-block-list\">\n<li><a href=\"\/mx\/tutoriales\/minificar-html\/\">Minificar HTML<\/a><strong>: ON<\/strong>. Borra caracteres innecesarios dentro del c&oacute;digo HTML.<\/li>\n\n\n\n<li><strong>Prefetch DNS:<\/strong> lleva a cabo la resoluci&oacute;n de DNS de los dominios enumerados antes de que tus visitantes los soliciten, lo que reduce el tiempo de carga de tu p&aacute;gina. Esto es &uacute;til para cargar enlaces externos, como AdSense o Facebook.<\/li>\n\n\n\n<li><strong>Control del prefetch DNS: ON<\/strong>. Si agregas enlaces en la configuraci&oacute;n anterior, esta funci&oacute;n precargar&aacute; autom&aacute;ticamente el DNS enumerado junto con todas las URL en tus publicaciones y p&aacute;ginas, incluido CSS, JavaScript e im&aacute;genes.<\/li>\n\n\n\n<li><strong>Selectores HTML de carga diferida<\/strong>: especifica la clase o ID de los elementos a los que quieres aplicar la carga diferida agregando uno por l&iacute;nea en el campo provisto.<\/li>\n\n\n\n<li><strong>Eliminar query strings: OFF<\/strong>. Esta opci&oacute;n por lo general no afecta directamente el rendimiento de tu sitio web, por lo que mantenerla desactivada no deber&iacute;a causar problemas.<\/li>\n\n\n\n<li><strong>Cargar Google Fonts as&iacute;ncronamente: OFF<\/strong>. Esta funci&oacute;n carga Google Fonts de forma as&iacute;ncrona mientras deja intactos otros elementos CSS. Sin embargo, recomendamos deshabilitar esta opci&oacute;n, ya que la mayor&iacute;a de las fuentes de Google ya est&aacute;n almacenadas en cach&eacute; en los navegadores de tus visitantes.<\/li>\n\n\n\n<li><strong>Eliminar Google Fonts: ON<\/strong>. Habilita esta configuraci&oacute;n solo si almacenas fuentes localmente y no deseas que se carguen fuentes de terceros en tu sitio de WordPress.<\/li>\n\n\n\n<li><strong>Eliminar emojis de WordPress: ON<\/strong>. La activaci&oacute;n de esta funci&oacute;n evitar&aacute; que el sistema cargue los emoji de WordPress.org y, en su lugar, cargue los predeterminados.<\/li>\n\n\n\n<li><strong>Eliminar la etiqueta Noscript: OFF<\/strong>. Mantener esta opci&oacute;n activada ayuda a garantizar la compatibilidad con todos los navegadores, incluidas las versiones anteriores.<\/li>\n<\/ul><p><strong>Ajustes de medios<\/strong><\/p><ul class=\"wp-block-list\">\n<li><strong>Retrasar la carga de im&aacute;genes: ON<\/strong>. Esta opci&oacute;n permite que el sistema cargue im&aacute;genes de forma diferida en tu sitio web. Aunque hacer esto puede acelerar el tiempo de carga, podr&iacute;a afectar la experiencia del usuario.<\/li>\n\n\n\n<li><strong>Marcador de posici&oacute;n de imagen b&aacute;sica<\/strong>: cuando habilites la carga diferida, se mostrar&aacute; un marcador de posici&oacute;n de imagen de color gris. Sin embargo, tambi&eacute;n puedes personalizarlo definiendo la base64 de una imagen y agreg&aacute;ndola al campo. Utiliza una <a href=\"https:\/\/elmah.io\/tools\/base64-image-encoder\/\" target=\"_blank\" rel=\"noreferrer noopener\">herramienta en l&iacute;nea<\/a> para averiguar la base64 de una imagen.<\/li>\n\n\n\n<li><strong>Marcador de posici&oacute;n adaptable: ON<\/strong>. Esta opci&oacute;n permite que el marcador de posici&oacute;n de tu imagen se ajuste a las dimensiones de la imagen, lo que reduce la reorganizaci&oacute;n del dise&ntilde;o.<\/li>\n\n\n\n<li><strong>Marcador de posici&oacute;n SVG adaptable<\/strong>: especifica un archivo SVG para utilizar como tu imagen de marcador de posici&oacute;n. El sistema lo convertir&aacute; autom&aacute;ticamente en un marcador de posici&oacute;n base64.<\/li>\n\n\n\n<li><strong>Color del marcador de posici&oacute;n adaptable<\/strong>: el valor predeterminado funciona bien. Alternativamente, personaliza el color moviendo el selector de color.<\/li>\n\n\n\n<li><strong>Generador de LQIP&nbsp;en la nube: OFF<\/strong>. Habilitar esto generar&aacute; un marcador de posici&oacute;n de imagen de baja calidad que muestra una versi&oacute;n borrosa de tu imagen a medida que se carga. Mant&eacute;n esta configuraci&oacute;n desactivada si prefieres utilizar un color uniforme como marcador de posici&oacute;n.<\/li>\n\n\n\n<li><strong>Calidad de LQIP: <\/strong>define la calidad de tu LQIP. El valor oscila entre 1 y 20, y cuanto mayor sea el valor, mayor ser&aacute; la resoluci&oacute;n. Sin embargo, establecerla en un valor mayor podr&iacute;a aumentar los tiempos de carga.<\/li>\n\n\n\n<li><strong>Dimensiones m&iacute;nimas de LQIP<\/strong>: el LQIP solo aparecer&aacute; en im&aacute;genes con las mismas dimensiones que las especificadas en la configuraci&oacute;n. No se cargar&aacute; en im&aacute;genes que tengan alturas y anchos m&aacute;s peque&ntilde;os.<\/li>\n\n\n\n<li><strong>Generar LQIP en segundo plano: ON<\/strong>. Activar esto permite que el sistema cargue el LQIP en segundo plano a trav&eacute;s de una cola basada en cron. Desactivar esto podr&iacute;a aumentar los tiempos de carga.<\/li>\n\n\n\n<li><strong>Retrasar la carga de iframes: ON<\/strong>. Esta opci&oacute;n funciona de manera similar a la carga diferida de im&aacute;genes. La misma ayuda a la carga diferida de cuadros, como mapas y videos.<\/li>\n\n\n\n<li><strong>A&ntilde;adir tama&ntilde;os que faltan: ON<\/strong>. Establece un ancho y una altura definidos para tus im&aacute;genes y ayuda al plugin LiteSpeed &#8203;&#8203;Cache a agregar autom&aacute;ticamente las dimensiones de la imagen que faltan. Esta configuraci&oacute;n s&oacute;lo funciona si la carga diferida de im&aacute;genes est&aacute; activada.<\/li>\n\n\n\n<li><strong>Biblioteca integrada de im&aacute;genes de carga diferida: ON<\/strong>. Activar esto ayuda a mejorar la puntuaci&oacute;n de tu p&aacute;gina.<\/li>\n<\/ul><p><strong>Exclusiones de medios<\/strong><\/p><p>Esta configuraci&oacute;n excluir&aacute; ciertas im&aacute;genes de la carga diferida. La exclusi&oacute;n de im&aacute;genes en la mitad superior de la p&aacute;gina, como logotipos e im&aacute;genes de fondo, puede mejorar la experiencia del usuario. Esto se debe a que querr&aacute;s que esos elementos se carguen antes que el resto de la p&aacute;gina.<\/p><p>Para excluir los medios de la carga diferida, simplemente completa la informaci&oacute;n en el campo proporcionado. Por ejemplo, excluye las im&aacute;genes por su clase y el nombre de la clase principal.<\/p><p><strong>Localizaci&oacute;n<\/strong><\/p><ul class=\"wp-block-list\">\n<li><strong>Cach&eacute; de Gravatar: ON.<\/strong> Esto permite que el sistema almacene gravatares localmente. Esta opci&oacute;n funciona mejor para los sitios web de WordPress que tienen muchos comentarios con gravatares.<\/li>\n\n\n\n<li><strong>Cron de la cach&eacute; de Gravatar: ON<\/strong>. Si has habilitado la opci&oacute;n anterior, tambi&eacute;n debes habilitar esta para actualizar el cach&eacute; de gravatar a trav&eacute;s de un trabajo cron.<\/li>\n\n\n\n<li><strong>TTL de la cach&eacute; de Gravatar<\/strong>: esta opci&oacute;n define cu&aacute;nto tiempo se almacenan en cach&eacute; los gravatares. El valor predeterminado deber&iacute;a funcionar bien. Sin embargo, puedes personalizar este valor siempre que sea superior a 3600 segundos.<\/li>\n<\/ul><p><strong>Ajustes<\/strong><\/p><p>Todas las configuraciones en esta secci&oacute;n te permiten excluir elementos espec&iacute;ficos, como CSS, JS y URL,  para evitar que sean minificados o combinados.<\/p><p>Por lo general, no tienes que modificar tanto esta configuraci&oacute;n a menos que encuentres un archivo inusual en tu c&oacute;digo fuente despu&eacute;s de minificar o combinar CSS\/JS. En tales casos, puedes enumerar los archivos dentro de los campos proporcionados.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1148\" height=\"578\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/configuracion-de-ajustes.png\/w=1024,h=1024,fit=scale-down\" alt=\"P&aacute;gina de configuraci&oacute;n de ajustes\" class=\"wp-image-20057\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/configuracion-de-ajustes.png\/w=1148,fit=scale-down 1148w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/configuracion-de-ajustes.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/configuracion-de-ajustes.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/configuracion-de-ajustes.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/configuracion-de-ajustes.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1148px) 100vw, 1148px\" \/><\/figure><\/div><p>Una vez que hayas terminado de configurar los ajustes, aseg&uacute;rate de hacer clic en <strong>Guardar cambios<\/strong>.<\/p><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"\/mx\/hosting-wordpress\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/06\/ES-New-WP_in-text-banner.png\/public\" alt=\"\" class=\"wp-image-40615\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/06\/ES-New-WP_in-text-banner.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/06\/ES-New-WP_in-text-banner.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/06\/ES-New-WP_in-text-banner.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/06\/ES-New-WP_in-text-banner.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div><h3 class=\"wp-block-heading\" id=\"h-4-configura-la-cdn-de-quic-cloud-opcional\">4. Configura la CDN de QUIC.cloud (opcional)<\/h3><p>QUIC.cloud es una red de entrega de contenido de LiteSpeed &#8203;&#8203;Technologies que ofrece almacenamiento en cach&eacute; din&aacute;mico. Esta CDN utiliza servidores en todo el mundo para almacenar en cach&eacute; el contenido del sitio web. <\/p><p>Cada vez que un visitante realiza una solicitud, el servidor obtendr&aacute; los recursos del servidor m&aacute;s cercano.<\/p><p>Vincular la CDN de QUIC.cloud con las funciones de cach&eacute; de LiteSpeed &#8203;&#8203;Cache puede mejorar en gran medida la velocidad de tu p&aacute;gina. Esta secci&oacute;n explicar&aacute; los pasos para activar esta red de entrega de contenido.<\/p><p>Para hacerlo, comienza configurando <a href=\"\/mx\/tutoriales\/como-configurar-cloudflare-en-wordpress\/\">Cloudflare para WordPress<\/a>. Hacer esto garantiza que todo el contenido de tu sitio web se almacene en cach&eacute; de manera &oacute;ptima: la CDN de QUIC.cloud almacenar&aacute; en cach&eacute; todas las p&aacute;ginas din&aacute;micas, mientras que la CDN de Cloudflare manejar&aacute; el contenido est&aacute;tico.<\/p><p>Una vez que hayas configurado Cloudflare en tu servidor, el siguiente paso es obtener tu clave de dominio. Dir&iacute;gete a la p&aacute;gina <strong>Ajustes generales <\/strong>y haz clic en el bot&oacute;n <strong>Solicitar clave de dominio<\/strong>.<\/p><div class=\"wp-block-image is-resized\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1076\" height=\"64\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/clave-de-dominio-1.png\/w=1024,h=1024,fit=scale-down\" alt=\"P&aacute;gina ajustes generales, secci&oacute;n Clave de dominio\" class=\"wp-image-20046\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/clave-de-dominio-1.png\/w=1076,fit=scale-down 1076w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/clave-de-dominio-1.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/clave-de-dominio-1.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/clave-de-dominio-1.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/clave-de-dominio-1.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1076px) 100vw, 1076px\" \/><\/figure><\/div><p>Luego, espera a que el sistema procese tu solicitud.<\/p><div class=\"wp-block-image is-resized\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1103\" height=\"178\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/solicitud-clave-dominio.png\/w=1024,h=1024,fit=scale-down\" alt=\"Env&iacute;o de la Solicitud de clave de dominio\" class=\"wp-image-20058\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/solicitud-clave-dominio.png\/w=1103,fit=scale-down 1103w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/solicitud-clave-dominio.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/solicitud-clave-dominio.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/solicitud-clave-dominio.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/solicitud-clave-dominio.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1103px) 100vw, 1103px\" \/><\/figure><\/div><p>Actualiza la p&aacute;gina de administraci&oacute;n de WordPress. Una vez que se complete el proceso, el sistema completar&aacute; autom&aacute;ticamente la clave de dominio. A continuaci&oacute;n, haz clic en el bot&oacute;n <strong>Enlace a QUIC.cloud<\/strong>.<\/p><div class=\"wp-block-image is-resized\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1104\" height=\"82\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/enlace-quic.cloud_.png\/w=1024,h=1024,fit=scale-down\" alt=\"Enlace a Quic.cloud luego de la obtenci&oacute;n de la clave de dominio\" class=\"wp-image-20059\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/enlace-quic.cloud_.png\/w=1104,fit=scale-down 1104w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/enlace-quic.cloud_.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/enlace-quic.cloud_.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/enlace-quic.cloud_.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/enlace-quic.cloud_.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1104px) 100vw, 1104px\" \/><\/figure><\/div><p>Esto te llevar&aacute; a la p&aacute;gina de registro. Contin&uacute;a completando toda la informaci&oacute;n.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1319\" height=\"590\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/quic-cloud.png\/w=1024,h=1024,fit=scale-down\" alt=\"P&aacute;gina de registro de Quic.cloud\" class=\"wp-image-20060\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/quic-cloud.png\/w=1319,fit=scale-down 1319w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/quic-cloud.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/quic-cloud.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/quic-cloud.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/quic-cloud.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1319px) 100vw, 1319px\" \/><\/figure><\/div><p>Si a&uacute;n no tienes una cuenta de QUIC.cloud, reg&iacute;strate para obtener una. Una vez hecho esto, el sistema enviar&aacute; un correo electr&oacute;nico de validaci&oacute;n a la direcci&oacute;n registrada. Abre tu correo electr&oacute;nico y haz clic en el enlace adjunto.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"693\" height=\"299\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/activacion-exitosa.png\/public\" alt=\"Mensaje de activaci&oacute;n exitosa de Quic.cloud\" class=\"wp-image-20061\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/activacion-exitosa.png\/w=693,fit=scale-down 693w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/activacion-exitosa.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/activacion-exitosa.png\/w=150,fit=scale-down 150w\" sizes=\"(max-width: 693px) 100vw, 693px\" \/><\/figure><\/div><p>Si ves el mensaje anterior, has vinculado con &eacute;xito tu sitio web de WordPress con la CDN de QUIC.cloud. Ahora, haz clic en el bot&oacute;n <strong>Mi escritorio <\/strong>para volver.<\/p><p>Aunque hayas completado el proceso de registro, a&uacute;n necesitas configurar correctamente tu ajuste de DNS. Para hacerlo, navega a la secci&oacute;n <strong>CDN<\/strong> y busca la opci&oacute;n<strong> QUIC.cloud<\/strong>.<\/p><div class=\"wp-block-image is-resized\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1066\" height=\"94\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cdn-quic-cloud.png\/w=1024,h=1024,fit=scale-down\" alt=\"P&aacute;gina CDN de LiteSpees Cache, secci&oacute;n CDN de QUIC.cloud\" class=\"wp-image-20062\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cdn-quic-cloud.png\/w=1066,fit=scale-down 1066w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cdn-quic-cloud.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cdn-quic-cloud.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cdn-quic-cloud.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/cdn-quic-cloud.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1066px) 100vw, 1066px\" \/><\/figure><\/div><p>Cambia el bot&oacute;n a <strong>ON <\/strong>para habilitar la funcionalidad de la API de la CDN de QUIC.cloud.<\/p><p>A continuaci&oacute;n, configura QUIC.cloud con los detalles de Cloudflare. Antes de hacerlo, accede a tu <a href=\"https:\/\/dash.cloudflare.com\/login\" target=\"_blank\" rel=\"noreferrer noopener\">panel de control de Cloudflare<\/a> para obtener la clave de API global.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"955\" height=\"616\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/api-token-templates.png\/public\" alt=\"Panel de control de Cloudflare\" class=\"wp-image-20083\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/api-token-templates.png\/w=955,fit=scale-down 955w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/api-token-templates.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/api-token-templates.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/api-token-templates.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 955px) 100vw, 955px\" \/><\/figure><\/div><p>Ahora que tienes la informaci&oacute;n, simplemente completa los campos correspondientes.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1082\" height=\"414\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/api-cloudflare.png\/w=1024,h=1024,fit=scale-down\" alt=\"P&aacute;gina CDN de LiteSpees Cache, secci&oacute;n API de Cloudflare\" class=\"wp-image-20063\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/api-cloudflare.png\/w=1082,fit=scale-down 1082w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/api-cloudflare.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/api-cloudflare.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/api-cloudflare.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/api-cloudflare.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1082px) 100vw, 1082px\" \/><\/figure><\/div><p>Una vez hecho esto, haz clic en <strong>Guardar cambios<\/strong>.<\/p><p><div class=\"protip\">\n                    <p class=\"title\">Consejo profesional<\/p>\n                    <p>Si Cloudflare est&aacute; conectado al plugin LS Cache, puedes utilizar el bot&oacute;n \"Vaciar cach&eacute;\" en hPanel para vaciar la cach&eacute; de Litespeed, Cloudflare y del lado del servidor en un solo clic.<\/p>\n                <\/div><\/p><h3 class=\"wp-block-heading\" id=\"h-5-obten-contenido-estatico-a-traves-de-una-cdn-opcional\">5. Obt&eacute;n contenido est&aacute;tico a trav&eacute;s de una CDN (opcional)<\/h3><p>Obtener contenido est&aacute;tico a trav&eacute;s de una CDN puede reducir la latencia de tu red. Esto se debe a que la CDN replicar&aacute; los recursos m&aacute;s solicitados en los servidores de almacenamiento en cach&eacute; globales. Siempre que los visitantes accedan a esos recursos, el servidor m&aacute;s cercano los entregar&aacute;.<\/p><p>Para obtener contenido est&aacute;tico de una CDN deber&aacute;s <a href=\"https:\/\/support.hostinger.com\/es\/articles\/1583405-como-crear-y-eliminar-subdominios\" target=\"_blank\" rel=\"noreferrer noopener\">crear un subdominio<\/a> que entregue los recursos, por ejemplo,<strong> cdn.tu-sitioweb.com<\/strong>. Este subdominio debe estar en la misma carpeta que tu dominio principal.<\/p><p><div><p class=\"important\"><strong>&iexcl;Importante!<\/strong> Los usuarios de planes compartidos y en la nube de Hostinger deber&aacute;n agregar el nuevo dominio como un nuevo sitio web en lugar de un subdominio.<\/p><\/div><\/p><p>Adem&aacute;s, es fundamental asegurarse de que el subdominio CDN funcione bien. De lo contrario, tus recursos est&aacute;ticos no se cargar&aacute;n y esto podr&iacute;a da&ntilde;ar tu sitio web.<\/p><p>Si est&aacute;s seguro de que el subdominio funciona correctamente, habilita la opci&oacute;n <strong>Usar mapeo de CDN <\/strong>para el subdominio reci&eacute;n creado:<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"779\" height=\"480\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2020\/05\/url-de-cdn.png\/public\" alt=\"P&aacute;gina CDN de LiteSpees Cache, secci&oacute;n URL de CDN\" class=\"wp-image-20145\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2020\/05\/url-de-cdn.png\/w=779,fit=scale-down 779w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2020\/05\/url-de-cdn.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2020\/05\/url-de-cdn.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2020\/05\/url-de-cdn.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 779px) 100vw, 779px\" \/><\/figure><\/div><p>Ahora que hemos terminado de configurar el plugin LiteSpeed &#8203;&#8203;Cache, echemos un vistazo a los siguientes gr&aacute;ficos:<\/p><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"1013\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-02.jpg\/public\" alt=\"Gr&aacute;ficos de comparaci&oacute;n de sitios web\" class=\"wp-image-38074\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-02.jpg\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-02.jpg\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-02.jpg\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/02\/litespeed-cache-es-02.jpg\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><p>Estos muestran el rendimiento de los tres sitios web analizados antes y despu&eacute;s de aplicar los ajustes de configuraci&oacute;n de LiteSpeed &#8203;&#8203;adecuados.<\/p><p>Antes de aplicar la optimizaci&oacute;n de im&aacute;genes y p&aacute;ginas, el sitio web de portfolio obtuvo solo 45 puntos en la categor&iacute;a m&oacute;vil de PageSpeed. Despu&eacute;s de que se optimiz&oacute;, el puntaje se dispar&oacute; a 100. Mientras tanto, los mismos cambios mejoraron el puntaje de la tienda de comercio electr&oacute;nico de 53 puntos a 99.<\/p><p>En t&eacute;rminos de rendimiento de GTMetrix, la puntuaci&oacute;n del sitio de blog aument&oacute; de 84 a 100.<\/p><p><div><p class=\"important\"><strong>&iexcl;Importante!<\/strong> Todos los sitios web (el blog, la tienda de comercio electr&oacute;nico y el sitio de portfolio) demostraron mejores resultados despu&eacute;s de activar LiteSpeed Cache para WordPress y aplicar la optimizaci&oacute;n de im&aacute;genes y p&aacute;ginas.<\/p><\/div><\/p><h2 class=\"wp-block-heading\" id=\"h-que-mas-puede-hacer-litespeed\">&iquest;Qu&eacute; m&aacute;s puede hacer LiteSpeed?<\/h2><p>Una vez que hayas configurado todos los ajustes del plugin LiteSpeed &#8203;&#8203;Cache para WordPress, el sistema deber&iacute;a funcionar correctamente. Por lo tanto, se requerir&aacute; poca administraci&oacute;n de cach&eacute; adicional. Sin embargo, LiteSpeed &#8203;&#8203;ofrece m&aacute;s funcionalidades para modificar seg&uacute;n lo necesites.<\/p><p>Las siguientes secciones hablar&aacute;n sobre la optimizaci&oacute;n de la base de datos de LiteSpeed, su crawler y las herramientas para ayudarte a mejorar a&uacute;n m&aacute;s el rendimiento de tu sitio web.<\/p><h3 class=\"wp-block-heading\" id=\"h-optimizacion-de-la-base-de-datos\">Optimizaci&oacute;n de la base de datos<\/h3><p>La secci&oacute;n <strong>Base de datos<\/strong> ofrece funciones para ayudarte a ejecutar varias tareas en tu base de datos de WordPress de manera m&aacute;s conveniente. Esto incluye borrar las revisiones de publicaciones antiguas y eliminar los <a href=\"\/mx\/tutoriales\/que-es-pingback-wordpress\/\">pingbacks<\/a> con un solo clic.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1097\" height=\"589\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/base-de-datos.png\/w=1024,h=1024,fit=scale-down\" alt=\"Secci&oacute;n Optimizador de base de datos\" class=\"wp-image-20065\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/base-de-datos.png\/w=1097,fit=scale-down 1097w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/base-de-datos.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/base-de-datos.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/base-de-datos.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/base-de-datos.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1097px) 100vw, 1097px\" \/><\/figure><\/div><p>Adem&aacute;s, l<strong>os ajustes de optimizaci&oacute;n de la base de datos<\/strong> controlan el n&uacute;mero de revisiones de las entradas para aliviar y automatizar el proceso.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1147\" height=\"478\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ajustes-optimizacion-base-de-datos.png\/w=1024,h=1024,fit=scale-down\" alt=\"Secci&oacute;n Ajustes de optimizaci&oacute;n de la base de datos\" class=\"wp-image-20066\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ajustes-optimizacion-base-de-datos.png\/w=1147,fit=scale-down 1147w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ajustes-optimizacion-base-de-datos.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ajustes-optimizacion-base-de-datos.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ajustes-optimizacion-base-de-datos.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/ajustes-optimizacion-base-de-datos.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1147px) 100vw, 1147px\" \/><\/figure><\/div><p>Por ejemplo, si deseas guardar dos revisiones anteriores para cada entrada, cambia el valor de <strong>N&uacute;mero m&aacute;ximo de revisiones<\/strong> a <strong>2<\/strong>. Mientras tanto, para mantener las revisiones de entradas antiguas durante un per&iacute;odo espec&iacute;fico, cambia la <strong>Edad m&aacute;xima de las revisiones<\/strong>.<\/p><h3 class=\"wp-block-heading\" id=\"h-crawler\">Crawler<\/h3><p>El plugin LSCache incluye una funcionalidad de <strong>Crawler<\/strong>, el cual navega por el backend de tu sitio web, busca p&aacute;ginas caducadas y las actualiza en el proceso. Esto evita que los visitantes vean cualquier p&aacute;gina no almacenada en cach&eacute;.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1151\" height=\"575\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/crawler.png\/w=1024,h=1024,fit=scale-down\" alt=\"Secci&oacute;n Crawler\" class=\"wp-image-20067\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/crawler.png\/w=1151,fit=scale-down 1151w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/crawler.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/crawler.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/crawler.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/crawler.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1151px) 100vw, 1151px\" \/><\/figure><\/div><p>Esta funci&oacute;n est&aacute; deshabilitada de forma predeterminada y debe habilitarse desde el lado del servidor; deber&aacute;s consultar al administrador del servidor o al proveedor de alojamiento web. <\/p><p>Esto se debe a que la activaci&oacute;n de la funcionalidad del crawler sin suficientes recursos del servidor podr&iacute;a afectar negativamente el rendimiento de tu sitio.<\/p><p><div><p class=\"important\"><strong>&iexcl;Importante! <\/strong>La funcionalidad de Crawler solo est&aacute; disponible en los planes de alojamiento en la nube de Hostinger.<\/p><\/div><\/p><h3 class=\"wp-block-heading\" id=\"h-herramientas\">Herramientas<\/h3><p>Utiliza la secci&oacute;n <strong>Herramientas<\/strong> de LiteSpeed Cache &#8203;&#8203;para ajustar tus configuraciones de cach&eacute; manualmente. Esta secci&oacute;n proporciona funciones de almacenamiento en cach&eacute; m&aacute;s espec&iacute;ficas, desde vaciar p&aacute;ginas de <a href=\"\/mx\/tutoriales\/error-403-prohibido-arreglarlo\/\">error 403<\/a> hasta editar la ruta del archivo <strong>.htaccess<\/strong>.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1157\" height=\"577\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/herramientas.png\/w=1024,h=1024,fit=scale-down\" alt=\"Secci&oacute;n Herramientas\" class=\"wp-image-20068\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/herramientas.png\/w=1157,fit=scale-down 1157w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/herramientas.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/herramientas.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/herramientas.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2022\/06\/herramientas.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1157px) 100vw, 1157px\" \/><\/figure><\/div><p>Aunque la pesta&ntilde;a <strong>Vaciar <\/strong>contiene funciones sencillas, otras pesta&ntilde;as como <strong>Editar .htaccess <\/strong>y <strong>Heartbeat <\/strong>est&aacute;n destinadas a usuarios avanzados. Por lo tanto, es mejor dejar los valores predeterminados para estas configuraciones o consultar a tu servidor web antes de realizar cambios.<\/p><p>Para m&aacute;s detalles, ampliaremos la funcionalidad de cada secci&oacute;n:<\/p><ul class=\"wp-block-list\">\n<li><strong>Vaciar<\/strong>. Esta pesta&ntilde;a enumera diferentes tipos de contenido para que los purgues de forma selectiva. Las funciones son especialmente &uacute;tiles para realizar cambios en un archivo que se almacena en cach&eacute;. De esta manera, solo se purgan los archivos seleccionados, sin afectar el resto de tu contenido.<\/li>\n\n\n\n<li><strong>Importar \/ Exportar<\/strong>. Esta funci&oacute;n incluye herramientas para exportar o importar varias configuraciones de LiteSpeed. Estas herramientas son &uacute;tiles si est&aacute;s experimentando con tu sitio y deseas restaurar las configuraciones anteriores en un futuro. Adem&aacute;s, tambi&eacute;n puedes transferir la configuraci&oacute;n de tu sitio a un archivo local y utilizarlo en otro sitio web.<\/li>\n\n\n\n<li><strong>Ver .htaccess<\/strong>. Utiliza las herramientas disponibles dentro de esta pesta&ntilde;a para editar directamente tu archivo <strong>.htaccess<\/strong> sin tener que configurar un cliente FTP o SSH. Ten en cuenta que cambiar el <a href=\"\/mx\/tutoriales\/crear-archivo-htaccess\/\">archivo .htaccess<\/a> podr&iacute;a da&ntilde;ar tu sitio. Si no est&aacute;s seguro, siempre consulta a tu proveedor de alojamiento web antes de realizar cualquier cambio.<\/li>\n\n\n\n<li><strong>Heartbeat<\/strong>. WordPress <strong>Heartbeat API <\/strong>permite que tu navegador se comunique con los servidores mediante llamadas <a href=\"\/mx\/tutoriales\/que-es-ajax\/\">AJAX<\/a>. Esta funcionalidad te permite administrar la carga del servidor. Sin embargo, ten cuidado al ajustar los intervalos del heartbeat de WordPress, ya que esto puede consumir una gran cantidad de energ&iacute;a de la CPU.<\/li>\n\n\n\n<li><strong>Informe<\/strong>. En caso de que experimentes problemas con el plugin LiteSpeed &#8203;&#8203;Cache, puedes enviar informes presionando el bot&oacute;n <strong>Enviar a LiteSpeed<\/strong> &#8203;&#8203;en esta pesta&ntilde;a. Luego, el sistema enviar&aacute; una copia de tu informe al equipo de LiteSpeed.<\/li>\n\n\n\n<li><strong>Ajustes de depuraci&oacute;n<\/strong>. Si deseas deshabilitar el plugin LiteSpeed &#8203;&#8203;Cache para depurar tu sitio web, utiliza las herramientas disponibles en esta pesta&ntilde;a.<\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-conclusion\">Conclusi&oacute;n<\/h2><p>El almacenamiento en cach&eacute; web es una de las formas m&aacute;s efectivas y eficientes de mejorar el rendimiento de un sitio web. <\/p><p>Cuando se implementa correctamente, este puede acelerar su tiempo de carga y reducir la carga del servidor. La forma m&aacute;s sencilla de configurar el almacenamiento en cach&eacute; web es instalar un plugin de cach&eacute;.<\/p><p>LiteSpeed &#8203;&#8203;Cache es uno de los mejores plugins de WordPress con t&eacute;cnicas avanzadas de almacenamiento en cach&eacute;. Adem&aacute;s, cuando se combina con el servidor LiteSpeed, su almacenamiento en cach&eacute; de p&aacute;ginas a nivel de servidor puede mejorar el rendimiento de manera efectiva.<\/p><p>En este art&iacute;culo, hemos explicado la mejor forma de configurar LiteSpeed &#8203;&#8203;Cache para WordPress. Aunque aplicar la mejor configuraci&oacute;n te brindar&aacute; un rendimiento optimizado, no es necesario modificar los ajustes predeterminados si no te sientes c&oacute;modo haci&eacute;ndolo.<\/p><p>Esperamos que este art&iacute;culo te haya ayudado a configurar LiteSpeed &#8203;&#8203;Cache para WordPress y que puedas aprovecharlo al m&aacute;ximo. Si tienes alguna pregunta, no dudes en dejarla en la secci&oacute;n de comentarios a continuaci&oacute;n.<\/p><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"\/mx\/hosting-wordpress\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/06\/ES-New-WP_in-text-banner.png\/public\" alt=\"\" class=\"wp-image-40615\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/06\/ES-New-WP_in-text-banner.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/06\/ES-New-WP_in-text-banner.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/06\/ES-New-WP_in-text-banner.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/39\/2024\/06\/ES-New-WP_in-text-banner.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div><h2 class=\"wp-block-heading\" id=\"h-litespeed-cache-preguntas-frecuentes\">LiteSpeed &#8203;&#8203;Cache &ndash; Preguntas frecuentes <\/h2><p>A continuaci&oacute;n vamos a responder a algunas de las preguntas m&aacute;s comunes sobre LiteSpeed web server. <\/p><div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-69447330bd239\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">&iquest;Deber&iacute;a usar LiteSpeed Cache?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>LiteSpeed Cache es una magn&iacute;fica elecci&oacute;n como plugin de cach&eacute; si est&aacute;s buscando un plugin con amplias opciones de configuraci&oacute;n, buenas cr&iacute;ticas y un r&aacute;pido almacenamiento en cach&eacute; a nivel de servidor.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-69447330bd23d\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">&iquest;Es LiteSpeed Cache gratuito?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>S&iacute;, LiteSpeed Cache es gratuito, pero s&oacute;lo te beneficiar&aacute;s del almacenamiento en cach&eacute; si los servidores de tu sitio web tambi&eacute;n utilizan LiteSpeed.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La optimizaci&oacute;n de la velocidad debe ser una prioridad para todos los propietarios de sitios web, ya que esta afecta directamente al SEO en WordPress. Adem&aacute;s, cuanto m&aacute;s tiempo tarda en cargar un sitio web, mayor es su tasa de rebote. Esto puede evitar que generes conversiones y que llegue tr&aacute;fico a tu sitio. Con [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/mx\/tutoriales\/litespeed-cache-plugin\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":334,"featured_media":46821,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_title":"LiteSpeed Cache: optimiza la velocidad de tu web de WordPress","rank_math_description":"Descubre c\u00f3mo el plugin LiteSpeed Cache puede acelerar tu web de WordPress, Incluido en todos nuestros planes para tu beneficio.","rank_math_focus_keyword":"litespeed","footnotes":""},"categories":[4747],"tags":[13023],"class_list":["post-10491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wordpress","tag-litespeed"],"hreflangs":[{"locale":"en-US","link":"https:\/\/www.hostinger.com\/tutorials\/wordpress-litespeed-website-optimization-tool","default":0},{"locale":"fr-FR","link":"https:\/\/www.hostinger.com\/fr\/tutoriels\/litespeed-cache","default":0},{"locale":"es-ES","link":"https:\/\/www.hostinger.com\/es\/tutoriales\/litespeed-cache-plugin","default":0},{"locale":"id-ID","link":"https:\/\/www.hostinger.com\/id\/tutorial\/litespeed-cache","default":0},{"locale":"en-GB","link":"https:\/\/www.hostinger.com\/uk\/tutorials\/litespeed-website-optimization-tool\/","default":0},{"locale":"en-MY","link":"https:\/\/www.hostinger.com\/my\/tutorials\/litespeed-website-optimization-tool\/","default":0},{"locale":"en-PH","link":"https:\/\/www.hostinger.com\/ph\/tutorials\/litespeed-website-optimization-tool\/","default":0},{"locale":"es-MX","link":"https:\/\/www.hostinger.com\/mx\/tutoriales\/entorno-staging-wordpress-2","default":0},{"locale":"es-CO","link":"https:\/\/www.hostinger.com\/co\/tutoriales\/como-usar-sftp-15","default":0},{"locale":"es-AR","link":"https:\/\/www.hostinger.com\/ar\/tutoriales\/entorno-staging-wordpress-2","default":0},{"locale":"en-IN","link":"https:\/\/www.hostinger.com\/in\/tutorials\/litespeed-website-optimization-tool\/","default":0},{"locale":"en-CA","link":"https:\/\/www.hostinger.com\/ca\/tutorials\/wordpress-litespeed-website-optimization-tool","default":0},{"locale":"en-AU","link":"https:\/\/www.hostinger.com\/au\/tutorials\/wordpress-litespeed-website-optimization-tool","default":0},{"locale":"en-NG","link":"https:\/\/www.hostinger.com\/ng\/tutorials\/wordpress-litespeed-website-optimization-tool","default":0}],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts\/10491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/users\/334"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/comments?post=10491"}],"version-history":[{"count":65,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts\/10491\/revisions"}],"predecessor-version":[{"id":46820,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/posts\/10491\/revisions\/46820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/media\/46821"}],"wp:attachment":[{"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/media?parent=10491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/categories?post=10491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-json\/wp\/v2\/tags?post=10491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}