{"id":42446,"date":"2025-09-30T19:04:15","date_gmt":"2025-09-30T19:04:15","guid":{"rendered":"\/fr\/tutoriels\/?p=42446"},"modified":"2025-09-30T19:16:12","modified_gmt":"2025-09-30T19:16:12","slug":"localhost-c-est-quoi","status":"publish","type":"post","link":"\/fr\/tutoriels\/localhost-c-est-quoi\/","title":{"rendered":"Localhost c\u2019est quoi ? Explication simple pour d\u00e9butants"},"content":{"rendered":"<p>En informatique, <strong>localhost<\/strong> peut &ecirc;tre consid&eacute;r&eacute; comme &laquo; cet ordinateur &raquo;. Il s&rsquo;agit du nom par d&eacute;faut utilis&eacute; pour &eacute;tablir une connexion avec votre ordinateur &agrave; l&rsquo;aide du r&eacute;seau d&rsquo;adresses de bouclage.<\/p><p>L&rsquo;adresse de bouclage a une adresse IP par d&eacute;faut (127.0.0.1) utile pour tester des programmes sur votre ordinateur, sans envoyer d&rsquo;informations sur Internet. Cela vous aide lorsque vous testez des applications qui ne sont pas encore pr&ecirc;tes &agrave; &ecirc;tre d&eacute;voil&eacute;es au monde entier.<\/p><p>Lorsque vous appelez une adresse IP depuis votre ordinateur, vous essayez g&eacute;n&eacute;ralement de contacter un autre ordinateur via Internet. Cependant, avec l&rsquo;adresse de bouclage, vous appelez le localhost, c&rsquo;est-&agrave;-dire votre ordinateur.<\/p><p>Si vous souhaitez en savoir plus sur les r&eacute;seaux informatiques, il est important de comprendre le langage que vous allez rencontrer. Il n&rsquo;y a pas de meilleur point de d&eacute;part que d&rsquo;apprendre ce qu&rsquo;est <strong>localhost.<\/strong><\/p><p>\n\n\n\n\n\n<div class=\"protip\"><div class=\"protip__heading\">\n                <svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M1.49234 23.5024C1.23229 23.5024 0.972242 23.4024 0.782206 23.2123C0.562165 22.9923 0.452144 22.6822 0.502153 22.3722C0.562165 21.9221 1.14227 17.9113 3.00262 16.351C3.63274 15.8209 4.43289 15.5509 5.26305 15.5609C6.09321 15.5909 6.87335 15.9109 7.47347 16.4911C8.6937 17.6913 8.76371 19.6717 7.6435 20.9919C6.0832 22.8523 2.08245 23.4324 1.63237 23.4924C1.59236 23.4924 1.54235 23.4924 1.50234 23.4924L1.49234 23.5024ZM5.16303 17.5613C4.84297 17.5613 4.53291 17.6713 4.29287 17.8813C3.60274 18.4614 3.07264 19.9317 2.75258 21.242C4.06282 20.9219 5.5331 20.3918 6.11321 19.7017C6.55329 19.1716 6.54329 18.3814 6.0832 17.9213C5.85316 17.7013 5.5431 17.5713 5.20304 17.5613C5.19304 17.5613 5.17303 17.5613 5.16303 17.5613ZM11.7243 21.8821C11.4942 21.8821 11.2642 21.8021 11.0841 21.652C10.8541 21.462 10.7241 21.1819 10.7241 20.8819V15.9109L8.08358 13.2705H3.11264C2.81259 13.2705 2.53254 13.1404 2.3425 12.9104C2.15246 12.6803 2.07245 12.3803 2.12246 12.0902C2.19247 11.7102 2.84259 8.36953 4.70294 7.12929C6.33325 6.04909 8.96375 6.49918 10.244 6.80923C11.5442 4.96889 13.2546 3.4286 15.2349 2.33839C17.4553 1.11816 19.9858 0.518051 22.4963 0.498047C23.0464 0.498047 23.4865 0.948132 23.4865 1.49824C23.4865 5.0389 22.3763 9.97983 17.1753 13.7605C17.4853 15.0408 17.9354 17.6613 16.8552 19.2816C15.615 21.1419 12.2744 21.7921 11.8943 21.8621C11.8343 21.8721 11.7743 21.8821 11.7143 21.8821H11.7243ZM12.7245 16.181V19.6016C13.7146 19.2916 14.7948 18.7915 15.2049 18.1814C15.675 17.4812 15.605 16.091 15.385 14.9008C14.5248 15.3808 13.6346 15.8109 12.7245 16.181ZM9.66388 12.0302L11.9643 14.3307C13.1845 13.8306 14.3648 13.2204 15.485 12.5103C19.9358 9.51974 21.2361 5.60901 21.4561 2.53843C19.6157 2.67846 17.8254 3.20856 16.2051 4.09872C14.2847 5.14892 12.6544 6.68921 11.4942 8.54956C10.7841 9.65977 10.174 10.82 9.66388 12.0302ZM4.39289 11.2701H7.81353C8.1936 10.3599 8.63368 9.46974 9.11377 8.60957C7.92355 8.38953 6.51329 8.31952 5.81315 8.78961C5.19304 9.19968 4.70294 10.3099 4.39289 11.2701Z\" fill=\"#673DE6\"\/>\n                <\/svg>\n                <p class=\"protip__title\">\n                   Qu'est-ce que Localhost ?\n                <\/p>\n            <\/div>\n            <p class=\"protip__content\">Localhost est le nom d&rsquo;h&ocirc;te ou l&rsquo;ordinateur actuellement utilis&eacute; pour ex&eacute;cuter un programme, dans lequel l&rsquo;ordinateur joue le r&ocirc;le de serveur virtuel. Dans le d&eacute;veloppement web, vous pouvez d&eacute;velopper un serveur en modifiant le code dans localhost et en exportant vos donn&eacute;es vers le serveur.<\/p><\/div>\n\n\n\n<\/p><h2 class=\"wp-block-heading\" id=\"h-qu-est-ce-que-127-0-0-1-et-une-adresse-de-bouclage\"><strong>Qu&rsquo;est-ce que 127.0.0.1 et une adresse de bouclage ?<\/strong><\/h2><p>Tout comme une <a href=\"https:\/\/www.hostinger.com\/fr\/tutoriels\/qu-est-ce-qu-une-adresse-ip\/\"><strong>adresse IP<\/strong><\/a>, lorsque vous tapez <strong>google.com <\/strong>dans un navigateur web, vous &ecirc;tes redirig&eacute; vers son site web d&rsquo;h&eacute;bergement local, la page principale de Google. Alors, o&ugrave; vous m&egrave;nera localhost ? Il vous m&egrave;nera &agrave; votre ordinateur. Cette situation est &eacute;galement connue sous le nom d&rsquo;adresse de bouclage.<\/p><p>Comme tout autre nom de domaine, localhost poss&egrave;de &eacute;galement une adresse IP (Internet Protocol). Les adresses vont de<strong> 127.0.0.0 <\/strong>&agrave;<strong> 127.255.255.255<\/strong>, mais elles sont g&eacute;n&eacute;ralement<strong> 127.0.0.1<\/strong>. Si vous essayez d&rsquo;ouvrir l&rsquo;adresse<strong> 127.0.0.1 <\/strong>dans une connexion<strong> IPv4<\/strong>, cela d&eacute;clenchera une boucle de retour qui vous renverra vers votre propre serveur web. Vous pouvez &eacute;galement lancer une boucle de retour vers votre propre serveur avec une connexion<strong> IPv6 <\/strong>en saisissant :1.<\/p><p>Fait int&eacute;ressant : la premi&egrave;re partie de l&rsquo;adresse (<strong>127<\/strong>) est r&eacute;serv&eacute;e uniquement aux boucles de retour. C&rsquo;est pourquoi le protocole TCP\/IP (<strong>Transmission Control Protocol <\/strong>and <strong>Internet Protocol<\/strong>) reconna&icirc;t imm&eacute;diatement que vous souhaitez contacter votre ordinateur apr&egrave;s avoir saisi une adresse commen&ccedil;ant par ces chiffres. C&rsquo;est pourquoi aucun site web ne peut avoir d&rsquo;adresse IP commen&ccedil;ant par<strong> 127. <\/strong>Une fois lanc&eacute;e, cette action cr&eacute;era un p&eacute;riph&eacute;rique de bouclage, qui est une interface virtuelle &agrave; l&rsquo;int&eacute;rieur du syst&egrave;me d&rsquo;exploitation (<strong>OS)<\/strong> de votre ordinateur.<\/p><h2 class=\"wp-block-heading\" id=\"h-a-quoi-sert-localhost\"><strong>&Agrave; quoi sert Localhost ?<\/strong><\/h2><p>Malgr&eacute; sa signification simple, localhost est utile si vous &ecirc;tes d&eacute;veloppeur, administrateur r&eacute;seau ou pour effectuer des tests. En g&eacute;n&eacute;ral, la boucle locale offre trois avantages :<\/p><h3 class=\"wp-block-heading\" id=\"h-test-de-programmes-ou-d-applications-web\"><strong>Test de programmes ou d&rsquo;applications web<\/strong><\/h3><p>L&rsquo;utilisation de localhost est l&rsquo;une des principales utilisations pour les d&eacute;veloppeurs, en particulier s&rsquo;ils cr&eacute;ent des applications web ou des programmes qui n&eacute;cessitent une connexion Internet. Pendant le d&eacute;veloppement, des tests sont effectu&eacute;s pour v&eacute;rifier si les applications fonctionnent r&eacute;ellement. En utilisant une boucle de retour pour les tester, les d&eacute;veloppeurs peuvent cr&eacute;er une connexion au localhost, afin de les tester &agrave; l&rsquo;int&eacute;rieur de l&rsquo;ordinateur et du syst&egrave;me qu&rsquo;ils utilisent actuellement.<\/p><p>Une fois le loopback d&eacute;clench&eacute;, votre <strong>syst&egrave;me d&rsquo;exploitation <\/strong>devient un serveur web simul&eacute;. Vous pouvez charger les fichiers n&eacute;cessaires d&rsquo;un programme dans les serveurs web et v&eacute;rifier son fonctionnement.<\/p><h3 class=\"wp-block-heading\" id=\"h-blocage-de-sites\"><strong>Blocage de sites<\/strong><\/h3><p>Une autre astuce int&eacute;ressante consiste &agrave; bloquer les sites web auxquels vous ne souhaitez pas acc&eacute;der. Le loopback est utile pour emp&ecirc;cher votre navigateur d&rsquo;acc&eacute;der &agrave; des sites dangereux, tels que ceux contenant des virus.<\/p><p>Avant d&rsquo;apprendre comment cela fonctionne, vous devez toutefois savoir ce qu&rsquo;est un &laquo; <strong>fichier hosts <\/strong>&raquo; et quel est son r&ocirc;le dans ce contexte. Comme vous le savez d&eacute;j&agrave;, tous les <a href=\"https:\/\/www.hostinger.com\/fr\/nom-de-domaine-disponible\">noms de domaine<\/a> ont des adresses IP. Vous pouvez acc&eacute;der &agrave; un site web parce que le <strong>DNS <\/strong>(<strong>Domain Name System) <\/strong>recherche l&rsquo;adresse IP appropri&eacute;e sous laquelle le site est enregistr&eacute;.<\/p><p>Votre ordinateur contribue &agrave; am&eacute;liorer ce processus en stockant un fichier h&ocirc;te pour chaque site que vous avez visit&eacute;. Ce fichier contient l&rsquo;adresse IP et les noms de domaine des sites web. Vous pouvez changer l&rsquo;adresse IP en<strong> 127.0.0.1 <\/strong>et le site qui h&eacute;berge le fichier que vous avez modifi&eacute; vous redirige alors vers l&rsquo;h&ocirc;te local.<\/p><p>Un exemple pourrait &ecirc;tre l&rsquo;administrateur informatique d&rsquo;une entreprise qui bloque l&rsquo;acc&egrave;s &agrave; un site web.<\/p><h3 class=\"wp-block-heading\" id=\"h-test-de-vitesse\"><strong>Test de vitesse<\/strong><\/h3><p>En tant qu&rsquo;administrateur r&eacute;seau, vous devez vous assurer que tous les &eacute;quipements et le protocole TCP\/IP fonctionnent correctement. Pour cela, vous pouvez effectuer un test de connexion et envoyer une requ&ecirc;te ping &agrave; l&rsquo;h&ocirc;te local.<\/p><p>Par exemple, vous pouvez facilement ouvrir l&rsquo;invite de commande ou le terminal et saisir <strong>&laquo; ping localhost <\/strong>&raquo; ou &laquo; <strong>ping 127.0.0.1 <\/strong>&raquo;. Le test localhost montrera les performances globales, du nombre de paquets de donn&eacute;es re&ccedil;us, envoy&eacute;s ou perdus au temps de transmission des donn&eacute;es. Si des probl&egrave;mes surviennent, vous pouvez les r&eacute;soudre imm&eacute;diatement.<\/p><p>Pour des tests plus d&eacute;taill&eacute;s et des informations compl&egrave;tes, modifiez les paquets envoy&eacute;s &agrave; l&rsquo;h&ocirc;te local. Consultez notre tutoriel sur la <a href=\"https:\/\/www.hostinger.com\/fr\/tutoriels\/commande-ping-linux\/\"><strong>commande ping sous Linux<\/strong><\/a> pour savoir comment proc&eacute;der.<\/p><figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.hostinger.com\/fr\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/46\/2022\/12\/FR-Web-hosting_in-text-banner-1-1024x300-1.png\/public\" alt=\"\" class=\"wp-image-41467\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/46\/2022\/12\/FR-Web-hosting_in-text-banner-1-1024x300-1.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/46\/2022\/12\/FR-Web-hosting_in-text-banner-1-1024x300-1.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/46\/2022\/12\/FR-Web-hosting_in-text-banner-1-1024x300-1.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/46\/2022\/12\/FR-Web-hosting_in-text-banner-1-1024x300-1.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><h2 class=\"wp-block-heading\" id=\"h-conclusion\"><strong>Conclusion<\/strong><\/h2><p>Vous comprenez d&eacute;sormais que localhost n&rsquo;est pas seulement un terme technique d&eacute;signant votre ordinateur. Il s&rsquo;agit d&rsquo;un nom par d&eacute;faut qui vous permet de tester des programmes et m&ecirc;me de fermer l&rsquo;acc&egrave;s &agrave; des sites web. Si vous aspirez &agrave; devenir technicien informatique, il est essentiel de savoir ce qu&rsquo;est localhost et comment utiliser une boucle de retour en fonction de vos besoins.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En informatique, localhost peut &ecirc;tre consid&eacute;r&eacute; comme &laquo; cet ordinateur &raquo;. Il s&rsquo;agit du nom par d&eacute;faut utilis&eacute; pour &eacute;tablir une connexion avec votre ordinateur &agrave; l&rsquo;aide du r&eacute;seau d&rsquo;adresses de bouclage. L&rsquo;adresse de bouclage a une adresse IP par d&eacute;faut (127.0.0.1) utile pour tester des programmes sur votre ordinateur, sans envoyer d&rsquo;informations sur Internet. [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/fr\/tutoriels\/localhost-c-est-quoi\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":355,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rank_math_title":"Localhost c'est quoi ? Localhost expliqu\u00e9 aux d\u00e9butants","rank_math_description":"En r\u00e9seau informatique localhost d\u00e9signe un ordinateur ex\u00e9cutant un programme, dans lequel l'ordinateur fonctionne comme un serveur virtuel.","rank_math_focus_keyword":"localhost c'est quoi","footnotes":""},"categories":[5259],"tags":[],"class_list":["post-42446","post","type-post","status-publish","format-standard","hentry","category-glossaire"],"hreflangs":[{"locale":"en-US","link":"https:\/\/www.hostinger.com\/tutorials\/what-is-localhost","default":0},{"locale":"pt-BR","link":"https:\/\/www.hostinger.com\/br\/tutoriais\/o-que-e-localhost","default":0},{"locale":"fr-FR","link":"https:\/\/www.hostinger.com\/fr\/tutoriels\/localhost-c-est-quoi","default":0},{"locale":"es-ES","link":"https:\/\/www.hostinger.com\/es\/tutoriales\/que-es-localhost","default":0},{"locale":"id-ID","link":"https:\/\/www.hostinger.com\/id\/tutorial\/apa-itu-localhost","default":0},{"locale":"en-GB","link":"https:\/\/www.hostinger.com\/uk\/tutorials\/what-is-localhost","default":0},{"locale":"en-MY","link":"https:\/\/www.hostinger.com\/my\/tutorials\/what-is-localhost","default":0},{"locale":"en-PH","link":"https:\/\/www.hostinger.com\/ph\/tutorials\/what-is-localhost","default":0},{"locale":"es-MX","link":"https:\/\/www.hostinger.com\/mx\/tutoriales\/que-es-localhost","default":0},{"locale":"es-CO","link":"https:\/\/www.hostinger.com\/co\/tutoriales\/que-es-localhost","default":0},{"locale":"es-AR","link":"https:\/\/www.hostinger.com\/ar\/tutoriales\/que-es-localhost","default":0},{"locale":"pt-PT","link":"https:\/\/www.hostinger.com\/pt\/tutoriais\/o-que-e-localhost","default":0},{"locale":"en-IN","link":"https:\/\/www.hostinger.com\/in\/tutorials\/what-is-localhost","default":0},{"locale":"en-CA","link":"https:\/\/www.hostinger.com\/ca\/tutorials\/what-is-localhost","default":0},{"locale":"en-AU","link":"https:\/\/www.hostinger.com\/au\/tutorials\/what-is-localhost","default":0},{"locale":"en-NG","link":"https:\/\/www.hostinger.com\/ng\/tutorials\/what-is-localhost","default":0}],"_links":{"self":[{"href":"https:\/\/www.hostinger.com\/fr\/tutoriels\/wp-json\/wp\/v2\/posts\/42446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinger.com\/fr\/tutoriels\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinger.com\/fr\/tutoriels\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/fr\/tutoriels\/wp-json\/wp\/v2\/users\/355"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/fr\/tutoriels\/wp-json\/wp\/v2\/comments?post=42446"}],"version-history":[{"count":3,"href":"https:\/\/www.hostinger.com\/fr\/tutoriels\/wp-json\/wp\/v2\/posts\/42446\/revisions"}],"predecessor-version":[{"id":42451,"href":"https:\/\/www.hostinger.com\/fr\/tutoriels\/wp-json\/wp\/v2\/posts\/42446\/revisions\/42451"}],"wp:attachment":[{"href":"https:\/\/www.hostinger.com\/fr\/tutoriels\/wp-json\/wp\/v2\/media?parent=42446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinger.com\/fr\/tutoriels\/wp-json\/wp\/v2\/categories?post=42446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinger.com\/fr\/tutoriels\/wp-json\/wp\/v2\/tags?post=42446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}