{"id":9096,"date":"2019-09-12T08:17:54","date_gmt":"2019-09-12T08:17:54","guid":{"rendered":"https:\/\/blog.hostinger.io\/es-tutoriales\/?p=9096"},"modified":"2025-03-26T09:04:31","modified_gmt":"2025-03-26T08:04:31","slug":"comando-shutdown-linux","status":"publish","type":"post","link":"\/es\/tutoriales\/comando-shutdown-linux\/","title":{"rendered":"C\u00f3mo usar el comando Shutdown de Linux en Ubuntu y CentOS"},"content":{"rendered":"<p>Los sistemas operativos m&aacute;s populares te permiten apagar tu PC o computadora port&aacute;til usando diferentes m&eacute;todos. Los sistemas operativos Linux tambi&eacute;n tienen formas para que un usuario apague, reinicie, hiberne o suspenda de manera segura su <a href=\"http:\/\/www.unix.org\/what_is_unix.html\" target=\"_blank\" rel=\"noopener\">m&aacute;quina basada en Unix<\/a>. <\/p><p>En este tutorial te mostraremos c&oacute;mo usar de manera segura el comando Shutdown de Linux para apagar, reiniciar o hibernar tu <a href=\"\/es\/servidor-vps\">VPS<\/a>.<\/p><p>Te ayudaremos a hacerlo considerando dos versiones de Linux diferentes: CentOS y Ubuntu 22.04.<\/p><p>Apagar o reiniciar el servidor es importante en todos los sistemas operativos, esto permitir&aacute; que todo funcione seg&uacute;n lo previsto. Apagar el servidor a trav&eacute;s de la l&iacute;nea de <a href=\"\/es\/tutoriales\/linux-comandos\/\">comandos<\/a> es una forma segura de hacerlo, ya que notifica a todos los usuarios registrados que el sistema est&aacute; a punto de apagarse.<\/p><figure class=\"wp-block-image size-large\"><a href=\"https:\/\/assets.hostinger.com\/content\/tutorials\/pdf\/Linux-Commands-Cheatsheet-ES.pdf\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"1024\" height=\"283\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2022\/12\/Linux-cheat-sheet-ES.png\/w=1024,h=1024,fit=scale-down\" alt=\"\" class=\"wp-image-26004\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2022\/12\/Linux-cheat-sheet-ES.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2022\/12\/Linux-cheat-sheet-ES.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2022\/12\/Linux-cheat-sheet-ES.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2022\/12\/Linux-cheat-sheet-ES.png\/w=768,fit=scale-down 768w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2022\/12\/Linux-cheat-sheet-ES.png\/w=1536,fit=scale-down 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><p>A continuaci&oacute;n te ense&ntilde;aremos incluso c&oacute;mo programar el sistema operativo para que se apague a una hora determinada.<\/p><h2 class=\"wp-block-heading\" id=\"h-comando-de-apagado-en-linux-ubuntu-y-centos\">Comando de apagado en Linux Ubuntu y CentOS<\/h2><p>El comando de apagado (Shutdown) en Ubuntu y CentOS te permite apagar, reiniciar y detener tu sistema. La sintaxis del comando que se utiliza para apagar y reiniciar la m&aacute;quina es:<\/p><pre class=\"wp-block-preformatted\">Shutdown [OPTIONS] [TIME] [WALL]<\/pre><p>El comando Shutdown puede reiniciar, detener o apagar.<\/p><p>El primer argumento <strong>[OPTIONS]<\/strong> puede ser una cadena caracteres, seguido de los detalles de tiempo <strong>[TIME]<\/strong>. Despu&eacute;s del argumento, opcionalmente puedes escribir un mensaje en <strong>[WALL] <\/strong>para notificar a los usuarios registrados que se apagar&aacute; el sistema.<\/p><p>El formato para la cadena de tiempo es <strong>hh:mm<\/strong> (hora\/minutos), en forma de hora de 24 horas. Esto especificar&aacute; el momento en el que se ejecutar&aacute; el comando de apagado. Alternativamente, puedes usar <strong>+m<\/strong>, donde m indica minutos. As&iacute; le puedes indicar a la m&aacute;quina que se apague la cantidad de minutos que desees.<\/p><p>Tambi&eacute;n puedes usar <strong>now<\/strong> (ahora) en la sintaxis, que es un alias para <strong>+0<\/strong> minutos, esto activar&aacute; el apagado inmediato de tu VPS. Si no especificas el argumento <strong>[TIME]<\/strong>, Linux por defecto aplica <strong>+1<\/strong> antes de cerrar.<\/p><p>Toma en cuenta que un argumento de tiempo es imprescindible si deseas especificar un mensaje para el resto de los usuarios. El archivo <strong>\/run\/nologin<\/strong> se crear&aacute; 5 minutos antes de que el sistema se apague para garantizar que no se permitan m&aacute;s inicios de sesi&oacute;n, esto pasar&aacute; si y solo si has detallado una cadena de tiempo.<\/p><h2 class=\"wp-block-heading\" id=\"h-uso-del-comando-shutdown-en-linux-ubuntu-y-centos\">Uso del comando Shutdown en Linux Ubuntu y CentOS<\/h2><p>El comando de apagado para Ubuntu y CentOS es relativamente similar. Cada comando que se muestra a continuaci&oacute;n lo puedes usar en tu Terminal. Recuerda que tendr&aacute;s que usar SSH para acceder a tu servidor VPS. &iexcl;Tenemos un <a href=\"\/es\/tutoriales\/conectar-usando-terminal-putty-ssh\/\">tutorial<\/a> que cubre este proceso usando PuTTY!<\/p><p>El comando shutdown b&aacute;sico para CentOS y Ubuntu se ve as&iacute;:<\/p><pre class=\"wp-block-preformatted\">shutdown<\/pre><p>El comando anterior no apagar&aacute; tu PC de inmediato, establecer&aacute; un temporizador de un minuto antes de apagarse. Recuerda guardar tu trabajo antes de que se produzca el cierre.<\/p><p>Para apagar tu PC inmediatamente, escribe el siguiente comando y presiona enter:<\/p><pre class=\"wp-block-preformatted\">shutdown now<\/pre><p>Como mencionamos antes, el comando es el mismo para ambos sistemas operativos.<\/p><p>Para apagar tu PC a una hora espec&iacute;fica, escribe el siguiente comando y presiona enter:<\/p><pre class=\"wp-block-preformatted\">shutdown hh:mm<\/pre><p>El comando de apagado de Linux sigue un formato de 24 horas, as&iacute; que escribe la hora en lugar de <strong>hh<\/strong> y minutos en lugar de <strong>mm<\/strong>.<\/p><p>Para apagar despu&eacute;s de unos minutos u horas, escribe el siguiente comando y presiona enter:<\/p><pre class=\"wp-block-preformatted\">shutdown +m<\/pre><p>Recuerda, aqu&iacute; m indica minutos. Solo especifica la cantidad de minutos.<\/p><p>Para mostrar un mensaje antes de apagar el equipo a las personas que han iniciado sesi&oacute;n en tu VPS, escribe el siguiente comando y presione Intro:<\/p><pre class=\"wp-block-preformatted\">Shutdown +m \"Guarde su trabajo, la PC se apagar&aacute; en 5 minutos\"<\/pre><p>Aqu&iacute; el texto entre comillas puede ser cualquier mensaje que desees.<\/p><h2 class=\"wp-block-heading\" id=\"h-reinicia-tu-vps-usando-el-comando-shutdown-de-linux\">Reinicia tu VPS usando el comando Shutdown de Linux<\/h2><p>Para reiniciar tu PC de manera segura, usa el siguiente comando:<\/p><pre class=\"wp-block-preformatted\">shutdown &ndash;r<\/pre><p>Este comando no reiniciar&aacute; tu m&aacute;quina de inmediato, establecer&aacute; un temporizador de un minuto antes de reiniciar. As&iacute; puedes guardar tu trabajo antes de que se reinicie.<\/p><p>Para reiniciar tu PC de inmediato, simplemente agrega la opci&oacute;n <strong>now<\/strong>, como comentamos anteriormente.<\/p><pre class=\"wp-block-preformatted\">shutdown &ndash;r now<\/pre><p>Para programar un reinicio del sistema, escribe el siguiente comando y presiona enter:<\/p><pre class=\"wp-block-preformatted\">shutdown &ndash;r hh:mm<\/pre><p>Para reiniciar el equipo despu&eacute;s de unos minutos u horas, escribe el siguiente comando y presiona enter:<\/p><pre class=\"wp-block-preformatted\">shutdown &ndash;r +m<\/pre><p>Recuerda, aqu&iacute; <strong>m<\/strong> indica minutos. Solo especifica la cantidad de minutos.<\/p><p>Para mostrar un mensaje a las personas que han iniciado sesi&oacute;n con tu servidor antes de que se reinicie, escribe el siguiente comando y presiona enter:<\/p><pre class=\"wp-block-preformatted\">Shutdown -r +m \"Guarde su trabajo, la PC se reiniciar&aacute; en 5 minutos\"<\/pre><p>Te dejamos algunas opciones adicionales del comando de Linux Shutdown con las que puedes familiarizarte:<\/p><ul class=\"wp-block-list\">\n<li>-poweroff, -P: Apaga el sistema (apagando tambi&eacute;n la unidad)<\/li>\n\n\n\n<li>-reboot, -r: reinicia el sistema.<\/li>\n\n\n\n<li>-halt, -h: Detiene la m&aacute;quina despu&eacute;s de terminar los procesos.<\/li>\n<\/ul><p>Tambi&eacute;n puedes apagar el sistema usando las opciones de detener (halt) y apagar (poweroff) usando el siguiente comando:<\/p><pre class=\"wp-block-preformatted\">shutdown &ndash;h<\/pre><p>Para detener el uso:<\/p><pre class=\"wp-block-preformatted\">shutdown &ndash;p<\/pre><p>En los comandos anteriores, tambi&eacute;n puedes especificar la hora y luego el mensaje a mostrar despu&eacute;s del argumento de la opci&oacute;n.<\/p><h2 class=\"wp-block-heading\" id=\"h-cancelar-un-comando-de-apagado-programado-en-linux\">Cancelar un comando de apagado programado en Linux<\/h2><p>Para cancelar un apagado programado o un reinicio de tu PC, simplemente escribe el siguiente comando antes de llegar a la hora programada para que se apague la PC.<\/p><pre class=\"wp-block-preformatted\">shutdown &ndash;c<\/pre><p>Este comando cancelar&aacute; inmediatamente la acci&oacute;n programada de apagado o reinicio. Ten en cuenta que no puedes usar este comando si usaste <strong>+0<\/strong> en la l&iacute;nea de comando o <strong>now<\/strong>.<\/p><figure class=\"wp-block-image size-large\"><a href=\"\/es\/servidor-vps\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=1024,h=1024,fit=scale-down\" alt=\"\" class=\"wp-image-29287\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=768,fit=scale-down 768w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2023\/02\/ES-VPS-hosting_in-text-banner.png\/w=1536,fit=scale-down 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><h2 class=\"wp-block-heading\" id=\"h-conclusion\">Conclusi&oacute;n<\/h2><p>Esperamos que este art&iacute;culo te haya ayudado a saber c&oacute;mo usar el comando Shutdown de Linux y sus opciones para realizar el apagado de tu sistema. Si a&uacute;n tienes dudas o te ha surgido alguna confusi&oacute;n durante el tutorial, h&aacute;znoslo saber para que podamos ayudarte a resolverlo.<\/p><p>\n\n\n\n<div class=\"protip\">\n                    <p class=\"title\">Descubre otros comandos de Linux<\/p>\n                    <p><a href=\"\/es\/tutoriales\/espacio-en-el-disco-linux\/\">C&oacute;mo comprobar el espacio en disco<\/a><br><a href=\"\/es\/tutoriales\/comando-curl\/\">C&oacute;mo transferir datos con el comando Curl<\/a><br><a href=\"\/es\/tutoriales\/comando-linux-time\/\">C&oacute;mo calcular la ejecuci&oacute;n de procesos con el comando Time<\/a><br><a href=\"\/es\/tutoriales\/comando-scp\/\">C&oacute;mo transferir archivos usando el comando Scp<\/a><br><a href=\"\/es\/tutoriales\/rsync-linux\/\">C&oacute;mo transferir y sincronizar datos con Rsync<\/a><br><a href=\"\/es\/tutoriales\/cancelar-proceso-comando-kill-linux\/\">C&oacute;mo cancelar un proceso en Linux<\/a><\/p>\n                <\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los sistemas operativos m&aacute;s populares te permiten apagar tu PC o computadora port&aacute;til usando diferentes m&eacute;todos. Los sistemas operativos Linux tambi&eacute;n tienen formas para que un usuario apague, reinicie, hiberne o suspenda de manera segura su m&aacute;quina basada en Unix. En este tutorial te mostraremos c&oacute;mo usar de manera segura el comando Shutdown de Linux [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/es\/tutoriales\/comando-shutdown-linux\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":138,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_title":"Comando shutdown de Linux: c\u00f3mo apagar o reiniciar el sistema","rank_math_description":"En este tutorial te mostramos c\u00f3mo reiniciar y apagar tu sistema Ubuntu o CentOS con el comando Shutdown de Linux. \u00a1Aprende con Hostinger!","rank_math_focus_keyword":"shutdown linux","footnotes":""},"categories":[5700],"tags":[],"class_list":["post-9096","post","type-post","status-publish","format-standard","hentry","category-vps"],"hreflangs":[{"locale":"en-US","link":"https:\/\/www.hostinger.com\/tutorials\/linux-shutdown-command","default":0},{"locale":"fr-FR","link":"https:\/\/www.hostinger.com\/fr\/tutoriels\/commande-shutdown-de-linux","default":0},{"locale":"es-ES","link":"https:\/\/www.hostinger.com\/es\/tutoriales\/comando-shutdown-linux","default":0},{"locale":"id-ID","link":"https:\/\/www.hostinger.com\/id\/tutorial\/perintah-shutdown-linux","default":0},{"locale":"ja-JP","link":"https:\/\/www.hostinger.com\/jp\/tutorials\/linux-shutdown-command","default":0},{"locale":"en-GB","link":"https:\/\/www.hostinger.com\/uk\/tutorials\/linux-shutdown-command","default":0},{"locale":"en-MY","link":"https:\/\/www.hostinger.com\/my\/tutorials\/linux-shutdown-command\/","default":0},{"locale":"en-PH","link":"https:\/\/www.hostinger.com\/ph\/tutorials\/linux-shutdown-command\/","default":0},{"locale":"es-MX","link":"https:\/\/www.hostinger.com\/mx\/tutoriales\/comando-shutdown-linux","default":0},{"locale":"es-CO","link":"https:\/\/www.hostinger.com\/co\/tutoriales\/comando-shutdown-linux","default":0},{"locale":"es-AR","link":"https:\/\/www.hostinger.com\/ar\/tutoriales\/comando-shutdown-linux","default":0},{"locale":"en-IN","link":"https:\/\/www.hostinger.com\/in\/tutorials\/linux-shutdown-command","default":0},{"locale":"en-CA","link":"https:\/\/www.hostinger.com\/ca\/tutorials\/linux-shutdown-command","default":0},{"locale":"en-AU","link":"https:\/\/www.hostinger.com\/au\/tutorials\/linux-shutdown-command","default":0},{"locale":"en-NG","link":"https:\/\/www.hostinger.com\/ng\/tutorials\/linux-shutdown-command","default":0}],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/posts\/9096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/users\/138"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/comments?post=9096"}],"version-history":[{"count":15,"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/posts\/9096\/revisions"}],"predecessor-version":[{"id":46361,"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/posts\/9096\/revisions\/46361"}],"wp:attachment":[{"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/media?parent=9096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/categories?post=9096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/tags?post=9096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}