{"id":8458,"date":"2019-05-06T14:49:03","date_gmt":"2019-05-06T14:49:03","guid":{"rendered":"https:\/\/blog.hostinger.io\/es-tutoriales\/?p=8458"},"modified":"2025-12-18T22:36:50","modified_gmt":"2025-12-18T21:36:50","slug":"que-es-widget-wordpress","status":"publish","type":"post","link":"\/es\/tutoriales\/que-es-widget-wordpress\/","title":{"rendered":"\u00bfQu\u00e9 son los widgets de WordPress y c\u00f3mo crearlos?"},"content":{"rendered":"<p>Los widgets de WordPress son objetos PHP que pueden ayudarte a a&ntilde;adir f&aacute;cilmente contenido o funciones a tu sitio web sin codificar.&nbsp;<\/p><p>Puedes utilizar widgets integrados, de terceros o personalizados para diversos fines, como integrar feeds de redes sociales, mostrar entradas recientes del blog o a&ntilde;adir un formulario de contacto.<\/p><p>En este art&iacute;culo, veremos todo lo que necesitas saber sobre los widgets de WordPress, incluidos sus conceptos b&aacute;sicos y c&oacute;mo encontrar widgets preinstalados.&nbsp;<\/p><p>Tambi&eacute;n te explicaremos c&oacute;mo aplicarlos a tu sitio, crear nuevos widgets desde cero y personalizarlos para adaptarlos a tus necesidades espec&iacute;ficas.<\/p><p class=\"has-text-align-center\"><a href=\"https:\/\/assets.hostinger.com\/content\/tutorials\/pdf\/Mega-WordPress-Cheat-ES.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Descarga la hoja de trucos de WordPress definitiva<\/a><\/p><h2 class=\"wp-block-heading\" id=\"h-donde-encontrar-widgets-en-wordpress\">&iquest;D&oacute;nde encontrar widgets en WordPress?<\/h2><p>Si utilizas un <strong>tema cl&aacute;sico<\/strong>, sigue estos pasos para acceder al &aacute;rea de widgets de tu sitio web WordPress:<\/p><ol class=\"wp-block-list\">\n<li>Accede a tu panel de control de WordPress.<\/li>\n\n\n\n<li>Aseg&uacute;rate de que el plugin <a href=\"https:\/\/es.wordpress.org\/plugins\/classic-widgets\/\" target=\"_blank\" rel=\"noreferrer noopener\">Classic Widgets<\/a> est&aacute; instalado y activado.<\/li>\n\n\n\n<li>Busca y haz clic en <strong>Apariencia <\/strong>en la barra lateral izquierda.<\/li>\n\n\n\n<li>Selecciona <strong>Widgets<\/strong>.<\/li>\n<\/ol><figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"630\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/widgets-wordpress.png\/w=1024,h=1024,fit=scale-down\" alt=\"\" class=\"wp-image-42507\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/widgets-wordpress.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/widgets-wordpress.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/widgets-wordpress.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/widgets-wordpress.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><p>Ver&aacute;s los <strong>Widgets disponibles <\/strong>en la parte izquierda de la pantalla. Estos son los widgets que puedes a&ntilde;adir directamente a tu sitio.<\/p><p>En el lado derecho, ver&aacute;s las &aacute;reas de widgets o barras laterales, que suelen incluir la barra lateral, el pie de p&aacute;gina y la cabecera.&nbsp;<\/p><p>Las &aacute;reas de widgets disponibles depender&aacute;n del tema cl&aacute;sico de WordPress que hayas elegido.<\/p><p>Si utilizas un <strong>tema de bloques<\/strong>, puedes encontrar widgets en el Editor de sitios, P&aacute;ginas o Entradas. Simplemente despliega el <strong>insertador de bloques <\/strong>o el bot&oacute;n <strong>+ <\/strong>en la esquina superior izquierda de la pantalla y despl&aacute;zate hacia abajo para ver los widgets disponibles.<\/p><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"686\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/editor-bloques-wp.png\/public\" alt=\"Editor de bloques de WP\" class=\"wp-image-42508\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/editor-bloques-wp.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/editor-bloques-wp.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/editor-bloques-wp.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/editor-bloques-wp.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><h2 class=\"wp-block-heading\" id=\"h-como-anadir-un-widget-en-wordpress\">C&oacute;mo a&ntilde;adir un widget en WordPress<\/h2><p>Hay muchos widgets listos para usar que puedes a&ntilde;adir a tu sitio de WordPress. Algunos est&aacute;n convenientemente integrados en el propio WordPress y otros puedes conseguirlos <a href=\"\/es\/tutoriales\/plugins-en-wordpress-gratis\/\">instalando plugins<\/a>. Repasemos ambas opciones.<\/p><h3 class=\"wp-block-heading\">A&ntilde;adir widgets integrados a tu sitio web<\/h3><p>Si utilizas un <strong>tema cl&aacute;sico<\/strong>, sigue estos pasos para a&ntilde;adir cualquiera de los widgets preinstalados a tu sitio web WordPress:<\/p><ol class=\"wp-block-list\">\n<li>Desde el panel de administraci&oacute;n de WordPress, ve a <strong>Apariencia &rarr; Widgets.<\/strong><\/li>\n\n\n\n<li>Elige una opci&oacute;n de los <strong>Widgets disponibles <\/strong>y arr&aacute;strala a la zona preferida del lado derecho. Por ejemplo, a&ntilde;adiremos un widget de <strong>Entradas recientes <\/strong>a la <strong>Barra de pie de p&aacute;gina 1<\/strong>.<\/li>\n\n\n\n<li>Personaliza el widget introduciendo un <strong>T&iacute;tulo <\/strong>y especificando el <strong>N&uacute;mero de entradas a mostrar<\/strong>. Tambi&eacute;n tienes la opci&oacute;n de mostrar la fecha de publicaci&oacute;n.<\/li>\n\n\n\n<li>Cuando hayas terminado de personalizar, haz clic en <strong>Guardar<\/strong>.<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-medium\"><img decoding=\"async\" width=\"732\" height=\"650\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/widget-entradas-recientes.png\/w=300,h=300,fit=scale-down\" alt=\"Widget entradas recientes de WordPress\" class=\"wp-image-42509\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/widget-entradas-recientes.png\/w=732,fit=scale-down 732w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/widget-entradas-recientes.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/widget-entradas-recientes.png\/w=150,fit=scale-down 150w\" sizes=\"(max-width: 732px) 100vw, 732px\" \/><\/figure>\n<\/div><p>As&iacute; es como se ver&iacute;a el widget en el sitio web.<\/p><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"102\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/image-102.png\/public\" alt=\"Ejemplo de widget en sitio web de WP\" class=\"wp-image-42510\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/image-102.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/image-102.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/image-102.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/image-102.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><p>Si utilizas un <strong>tema en bloque<\/strong>, sigue estos pasos para a&ntilde;adir cualquiera de los widgets preinstalados a tu sitio web WordPress:<\/p><ol class=\"wp-block-list\">\n<li>Desde el panel de administraci&oacute;n de WordPress, ve a <strong>Apariencia &rarr; Editor.<\/strong><\/li>\n\n\n\n<li>En la vista previa del sitio web, selecciona el &aacute;rea de widgets que prefieras. En este ejemplo, seleccionaremos el <strong>Pie de p&aacute;gina<\/strong>.<\/li>\n\n\n\n<li>Haz clic en el bot&oacute;n <strong>+ <\/strong>y despl&aacute;zate hacia abajo hasta que encuentres la categor&iacute;a <strong>Widgets<\/strong>. Como ejemplo, seleccionaremos el widget <strong>&Uacute;ltimas entradas<\/strong>.<\/li>\n\n\n\n<li>El widget aparecer&aacute; en el &aacute;rea de previsualizaci&oacute;n. Puedes personalizar su alineaci&oacute;n y decidir si quieres que los enlaces se muestren en una vista de lista o de cuadr&iacute;cula.<\/li>\n\n\n\n<li>Cuando hayas terminado de personalizar, haz clic en <strong>Guardar<\/strong>.<\/li>\n<\/ol><p>As&iacute; es como se ver&iacute;a el widget en el sitio web.<\/p><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"165\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/image-103.png\/public\" alt=\"Ejemplo de sitio web de WordPress con un widget\" class=\"wp-image-42511\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/image-103.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/image-103.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/image-103.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/image-103.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><h3 class=\"wp-block-heading\">A&ntilde;adir widgets a tu sitio mediante plugins<\/h3><p>Tambi&eacute;n puedes a&ntilde;adir un widget a tu sitio instalando un plugin de terceros que lo ofrezca.&nbsp;<\/p><p>Por ejemplo, utilizaremos el plugin <a href=\"https:\/\/es.wordpress.org\/plugins\/raratheme-companion\/\" target=\"_blank\" rel=\"noreferrer noopener\">RaraTheme Companion<\/a>, que a&ntilde;ade 23 widgets adicionales para ayudarte a personalizar a&uacute;n m&aacute;s tu tema de WordPress. Sin embargo, ten en cuenta que algunos de estos plugins de widgets s&oacute;lo son compatibles con temas cl&aacute;sicos.<\/p><p>Sigue estos pasos:<\/p><ol class=\"wp-block-list\">\n<li>Aseg&uacute;rate de que <strong>RaraTheme Companion <\/strong>est&aacute; instalado y activado.&nbsp;<\/li>\n\n\n\n<li>Ve a <strong>Apariencia &rarr; Widgets<\/strong>. Ver&aacute;s m&aacute;s opciones en <strong>Widgets disponibles<\/strong>.<\/li>\n<\/ol><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"787\" height=\"1200\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/widgets-raratheme-companion.png\/public\" alt=\"Ventana de widgets disponibles de WordPress\" class=\"wp-image-42512\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/widgets-raratheme-companion.png\/w=787,fit=scale-down 787w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/widgets-raratheme-companion.png\/w=197,fit=scale-down 197w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/widgets-raratheme-companion.png\/w=672,fit=scale-down 672w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/widgets-raratheme-companion.png\/w=98,fit=scale-down 98w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/widgets-raratheme-companion.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 787px) 100vw, 787px\" \/><\/figure><ol class=\"wp-block-list\" start=\"3\">\n<li>Elige el widget que quieras a&ntilde;adir y arr&aacute;stralo a la zona de widgets que prefieras. Por ejemplo, vamos a a&ntilde;adir el widget <strong>Biograf&iacute;a del autor <\/strong>al <strong>Pie de p&aacute;gina<\/strong>.<\/li>\n\n\n\n<li>Personaliza el widget. Puedes a&ntilde;adir un t&iacute;tulo, el nombre del autor, una foto y muchas cosas m&aacute;s.<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"744\" height=\"956\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/editar-widget.png\/public\" alt=\"Editar widget en WordPress\" class=\"wp-image-42513\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/editar-widget.png\/w=744,fit=scale-down 744w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/editar-widget.png\/w=233,fit=scale-down 233w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/editar-widget.png\/w=117,fit=scale-down 117w\" sizes=\"(max-width: 744px) 100vw, 744px\" \/><\/figure>\n<\/div><ol class=\"wp-block-list\" start=\"5\">\n<li>Haz clic en <strong>Guardar <\/strong>cuando hayas terminado.<\/li>\n<\/ol><p>&iexcl;Listo! El widget del plugin ya deber&iacute;a estar activo en tu sitio.<\/p><h2 class=\"wp-block-heading\" id=\"h-como-personalizar-los-widgets-de-wordpress-con-css\">C&oacute;mo personalizar los widgets de WordPress con CSS<\/h2><p>Dependiendo de tu tema, puedes personalizar los widgets a trav&eacute;s del panel de control de WordPress o del Editor de Sitios. Sin embargo, el nivel de personalizaci&oacute;n puede ser limitado para algunos.<\/p><p>Si quieres un estilo m&aacute;s avanzado y te sientes c&oacute;modo con los conceptos b&aacute;sicos de HTML y CSS, puedes <a href=\"\/es\/tutoriales\/anadir-css-personalizado-wordpress\/\">a&ntilde;adir CSS personalizado a WordPress<\/a>. A continuaci&oacute;n te explicamos c&oacute;mo:<\/p><ol class=\"wp-block-list\">\n<li>En el Editor, selecciona el widget al que quieras a&ntilde;adir CSS personalizado.<\/li>\n\n\n\n<li>En la barra lateral derecha, cambia a la pesta&ntilde;a <strong>Bloque <\/strong>y despl&aacute;zate hacia abajo hasta que encuentres <strong>Avanzado.<\/strong><\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"386\" height=\"1200\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/opciones-de-bloque-en-wp.png\/w=1024,h=1024,fit=scale-down\" alt=\"Opciones de bloque en el Editor de WordPress\" class=\"wp-image-42514\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/opciones-de-bloque-en-wp.png\/w=386,fit=scale-down 386w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/opciones-de-bloque-en-wp.png\/w=329,fit=scale-down 329w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/opciones-de-bloque-en-wp.png\/w=48,fit=scale-down 48w\" sizes=\"(max-width: 386px) 100vw, 386px\" \/><\/figure>\n<\/div><ol class=\"wp-block-list\" start=\"3\">\n<li>Especifica un nombre de clase CSS en la barra <strong>CLASE(S) CSS ADICIONAL(ES) <\/strong>y pulsa <strong>Actualizar. <\/strong>Utilizar&aacute;s esta clase personalizada para especificar el nuevo CSS de tu widget.<\/li>\n\n\n\n<li>Vuelve al panel de administraci&oacute;n y ve a <strong>Apariencia &rarr; Personalizar &rarr; CSS adicional.<\/strong><\/li>\n\n\n\n<li>Aparecer&aacute; un cuadro de texto donde a&ntilde;adir&aacute;s el estilo CSS. Por ejemplo, aqu&iacute; se muestra c&oacute;mo a&ntilde;adir un color de fondo para tu widget. Observa que el <strong>widget <\/strong>en el CSS de abajo significa la clase personalizada que definimos en el paso anterior.<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"508\" height=\"1012\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/personalizacion-css.png\/public\" alt=\"Seccion de personalizacon de CSS adicional en WordPress\" class=\"wp-image-42515\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/personalizacion-css.png\/w=508,fit=scale-down 508w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/personalizacion-css.png\/w=151,fit=scale-down 151w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/32\/2024\/09\/personalizacion-css.png\/w=75,fit=scale-down 75w\" sizes=\"(max-width: 508px) 100vw, 508px\" \/><\/figure>\n<\/div><ol class=\"wp-block-list\" start=\"6\">\n<li>Cuando hayas terminado, haz clic en <strong>Guardar.<\/strong><\/li>\n<\/ol><p>Eso es todo lo que tienes que hacer. El CSS adicional se aplicar&aacute; ahora a tu widget.<\/p><h2 class=\"wp-block-heading\" id=\"h-como-crear-un-nuevo-widget-en-wordpress\">C&oacute;mo crear un nuevo widget en WordPress<\/h2><p>Aunque hay muchos widgets listos para usar integrados en WordPress y en plugins de terceros, crear un nuevo widget personalizado puede ser &uacute;til si tienes una necesidad muy espec&iacute;fica.<\/p><p>Los siguientes pasos te guiar&aacute;n sobre <a href=\"\/es\/tutoriales\/crear-widgets-wordpress-personalizados\/\">c&oacute;mo crear un widget en WordPress<\/a>. Para ayudarte a visualizar mejor el proceso, crearemos un widget sencillo para a&ntilde;adir un bloque de contenido a la barra lateral o al &aacute;rea de widgets de tu sitio.<\/p><h3 class=\"wp-block-heading\">1. Crea el archivo del plugin del widget<\/h3><p>Primero, crea un nuevo directorio llamado <strong>mi-widget-personalizado. <\/strong>Dentro del directorio, crea un nuevo archivo llamado <strong>mi-widget-personalizado.php. <\/strong>Este archivo contendr&aacute; el c&oacute;digo de tu widget.<\/p><p>Ahora, abre el archivo en un editor de texto y copia y pega el c&oacute;digo que aparece a continuaci&oacute;n.&nbsp;<\/p><p>Este c&oacute;digo crear&aacute; la cabecera del plugin, que proporciona metadatos sobre el plugin. Incluye el nombre del plugin, la descripci&oacute;n, la versi&oacute;n y el autor.&nbsp;<\/p><p>Tambi&eacute;n tiene una medida de seguridad que impide que el c&oacute;digo del plugin se ejecute fuera de los sitios web de WordPress.<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">&lt;?php\n\n\/*\n\nPlugin Name: My Widget Personalizado\n\nDescription: Un widget simple de ejemplo\n\nVersion: 1.0\n\nAuthor: Diego Vargas\n\n*\/\n\n\/\/ Ensure this file is being included by WordPress.\n\ndefined('ABSPATH') or die('No script kiddies please!')<\/pre><p>A continuaci&oacute;n, crearemos la clase <strong>My_Custom_Widget<\/strong>. Esta clase define un widget personalizado de WordPress que extiende la clase <strong>WP_Widget<\/strong>. Estas son las funciones esenciales de este widget:<\/p><ul class=\"wp-block-list\">\n<li><strong>__construct():<\/strong> inicializa el widget de WordPress con un identificador &uacute;nico, un nombre y una descripci&oacute;n.<\/li>\n\n\n\n<li><strong>widget():<\/strong> muestra el contenido del widget en el front-end, incluyendo un t&iacute;tulo si lo has establecido en la configuraci&oacute;n del widget. A continuaci&oacute;n aparece un mensaje por defecto: &ldquo;&iexcl;Hola, mundo!&rdquo;.<\/li>\n\n\n\n<li><strong>form():<\/strong> genera el formulario de configuraci&oacute;n del widget en el &aacute;rea de administraci&oacute;n, permitiendo a los usuarios establecer un t&iacute;tulo personalizado para su widget.&nbsp;<\/li>\n\n\n\n<li><strong>update():<\/strong> guarda la configuraci&oacute;n del widget en la base de datos.<\/li>\n<\/ul><p>Las funciones <strong>__construct() <\/strong>y <strong>widget() <\/strong>son obligatorias para definir un plugin de widget.<\/p><p>Aunque t&eacute;cnicamente es posible omitir las funciones <strong>form() <\/strong>y <strong>update() <\/strong>si tu widget no tiene opciones, la mejor pr&aacute;ctica es incluirlas, aunque se mantengan vac&iacute;as.<\/p><p>Ahora, sigue adelante y copia y pega el siguiente c&oacute;digo en el mismo archivo PHP.<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">class My_Custom_Widget extends WP_Widget {\n\n\/\/ Constructor\n\nfunction __construct() {\n\n&nbsp; parent::__construct(\n\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 'my_custom_widget', \/\/ Base ID\n\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; __('My Custom Widget', 'text_domain'), \/\/ Name\n\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; array('description' =&gt; __('A Custom Widget', 'text_domain'),) \/\/ Args\n\n&nbsp; );\n\n}\n\n\/\/ The widget() method to display the widget content on the front-end\n\npublic function widget($args, $instance) {\n\n&nbsp; echo $args['before_widget'];\n\n&nbsp; if (!empty($instance['title'])) {\n\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; echo $args['before_title'] . apply_filters('widget_title', $instance['title']) . $args['after_title'];\n\n&nbsp; }\n\n&nbsp; echo __('Hola, mundo!', 'text_domain');\n\n&nbsp; echo $args['after_widget'];\n\n}\n\n\/\/ The form() method to create the widget settings form in the admin area\n\npublic function form($instance) {\n\n&nbsp; $title = !empty($instance['title']) ? $instance['title'] : __('New title', 'text_domain');\n\n&nbsp; ?&gt;\n\n&nbsp; &lt;p&gt;\n\n&nbsp; &lt;label for=\"&lt;?php echo $this-&gt;get_field_id('title'); ?&gt;\"&gt;&lt;?php _e('Title:'); ?&gt;&lt;\/label&gt;\n\n&nbsp; &lt;input class=\"widefat\" id=\"&lt;?php echo $this-&gt;get_field_id('title'); ?&gt;\" name=\"&lt;?php echo $this-&gt;get_field_name('title'); ?&gt;\" type=\"text\" value=\"&lt;?php echo esc_attr($title); ?&gt;\"&gt;\n\n&nbsp; &lt;\/p&gt;\n\n&nbsp; &lt;?php\n\n}\n\n\/\/ The update() method to save the widget settings\n\npublic function update($new_instance, $old_instance) {\n\n&nbsp; $instance = array();\n\n&nbsp; $instance['title'] = (!empty($new_instance['title'])) ? strip_tags($new_instance['title']) : '';\n\n&nbsp; return $instance;\n\n}\n\n}<\/pre><p>Por &uacute;ltimo, a&ntilde;ade el siguiente c&oacute;digo a tu archivo. Este c&oacute;digo se encarga de registrar el widget. Con esto, el archivo del plugin est&aacute; completo.<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">\/\/ Register the widget\n\nfunction register_my_custom_widget() {\n\nregister_widget('My_Custom_Widget');\n\n}\n\nadd_action('widgets_init', 'register_my_custom_widget');<\/pre><h3 class=\"wp-block-heading\">2. Crea un archivo y s&uacute;belo<\/h3><p>Una vez que el archivo PHP de tu plugin est&eacute; listo, crea un archivo ZIP del directorio <strong>Mi-widget-personalizado<\/strong>.<\/p><p>A continuaci&oacute;n, accede al panel de control de WordPress y ve a <strong>Plugins &rarr; A&ntilde;adir nuevo plugin. <\/strong>Sube el archivo ZIP y espera hasta que se instale el plugin.<\/p><p>Por &uacute;ltimo, ve a <strong>Plugins &rarr; Plugins instalados<\/strong>, despl&aacute;zate hacia abajo hasta que veas <strong>Mi widget personalizado <\/strong>en el &aacute;rea de widgets y haz clic en <strong>Activar.<\/strong><\/p><h3 class=\"wp-block-heading\">3. A&ntilde;ade el widget a una barra lateral de WordPress<\/h3><p>Para a&ntilde;adir el widget personalizado que acabas de hacer a una barra lateral, ve a <strong>Apariencia &rarr; Widgets.<\/strong><\/p><p>A continuaci&oacute;n, selecciona la barra lateral en la que quieres colocar el widget. Haz clic en el icono<strong> + <\/strong>y, a continuaci&oacute;n, busca <strong>Mi widget personalizado <\/strong>en la barra de b&uacute;squeda. Cuando aparezca el widget, haz clic en &eacute;l.<\/p><p>A continuaci&oacute;n, puedes establecer el t&iacute;tulo del widget y la visibilidad preferida.<\/p><p>Por &uacute;ltimo, haz clic en <strong>Actualizar <\/strong>en la parte superior derecha de la pantalla. Eso es todo: el nuevo widget ya est&aacute; instalado y puedes a&ntilde;adirlo a tu sitio de WordPress.<\/p><h2 class=\"wp-block-heading\" id=\"h-10-ejemplos-de-widgets-populares-en-wordpress\">10 ejemplos de widgets populares en WordPress<\/h2><p>WordPress ofrece cientos de widgets integrados y de terceros. En esta secci&oacute;n, hablaremos de diez opciones populares que pueden a&ntilde;adir funciones &uacute;tiles a tu sitio web y mejorar su experiencia de usuario.<\/p><h3 class=\"wp-block-heading\">&Uacute;ltimas entradas<\/h3><p>Por algo se considera uno de los widgets cl&aacute;sicos. Como su nombre indica, destaca las &uacute;ltimas entradas de tu blog, manteniendo a los visitantes informados sobre tu contenido m&aacute;s reciente y llev&aacute;ndoles potencialmente a explorar m&aacute;s tu sitio.<\/p><h3 class=\"wp-block-heading\">Lista de categor&iacute;as<\/h3><p>El widget Lista de categor&iacute;as es otra opci&oacute;n integrada que enumera todas las categor&iacute;as de tu blog. Ayuda a los visitantes a navegar r&aacute;pidamente por el contenido que m&aacute;s les interesa.<\/p><h3 class=\"wp-block-heading\">Nube de etiquetas<\/h3><p>El widget Nube de etiquetas muestra tus etiquetas m&aacute;s utilizadas en un formato de nube, facilitando a los visitantes ver sobre qu&eacute; temas escribes con frecuencia.&nbsp;<\/p><p>Cuanto m&aacute;s a menudo utilices una etiqueta, mayor ser&aacute; el tama&ntilde;o de la fuente, lo que har&aacute; que destaque.<\/p><h3 class=\"wp-block-heading\">Iconos sociales<\/h3><p>Este widget muestra iconos vinculados a tus perfiles en las redes sociales, ayudando a los visitantes a conectar f&aacute;cilmente contigo en otras plataformas.&nbsp;<\/p><p>Puedes personalizar los colores, el tama&ntilde;o y la alineaci&oacute;n de los iconos para adaptarlos a tu tema de WordPress.<\/p><h3 class=\"wp-block-heading\">HTML personalizado<\/h3><p>Este widget integrado te permite a&ntilde;adir c&oacute;digo HTML a tus &aacute;reas de widgets.&nbsp;<\/p><p>Es ideal para desarrolladores y usuarios avanzados que quieran a&ntilde;adir funciones personalizadas o elementos de dise&ntilde;o a su sitio.<\/p><h3 class=\"wp-block-heading\">Archivos<\/h3><p>El widget de archivos se puede utilizar para mostrar un archivo de fechas de tus entradas. Esta funci&oacute;n permite a los visitantes navegar por contenidos antiguos de tu sitio.<\/p><h3 class=\"wp-block-heading\">Jetpack Search<\/h3><p><a href=\"https:\/\/es.wordpress.org\/plugins\/jetpack-search\/\" target=\"_blank\" rel=\"noreferrer noopener\">Jetpack Search<\/a> funciona con Elasticsearch, un potente motor de b&uacute;squeda. Incluye varias funciones &uacute;tiles, como la indexaci&oacute;n autom&aacute;tica de todas las publicaciones y p&aacute;ginas p&uacute;blicas.<\/p><h3 class=\"wp-block-heading\">Preguntas frecuentes de RaraTheme Companion<\/h3><p>Un widget de terceros ofrecido por <a href=\"https:\/\/es.wordpress.org\/plugins\/raratheme-companion\/\" target=\"_blank\" rel=\"noreferrer noopener\">RaraTheme Companion<\/a> que a&ntilde;ade una secci&oacute;n de preguntas frecuentes a tu sitio.&nbsp;<\/p><p>Puedes especificar las preguntas y respuestas directamente desde el widget del formulario, as&iacute; como personalizar la visibilidad y otros aspectos.<\/p><h3 class=\"wp-block-heading\">WPForms<\/h3><p>El widget <a href=\"https:\/\/es.wordpress.org\/plugins\/wpforms-lite\/\" target=\"_blank\" rel=\"noreferrer noopener\">WPForms<\/a> es una opci&oacute;n de terceros que te permite a&ntilde;adir f&aacute;cilmente formularios de contacto, encuestas, formularios de pago o formularios de registro a tu barra lateral o a otras &aacute;reas de widgets.<\/p><h3 class=\"wp-block-heading\">WP Go Maps<\/h3><p>El widget <a href=\"https:\/\/es.wordpress.org\/plugins\/wp-google-maps\/\" target=\"_blank\" rel=\"noreferrer noopener\">WP Go Maps<\/a> viene con el popular plugin de mapas. Ofrece a los visitantes de tu sitio web un c&oacute;modo acceso a una ubicaci&oacute;n espec&iacute;fica en Google Maps.&nbsp;<\/p><p>Puedes personalizar la apariencia del mapa, establecer una ubicaci&oacute;n predeterminada, a&ntilde;adir varios pines, crear marcadores utilizando texto e im&aacute;genes, y muchas cosas m&aacute;s.<\/p><h2 class=\"wp-block-heading\" id=\"h-consejos-para-gestionar-los-widgets-de-wordpress\">Consejos para gestionar los widgets de WordPress<\/h2><p>Los widgets son una forma fant&aacute;stica de a&ntilde;adir caracter&iacute;sticas y funcionalidades a tu sitio web. Sin embargo, cada funci&oacute;n que a&ntilde;ades tiene un coste para los tiempos de carga de la p&aacute;gina, la capacidad de respuesta y la simplicidad visual de la interfaz de usuario de tu sitio web.<\/p><p>Estos costes pueden parecer min&uacute;sculos si se consideran individualmente. Por ejemplo, puede que tu nuevo widget de redes sociales s&oacute;lo a&ntilde;ada un milisegundo a los tiempos de carga de tu p&aacute;gina. Pero cuantos m&aacute;s widgets a&ntilde;adas, m&aacute;s pueden entorpecer el rendimiento de tu sitio.<\/p><p>Aunque no hay un l&iacute;mite estricto para el n&uacute;mero de widgets que puedes ejecutar, s&oacute;lo debes a&ntilde;adir los widgets que realmente necesites para mantener el rendimiento de tu sitio web y la experiencia del usuario.&nbsp;<\/p><p>Normalmente, <strong>hasta cinco widgets <\/strong>son suficientes para la mayor&iacute;a de los sitios web.<\/p><p>Ten en cuenta que hay otros factores importantes que afectan al rendimiento de tu sitio web, como tu proveedor de alojamiento. Puesto que el alojamiento web es la base de tu sitio, es importante elegir un proveedor que est&eacute; bien optimizado para WordPress.<\/p><p>Recomendados por WordPress.org, los planes de alojamiento WordPress Gestionado de Hostinger ofrecen un conjunto de funciones de optimizaci&oacute;n para garantizar el m&aacute;ximo rendimiento de tu sitio web.<\/p><figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-qw.googleusercontent.com\/docsz\/AD_4nXcdKKPIqK0QQQDwD2vFGjfIhwsjugC5XYc8m-_SD0Ed5YJ6e_8_OpWionfBcrHInl4--xtfUg6HdlkHcJK_4AlnIrC7HOmlPsan-_buxdBfErKB5hRacJAgaxOkRuu-BpzISoq8KI5TnUQtemc-FfQDpuTyIvYI7Uwci07hg2Rz5q_18KG8ew?key=3ufJC65WF8v7VhzJF9IfTQ\" alt=\"\"><\/figure><p>Aqu&iacute; tienes otras buenas pr&aacute;cticas para mantener tu sitio web lo m&aacute;s limpio e intuitivo posible mientras utilizas widgets.<\/p><ul class=\"wp-block-list\">\n<li><strong>Organiza tus widgets<\/strong>: utiliza varias &aacute;reas de widgets e intenta mantenerlos organizados de forma l&oacute;gica. Por ejemplo, utiliza la barra lateral para la navegaci&oacute;n y el pie de p&aacute;gina para la informaci&oacute;n adicional.<\/li>\n\n\n\n<li><strong>Previsualiza tus cambios<\/strong>: antes de publicar los widgets en tu sitio, utiliza la opci&oacute;n de <strong>previsualizaci&oacute;n en vivo <\/strong>del personalizador para asegurarte de que tienen el aspecto y funcionan como esperas.<\/li>\n\n\n\n<li><strong>Actualiza regularmente los plugins<\/strong>: los widgets son una clase especial de plugins en el entorno WordPress. Debes mantener siempre actualizados tus plugins para garantizar la compatibilidad y seguridad de tus widgets.&nbsp;<\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-conclusion\">Conclusi&oacute;n<\/h2><p>Los widgets de WordPress son una forma estupenda de personalizar el dise&ntilde;o y la funcionalidad de tu sitio.&nbsp;<\/p><p>Desde mostrar entradas recientes del blog e iconos de redes sociales hasta integrar formularios de contacto y mostrar testimonios, puedes hacerlo todo con los widgets de WordPress.<\/p><p>En esta gu&iacute;a, has aprendido d&oacute;nde encontrar widgets de WordPress, as&iacute; como a a&ntilde;adirlos a tu sitio web y personalizarlos.&nbsp;<\/p><p>Tambi&eacute;n hemos examinado algunos de los widgets de WordPress m&aacute;s populares del mercado, incluidas las opciones integradas en WordPress y las de terceros, como RaraTheme Companion y Jetpack Search.<\/p><p>Si te sientes creativo, puedes probar a crear tu propio widget. Todo lo que hace falta es un poco de conocimiento de CSS y la gu&iacute;a paso a paso que hemos descrito.<\/p><p>Esperamos que las ideas compartidas en esta gu&iacute;a te permitan experimentar con diferentes widgets y hacer que tu sitio sea din&aacute;mico y atractivo, sin dejar de ser f&aacute;cil de usar.<\/p><h2 class=\"wp-block-heading\" id=\"h-widgets-de-wordpress-preguntas-frecuentes\">Widgets de WordPress &ndash; Preguntas frecuentes&nbsp;<\/h2><p>Esta secci&oacute;n cubre algunas de las preguntas m&aacute;s comunes sobre los widgets de WordPress.&nbsp;<\/p><div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-694473f2da00b\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">&iquest;Sigue utilizando WordPress widgets?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>S&iacute;. Los widgets de WordPress siguen siendo una funci&oacute;n esencial para personalizar las barras laterales y las &aacute;reas de widgets. Puedes acceder a una pl&eacute;tora de widgets integrados y de terceros directamente desde el panel de control de WordPress.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-694473f2da00e\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">&iquest;Por qu&eacute; necesito widgets de WordPress?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Los widgets de WordPress te permiten a&ntilde;adir funciones y contenido a tu sitio de WordPress sin necesidad de codificaci&oacute;n manual.<\/p>\n<p>Act&uacute;an como bloques de construcci&oacute;n para barras laterales y &aacute;reas de widgets preestablecidas, permiti&eacute;ndote integrar redes sociales, formularios de contacto, entradas recientes y mucho m&aacute;s mediante una sencilla interfaz de arrastrar y soltar.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-694473f2da00f\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">&iquest;Cu&aacute;l es la diferencia entre un widget y una barra lateral en WordPress?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Un widget de WordPress es un bloque de contenido que a&ntilde;ade funciones como entradas recientes o enlaces a redes sociales a los sitios web.&nbsp;<\/p>\n<p>Por su parte, una <a href=\"\/tutoriales\/eliminar-barra-lateral-wordpress\">barra lateral<\/a> es una zona donde se pueden colocar widgets, como la cabecera o el pie de p&aacute;gina.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div><h3 class=\"wp-block-heading\" id=\"h-\"><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Los widgets de WordPress son objetos PHP que pueden ayudarte a a&ntilde;adir f&aacute;cilmente contenido o funciones a tu sitio web sin codificar.&nbsp; Puedes utilizar widgets integrados, de terceros o personalizados para diversos fines, como integrar feeds de redes sociales, mostrar entradas recientes del blog o a&ntilde;adir un formulario de contacto. En este art&iacute;culo, veremos todo [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/es\/tutoriales\/que-es-widget-wordpress\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":85,"featured_media":25069,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_title":"Widgets en WordPress: tipos, funciones y c\u00f3mo a\u00f1adirlos","rank_math_description":"Descubre qu\u00e9 son los widgets en WordPress, los tipos disponibles y c\u00f3mo a\u00f1adirlos f\u00e1cilmente para mejorar la funcionalidad de tu web.","rank_math_focus_keyword":"widgets wordpress","footnotes":""},"categories":[4747,14349],"tags":[14109],"class_list":["post-8458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wordpress","category-basico","tag-que-es-un-widget"],"hreflangs":[{"locale":"en-US","link":"https:\/\/www.hostinger.com\/tutorials\/wordpress-widgets","default":0},{"locale":"pt-BR","link":"https:\/\/www.hostinger.com\/br\/tutoriais\/o-que-e-widget\/","default":0},{"locale":"fr-FR","link":"https:\/\/www.hostinger.com\/fr\/tutoriels\/widget-wordpress","default":0},{"locale":"es-ES","link":"https:\/\/www.hostinger.com\/es\/tutoriales\/que-es-widget-wordpress","default":0},{"locale":"id-ID","link":"https:\/\/www.hostinger.com\/id\/tutorial\/apa-itu-widget","default":0},{"locale":"en-GB","link":"https:\/\/www.hostinger.com\/uk\/tutorials\/wordpress-widgets","default":0},{"locale":"en-MY","link":"https:\/\/www.hostinger.com\/my\/tutorials\/wordpress-widgets","default":0},{"locale":"en-PH","link":"https:\/\/www.hostinger.com\/ph\/tutorials\/wordpress-widgets","default":0},{"locale":"es-MX","link":"https:\/\/www.hostinger.com\/mx\/tutoriales\/que-es-widget-wordpress","default":0},{"locale":"es-CO","link":"https:\/\/www.hostinger.com\/co\/tutoriales\/que-es-widget-wordpress","default":0},{"locale":"es-AR","link":"https:\/\/www.hostinger.com\/ar\/tutoriales\/como-usar-tmux-21","default":0},{"locale":"pt-PT","link":"https:\/\/www.hostinger.com\/pt\/tutoriais\/o-que-e-widget\/","default":0},{"locale":"en-IN","link":"https:\/\/www.hostinger.com\/in\/tutorials\/wordpress-widgets","default":0},{"locale":"en-CA","link":"https:\/\/www.hostinger.com\/ca\/tutorials\/wordpress-widgets","default":0},{"locale":"en-AU","link":"https:\/\/www.hostinger.com\/au\/tutorials\/wordpress-widgets","default":0},{"locale":"en-NG","link":"https:\/\/www.hostinger.com\/ng\/tutorials\/wordpress-widgets","default":0}],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/posts\/8458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/users\/85"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/comments?post=8458"}],"version-history":[{"count":28,"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/posts\/8458\/revisions"}],"predecessor-version":[{"id":49975,"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/posts\/8458\/revisions\/49975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/media\/25069"}],"wp:attachment":[{"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/media?parent=8458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/categories?post=8458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-json\/wp\/v2\/tags?post=8458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}