{"id":7361,"date":"2025-11-28T03:41:08","date_gmt":"2025-11-28T03:41:08","guid":{"rendered":"\/de\/tutorials\/?p=7361"},"modified":"2025-11-28T03:41:11","modified_gmt":"2025-11-28T03:41:11","slug":"redaktionelle-standards-und-werte","status":"publish","type":"post","link":"\/de\/tutorials\/redaktionelle-standards-und-werte\/","title":{"rendered":"Redaktionelle Standards und Werte"},"content":{"rendered":"<p>Diese Standards und Werte sind Leitfaden f&uuml;r alles, was wir ver&ouml;ffentlichen &ndash; ob detailliertes Tutorial, Produktank&uuml;ndigung oder &Auml;nderungsprotokoll. Sie &uuml;bersetzen klassische redaktionelle Ethik in t&auml;gliche Inhalte der Hosting-Branche.<\/p><p>Jeder Punkt auf dieser Liste wird von einem oder mehreren unserer Hostinger-Prinzipien gest&uuml;tzt, die jeden Aspekt unserer Arbeit pr&auml;gen.<\/p><p>\n\n\n\n\n\n\n<\/p><h2 class=\"wp-block-heading\" id=\"h-1-technische-genauigkeit-zuerst\">1. Technische Genauigkeit zuerst<\/h2><h3 class=\"wp-block-heading\" id=\"h-was-das-fur-uns-bedeutet\">Was das f&uuml;r uns bedeutet:<\/h3><p>Jeder Artikel muss sachlich korrekt, aktuell und durch verifizierte Tests auf unserer Produktionsinfrastruktur belegt sein. Alle technischen Aussagen ben&ouml;tigen reproduzierbare Nachweise.<\/p><h3 class=\"wp-block-heading\" id=\"h-so-setzen-wir-es-um\">So setzen wir es um:<\/h3><ul class=\"wp-block-list\">\n<li>Jeder Ablauf, jeder Befehl und jeder Workflow wird in einer sauberen Umgebung getestet, die den Bedingungen der Leser entspricht.<\/li>\n\n\n\n<li>Informationen werden auf Richtigkeit und Aktualit&auml;t gepr&uuml;ft; technische Spezifikationen, Versionsnummern und Funktionsverf&uuml;gbarkeit werden verifiziert.<\/li>\n\n\n\n<li>Es werden Quellen oder interne Vergleichswerte zitiert.<\/li>\n<\/ul><p><strong>Hostinger-Prinzip:<\/strong><\/p><ul class=\"wp-block-list\">\n<li><a href=\"text=des%20Unternehmens%20aufzusteigen.-,H%C3%B6chste%20Standards,-Sie%20streben%20nach\">H&ouml;chste Standards<\/a><\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-2-nutzerzentrierte-hilfsbereitschaft\">2. Nutzerzentrierte Hilfsbereitschaft<\/h2><h3 class=\"wp-block-heading\" id=\"h-was-das-fur-uns-bedeutet-0\">Was das f&uuml;r uns bedeutet:<\/h3><p>Inhalte dienen Lesern zur L&ouml;sung ihrer Probleme und Entscheidungsfindung &ndash; nicht dem Verkauf von Produkten, die sie nicht brauchen.<\/p><h3 class=\"wp-block-heading\" id=\"h-so-setzen-wir-es-um-0\">So setzen wir es um:<\/h3><ul class=\"wp-block-list\">\n<li>Das zu l&ouml;sende Problem wird hervorgehoben, nicht das Produkt.<\/li>\n\n\n\n<li>Inhalte bieten echte Erkenntnisse, Informationen oder einen einzigartigen Blickwinkel &ndash; statt zu reproduzieren, was bereits woanders zu finden ist.<\/li>\n\n\n\n<li>Es werden Schritt-f&uuml;r-Schritt-Anleitungen, Screenshots und sauber kopierbare Codebl&ouml;cke bereitgestellt.<\/li>\n\n\n\n<li>&Uuml;berschriften sind aussagekr&auml;ftig, Abl&auml;ufe nummeriert und Kerninfos werden hervorgehoben, damit vielbesch&auml;ftigte Leser schnell navigieren k&ouml;nnen.<\/li>\n\n\n\n<li>H&auml;ufige Varianten, Fehlerbehebungs-Szenarien und Folgeschritte werden abgedeckt, die Leser typischerweise ben&ouml;tigen.<\/li>\n<\/ul><p><strong>Hostinger-Prinzip:<\/strong><\/p><ul class=\"wp-block-list\">\n<li><a href=\"text=und%20dem%20Feedbackgeben.-,Kundenbesessenheit,-Man%20beginnt%20mit\">Kundenbesessenheit<\/a><\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-3-unabhangigkeit-und-transparenz\">3. Unabh&auml;ngigkeit und Transparenz<\/h2><h3 class=\"wp-block-heading\" id=\"h-was-das-fur-uns-bedeutet-1\">Was das f&uuml;r uns bedeutet:<\/h3><p>Unsere Empfehlungen basieren auf technischer Qualit&auml;t und Nutzwert &ndash; unabh&auml;ngig von Gesch&auml;ftsbeziehungen.<\/p><h3 class=\"wp-block-heading\" id=\"h-so-setzen-wir-es-um-1\">So setzen wir es um:<\/h3><ul class=\"wp-block-list\">\n<li>Eine ehrliche Beurteilung steht immer &uuml;ber umsatzbezogenen Erw&auml;gungen.<\/li>\n\n\n\n<li>Weder Umsatz noch Partnerschaften f&uuml;hren zum Ausschluss kritischer Erkenntnisse.<\/li>\n<\/ul><p><strong>Hostinger-Prinzip:<\/strong><\/p><ul class=\"wp-block-list\">\n<li><a href=\"text=Freiheit%20und%20Verantwortung\">Freiheit und Verantwortung<\/a><\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-4-fairness-statt-hype\">4. Fairness statt Hype<\/h2><h3 class=\"wp-block-heading\" id=\"h-was-das-fur-uns-bedeutet-2\">Was das f&uuml;r uns bedeutet:<\/h3><p>Wir vergleichen Alternativen ehrlich und transparent anhand messbarer Kriterien und vermeiden &uuml;bertriebene Behauptungen oder Marketingversprechen, die Leser in die Irre f&uuml;hren.<\/p><h3 class=\"wp-block-heading\" id=\"h-so-setzen-wir-es-um-2\">So setzen wir es um:<\/h3><ul class=\"wp-block-list\">\n<li>Vergleiche werden anhand klarer Kennzahlen, wie Ladezeiten, Uptime-Prozentwerten oder Kosten-pro-Funktion-Verh&auml;ltnissen durchgef&uuml;hrt.<\/li>\n\n\n\n<li>Dieselben technischen Kriterien und dieselbe Teststrenge werden sowohl auf unsere Produkte als auch auf Partner-Tools und L&ouml;sungen der Konkurrenz angewendet.<\/li>\n\n\n\n<li>Abw&auml;gungen von Vor- und Nachteilen &ndash; sowohl von Hostinger als auch von Wettbewerbern &ndash; werden einbezogen.<\/li>\n<\/ul><p><strong>Hostinger-Prinzipien:<\/strong><\/p><ul class=\"wp-block-list\">\n<li><a href=\"text=und%20zu%20erhalten.-,Eigentum,-Sie%20k%C3%BCmmern%20sich\">Eigentum<\/a><\/li>\n\n\n\n<li><a href=\"text=von%20diskussionsbasierter%20Arbeit.-,Mut%20und%20Offenheit,-Du%20sagst%2C%20was\">Mut und Offenheit<\/a><\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-5-klarheit-und-barrierefreiheit\">5. Klarheit und Barrierefreiheit<\/h2><h3 class=\"wp-block-heading\" id=\"h-was-das-fur-uns-bedeutet-3\">Was das f&uuml;r uns bedeutet:<\/h3><p>Wir erkl&auml;ren komplexe Webhosting- und Technikthemen in klarer Sprache. Dar&uuml;ber hinaus gibt es<a href=\"\/de\/legal\/hostinger-accessibility-statement\"> laufende Initiativen<\/a>, um sicherzustellen, dass s&auml;mtliche Inhalte den Richtlinien f&uuml;r barrierefreie Webinhalte (WCAG) Level 2.0 AA oder h&ouml;her in &Uuml;bereinstimmung mit dem Barrierefreiheitsst&auml;rkungsgesetz (EAA) entsprechen.<\/p><h3 class=\"wp-block-heading\" id=\"h-so-setzen-wir-es-um-3\">So setzen wir es um:<\/h3><ul class=\"wp-block-list\">\n<li>Es werden kurze, pr&auml;gnante S&auml;tze und Abs&auml;tze verwendet.<\/li>\n\n\n\n<li>Es werden Informationen bereitgestellt, die der Absicht, Erfahrung und Kompetenz des Lesers entsprechen.<\/li>\n\n\n\n<li>Sinnstiftende &Uuml;berschriften schaffen im gesamten Inhalt eine klare, benutzerfreundliche Struktur.<\/li>\n\n\n\n<li>Gro&szlig;- und Kleinschreibung in Titeln und &Uuml;berschriften verbessern die Lesbarkeit.<\/li>\n\n\n\n<li>Unvermeidliche Fachbegriffe, Initialw&ouml;rter, Abk&uuml;rzungen oder sonstige technische Ausdr&uuml;cke werden definiert.<\/li>\n\n\n\n<li>Bilder werden durch Alternativtexte erg&auml;nzt und f&uuml;r schnelle Ladezeiten auf mobilen Ger&auml;ten und langsamen Verbindungen optimiert.<\/li>\n<\/ul><p><strong>Hostinger-Prinzipien:<\/strong><\/p><ul class=\"wp-block-list\">\n<li><a href=\"text=des%20Unternehmens%20aufzusteigen.-,H%C3%B6chste%20Standards,-Sie%20streben%20nach\">H&ouml;chste Standards<\/a><\/li>\n\n\n\n<li><a href=\"text=und%20dem%20Feedbackgeben.-,Kundenbesessenheit,-Man%20beginnt%20mit\">Kundenbesessenheit<\/a><\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-6-globale-und-inklusive-stimme\">6. Globale und inklusive Stimme<\/h2><h3 class=\"wp-block-heading\" id=\"h-was-das-fur-uns-bedeutet-4\">Was das f&uuml;r uns bedeutet:<\/h3><p>Unser Publikum umfasst &uuml;ber 150 L&auml;nder. Ein dediziertes &Uuml;bersetzungs- und Lokalisierungsteam sorgt f&uuml;r Genauigkeit und Relevanz &uuml;ber alle Regionen und Sprachen hinweg.<\/p><h3 class=\"wp-block-heading\" id=\"h-so-setzen-wir-es-um-4\">So setzen wir es um:<\/h3><ul class=\"wp-block-list\">\n<li>Geschlechtsneutrale Sprache ist Standard.<\/li>\n\n\n\n<li>Hassrede und diskriminierende Sprache werden strikt vermieden.<\/li>\n\n\n\n<li>UTF-8-sichere Codebeispiele und RTL-freundliche Diagramme werden bereitgestellt.<\/li>\n\n\n\n<li>Inhalte werden mit kulturellem Feingef&uuml;hl verfasst.<\/li>\n\n\n\n<li>Redewendungen oder schwer &uuml;bersetzbare kulturelle Anspielungen werden vermieden.<\/li>\n<\/ul><p><strong>Hostinger-Prinzip:<\/strong><\/p><ul class=\"wp-block-list\">\n<li><a href=\"text=und%20dem%20Feedbackgeben.-,Kundenbesessenheit,-Man%20beginnt%20mit\">Kundenbesessenheit<\/a><\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-7-keine-interessenkonflikte\">7. Keine Interessenkonflikte<\/h2><h3 class=\"wp-block-heading\" id=\"h-was-das-fur-uns-bedeutet-5\">Was das f&uuml;r uns bedeutet:<\/h3><p>Teammitglieder mit pers&ouml;nlichen Interessen an Drittanbieter-Tools oder -Diensten m&uuml;ssen sich aus entsprechender Berichterstattung zur&uuml;ckziehen oder ihre Beziehung vollst&auml;ndig offenlegen.<\/p><h3 class=\"wp-block-heading\" id=\"h-so-setzen-wir-es-um-5\">So setzen wir es um:<\/h3><ul class=\"wp-block-list\">\n<li>Interessenkonflikterkl&auml;rung f&uuml;r alle internen Mitarbeiter.<\/li>\n\n\n\n<li>Bei unvermeidbaren &Uuml;berschneidungen werden diese offengelegt.<\/li>\n<\/ul><p><strong>Hostinger-Prinzip:<\/strong><\/p><ul class=\"wp-block-list\">\n<li><a href=\"text=Freiheit%20und%20Verantwortung\">Freiheit und Verantwortung<\/a><\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-8-technische-ethik\">8. Technische Ethik<\/h2><h3 class=\"wp-block-heading\" id=\"h-was-das-fur-uns-bedeutet-6\">Was das f&uuml;r uns bedeutet:<\/h3><p>Wir ver&ouml;ffentlichen keine Anleitungen, die unethisches Hacking erm&ouml;glichen.<\/p><h3 class=\"wp-block-heading\" id=\"h-so-setzen-wir-es-um-6\">So setzen wir es um:<\/h3><ul class=\"wp-block-list\">\n<li>Links zu Drittanbieter-Tools und Ressourcen werden gepr&uuml;ft.<\/li>\n\n\n\n<li>Sicherheitstutorials fokussieren Verteidigung, nicht Ausnutzung.<\/li>\n<\/ul><p><strong>Hostinger-Prinzipien:<\/strong><\/p><ul class=\"wp-block-list\">\n<li><a href=\"text=Freiheit%20und%20Verantwortung\">Freiheit und Verantwortung<\/a><\/li>\n\n\n\n<li><a href=\"text=des%20Unternehmens%20aufzusteigen.-,H%C3%B6chste%20Standards,-Sie%20streben%20nach\">H&ouml;chste Standards<\/a><\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-9-unermudliche-verbesserung\">9. Unerm&uuml;dliche Verbesserung<\/h2><h3 class=\"wp-block-heading\" id=\"h-was-das-fur-uns-bedeutet-7\">Was das f&uuml;r uns bedeutet:<\/h3><p>Redaktionelle Richtlinien werden weiterentwickelt &ndash; anhand von Branchenstandards, Leserfeedback und Hostingers eigener Produkt-Roadmap.<\/p><h3 class=\"wp-block-heading\" id=\"h-so-setzen-wir-es-um-7\">So setzen wir es um:<\/h3><ul class=\"wp-block-list\">\n<li>Redaktionelle und technische Teams im gesamten Unternehmen tragen gemeinsam Verantwortung f&uuml;r die Aktualit&auml;t von Inhalten, Style Guides und Dokumentation.<\/li>\n\n\n\n<li>&Auml;nderungen an Dokumentation werden laufend oder bei Bedarf vorgenommen, begleitet von regelm&auml;&szlig;iger und lebhafter Diskussion und Zusammenarbeit.<\/li>\n\n\n\n<li>Inhalte werden regelm&auml;&szlig;ig auf sachliche Korrektheit und Richtlinienkonformit&auml;t gepr&uuml;ft und aktualisiert.<\/li>\n\n\n\n<li>Workshops werden von internen Fachexperten erstellt und durchgef&uuml;hrt.<\/li>\n\n\n\n<li>Es gibt eine Richtlinie f&uuml;r die kontinuierliche berufliche Weiterbildung aller Mitarbeitenden.<\/li>\n<\/ul><p><strong>Hostinger-Prinzipien:<\/strong><\/p><ul class=\"wp-block-list\">\n<li><a href=\"text=du%20verdienst%20sie.-,Fokus,-Sie%20fragen%20sich\">Fokus<\/a><\/li>\n\n\n\n<li><a href=\"text=des%20Unternehmens%20aufzusteigen.-,H%C3%B6chste%20Standards,-Sie%20streben%20nach\">H&ouml;chste Standards<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Diese Standards und Werte sind Leitfaden f&uuml;r alles, was wir ver&ouml;ffentlichen &ndash; ob detailliertes Tutorial, Produktank&uuml;ndigung oder &Auml;nderungsprotokoll. Sie &uuml;bersetzen klassische redaktionelle Ethik in t&auml;gliche Inhalte der Hosting-Branche. Jeder Punkt auf dieser Liste wird von einem oder mehreren unserer Hostinger-Prinzipien gest&uuml;tzt, die jeden Aspekt unserer Arbeit pr&auml;gen. 1. Technische Genauigkeit zuerst Was das f&uuml;r uns [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/de\/tutorials\/redaktionelle-standards-und-werte\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":472,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rank_math_title":"%title% %page%","rank_math_description":"","rank_math_focus_keyword":"Redaktionelle Standards und Werte","footnotes":""},"categories":[26],"tags":[],"class_list":["post-7361","post","type-post","status-publish","format-standard","hentry","category-andere"],"hreflangs":[],"_links":{"self":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts\/7361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/users\/472"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/comments?post=7361"}],"version-history":[{"count":3,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts\/7361\/revisions"}],"predecessor-version":[{"id":7364,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts\/7361\/revisions\/7364"}],"wp:attachment":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/media?parent=7361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/categories?post=7361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/tags?post=7361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}