{"id":6778,"date":"2025-10-15T19:59:39","date_gmt":"2025-10-15T19:59:39","guid":{"rendered":"\/de\/tutorials\/?p=6778"},"modified":"2025-10-15T19:59:41","modified_gmt":"2025-10-15T19:59:41","slug":"n8n-vorlagen","status":"publish","type":"post","link":"\/de\/tutorials\/n8n-vorlagen\/","title":{"rendered":"Die besten n8n Vorlagen zur Steigerung Ihrer Produktivit\u00e4t"},"content":{"rendered":"<p>Moderne Workflows erfordern mehr als nur Effizienz &ndash; sie erfordern intelligente Automatisierung, und n8n bietet genau das. Als Tool zur Workflow-Automatisierung hilft es Unternehmen und Einzelpersonen, ihre Workflows zu optimieren.<\/p><p>Um n8n f&uuml;r alle Interessierten zug&auml;nglich zu machen, bietet die n8n-Community vorgefertigte Vorlagen an, die die Notwendigkeit komplexer Einstellungen beseitigen. In diesem Artikel stellen wir Ihnen einige der besten n8n Vorlagen vor, mit denen Sie Ihre Effizienz steigern und sich auf das Wesentliche konzentrieren k&ouml;nnen.<\/p><p>\n\n\n\n\n\n\n<\/p><h2 class=\"wp-block-heading\" id=\"h-die-besten-n8n-vorlagen-fur-kleine-unternehmen\">Die besten n8n Vorlagen f&uuml;r kleine Unternehmen<\/h2><p>Kleine Unternehmen haben oft mit zeitaufw&auml;ndigen manuellen Aufgaben zu k&auml;mpfen, die den Betrieb verlangsamen: Leads nachverfolgen, Auftr&auml;ge verwalten, Rechnungen bearbeiten und Ausgaben messen. Diese Prozesse zehren an Ihren Ressourcen und lassen weniger Zeit f&uuml;r das Wachstum Ihres Unternehmens.<\/p><p>Die folgenden n8n Vorlagen gehen diese h&auml;ufigen Probleme direkt an und helfen Ihnen, Ihre Zeit dort einzusetzen, wo sie am wichtigsten ist.<\/p><h3 class=\"wp-block-heading\" id=\"h-scrapen-sie-geschafts-e-mails-aus-google-maps\">Scrapen Sie Gesch&auml;fts-E-Mails aus Google Maps<\/h3><p>Die Suche nach neuen Kunden kann sehr zeitaufw&auml;ndig sein, und die manuelle Suche nach Leads im Internet ist m&uuml;hsam. Anstatt die Kontaktdaten einzeln zu kopieren, sammelt diese Vorlage automatisch Kontaktinformationen aus Google Maps.<\/p><p>W&auml;hrend n8n sich um die Beschaffung der Leads k&uuml;mmert, k&ouml;nnen Sie sich stattdessen auf die Kontaktaufnahme und den Gesch&auml;ftsabschluss konzentrieren.<\/p><p>Vorteile:<\/p><ul class=\"wp-block-list\">\n<li>Erspart stundenlanges manuelles Recherchieren<\/li>\n\n\n\n<li>Erweitert m&uuml;helos Ihren Aktionsradius<\/li>\n\n\n\n<li>Eliminiert die Abh&auml;ngigkeit von teuren Lead-Datenbanken<\/li>\n<\/ul><p><a href=\"https:\/\/n8n.io\/workflows\/2567-scrape-business-emails-from-google-maps-without-the-use-of-any-third-party-apis\/\" target=\"_blank\" rel=\"noopener\">Probieren Sie die Google Maps Scraping-Vorlage aus<\/a><\/p><h3 class=\"wp-block-heading\" id=\"h-inhaltserstellung-per-ki\">Inhaltserstellung per KI<\/h3><p>Die regelm&auml;&szlig;ige Erstellung hochwertiger Inhalte kann f&uuml;r viele kleine Unternehmen eine Herausforderung darstellen. Diese Vorlage nutzt jedoch KI, um die Erstellung hochwertiger Artikel zu automatisieren, sie in Google Drive zu organisieren und ihren Fortschritt in Google Sheets zu verfolgen.<\/p><p>Durch die Optimierung der Inhaltserstellung k&ouml;nnen Sie eine aktive Online-Pr&auml;senz aufrechterhalten, ohne &uuml;berm&auml;&szlig;ig viel Zeit f&uuml;r das Schreiben aufwenden zu m&uuml;ssen.<\/p><p>Vorteile:<\/p><ul class=\"wp-block-list\">\n<li>Gew&auml;hrleistung regelm&auml;&szlig;iger Aktualisierungen der Inhalte<\/li>\n\n\n\n<li>Spart Zeit bei der Erstellung von Inhalten<\/li>\n\n\n\n<li>Effizientes Organisieren Ihrer Inhalte<\/li>\n<\/ul><p><a href=\"https:\/\/n8n.io\/workflows\/2525-create-content-from-form-inputs-and-save-it-to-google-drive-using-ai\/\" target=\"_blank\" rel=\"noopener\">Probieren Sie die Vorlage zur Erstellung von KI-Inhalten aus<\/a><\/p><h3 class=\"wp-block-heading\" id=\"h-automatisierte-erfassung-von-kundenfeedback\">Automatisierte Erfassung von Kundenfeedback<\/h3><p>Um Ihre Produkte und Dienstleistungen zu verbessern, ist es wichtig, die Stimmung der Kunden zu verstehen. Das Sammeln von Feedback erfordert jedoch viel zus&auml;tzlichen Aufwand. Diese Vorlage &uuml;bernimmt das f&uuml;r Sie. Sie sendet Umfragen an Kunden, kategorisiert das Feedback anhand der Zufriedenheit und organisiert es in Google Sheets.<\/p><p>Mit diesem Workflow erhalten Sie wertvolle Einblicke in Ihre Servicequalit&auml;t ohne manuellen Aufwand.<\/p><p>Vorteile:<\/p><ul class=\"wp-block-list\">\n<li>Automatisiert die Erfassung von Feedback<\/li>\n\n\n\n<li>Bietet eine Stimmungsanalyse<\/li>\n\n\n\n<li>Organisiert Daten zur einfachen &Uuml;berpr&uuml;fung<\/li>\n<\/ul><p><a href=\"https:\/\/n8n.io\/workflows\/1996-ai-customer-feedback-sentiment-analysis\/\" target=\"_blank\" rel=\"noopener\">Probieren Sie die Vorlage f&uuml;r die Erfassung von Kundenfeedback aus<\/a><\/p><h3 class=\"wp-block-heading\" id=\"h-automatisierte-rechnungserstellung\">Automatisierte Rechnungserstellung<\/h3><p>Die Erstellung von Rechnungen ist zeitaufwendig und fehleranf&auml;llig. Mit dieser Vorlage wird der Prozess automatisiert, indem Rechnungen auf der Grundlage von Typeform-Eingaben erstellt und an Kunden gesendet werden.<\/p><p>Durch die Automatisierung der Rechnungsstellung k&ouml;nnen Sie eine rechtzeitige und korrekte Rechnungsstellung sicherstellen, Ihre Arbeitsbelastung verringern und sich auf den Verkauf konzentrieren, anstatt Verk&auml;ufe zu dokumentieren.<\/p><p>Vorteile:<\/p><ul class=\"wp-block-list\">\n<li>Beschleunigung des Rechnungsprozesses<\/li>\n\n\n\n<li>Eliminiert menschliche Fehler bei der Rechnungsstellung<\/li>\n\n\n\n<li>Gew&auml;hrleistet rechtzeitigen Zahlungseingang<\/li>\n<\/ul><p><a href=\"https:\/\/n8n.io\/workflows\/989-create-an-invoice-based-on-the-typeform-submission\/\" target=\"_blank\" rel=\"noopener\">Probieren Sie die Vorlage zur Rechnungserstellung aus<\/a><\/p><h3 class=\"wp-block-heading\" id=\"h-spesenverfolgung-und-finanzberichte\">Spesenverfolgung und Finanzberichte<\/h3><p>Diese Vorlage automatisiert die Ausgabenerfassung &uuml;ber eine einfache Chat-Schnittstelle. Geben Sie einfach Ihre Ausgaben ein, und ein KI-Agent wird Ihre Nachricht analysieren und die Daten in Google Sheets speichern.<\/p><p>Mit dieser Vorlage k&ouml;nnen Sie ganz einfach genaue Finanzaufzeichnungen f&uuml;hren, ohne dass Sie die Daten manuell eingeben m&uuml;ssen.<\/p><p>Vorteile:<\/p><ul class=\"wp-block-list\">\n<li>Vereinfacht die Ausgabenerfassung<\/li>\n\n\n\n<li>Nutzt KI f&uuml;r die Datenanalyse<\/li>\n\n\n\n<li>Organisiert Ausgaben systematisch<\/li>\n<\/ul><p><a href=\"https:\/\/n8n.io\/workflows\/2819-simple-expense-tracker-with-n8n-chat-ai-agent-and-google-sheets\/\" target=\"_blank\" rel=\"noopener\">Probieren Sie die Vorlage f&uuml;r die Kostenerfassung aus<\/a><\/p><p>Diese Vorlagen sind nur ein kleiner Auszug aus dem Angebot f&uuml;r kleine Unternehmen. Die n8n-Workflow-Bibliothek ist voll von anderen Vorlagen, die Sie f&uuml;r Ihr Unternehmen &uuml;bernehmen k&ouml;nnen. Einige n&uuml;tzliche Kategorien sind:<\/p><ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/n8n.io\/workflows\/categories\/sales\/\" target=\"_blank\" rel=\"noopener\">Vertrieb<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/n8n.io\/workflows\/categories\/marketing\/\" target=\"_blank\" rel=\"noopener\">Marketing<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/n8n.io\/workflows\/categories\/finance\/\" target=\"_blank\" rel=\"noopener\">Finanzen<\/a><\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-die-besten-n8n-vorlagen-fur-personliche-produktivitat\">Die besten n8n Vorlagen f&uuml;r pers&ouml;nliche Produktivit&auml;t<\/h2><p>Das Verwalten von E-Mails, Organisieren von Aufgaben und Planen von Besprechungen kann wertvolle Zeit kosten.<\/p><p>n8n Vorlagen k&ouml;nnen Ihnen helfen, Zeit zu sparen, indem sie sich wiederholende Aufgaben automatisieren, f&uuml;r Ordnung sorgen und es einfacher machen, den &Uuml;berblick &uuml;ber Ihren Workflow zu behalten.<\/p><h3 class=\"wp-block-heading\" id=\"h-automatisierte-notion-aufgabenerinnerungen-uber-slack\">Automatisierte Notion-Aufgabenerinnerungen &uuml;ber Slack<\/h3><p>Damit Sie keine Fristen verpassen, verfolgt diese Vorlage unvollst&auml;ndige Aufgaben aus einer Notion-Datenbank und sendet Slack-Erinnerungen, damit Sie auf dem Laufenden bleiben. Sie ist so eingestellt, dass sie jeden Wochentag um 9 Uhr ausgef&uuml;hrt wird, damit Sie nie eine wichtige anstehende Aufgabe vergessen.<\/p><p>Vorteile:<\/p><ul class=\"wp-block-list\">\n<li>Gew&auml;hrleistet, dass Sie &uuml;ber anstehende Aufgaben auf dem Laufenden bleiben<\/li>\n\n\n\n<li>Verringert das Risiko, Fristen zu vers&auml;umen<\/li>\n<\/ul><p><a href=\"https:\/\/n8n.io\/workflows\/2488-automated-notion-task-reminders-via-slack\/\" target=\"_blank\" rel=\"noopener\">Probieren Sie die Vorlage f&uuml;r Aufgabenerinnerungen aus<\/a><\/p><h3 class=\"wp-block-heading\" id=\"h-ki-e-mail-entwurf\">KI-E-Mail-Entwurf<\/h3><p>Dieser Workflow nutzt das GPT-4 Turbo-Modell von OpenAI, um automatisch Antworten auf eingehende E-Mails zu verfassen. Sobald er eingerichtet ist, k&ouml;nnen Sie die generierten Nachrichten bearbeiten und Antworten versenden.<\/p><p>Vorteile:<\/p><ul class=\"wp-block-list\">\n<li>Beschleunigt die Antworten<\/li>\n\n\n\n<li>Ermittelt automatisch, ob eine Antwort erforderlich ist<\/li>\n\n\n\n<li>Sorgt f&uuml;r gut geschriebene und einheitliche Entw&uuml;rfe<\/li>\n<\/ul><p><a href=\"https:\/\/n8n.io\/workflows\/2271-gmail-ai-auto-responder-create-draft-replies-to-incoming-emails\/\" target=\"_blank\" rel=\"noopener\">Probieren Sie diese Vorlage f&uuml;r E-Mail-Entw&uuml;rfe aus<\/a><\/p><h3 class=\"wp-block-heading\" id=\"h-ki-gestutztes-web-scraping-mit-jina-google-sheets-und-openai\">KI-gest&uuml;tztes Web-Scraping mit Jina, Google Sheets und OpenAI<\/h3><p>Die Recherche kann ein sehr langer Prozess sein, bei dem man oft Hunderte von Seiten durchforsten muss, bis man findet, was man braucht.<\/p><p>Dieser Workflow &uuml;bernimmt das Web-Scraping f&uuml;r Sie, organisiert die extrahierten Inhalte und erstellt Zusammenfassungen, so dass Sie die wichtigsten Informationen schnell finden k&ouml;nnen, anstatt ganze Artikel zu lesen.<\/p><p>Vorteile:<\/p><ul class=\"wp-block-list\">\n<li>Automatisiert die Online-Recherche<\/li>\n\n\n\n<li>Fasst die wichtigsten Erkenntnisse zusammen<\/li>\n\n\n\n<li>Organisiert Einblicke und Daten<\/li>\n<\/ul><p><a href=\"https:\/\/n8n.io\/workflows\/2552-ai-powered-web-scraping-with-jina-google-sheets-and-openai-the-easy-way\/\" target=\"_blank\" rel=\"noopener\">Probieren Sie die Web-Scraping-Vorlage aus<\/a><\/p><h3 class=\"wp-block-heading\" id=\"h-eingehende-google-mail-nachrichten-mit-ki-knoten-automatisch-kennzeichnen\">Eingehende Google Mail-Nachrichten mit KI-Knoten automatisch kennzeichnen<\/h3><p>Das Sortieren Ihrer Posteing&auml;nge ist entweder ein &uuml;berw&auml;ltigender Aufwand oder erfordert die Konfiguration eines komplexen Satzes von Posteingangsregeln.<\/p><p>Mit dieser Vorlage k&ouml;nnen Sie sich die manuelle Sortierung des Posteingangs und komplexe Posteingangsregeln sparen. Sie kennzeichnet eingehende Nachrichten auf der Grundlage allgemeiner Kategorien, was das Auffinden wichtiger Nachrichten erheblich erleichtert.<\/p><p>Vorteile:<\/p><ul class=\"wp-block-list\">\n<li>Automatisches Kategorisieren von E-Mails<\/li>\n\n\n\n<li>Hebt vorrangige Nachrichten hervor<\/li>\n\n\n\n<li>Reduziert die manuelle Verwaltung von Postf&auml;chern betr&auml;chtlich<\/li>\n<\/ul><p><a href=\"https:\/\/n8n.io\/workflows\/2197-auto-label-incoming-gmail-messages-with-ai-nodes\/\" target=\"_blank\" rel=\"noopener\">Probieren Sie diese Vorlage zur E-Mail-Beschriftung aus<\/a><\/p><h3 class=\"wp-block-heading\" id=\"h-zoom-ki-meeting-assistent\">Zoom KI Meeting-Assistent<\/h3><p>Das Anfertigen von Besprechungsprotokollen, das &Uuml;berpr&uuml;fen von Aufzeichnungen oder der Versuch, sich an die wichtigsten Punkte zu erinnern, kann leicht frustrierend und fehleranf&auml;llig werden, wenn man versucht, die Erkenntnisse aus einer Arbeitsbesprechung zusammenzufassen.<\/p><p>Dieser Workflow automatisiert diese Arbeit f&uuml;r Sie, indem er Zoom-Meetings zusammenfasst, strukturierte Aktionslisten erstellt und Folgetermine plant. So k&ouml;nnen Sie sich ausschlie&szlig;lich auf die Besprechung konzentrieren und den Wert, den Sie bieten k&ouml;nnen, erh&ouml;hen.<\/p><p>Vorteile:<\/p><ul class=\"wp-block-list\">\n<li>Automatische Erstellung von Besprechungszusammenfassungen<\/li>\n\n\n\n<li>Extrahiert wichtige Aktionspunkte und Folgema&szlig;nahmen<\/li>\n\n\n\n<li>Spart Zeit bei der Durchsicht von Aufzeichnungen und Notizen<\/li>\n<\/ul><p><a href=\"https:\/\/n8n.io\/workflows\/2800-zoom-ai-meeting-assistant-creates-mail-summary-clickup-tasks-and-follow-up-call\/\" target=\"_blank\" rel=\"noopener\">Probieren Sie die Zoom KI Meeting-Vorlage aus<\/a><\/p><p>Diese Vorlagen k&ouml;nnen Ihre Produktivit&auml;t steigern, aber sie sind nicht f&uuml;r jede Situation geeignet. Erkunden Sie diese n8n-Workflow-Kategorien, um die richtige L&ouml;sung f&uuml;r Sie zu finden:<\/p><ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/n8n.io\/workflows\/categories\/ai\/\" target=\"_blank\" rel=\"noopener\">KI<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/n8n.io\/workflows\/categories\/product\/\" target=\"_blank\" rel=\"noopener\">Engineering<\/a><\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-die-besten-n8n-vorlagen-fur-die-it-automatisierung\">Die besten n8n Vorlagen f&uuml;r die IT-Automatisierung<\/h2><p>Die Verwaltung von Ressourcen, die Bearbeitung von Vorf&auml;llen und die Gew&auml;hrleistung eines reibungslosen Betriebs erfordern viel Aufwand und Aufmerksamkeit. Mit n8n k&ouml;nnen Sie diese Prozesse automatisieren und die Effizienz des IT-Betriebs verbessern.<\/p><p>Hier finden Sie einige Vorlagen f&uuml;r den IT-Betrieb, die Ihrem Team das Leben leichter machen.<\/p><h3 class=\"wp-block-heading\" id=\"h-ssl-ablaufwarnung\">SSL-Ablaufwarnung<\/h3><p>Ein abgelaufenes SSL-Zertifikat kann zu Ausfallzeiten und Sicherheitsproblemen f&uuml;r Ihre Website f&uuml;hren. Au&szlig;erdem k&ouml;nnen einige SSL-Zertifikatsanbieter abgelaufene SSL-Zertifikate widerrufen, was Ihre Wiederherstellungsbem&uuml;hungen in die L&auml;nge zieht.<\/p><p>Diese Vorlage hilft Ihnen, diese Risiken zu vermeiden und SSL-Zertifikate rechtzeitig zu erneuern, indem sie eine Liste von Websites &uuml;berwacht und Sie dar&uuml;ber informiert, wenn das Zertifikat bald abl&auml;uft.<\/p><p>Vorteile:<\/p><ul class=\"wp-block-list\">\n<li>Verhindert Ausfallzeiten aufgrund von abgelaufenen Zertifikaten<\/li>\n\n\n\n<li>Reduziert den manuellen &Uuml;berwachungsaufwand<\/li>\n<\/ul><p><a href=\"https:\/\/n8n.io\/workflows\/2694-ssl-expiry-alert-with-ssl-checkerio\/\" target=\"_blank\" rel=\"noopener\">Probieren Sie die Vorlage f&uuml;r SSL-Ablaufwarnungen aus<\/a><\/p><h3 class=\"wp-block-heading\" id=\"h-it-ops-ki-slackbot\">IT Ops KI-SlackBot<\/h3><p>IT-Teams haben h&auml;ufig mit Anfragen zur einfachen Fehlerbehebung oder allgemeinen Fragen zu tun, die bereits in einer Wissensdatenbank beantwortet wurden.<\/p><p>Mit dieser Vorlage nutzt ein benutzerdefinierter KI-SlackBot Ihre interne Wissensdatenbank als Quelle f&uuml;r Antworten auf verschiedene Anfragen, wodurch die Reaktionszeiten verk&uuml;rzt werden und Ingenieure Zeit sparen.<\/p><p>Vorteile:<\/p><ul class=\"wp-block-list\">\n<li>Automatisierte Antworten auf h&auml;ufige Fragen<\/li>\n\n\n\n<li>Reduziert die Arbeitsbelastung von IT-Teams<\/li>\n<\/ul><p><a href=\"https:\/\/n8n.io\/workflows\/2397-it-ops-ai-slackbot-workflow-chat-with-your-knowledge-base\/\" target=\"_blank\" rel=\"noopener\">Probieren Sie die KI-SlackBot-Vorlage aus<\/a><\/p><h3 class=\"wp-block-heading\" id=\"h-uberwachen-sie-eine-datei-auf-anderungen-und-senden-sie-eine-warnung\">&Uuml;berwachen Sie eine Datei auf &Auml;nderungen und senden Sie eine Warnung<\/h3><p>Einige Konfigurationsdateien oder unternehmenskritische Dateien sollten am besten unber&uuml;hrt bleiben. Wenn es zu &Auml;nderungen kommt, sollten Sie sofort informiert werden. Diese Vorlage &uuml;berwacht bestimmte Dateien und sendet Echtzeitwarnungen, sobald sie ge&auml;ndert werden. So bleiben Sie informiert und haben die Kontrolle.<\/p><p>Vorteile:<\/p><ul class=\"wp-block-list\">\n<li>Erkennt Datei&auml;nderungen sofort<\/li>\n\n\n\n<li>Hilft bei der Aufrechterhaltung der Stabilit&auml;t von unternehmenskritischen Dateien<\/li>\n<\/ul><p><a href=\"https:\/\/n8n.io\/workflows\/967-monitor-a-file-for-changes-and-send-an-alert\/\" target=\"_blank\" rel=\"noopener\">Probieren Sie die Vorlage zur Datei&uuml;berwachung aus<\/a><\/p><h3 class=\"wp-block-heading\" id=\"h-chat-mit-postgresql-datenbank\">Chat mit PostgreSQL-Datenbank<\/h3><p>Das Abrufen von Daten aus einer Datenbank ist ein relativ unkomplizierter Prozess, aber es kann eine Herausforderung sein, wenn Sie Verbindungen zu einer Datenbank herstellen und jedes Mal Ihre eigenen Abfragen eingeben m&uuml;ssen.<\/p><p>Diese Vorlage vereinfacht die Abfrage von PostgreSQL-Datenbanken. Sie nutzt einen KI-Agenten, um eine Chatbot-Schnittstelle zu erstellen, die Ihre Texteingaben interpretiert und f&uuml;r Sie mit der Datenbank interagiert.<\/p><p>Vorteile:<\/p><ul class=\"wp-block-list\">\n<li>Keine Abh&auml;ngigkeit von technischen Teams f&uuml;r Datenbankabfragen mehr<\/li>\n\n\n\n<li>Vereinfacht die Datenabfrage f&uuml;r nicht-technische Personen<\/li>\n<\/ul><p><a href=\"https:\/\/n8n.io\/workflows\/2859-chat-with-postgresql-database\/\" target=\"_blank\" rel=\"noopener\">Probieren Sie die Vorlage f&uuml;r PostgreSQL-Abfragen aus<\/a><\/p><h3 class=\"wp-block-heading\" id=\"h-loschen-der-n8n-ausfuhrungshistorie\">L&ouml;schen der n8n-Ausf&uuml;hrungshistorie<\/h3><p>Ja, Sie k&ouml;nnen sogar n8n Vorlagen verwenden, um Ihre n8n-Instanz zu verwalten! Wenn Sie mehrere Workflows ausf&uuml;hren und Ausf&uuml;hrungsprotokolle in einer Datenbank speichern, k&ouml;nnen die Tabellen schnell wachsen. Die manuelle Bereinigung ist zwar einfach, aber eine wiederkehrend Aufgabe und kann leicht vergessen werden.<\/p><p>Mit dieser Vorlage wird die Datenbankbereinigung automatisiert, indem eine SQL-Abfrage ausgef&uuml;hrt wird, die alte Eintr&auml;ge aus der Tabelle &bdquo;execution_entity&rdquo; l&ouml;scht, so dass sie schnell und effizient bleibt.<\/p><p>Vorteile:<\/p><ul class=\"wp-block-list\">\n<li>Verhindert exponentielles Wachstum der Datenbankgr&ouml;&szlig;e<\/li>\n\n\n\n<li>Reduziert die Speicherkosten<\/li>\n<\/ul><p><a href=\"https:\/\/n8n.io\/workflows\/700-purge-n8n-execution-history-located-in-mysql\/\" target=\"_blank\" rel=\"noopener\">Probieren Sie die n8n Vorlage zur Verwaltung der Historie aus<\/a><\/p><p>Es gibt eine F&uuml;lle von M&ouml;glichkeiten, die IT durch Automatisierung zu optimieren. Wenn die oben genannten Vorlagen nicht das sind, wonach Sie suchen, finden Sie hier einige n&uuml;tzliche Kategorien, die Sie sich ansehen sollten:<\/p><ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/n8n.io\/workflows\/categories\/engineering\/\" target=\"_blank\" rel=\"noopener\">Technik<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/n8n.io\/workflows\/categories\/devops\/\" target=\"_blank\" rel=\"noopener\">DevOps<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/n8n.io\/workflows\/categories\/it-ops\/\" target=\"_blank\" rel=\"noopener\">IT-Betrieb<\/a><\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-wie-installiert-man-eine-n8n-vorlage\"><strong>Wie installiert man eine n8n Vorlage?<\/strong><\/h2><p>Die Installation von n8n Vorlagen ist ein einfacher und unkomplizierter Prozess, aber bevor Sie mit der Vorlage-Installation beginnen k&ouml;nnen, m&uuml;ssen Sie sicherstellen, dass Sie eine laufende <a href=\"\/de\/n8n-hosting\"><strong>n8n Instanz<\/strong><\/a> haben, die Ihre Vorlage hosten wird.<\/p><p>Wenn Ihre n8n-Instanz bereit ist, k&ouml;nnen Sie mit der Installation der Vorlagen beginnen:<\/p><ol class=\"wp-block-list\">\n<li>Navigieren Sie in Ihrem Browser zur Seite <a href=\"https:\/\/n8n.io\/workflows\/\" target=\"_blank\" rel=\"noopener\"><strong>n8n Templates<\/strong><\/a> und &ouml;ffnen Sie die Vorlage, die Sie installieren m&ouml;chten. F&uuml;r dieses Beispiel verwenden wir die Vorlage <a href=\"https:\/\/n8n.io\/workflows\/2694-ssl-expiry-alert-with-ssl-checkerio\/\" target=\"_blank\" rel=\"noopener\"><strong>SSL Expiry Alert<\/strong><\/a>.<\/li>\n\n\n\n<li>Klicken Sie auf die Schaltfl&auml;che &bdquo;<strong>Use workflow<\/strong>&rdquo;.<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f539cc73\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f539cc73\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/ssl-expiry-alert-workflow.png\/w=1024,h=1024,fit=scale-down\" alt=\"Workflow-Ansicht f&uuml;r SSL Expiry Alert\" class=\"wp-image-122980\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><ol start=\"3\" class=\"wp-block-list\">\n<li>Unter &bdquo;<strong>Import to an n8n destination<\/strong>&rdquo; k&ouml;nnen Sie auf &bdquo;<strong>Import template to &lt;your_server_url&gt; self-hosted instance for a quick and straightforward installation<\/strong>&rdquo; oder &bdquo;<strong>Copy template to clipboard (JSON)<\/strong>&rdquo; klicken, wenn Sie sie manuell einrichten m&ouml;chten. Wir werden beide Optionen behandeln.<\/li>\n<\/ol><p>\n\n\n<div><p class=\"important\"><strong>Wichtig!<\/strong> Wenn Sie sich noch nicht bei Ihrer n8n-Instanz angemeldet haben, steht Ihnen die Option &bdquo;Import template to&rdquo; nicht zur Verf&uuml;gung. Stattdessen wird die Option &bdquo;Get started free with n8n cloud&rdquo; angezeigt. In diesem Fall steht Ihnen f&uuml;r die manuelle Einrichtung immer noch die Option &bdquo;Copy template to clipboard (JSON)&rdquo; zur Verf&uuml;gung.<\/p><\/div>\n\n\n\n<\/p><h3 class=\"wp-block-heading\"><strong>Importieren der Vorlage in eine selbst gehostete Instanz:<\/strong><\/h3><ol class=\"wp-block-list\">\n<li>Klicken Sie auf &bdquo;<strong>Import template to &lt;your_server_url&gt; self-hosted instance<\/strong>&rdquo;. Dadurch wird eine neue Registerkarte f&uuml;r Ihre n8n-Instanz ge&ouml;ffnet:<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f53a2e40\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f53a2e40\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/auto-setup-template-import.png\/w=1024,h=1024,fit=scale-down\" alt=\"n8n-Instanzansicht beim automatischen Import in eine selbst gehostete Instanz.\" class=\"wp-image-122982\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><ol start=\"2\" class=\"wp-block-list\">\n<li>In diesem Fall m&uuml;ssen Sie die Anmeldeinformationen f&uuml;r Google Sheets und Google Mail einrichten. Sie k&ouml;nnen sie einrichten oder dies vorerst &uuml;berspringen &ndash; wir werden die Einrichtung der Anmeldedaten im Abschnitt &bdquo;<strong>Ihre Vorlage konfigurieren<\/strong>&rdquo; in diesem Leitfaden behandeln. Wenn Sie sich entscheiden, Ihre Vorlage hier zu konfigurieren, befolgen Sie die in der n8n-Benutzeroberfl&auml;che beschriebenen Schritte, klicken Sie auf &bdquo;<strong>Continue<\/strong>&rdquo; und fahren Sie mit dem Abschnitt &bdquo;<strong>Ihre Vorlage konfigurieren<\/strong>&rdquo; fort.<\/li>\n<\/ol><h3 class=\"wp-block-heading\"><strong>Manuelle Einrichtung:<\/strong><\/h3><ol class=\"wp-block-list\">\n<li>Klicken Sie auf &bdquo;<strong>Copy template to clipboard (JSON)<\/strong>&rdquo; und f&uuml;gen Sie die kopierte Vorlage in eine Textdatei ein. Speichern Sie sie als <strong>.json<\/strong>-Datei.<\/li>\n\n\n\n<li>Verbinden Sie sich mit Ihrer <strong>n8n-Instanz<\/strong> &uuml;ber Ihre bevorzugte Methode und geben Sie Ihre Anmeldedaten ein.<\/li>\n\n\n\n<li>Navigieren Sie in Ihrer <strong>n8n-Instanz<\/strong> zu &bdquo;<strong>Overview<\/strong>&rdquo; und klicken Sie auf &bdquo;<strong>Create Workflow<\/strong>&rdquo;.<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f53b0fcd\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f53b0fcd\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/create-workflow.png\/w=1024,h=1024,fit=scale-down\" alt=\"&Uuml;bersichtsseite der n8n-Instanz mit hervorgehobener Option &bdquo;Create Workflow&ldquo;.\" class=\"wp-image-122984\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><ol start=\"4\" class=\"wp-block-list\">\n<li>Klicken Sie oben rechts auf den dreifachen Punkt und dann auf &bdquo;<strong>Import from file<\/strong>&rdquo;&hellip;<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f53b74c7\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f53b74c7\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/import-from-file.png\/w=1024,h=1024,fit=scale-down\" alt=\"Workflow-Ansicht mit der Option &bdquo;Import from file...&ldquo; hervorgehoben.\" class=\"wp-image-122985\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><ol start=\"5\" class=\"wp-block-list\">\n<li>W&auml;hlen Sie Ihre gespeicherte Datei aus, und Ihre Vorlage wird hochgeladen.<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f53bc579\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f53bc579\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/uploaded-template.png\/w=1024,h=1024,fit=scale-down\" alt=\"Der erfolgreich hochgeladene n8n-Workflow wird angezeigt.\" class=\"wp-image-122986\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>\n\n<div><p class=\"important\"><strong>Wichtig!<\/strong> Beachten Sie die rot hervorgehobenen Knoten &ndash; dies bedeutet, dass der Knoten nicht einsatzbereit ist und konfiguriert werden muss.<\/p><\/div>\n\n\n\n<\/p><h3 class=\"wp-block-heading\"><strong>Ihre Vorlage konfigurieren<\/strong><\/h3><p>Vorgefertigte n8n Vorlagenknoten m&uuml;ssen unter Umst&auml;nden konfiguriert werden, bevor sie verwendet werden k&ouml;nnen. Diese erforderlichen Konfigurationen sind in der Regel unter &bdquo;<strong>Template description<\/strong>&rdquo; vermerkt. Stellen Sie sicher, dass Sie sie lesen und die entsprechende Konfiguration hinzuf&uuml;gen.<\/p><p>F&uuml;r diese Vorlage m&uuml;ssen die Knoten &bdquo;<strong>Fetch URLs<\/strong>&rdquo;, &bdquo;<strong>URLs to Monitor<\/strong>&rdquo; und &bdquo;<strong>Send Alert Email<\/strong>&rdquo; konfiguriert werden. Konfigurieren wir den Knoten &bdquo;<strong>Fetch URLs<\/strong>&rdquo;.<\/p><ol class=\"wp-block-list\">\n<li>Doppelklicken Sie auf den Knoten. Dadurch wird die Knotenkonfiguration angezeigt. Erforderliche Werte, die nicht ausgef&uuml;llt sind, werden in rot hervorgehoben.<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f53cefac\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f53cefac\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/fetch-urls-credentials-missing.png\/w=1024,h=1024,fit=scale-down\" alt=\"Fehlermeldung wegen fehlender Anmeldedaten f&uuml;r den Knoten &bdquo;Fetch URLs&ldquo; wird angezeigt.\" class=\"wp-image-122989\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><ol start=\"2\" class=\"wp-block-list\">\n<li>Wenn Sie bereits Anmeldedaten konfiguriert haben, klicken Sie auf die <strong>Dropdown-Liste<\/strong>, w&auml;hlen Sie die gew&uuml;nschten Anmeldedaten aus und fahren Sie mit Schritt 8 fort.<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f53e1ec1\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f53e1ec1\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/use-existing-credentials.png\/w=1024,h=1024,fit=scale-down\" alt=\"Hervorgehobene Option zur Verwendung vorhandener Anmeldedaten f&uuml;r einen Knoten.\" class=\"wp-image-122990\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><ol start=\"3\" class=\"wp-block-list\">\n<li>Wenn Sie noch keine Zugangsdaten haben oder neue verwenden m&ouml;chten, klicken Sie auf <strong>die Dropdown-Liste<\/strong> &rarr; &bdquo;<strong>Create new credential<\/strong>&rdquo;<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f53e7865\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f53e7865\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/create-new-credential.png\/w=1024,h=1024,fit=scale-down\" alt='&bdquo;Create new Credential\"-Option, die f&uuml;r einen Knoten hervorgehoben ist.' class=\"wp-image-122991\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><ol start=\"4\" class=\"wp-block-list\">\n<li>Geben Sie Ihre Daten ein, um n8n &uuml;ber seine API in Google Cloud zu integrieren. Wenn Sie Hilfe ben&ouml;tigen, bietet n8n eine Schritt-f&uuml;r-Schritt-Anleitung f&uuml;r die <a href=\"https:\/\/docs.n8n.io\/integrations\/builtin\/credentials\/google\/oauth-single-service\/?utm_source=n8n_app&amp;utm_medium=credential_settings&amp;utm_campaign=create_new_credentials_modal\" target=\"_blank\" rel=\"noopener\"><strong>Einrichtung von OAuth<\/strong><\/a>.<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f5405962\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f5405962\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/cred-creation.png\/w=1024,h=1024,fit=scale-down\" alt=\"Ansicht der Schnittstelle zur Konfiguration von Anmeldeinformationen\" class=\"wp-image-122992\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><ol start=\"5\" class=\"wp-block-list\">\n<li>Sobald die Felder <strong>Client ID<\/strong> und <strong>Client Secret<\/strong> ausgef&uuml;llt sind, klicken Sie auf &bdquo;<strong>Sign in with Google<\/strong>&rdquo; und authentifizieren Sie sich mit Ihrem Google-Konto:<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f540b014\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f540b014\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/signin-with-google.png\/w=1024,h=1024,fit=scale-down\" alt=\"Die Option &bdquo;Sign in with Google&ldquo; wird angezeigt, sobald die Client-ID und der Client-Secret eingegeben wurden.\" class=\"wp-image-122993\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><ol start=\"6\" class=\"wp-block-list\">\n<li>Nachdem Sie sich bei Google angemeldet haben, wird die Best&auml;tigung der erfolgreichen Verbindung angezeigt.<\/li>\n\n\n\n<li>Schlie&szlig;en Sie die Schnittstelle f&uuml;r die Konfiguration Ihrer Anmeldeinformationen, um zu Ihren Knoteneinstellungen zur&uuml;ckzukehren. Vergewissern Sie sich, dass Ihre Anmeldeinformationen eingestellt sind und dass die Werte f&uuml;r &bdquo;<strong>Document<\/strong>&rdquo; und &bdquo;<strong>Sheet<\/strong>&rdquo; auf eine Google Sheets-Datei verweisen, die URLs enth&auml;lt, die Sie &uuml;berwachen m&ouml;chten.<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f5410182\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f5410182\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/fetchurls-configured-node.png\/w=1024,h=1024,fit=scale-down\" alt='&bdquo;Fetch URL\"-Knoten mit vollst&auml;ndig konfigurierten Optionen' class=\"wp-image-122994\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>Die Google Sheets-Datei ist ein einfaches Sheet mit einer Kopfzeile in der ersten Zeile und einer Liste von URLs unterhalb der Kopfzeile in Spalte A. So k&ouml;nnte ein Beispielsheet aussehen:<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f541f051\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f541f051\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/sheet-example.png\/w=1024,h=1024,fit=scale-down\" alt=\"Beispiel einer Google Sheets-Datei f&uuml;r diesen Workflow\" class=\"wp-image-122995\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>Lassen Sie uns nun schnell die restlichen Knoten &uuml;berpr&uuml;fen:<\/p><ul class=\"wp-block-list\">\n<li>Der Knoten &bdquo;<strong>URLs to Monitor<\/strong>&rdquo; sollte automatisch die Anmeldeinformationen verwenden, die Sie in den vorherigen Schritten authentifiziert haben. Sie m&uuml;ssen jedoch die Werte f&uuml;r &bdquo;Document&rdquo; und &bdquo;Sheet&rdquo; festlegen.<\/li>\n\n\n\n<li>Um den Knoten &bdquo;<strong>Send Alert Email<\/strong>&rdquo; einzurichten, m&uuml;ssen Sie Ihr Konto erneut authentifizieren, da n8n f&uuml;r jeden Integrationstyp separate Anmeldeinformationen ben&ouml;tigt. Sie k&ouml;nnen jedoch denselben OAuth-Client erneut authentifizieren, den Sie f&uuml;r Google Sheets konfiguriert haben. Geben Sie dann die E-Mail, an die Sie die Benachrichtigung senden m&ouml;chten, in das Feld &bdquo;<strong>To<\/strong>&rdquo; ein.<\/li>\n<\/ul><p>Aktualisieren Sie diese Knoten auf dieselbe Weise, wie Sie den Knoten &bdquo;<strong>Fetch URLs<\/strong>&rdquo; konfiguriert haben.<\/p><p>Wenn die Konfiguration abgeschlossen ist, sollten in Ihrem Workflow keine rot markierten Knoten vorhanden sein:<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f5425006\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f5425006\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/workflow-configured.png\/w=1024,h=1024,fit=scale-down\" alt=\"Beispiel f&uuml;r einen vollst&auml;ndig konfigurierten Workflow\" class=\"wp-image-122997\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>Um Ihren Workflow zu speichern, klicken Sie auf &bdquo;<strong>Save<\/strong>&rdquo;.<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f542ab68\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f542ab68\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/save-workflow.png\/w=1024,h=1024,fit=scale-down\" alt=\"&Uuml;bersicht &uuml;ber den Workflow mit hervorgehobener Schaltfl&auml;che &bdquo;Save&ldquo;\" class=\"wp-image-122999\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><h3 class=\"wp-block-heading\"><strong>Testen Ihres Workflows<\/strong><\/h3><p>Nachdem Sie alles eingerichtet haben, ist es an der Zeit, den Workflow zu testen. Klicken Sie unten auf dem Bildschirm &bdquo;Workflow&rdquo; auf &bdquo;<strong>Test workflow<\/strong>&rdquo;.<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f5437310\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f5437310\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/test-workflow-wideview.png\/w=1024,h=1024,fit=scale-down\" alt=\"&Uuml;bersicht &uuml;ber den Arbeitsablauf mit hervorgehobener Schaltfl&auml;che &bdquo;Test workflow&ldquo;\" class=\"wp-image-123000\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>Schauen wir uns die Ausgabe an:<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f543c0c0\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f543c0c0\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/partial-workflow.png\/w=1024,h=1024,fit=scale-down\" alt=\"Teilweise abgeschlossene Workflow-Ansicht, in der nicht alle Schritte ausgef&uuml;hrt wurden.\" class=\"wp-image-123001\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>Die <strong>gr&uuml;n<\/strong> hervorgehobenen Knoten wurden erfolgreich ausgef&uuml;hrt, aber Sie k&ouml;nnen sehen, dass der Knoten &bdquo;<strong>Send Alert Email<\/strong>&rdquo; immer noch grau ist, was bedeutet, dass er nicht ausgef&uuml;hrt wurde. Das ergibt Sinn, da die URL-Liste nur <strong>www.google.com<\/strong> enth&auml;lt &ndash; eine Website, die ein g&uuml;ltiges SSL-Zertifikat besitzt.<\/p><p>F&uuml;gen wir nun <strong>expired.badssl.com<\/strong> zur URL-Liste hinzu, eine Test-Website mit abgelaufenem SSL-Zertifikat, und f&uuml;hren den Test erneut durch:<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f54419ec\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f54419ec\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/url-list-with-badssl.png\/w=1024,h=1024,fit=scale-down\" alt=\"Beispiel-URL-Liste mit hinzugef&uuml;gtem Link zur Website f&uuml;r abgelaufene SSL-Zertifikate\" class=\"wp-image-123002\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>Da Sie nun ein abgelaufenes SSL-Zertifikat in unserer Liste haben, wurde erwartungsgem&auml;&szlig; der Knoten &bdquo;Send Alert Email&rdquo; ausgel&ouml;st:<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f54524f6\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f54524f6\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/workflow-completed.png\/w=1024,h=1024,fit=scale-down\" alt=\"Vollst&auml;ndig abgeschlossene Workflow-Ansicht\" class=\"wp-image-123003\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>Wenn Sie die E-Mail &uuml;berpr&uuml;fen, die Sie f&uuml;r den Knoten &bdquo;Send Alert Email&rdquo; eingestellt haben, sollten Sie eine neue Nachricht in Ihrem Posteingang sehen:<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f5458353\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f5458353\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/ssl-alert-email.png\/w=1024,h=1024,fit=scale-down\" alt=\"Beispiel einer E-Mail-Nachricht vom Knoten &bdquo;Warn-E-Mail senden&ldquo;.\n\" class=\"wp-image-123004\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>Damit sind die Konfiguration und der Test der n8n-Vorlage abgeschlossen. Jetzt m&uuml;ssen Sie sie nur noch aktivieren, indem Sie die Option &bdquo;<strong>Inactive<\/strong>&rdquo; umstellen:<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a572f545d44f\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a572f545d44f\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/2\/2025\/02\/activate-workflow.png\/w=1024,h=1024,fit=scale-down\" alt=\"&Uuml;bersicht &uuml;ber den Workflow, wobei die Option zur Aktivierung des Workflows hervorgehoben ist.\" class=\"wp-image-123005\"><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><h2 class=\"wp-block-heading\" id=\"h-fazit\"><strong>Fazit<\/strong><\/h2><p>n8n Vorlagen machen das Erstellen von Automatisierungen f&uuml;r jedermann zug&auml;nglich und verwandeln lange, komplexe Aufgaben in schnelle und m&uuml;helose Workflows. Ganz gleich, ob Sie sich um die IT k&uuml;mmern, Ihr Unternehmen optimieren oder zus&auml;tzliche Hilfe ben&ouml;tigen, um produktiv zu bleiben &ndash; diese vorgefertigten Workflows machen Ihnen das Leben leichter.<\/p><p>Diese Vorlagen stellen nur einen Bruchteil der Vielseitigkeit von n8n dar &ndash; seine Automatisierungsfunktionen reichen von der routinem&auml;&szlig;igen Planung von Aufgaben bis hin zu komplexeren IT-Vorg&auml;ngen und zeigen, was mit n8n automatisiert werden kann.<\/p><p>Durch den Einsatz von n8n k&ouml;nnen Sie Zeit sparen, Fehler minimieren und die Effizienz bei verschiedenen Aufgaben verbessern. Mit ein wenig Einrichtungsaufwand k&ouml;nnen Sie Ihre bevorzugten Tools integrieren, Workflows einrichten und sie den Rest erledigen lassen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Moderne Workflows erfordern mehr als nur Effizienz &ndash; sie erfordern intelligente Automatisierung, und n8n bietet genau das. Als Tool zur Workflow-Automatisierung hilft es Unternehmen und Einzelpersonen, ihre Workflows zu optimieren. Um n8n f&uuml;r alle Interessierten zug&auml;nglich zu machen, bietet die n8n-Community vorgefertigte Vorlagen an, die die Notwendigkeit komplexer Einstellungen beseitigen. In diesem Artikel stellen wir [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/de\/tutorials\/n8n-vorlagen\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":550,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rank_math_title":"Beste n8n Vorlagen f\u00fcr Produktivit\u00e4t, kleine Unternehmen und IT","rank_math_description":"Lesen Sie weiter, um die 15 besten Vorlagen f\u00fcr n8n f\u00fcr kleine Unternehmen, Produktivit\u00e4t und IT-Automatisierung zu finden.","rank_math_focus_keyword":"n8n vorlagen","footnotes":""},"categories":[25],"tags":[],"class_list":["post-6778","post","type-post","status-publish","format-standard","hentry","category-vps"],"hreflangs":[],"_links":{"self":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts\/6778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/users\/550"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/comments?post=6778"}],"version-history":[{"count":5,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts\/6778\/revisions"}],"predecessor-version":[{"id":6855,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts\/6778\/revisions\/6855"}],"wp:attachment":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/media?parent=6778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/categories?post=6778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/tags?post=6778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}