{"id":11936,"date":"2026-05-26T15:37:00","date_gmt":"2026-05-26T08:37:00","guid":{"rendered":"\/de\/tutorials\/?p=11936"},"modified":"2026-05-26T14:37:39","modified_gmt":"2026-05-26T07:37:39","slug":"docker-container-erstellen","status":"publish","type":"post","link":"\/de\/tutorials\/docker-container-erstellen\/","title":{"rendered":"So erstellen Sie einen Docker-Container f\u00fcr eine effiziente Anwendungsbereitstellung"},"content":{"rendered":"<p>Mit Docker-Containern k&ouml;nnen Sie Anwendungen in unterschiedlichen Umgebungen effizient bereitstellen und verwalten. Lesen Sie weiter, um zu erfahren, wie Sie einen Docker-Container erstellen und Ihre Entwicklungs- sowie Bereitstellungsprozesse optimieren.<\/p><p>Einen Docker-Container zu erstellen ist unkompliziert:<\/p><ol class=\"wp-block-list\">\n<li><strong>Ein Docker-Image herunterladen<\/strong>. Ein Image ist eine Vorlage, die den gesamten erforderlichen Code sowie alle Bibliotheken und Abh&auml;ngigkeiten enth&auml;lt. Sie k&ouml;nnen Images aus &ouml;ffentlichen Registries wie Docker Hub herunterladen.<\/li>\n\n\n\n<li><strong>Ein Dockerfile erstellen<\/strong>. Wenn Sie ein benutzerdefiniertes Image ben&ouml;tigen, erstellen Sie ein Dockerfile &ndash; eine einfache Textdatei mit Anweisungen dazu, wie Docker das Image erstellen soll.<\/li>\n\n\n\n<li><strong>Den Container erstellen<\/strong>. Mithilfe des Images f&uuml;hren Sie einen Befehl aus, um eine laufende Instanz des Containers zu starten.<\/li>\n\n\n\n<li><strong>Container verwalten<\/strong>. Sobald der Container ausgef&uuml;hrt wird, k&ouml;nnen Sie seinen Lebenszyklus mit Befehlen zum Starten, Stoppen und &Uuml;berwachen verwalten.<\/li>\n<\/ol><h2 class=\"wp-block-heading\" id=\"h-what-is-a-docker-container\">Was ist ein Docker-Container?<\/h2><p>Ein Docker-Container ist ein <strong>leichtgewichtiges, eigenst&auml;ndiges Softwarepaket, das alles enth&auml;lt, was zum Ausf&uuml;hren einer Anwendung erforderlich ist: Code, Bibliotheken, Abh&auml;ngigkeiten und Laufzeitumgebung<\/strong>.<\/p><p>So wie ein physischer Container von einem Schiff auf einen Zug und dann auf einen Lkw umgeladen werden kann, ohne dass sich sein Inhalt ver&auml;ndert, k&ouml;nnen Sie mit einem Docker-Container eine App vom Laptop eines Entwicklers in eine Testumgebung und anschlie&szlig;end in die Produktion verschieben, ohne etwas daran zu &auml;ndern.<\/p><p>Damit l&ouml;sen Sie das klassische Problem &bdquo;Bei mir funktioniert es&ldquo;.<\/p><p>Sie k&ouml;nnen zum Beispiel einen MySQL-Container ausf&uuml;hren, um eine portable Datenbank bereitzustellen, oder einen Node.js-Container f&uuml;r Web-Apps.<\/p><p>Container basieren auf Docker-Images, die als Vorlage dienen. Jedes Mal, wenn Sie ein Image ausf&uuml;hren, erstellt Docker eine neue Container-Instanz.<\/p><h2 class=\"wp-block-heading\" id=\"h-prerequisites\">Voraussetzungen<\/h2><p>Bevor Sie mit dem Erstellen von Containern beginnen, stellen Sie sicher, dass Sie Folgendes haben:<\/p><ul class=\"wp-block-list\">\n<li><strong>Ein Server oder ein lokaler Rechner<\/strong>. In dieser Anleitung wird ein <strong>Ubuntu 24.04 Server<\/strong> verwendet, aber die Befehle funktionieren auf den meisten modernen Linux-Distributionen.<\/li>\n\n\n\n<li><strong>Docker ist installiert<\/strong>. Stellen Sie sicher, dass es auf Ihrem System l&auml;uft. Wenn Sie Hilfe ben&ouml;tigen, folgen Sie unserer Anleitung zum <a href=\"\/de\/tutorials\/docker-auf-ubuntu-installieren\/\">Installieren von Docker unter Ubuntu<\/a>.<\/li>\n\n\n\n<li><strong>Grundkenntnisse der Befehlszeile<\/strong>. Grundkenntnisse im Navigieren durch Verzeichnisse und im Ausf&uuml;hren einfacher Docker-Befehle sind hilfreich.<\/li>\n<\/ul><p>F&uuml;r Kunden von <a href=\"\/de\/docker-hosting\">Hostingers Docker-VPS<\/a> werden Docker und alle daf&uuml;r erforderlichen Komponenten bei der Einrichtung Ihres Servers automatisch installiert.<\/p><p>Wenn Sie einen unserer regul&auml;ren VPS-Tarife nutzen, m&uuml;ssen Sie sich keine Sorgen machen. Mit nur wenigen Klicks richten Sie Docker selbst ein:<\/p><ol class=\"wp-block-list\">\n<li>Melden Sie sich mit Ihrem Hostinger-Konto bei hPanel an und wechseln Sie dann zu <strong>VPS<\/strong> &rarr; <strong>Verwalten<\/strong>.<\/li>\n\n\n\n<li>W&auml;hlen Sie in der linken Seitenleiste Ihres VPS-Dashboards <strong>Betriebssystem und Panel<\/strong> &rarr; <strong>Betriebssystem<\/strong> aus.<\/li>\n\n\n\n<li>Scrollen Sie nach unten zum Abschnitt <strong>Betriebssystem &auml;ndern<\/strong>, geben Sie <strong>Docker<\/strong> in das Suchfeld ein und w&auml;hlen Sie den Eintrag aus.<\/li>\n\n\n\n<li>Folgen Sie den Anweisungen auf dem Bildschirm und warten Sie etwa <strong>f&uuml;nf Minuten<\/strong>, bis der Vorgang abgeschlossen ist.<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712f90574e\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712f90574e\" class=\"aligncenter size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1015\" height=\"231\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/choose-docker-hpanel.png\" alt=\"Die Docker-Vorlage im hPanel-VPS\" class=\"wp-image-11454\" srcset=\"https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/choose-docker-hpanel.png 1015w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/choose-docker-hpanel-300x68.png 300w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/choose-docker-hpanel-768x175.png 768w\" sizes=\"(max-width: 1015px) 100vw, 1015px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><figure class=\"wp-block-image size-large\"><a href=\"\/de\/vps-server\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2024\/02\/DE-VPS-hosting_in-text-banner.png\/w=1024,h=1024,fit=scale-down\" alt=\"\" class=\"wp-image-3556\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2024\/02\/DE-VPS-hosting_in-text-banner.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2024\/02\/DE-VPS-hosting_in-text-banner.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2024\/02\/DE-VPS-hosting_in-text-banner.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><h2 class=\"wp-block-heading\" id=\"h-how-to-create-a-docker-container\">So erstellen Sie einen Docker-Container<\/h2><p>Das Erstellen eines Docker-Containers umfasst vier Hauptschritte. Im Folgenden behandeln wir alles &ndash; vom Herunterladen eines Basis-Images bis zum Starten und Verwalten Ihres neuen Containers.<\/p><h3 class=\"wp-block-heading\" id=\"h-1-build-a-docker-image\">1. Docker-Image erstellen<\/h3><p>Ein Docker-Image ist die Blaupause f&uuml;r Ihren Container und enth&auml;lt die erforderlichen Dateien und Anweisungen, um Ihre App auszuf&uuml;hren. Sie k&ouml;nnen Images von Grund auf selbst erstellen, aber deutlich schneller geht es mit offiziellen, vorgefertigten Images auf <a href=\"https:\/\/hub.docker.com\" target=\"_blank\" rel=\"noopener\">Docker Hub<\/a>.<\/p><ol class=\"wp-block-list\">\n<li>Erstellen Sie ein Verzeichnis f&uuml;r Ihre App und wechseln Sie dann dorthin:<\/li>\n<\/ol><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">mkdir myapp &amp;&amp; cd myapp<\/pre><ol start=\"2\" class=\"wp-block-list\">\n<li>Rufen Sie mit dem Befehl `docker pull` gefolgt vom Image-Namen ein Image von Docker Hub auf Ihr lokales System ab:<\/li>\n<\/ol><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">docker pull image_name<\/pre><p>Zum Beispiel, um das neueste MySQL-Image zu erhalten:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">docker pull mysql<\/pre><ol start=\"3\" class=\"wp-block-list\">\n<li>Sobald der Download abgeschlossen ist, listen Sie alle Images auf Ihrem System auf, um zu pr&uuml;fen, ob das Image vorhanden ist:<\/li>\n<\/ol><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">docker images<\/pre><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712f90781d\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712f90781d\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"525\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-images-herunterladen.png\/w=1024,h=1024,fit=scale-down\" alt=\"Eine Terminalausgabe nach dem Ausf&uuml;hren der Befehle `docker pull` und `images`\" class=\"wp-image-11930\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-images-herunterladen.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-images-herunterladen.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-images-herunterladen.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><h3 class=\"wp-block-heading\" id=\"h-2-write-a-dockerfile\">2. Dockerfile schreiben<\/h3><p>Wenn ein vorgefertigtes Image Ihren Anforderungen nicht entspricht, k&ouml;nnen Sie mit einer Dockerfile ein benutzerdefiniertes Image erstellen. Dies ist ein Textdokument, das alle Befehle enth&auml;lt, die zum Erstellen eines Bildes erforderlich sind.<\/p><p>\n\n\n<div><p class=\"important\"><strong>Wichtig!<\/strong> Dieser Schritt ist nur f&uuml;r benutzerdefinierte Apps erforderlich. Wenn Sie direkt ein vorgefertigtes Image wie MySQL verwenden, fahren Sie mit dem n&auml;chsten Schritt fort.<\/p><\/div>\n\n\n\n<\/p><ol class=\"wp-block-list\">\n<li>Erstellen Sie eine Dockerfile mit dem nano-Texteditor:<\/li>\n<\/ol><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">nano Dockerfile<\/pre><ol start=\"2\" class=\"wp-block-list\">\n<li>F&uuml;gen Sie den folgenden Beispielinhalt f&uuml;r die Dockerfile in die Datei ein. Dadurch wird ein einfacher HTTP-Server in Python erstellt.<\/li>\n<\/ol><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\"># Verwenden Sie das offizielle Python-Image von Docker Hub\nFROM python:3.8-slim\n\n# Legen Sie das Arbeitsverzeichnis im Container fest\nWORKDIR \/app\n\n# Installieren Sie curl (nur als Beispiel f&uuml;r die Verwendung von RUN)\nRUN apt-get update &amp;&amp; apt-get install -y curl\n\n# Geben Sie den Port frei, auf dem der HTTP-Server ausgef&uuml;hrt wird\nEXPOSE 8000\n\n# Starten Sie einen einfachen HTTP-Server, wenn der Container ausgef&uuml;hrt wird\nCMD [\"python\", \"-m\", \"http.server\", \"8000\"]<\/pre><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"586\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-nano-dockerfile.png\/w=1024,h=1024,fit=scale-down\" alt=\"Beispiel f&uuml;r den Inhalt einer Dockerfile\" class=\"wp-image-11900\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-nano-dockerfile.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-nano-dockerfile.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-nano-dockerfile.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><p>Hier ist eine kurze &Uuml;bersicht &uuml;ber die wichtigsten Befehle:<\/p><ul class=\"wp-block-list\">\n<li><strong>FROM<\/strong>. Gibt das Basis-Image an, auf dem der Build aufsetzt.<\/li>\n\n\n\n<li><strong>RUN<\/strong>. F&uuml;hrt w&auml;hrend des Build-Prozesses einen Befehl aus, etwa um Software zu installieren.<\/li>\n\n\n\n<li><strong>CMD<\/strong>. Legt den Standardbefehl f&uuml;r einen ausgef&uuml;hrten Container fest.<\/li>\n<\/ul><ol start=\"3\" class=\"wp-block-list\">\n<li>Sobald Sie fertig sind, speichern Sie die Datei und beenden <strong>nano<\/strong>, indem Sie <strong>Strg + X &rarr; Y &rarr; Eingabetaste<\/strong> dr&uuml;cken.<\/li>\n<\/ol><h3 class=\"wp-block-heading\" id=\"h-3-create-the-docker-container\">3. Docker-Container erstellen<\/h3><p>Jetzt ist es an der Zeit, den Container zu erstellen. Sie verwenden zwei zentrale Befehle: <strong>docker build<\/strong>, um aus einem Dockerfile ein Image zu erstellen, und <strong>docker run<\/strong>, um aus einem Image einen Container zu erstellen und zu starten.<\/p><ol class=\"wp-block-list\">\n<li>Wenn Sie eine Dockerfile erstellt haben, f&uuml;hren Sie <strong>docker build<\/strong> mit dem Flag <strong>-t<\/strong> aus, um das Image mit einem Namen zu versehen. Zum Beispiel:<\/li>\n<\/ol><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">docker build -t my-python-server .<\/pre><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712f9124bb\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712f9124bb\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"600\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-build.png\/w=1024,h=1024,fit=scale-down\" alt=\"Eine Terminalausgabe nach dem Ausf&uuml;hren des Befehls `docker build`\" class=\"wp-image-11901\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-build.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-build.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-build.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><ol start=\"2\" class=\"wp-block-list\">\n<li>Sobald Ihr Image bereit ist &ndash; unabh&auml;ngig davon, ob Sie es erstellt oder heruntergeladen haben &ndash; erstellen Sie den Container mit <strong>docker run<\/strong>. So starten Sie einen Container mit Ihrem benutzerdefinierten Python-Image:<\/li>\n<\/ol><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">docker run --name my-python-container -d -p 8000:8000 my-python-server<\/pre><p>Wenn Sie das MySQL-Image ausf&uuml;hren m&ouml;chten, das Sie zuvor heruntergeladen haben, verwenden Sie:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">docker run --name my-mysql-container -e MYSQL_ROOT_PASSWORD=my-secret-password -d mysql<\/pre><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712f912fbb\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712f912fbb\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"77\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-run.png\/w=1024,h=1024,fit=scale-down\" alt=\"Eine Terminalausgabe nach dem Ausf&uuml;hren der `docker run`-Befehle\" class=\"wp-image-11932\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-run.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-run.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-run.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>Bei beiden Befehlen weist <strong>&ndash;name<\/strong> einen benutzerdefinierten Namen f&uuml;r eine einfachere Verwaltung zu, und <strong>-d<\/strong> f&uuml;hrt den Container im Detached-Modus aus (im Hintergrund).<\/p><h3 class=\"wp-block-heading\" id=\"h-4-run-and-manage-containers\">4. Container ausf&uuml;hren und verwalten<\/h3><p>Sobald Ihr Container l&auml;uft, k&ouml;nnen Sie ihn mit mehreren n&uuml;tzlichen Befehlen verwalten.<\/p><ul class=\"wp-block-list\">\n<li>Laufende Container auflisten:<\/li>\n<\/ul><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">docker ps<\/pre><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712f913b9a\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712f913b9a\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"53\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-ps.png\/w=1024,h=1024,fit=scale-down\" alt=\"Eine Terminalausgabe nach dem Ausf&uuml;hren des Befehls `docker ps`\" class=\"wp-image-11933\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-ps.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-ps.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-ps.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><ul class=\"wp-block-list\">\n<li>Container-Protokolle zur Fehlerbehebung anzeigen:<\/li>\n<\/ul><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">docker logs my-mysql-container<\/pre><ul class=\"wp-block-list\">\n<li>Einen Container stoppen:<\/li>\n<\/ul><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">docker stop my-mysql-container<\/pre><ul class=\"wp-block-list\">\n<li>Ressourcennutzung in Echtzeit pr&uuml;fen:<\/li>\n<\/ul><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">docker stats<\/pre><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712f914709\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712f914709\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"59\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-stats.png\/w=1024,h=1024,fit=scale-down\" alt=\"Eine Terminalausgabe nach dem Ausf&uuml;hren des Befehls docker stats\" class=\"wp-image-11935\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-stats.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-stats.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2026\/05\/terminal-docker-stats.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>F&uuml;r die erweiterte Container-Verwaltung verwenden Sie den Befehl <strong>docker exec<\/strong>. Damit k&ouml;nnen Sie einen Befehl in einem bereits laufenden Container ausf&uuml;hren, ohne dessen Betrieb zu unterbrechen.<\/p><h2 class=\"wp-block-heading\" id=\"h-why-use-docker-containers\">Warum Docker-Container verwenden<\/h2><p>Docker-Container bieten Entwicklern und Unternehmen erheliche Vorteile, da sie die Entwicklung, Bereitstellung und Ausf&uuml;hrung von Anwendungen effizienter machen. Hier sind die wichtigsten Vorteile:<\/p><ul class=\"wp-block-list\">\n<li><strong>&Uuml;bertragbarkeit<\/strong>. Container b&uuml;ndeln eine Anwendung mit ihren Abh&auml;ngigkeiten, sodass sie in jeder Umgebung konsistent ausgef&uuml;hrt wird &ndash; vom lokalen Rechner bis zur Cloud.<\/li>\n\n\n\n<li><strong>Kosteneffizienz<\/strong>. Container nutzen gemeinsam den Kernel des Hostsystems und sind dadurch deutlich schlanker als herk&ouml;mmliche virtuelle Maschinen (VMs). Dadurch k&ouml;nnen Sie auf einem einzelnen Server mehr Container ausf&uuml;hren und die verf&uuml;gbaren Ressourcen effizienter nutzen.<\/li>\n\n\n\n<li><strong>Skalierbarkeit<\/strong>. Sie k&ouml;nnen schnell mehrere Instanzen eines Containers erstellen, um eine h&ouml;here Last zu bew&auml;ltigen, und Anwendungen bei Bedarf problemlos hoch- oder herunterskalieren.<\/li>\n\n\n\n<li><strong>Geschwindigkeit<\/strong>. Docker-Container lassen sich innerhalb weniger Sekunden erstellen und beschleunigen dadurch Entwicklungs-, Test- und Bereitstellungszyklen.<\/li>\n\n\n\n<li><strong>Isolation<\/strong>. Jeder Container l&auml;uft in einer isolierten Umgebung, wodurch Konflikte zwischen Anwendungen und ihren Abh&auml;ngigkeiten vermieden werden.<\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-what-are-some-docker-container-best-practices\">Was sind bew&auml;hrte Verfahren f&uuml;r Docker-Container?<\/h2><p>Wenn Sie bew&auml;hrte Methoden befolgen, sind Ihre Docker-Container effizient, sicher und leicht zu verwalten. Diese sind besonders n&uuml;tzlich in Szenarien wie dem Hosting von Websites und der Bereitstellung von Apps.<\/p><ul class=\"wp-block-list\">\n<li><strong>Halten Sie Bilder m&ouml;glichst schlank<\/strong>. Verwenden Sie zun&auml;chst ein minimales Basis-Image wie <strong>alpine<\/strong>. Kombinieren Sie in Ihrer Dockerfile <strong>RUN<\/strong>-Befehle und entfernen Sie tempor&auml;re Dateien in derselben Ebene, um die Image-Gr&ouml;&szlig;e zu minimieren. Zum Beispiel:<\/li>\n<\/ul><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">RUN apt-get update &amp;&amp; apt-get install -y python3 &amp;&amp; rm -rf \/var\/lib\/apt\/lists\/*<\/pre><ul class=\"wp-block-list\">\n<li><strong>Verwenden Sie offizielle Bilder<\/strong>. Verwenden Sie nach M&ouml;glichkeit offizielle Images aus Docker Hub. Sie werden regelm&auml;&szlig;ig aktualisiert, auf Sicherheitsl&uuml;cken gepr&uuml;ft und f&uuml;r eine optimale Leistung optimiert.<\/li>\n\n\n\n<li><strong>F&uuml;hren Sie Container als Nicht-Root-Benutzer aus<\/strong>. Standardm&auml;&szlig;ig werden Container mit Root-Rechten ausgef&uuml;hrt, was ein Sicherheitsrisiko darstellt. Erstellen Sie in Ihrer Dockerfile einen eigenen Benutzer und verwenden Sie die Anweisung <strong>USER<\/strong>, damit die App mit geringeren Berechtigungen ausgef&uuml;hrt wird.<\/li>\n\n\n\n<li><strong>Sch&uuml;tzen Sie sensible Informationen<\/strong>. Vermeiden Sie, sensible Daten wie API-Schl&uuml;ssel direkt in Ihrer Dockerfile fest zu hinterlegen. Verwenden Sie Umgebungsvariablen (Flag <strong>-e<\/strong>) oder Docker-Secrets, um sensible Informationen sicher zu verwalten.<\/li>\n\n\n\n<li><strong>Container-Ressourcen begrenzen<\/strong>. Verhindern Sie, dass ein einzelner Container s&auml;mtliche Ressourcen des Hosts beansprucht, indem Sie beim Ausf&uuml;hren CPU- und Arbeitsspeicherlimits festlegen:<\/li>\n<\/ul><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">docker run --cpus=0.5 --memory=500m image-name<\/pre><h2 class=\"wp-block-heading\" id=\"h-next-steps-for-using-docker-containers\">N&auml;chste Schritte f&uuml;r die Arbeit mit Docker-Containern<\/h2><p>Wir haben behandelt, wie Sie Docker-Container erstellen, verwalten und optimieren, um konsistentere, portablere und effizientere Anwendungen zu entwickeln. Diese Grundlage vereinfacht den Entwicklungszyklus und macht die Softwarebereitstellung zuverl&auml;ssiger.<\/p><p>Wenn Sie mit mehreren Containern f&uuml;r eine einzelne Anwendung arbeiten, sollten Sie sich mit Container-Orchestrierung befassen. Tools wie <strong>Docker Swarm<\/strong> und <strong>Kubernetes<\/strong> automatisieren die Bereitstellung, Skalierung und Verwaltung containerisierter Anwendungen.<\/p><p>Docker Swarm l&auml;sst sich einfach einrichten und ist eng in Docker integriert. Dadurch eignet sich die L&ouml;sung besonders f&uuml;r kleine bis mittelgro&szlig;e Cluster. Kubernetes bietet dagegen mehr Flexibilit&auml;t und umfangreichere Funktionen und ist damit ideal f&uuml;r gro&szlig;e, produktionsreife Bereitstellungen mit erweiterten Planungs- und Selbstheilungsfunktionen.<\/p><p>Nutzen Sie Docker Swarm f&uuml;r eine schlanke und einfach zu verwaltende L&ouml;sung oder Kubernetes, wenn Sie maximale Flexibilit&auml;t und Skalierbarkeit ben&ouml;tigen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit Docker-Containern k&ouml;nnen Sie Anwendungen in unterschiedlichen Umgebungen effizient bereitstellen und verwalten. Lesen Sie weiter, um zu erfahren, wie Sie einen Docker-Container erstellen und Ihre Entwicklungs- sowie Bereitstellungsprozesse optimieren. Einen Docker-Container zu erstellen ist unkompliziert: Was ist ein Docker-Container? Ein Docker-Container ist ein leichtgewichtiges, eigenst&auml;ndiges Softwarepaket, das alles enth&auml;lt, was zum Ausf&uuml;hren einer Anwendung erforderlich [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/de\/tutorials\/docker-container-erstellen\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":190,"featured_media":11929,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rank_math_title":"Docker-Container erstellen und verwalten","rank_math_description":"Docker-Container erstellen mit Images und Dockerfiles. Befehle und Best Practices f\u00fcr Performance und Sicherheit.","rank_math_focus_keyword":"Docker-Container erstellen","footnotes":""},"categories":[25],"tags":[],"class_list":["post-11936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vps"],"hreflangs":[],"_links":{"self":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts\/11936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/users\/190"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/comments?post=11936"}],"version-history":[{"count":5,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts\/11936\/revisions"}],"predecessor-version":[{"id":12246,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts\/11936\/revisions\/12246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/media\/11929"}],"wp:attachment":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/media?parent=11936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/categories?post=11936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/tags?post=11936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}