{"id":11549,"date":"2026-05-14T10:45:01","date_gmt":"2026-05-14T03:45:01","guid":{"rendered":"\/de\/tutorials\/?p=11549"},"modified":"2026-05-14T10:45:04","modified_gmt":"2026-05-14T03:45:04","slug":"n8n-mit-ollama-verbinden","status":"publish","type":"post","link":"\/de\/tutorials\/n8n-mit-ollama-verbinden\/","title":{"rendered":"Wie integrieren Sie n8n mit Ollama f\u00fcr lokale LLM-Workflows?"},"content":{"rendered":"<p>Die Integration von n8n mit Ollama erm&ouml;glicht es Ihnen, verschiedene KI-Modelle in Ihren Automatisierungs-Workflow einzubinden, sodass dieser komplexe Vorg&auml;nge ausf&uuml;hren kann, die andernfalls nicht m&ouml;glich w&auml;ren.<\/p><p>Allerdings kann der Prozess knifflig sein, da Sie in beiden Tools verschiedene Einstellungen konfigurieren m&uuml;ssen, damit sie reibungslos zusammenarbeiten.<\/p><p>Sobald n8n und Ollama bereits auf Ihrem Server installiert sind, k&ouml;nnen Sie beide in vier einfachen Schritten integrieren:<\/p><ol class=\"wp-block-list\">\n<li>F&uuml;gen Sie den Ollama Chat Model-Knoten hinzu<\/li>\n\n\n\n<li>W&auml;hlen Sie das KI-Modell aus und passen Sie die Laufzeiteinstellungen des KI-Modells an.<\/li>\n\n\n\n<li>Konfigurieren Sie die Prompt-Einstellungen des KI-Agent-Knotens<\/li>\n\n\n\n<li>Senden Sie einen Test-Prompt, um die Funktion zu &uuml;berpr&uuml;fen.<\/li>\n<\/ol><p>Nach Abschluss dieser Schritte verf&uuml;gen Sie &uuml;ber einen funktionierenden, von Ollama betriebenen Workflow zur KI-Verarbeitung, den Sie in ein umfassenderes Automatisierungssystem integrieren k&ouml;nnen. So k&ouml;nnen Sie zum Beispiel Messaging-Apps wie WhatsApp verbinden, um einen funktionsf&auml;higen KI-Chatbot zu erstellen.<\/p><p>Dar&uuml;ber hinaus haben Sie mehr Kontrolle &uuml;ber Ihre Daten, wenn Sie die Anwendung lokal auf einem privaten Server wie einem Hostinger VPS ausf&uuml;hren. Damit eignet sich die Integration f&uuml;r die Automatisierung von Aufgaben mit sensiblen Informationen, etwa f&uuml;r die Zusammenfassung interner Dokumente oder die Erstellung eines unternehmensinternen Chatbots.<\/p><p>Sehen wir uns im Detail an, wie Sie Ollama mit n8n verbinden und auf Basis dieser Integration einen Chatbot erstellen. Zum Schluss erl&auml;utern wir auch die g&auml;ngigen Anwendungsf&auml;lle f&uuml;r diese Integration und erweitern ihre M&ouml;glichkeiten mithilfe der LangChain-Knoten.<\/p><h2 class=\"wp-block-heading\" id=\"h-prerequisites\"><strong>Voraussetzungen<\/strong> <\/h2><p>Um n8n mit Ollama zu integrieren, m&uuml;ssen Sie die folgenden Voraussetzungen erf&uuml;llen:<\/p><ul class=\"wp-block-list\">\n<li><strong>Ollama muss lokal installiert sein<\/strong>. Stellen Sie sicher, dass Sie Ollama lokal auf einem Virtual Private Server (VPS) installiert haben. Der Host muss &uuml;ber ausreichend Hardware verf&uuml;gen, um die gew&uuml;nschten KI-Modelle auszuf&uuml;hren; daf&uuml;r k&ouml;nnen mehr als<strong> 8 GB<\/strong> RAM erforderlich sein. <\/li>\n\n\n\n<li><strong>n8n muss eingerichtet und zug&auml;nglich sein<\/strong>. Sie <a href=\"\/de\/tutorials\/wie-man-n8n-installiert\/\">installieren n8n<\/a> auf einem VPS und erstellen ein Konto. Aus Kompatibilit&auml;tsgr&uuml;nden muss es auf demselben Server wie Ollama konfiguriert werden.<\/li>\n\n\n\n<li><strong>Stellen Sie sicher, dass die erforderlichen Ports ge&ouml;ffnet sind<\/strong>. Vergewissern Sie sich, dass die Ports <strong>11434<\/strong> und <strong>5678<\/strong> auf Ihrem Server ge&ouml;ffnet sind, damit Ollama und n8n erreichbar sind. Wenn Sie sie auf einem Hostinger VPS hosten, pr&uuml;fen Sie die Ports und konfigurieren Sie sie, indem Sie einfach unseren <strong>KI-Assistenten Kodee<\/strong> fragen.<\/li>\n\n\n\n<li><strong>Grundlegende JSON-Kenntnisse<\/strong>. Lernen Sie, JSON zu lesen, da n8n-Knoten Daten in erster Linie in diesem Format austauschen. Dieses Verst&auml;ndnis hilft Ihnen, Daten gezielter auszuw&auml;hlen und Fehler effizienter zu beheben.<\/li>\n<\/ul><p>\n\n\n<div><p class=\"important\"><strong>Wichtig!<\/strong> Wir empfehlen dringend, sowohl n8n als auch Ollama f&uuml;r eine bessere Isolation im selben Docker-Container zu installieren. Das ist die Methode, mit der wir dieses Tutorial getestet haben; sie funktioniert also nachweislich.<br> Wenn Sie einen Hostinger-VPS verwenden, k&ouml;nnen Sie zun&auml;chst n8n oder Ollama in einem Docker-Container installieren, indem Sie einfach die entsprechende Betriebssystemvorlage ausw&auml;hlen &ndash; die Anwendung wird standardm&auml;&szlig;ig in einem Container installiert. Anschlie&szlig;end m&uuml;ssen Sie die andere App im selben Container installieren.<\/p><\/div>\n\n\n\n<\/p><h2 class=\"wp-block-heading\" id=\"h-how-to-set-up-ollama-integration-in-n8n\">Ollama-Integration in n8n einrichten<\/h2><p>Um Ollama mit n8n zu verbinden, m&uuml;ssen Sie den erforderlichen Knoten hinzuf&uuml;gen und mehrere Einstellungen konfigurieren. In diesem Abschnitt erl&auml;utern wir die einzelnen Schritte im Detail, einschlie&szlig;lich der Vorgehensweise zum Testen der Funktionalit&auml;t der Integration.<\/p><h3 class=\"wp-block-heading\" id=\"h-1-add-the-ollama-chat-model-node\"><strong>1. F&uuml;gen Sie den Ollama Chat Model-Knoten hinzu<\/strong> <\/h3><p>Durch das Hinzuf&uuml;gen des Ollama Chat Model-Knotens kann n8n &uuml;ber einen Konversationsagenten eine Verbindung zu Large Language Models (LLMs) auf der KI-Plattform herstellen.<\/p><p>n8n bietet zwei Ollama-Knoten: <strong>Ollama Model<\/strong> und <strong>Ollama Chat Model<\/strong>. Das <strong>Ollama Chat Model<\/strong> ist speziell f&uuml;r Konversationen ausgelegt und verf&uuml;gt &uuml;ber einen integrierten <strong>Basic LLM Chain<\/strong>-Knoten,<strong> <\/strong>der Ihre Nachricht an das ausgew&auml;hlte Modell weiterleitet. Der <strong>Ollama Model<\/strong>-Knoten eignet sich hingegen f&uuml;r allgemeinere Aufgaben mit anderen <strong>Chain<\/strong> -Knoten &ndash; darauf gehen wir im LangChain-Abschnitt noch n&auml;her ein.<\/p><p>In diesem Tutorial verwenden wir den Ollama Chat Model-Knoten, da er sich einfacher nutzen und in einen umfassenderen Workflow integrieren l&auml;sst. So f&uuml;gen Sie es in n8n hinzu:<\/p><ol class=\"wp-block-list\">\n<li>Greifen Sie auf Ihre n8n-Instanz zu. Je nach Ihrer Konfiguration sollten Sie die Seite im Webbrowser &uuml;ber den <strong>Hostnamen<\/strong> oder die <strong>IP-Adresse<\/strong> Ihres VPS &ouml;ffnen k&ouml;nnen. <\/li>\n\n\n\n<li>Melden Sie sich bei Ihrem n8n-Konto an. <\/li>\n\n\n\n<li>Erstellen Sie einen neuen Workflow, indem Sie auf die Schaltfl&auml;che oben rechts auf Ihrer n8n-Startseite klicken. <\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712e539201\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712e539201\" class=\"aligncenter size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"521\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/n8n-main-page-workflow-creation-button.png\" alt=\"Die Hauptseite von n8n, auf der die Schaltfl&auml;che zum Erstellen eines Workflows hervorgehoben ist\" class=\"wp-image-11535\" srcset=\"https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/n8n-main-page-workflow-creation-button.png 1024w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/n8n-main-page-workflow-creation-button-300x153.png 300w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/n8n-main-page-workflow-creation-button-768x391.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><ol start=\"4\" class=\"wp-block-list\">\n<li>Klicken Sie auf das <strong>Plus<\/strong> -Symbol und suchen Sie nach <strong>Ollama Chat Model<\/strong>.<\/li>\n\n\n\n<li>Klicken Sie auf den Knoten, um ihn hinzuzuf&uuml;gen. <\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712e539b2e\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712e539b2e\" class=\"aligncenter size-full is-resized wp-lightbox-container\"><img decoding=\"async\" width=\"936\" height=\"664\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/ollama-modell-knoten-in-n8n.png\" alt=\"Ollama-Modellknoten in n8n\" class=\"wp-image-11537\" style=\"width:558px;height:auto\" srcset=\"https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/ollama-modell-knoten-in-n8n.png 936w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/ollama-modell-knoten-in-n8n-300x213.png 300w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/ollama-modell-knoten-in-n8n-768x545.png 768w\" sizes=\"(max-width: 936px) 100vw, 936px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>Das Fenster zur Konfiguration des Knotens wird angezeigt. Fahren wir mit dem n&auml;chsten Schritt fort, um es einzurichten.<\/p><h3 class=\"wp-block-heading\" id=\"h-2-choose-your-model-and-runtime-settings\"><strong>2. W&auml;hlen Sie Ihr Modell und Ihre Laufzeiteinstellungen<\/strong> <\/h3><p>Bevor Sie ein KI-Modell ausw&auml;hlen und dessen Laufzeiteinstellungen konfigurieren, verbinden Sie n8n mit Ihrer selbst gehosteten Ollama-Instanz. So geht&rsquo;s:<\/p><ol class=\"wp-block-list\">\n<li>Erweitern Sie im Fenster f&uuml;r die Knotenkonfiguration das Dropdown-Men&uuml; <strong>Credential to connect with<\/strong>.<\/li>\n\n\n\n<li>W&auml;hlen Sie <strong>Create new credential<\/strong> aus.<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712e53a45a\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712e53a45a\" class=\"aligncenter size-full wp-lightbox-container\"><img decoding=\"async\" width=\"958\" height=\"600\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/ollama-chat-node-schaltflache-zum-erstellen-neuer-anmeldedaten.png\" alt=\"Neue Schaltfl&auml;che zum Erstellen von Zugangsdaten des Ollama-Chat-Knotens\" class=\"wp-image-11540\" srcset=\"https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/ollama-chat-node-schaltflache-zum-erstellen-neuer-anmeldedaten.png 958w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/ollama-chat-node-schaltflache-zum-erstellen-neuer-anmeldedaten-300x188.png 300w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/ollama-chat-node-schaltflache-zum-erstellen-neuer-anmeldedaten-768x481.png 768w\" sizes=\"(max-width: 958px) 100vw, 958px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><ol start=\"3\" class=\"wp-block-list\">\n<li>Geben Sie die Basis-URL Ihrer Ollama-Instanz ein. Je nach Ihrer Hosting-Umgebung kann dies <strong>localhost<\/strong> oder der <strong>Name Ihres Ollama-Docker-Containers<\/strong> sein.<\/li>\n\n\n\n<li>Klicken Sie auf <strong>Save<\/strong>.<\/li>\n<\/ol><p>Wenn die Verbindung erfolgreich ist, wird eine Best&auml;tigungsmeldung angezeigt. Stellen Sie andernfalls sicher, dass die Adresse korrekt ist und Ihre Ollama-Instanz l&auml;uft.<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712e53ac58\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712e53ac58\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"585\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/eine-bestaetigungsnachricht-die-die-verbindung-von-n8n-mit-ollama-bestaetigt.png\" alt=\"Eine Best&auml;tigungsnachricht, die die Verbindung von n8n mit Ollama best&auml;tigt\" class=\"wp-image-11541\" srcset=\"https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/eine-bestaetigungsnachricht-die-die-verbindung-von-n8n-mit-ollama-bestaetigt.png 1024w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/eine-bestaetigungsnachricht-die-die-verbindung-von-n8n-mit-ollama-bestaetigt-300x171.png 300w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/eine-bestaetigungsnachricht-die-die-verbindung-von-n8n-mit-ollama-bestaetigt-768x439.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>Sobald die Verbindung hergestellt ist, k&ouml;nnen Sie im Ollama-Modell-Knoten das zu verwendende LLM ausw&auml;hlen. &Ouml;ffnen Sie dazu einfach das Dropdown-Men&uuml; <strong>Model<\/strong> und w&auml;hlen Sie ein Modell aus der Liste aus. Wenn die Option ausgegraut ist, l&auml;sst sich das Problem durch Aktualisieren von n8n beheben.<\/p><p>Beachten Sie, dass n8n derzeit nur &auml;ltere Modelle wie Llama 3 und DeepSeek R1 unterst&uuml;tzt. Wenn das Men&uuml; <strong>Model<\/strong> einen Fehler und eine leere Liste anzeigt, liegt das h&ouml;chstwahrscheinlich daran, dass in Ihrer Ollama-Instanz nur inkompatible Modelle vorhanden sind.<\/p><p>Um das zu beheben, <a href=\"https:\/\/ollama.com\/library\" target=\"_blank\" rel=\"noreferrer noopener\">laden Sie einfach andere Ollama-Modelle herunter<\/a>. In der Ollama-CLI f&uuml;hren Sie dazu in Ihrer Ollama-Umgebung den folgenden Befehl aus:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">ollama run model-name<\/pre><p>Sie k&ouml;nnen auch ein Modell mit benutzerdefinierten Laufzeiteinstellungen verwenden, etwa mit einer h&ouml;heren Temperatur. So erstellen Sie eines in <a href=\"\/de\/tutorials\/ollama-cli-tutorial\/\">Ollama CLI<\/a>:<\/p><ol class=\"wp-block-list\">\n<li>Greifen Sie auf Ihre Ollama-Installation zu. Wenn Sie Docker verwenden, nutzen Sie den folgenden Befehl, wobei <strong>ollama<\/strong> dem tats&auml;chlichen Namen Ihres Containers entspricht:<\/li>\n<\/ol><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">docker exec -it ollama bash<\/pre><ol start=\"2\" class=\"wp-block-list\">\n<li>Erstellen Sie eine neue <a href=\"https:\/\/ollama.readthedocs.io\/en\/modelfile\/#format\" target=\"_blank\" rel=\"noreferrer noopener\">Modelfile<\/a>, in der die Laufzeiteinstellung Ihres Modells definiert ist. Zum Beispiel setzen wir die Temperatur unseres Llama-3-Modells auf <strong>0.7<\/strong>:<\/li>\n<\/ol><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">echo \"FROM llama3\" &gt; Modelfile<\/pre><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">echo \"PARAMETER temperature 0.7\" &gt;&gt; Modelfile<\/pre><ol start=\"3\" class=\"wp-block-list\">\n<li>F&uuml;hren Sie den folgenden Befehl aus, um die Modelfile-Konfiguration auf das Basis-Llama-3-Modell anzuwenden und ein benutzerdefiniertes LLM mit dem Namen <strong>llama3-temp07<\/strong> zu erstellen:<\/li>\n<\/ol><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">ollama create llama3-temp07 -f Modelfile<\/pre><p>Sobald Sie diese Schritte abgeschlossen haben, sollte n8n Ihr neues Llama-3-Modell mit der benutzerdefinierten Temperatur <strong>0.7<\/strong> verwenden.<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712e53b6ef\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712e53b6ef\" class=\"aligncenter size-large is-resized wp-lightbox-container\"><img decoding=\"async\" width=\"842\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/benutzerdefiniertes-ollama-modell-in-n8n.png\" alt=\"ein benutzerdefiniertes Ollama-Modell in n8n\" class=\"wp-image-11542\" style=\"width:520px;height:auto\" srcset=\"https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/benutzerdefiniertes-ollama-modell-in-n8n.png 842w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/benutzerdefiniertes-ollama-modell-in-n8n-247x300.png 247w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/benutzerdefiniertes-ollama-modell-in-n8n-768x934.png 768w\" sizes=\"(max-width: 842px) 100vw, 842px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>\n\n<div class=\"protip\">\n                    <p class=\"title\">Ollama GUI verwalten<\/p>\n                    <p>Wenn Sie Ollama GUI verwenden, sehen Sie sich unser Tutorial an, um mehr &uuml;ber die Benutzeroberfl&auml;che und die Verwaltung Ihrer Modelle zu erfahren.<\/p>\n                <\/div>\n\n\n\n<\/p><h3 class=\"wp-block-heading\" id=\"h-3-configure-prompt-settings\">3. Prompt-Einstellungen konfigurieren<\/h3><p>Mit den Prompt-Einstellungen legen Sie fest, wie der <strong>Basic LLM Chain<\/strong>-Knoten Ihre Eingabe anpasst, bevor der Knoten die Eingabe zur Verarbeitung an Ollama weitergibt. Sie k&ouml;nnen zwar die Standardeinstellungen verwenden, sollten diese jedoch je nach Aufgabe anpassen.<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712e53bf30\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712e53bf30\" class=\"aligncenter size-large is-resized wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"788\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/grundlegende-llm-ketten-prompt-quelloptionen.png\" alt=\"Prompt-Quelloptionen des Basic LLM Chain\" class=\"wp-image-11543\" style=\"width:584px;height:auto\" srcset=\"https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/grundlegende-llm-ketten-prompt-quelloptionen.png 1024w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/grundlegende-llm-ketten-prompt-quelloptionen-300x231.png 300w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/grundlegende-llm-ketten-prompt-quelloptionen-768x591.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>Hier sind zwei M&ouml;glichkeiten, die Prompt-Einstellungen des LLM-Chain-Knotens anzupassen, jeweils mit einem passenden Anwendungsbeispiel.<\/p><p><strong>Connected Chat-Trigger-Knoten<\/strong> <\/p><p>Die Option des <strong>Connected Chat Trigger-Knoten<\/strong> verwendet Nachrichten aus dem standardm&auml;&szlig;igen <strong>Chat<\/strong>-Knoten als Eingabe f&uuml;r Ollama. Dies ist standardm&auml;&szlig;ig der ausgew&auml;hlte Modus und gibt Nachrichten unver&auml;ndert weiter.<\/p><p>Sie k&ouml;nnen den Nachrichten jedoch zus&auml;tzliche Prompts hinzuf&uuml;gen, um die Ausgabe von Ollama zu ver&auml;ndern. Klicken Sie dazu in der Einstellung <strong>Chat Messages<\/strong> auf die Schaltfl&auml;che <strong>Add Prompt<\/strong> (wenn Sie ein Chat-Modell verwenden) und w&auml;hlen Sie eine von drei zus&auml;tzlichen Prompt-Optionen aus:<\/p><ul class=\"wp-block-list\">\n<li><strong>KI<\/strong>. Geben Sie im Feld <strong>Message<\/strong> ein Beispiel f&uuml;r die erwartete Antwort ein. Das KI-Modell wird versuchen, auf dieselbe Weise zu antworten wie der bereitgestellte Text.<\/li>\n\n\n\n<li><strong>System<\/strong>. Schreiben Sie eine Nachricht, die die Antworten des Modells steuert. Sie k&ouml;nnen zum Beispiel festlegen, welchen Ton die KI verwenden soll oder welche W&ouml;rter sie in ihren Antworten vermeiden soll.<\/li>\n\n\n\n<li><strong>Benutzer<\/strong>. F&uuml;gen Sie ein Beispiel f&uuml;r die Eingabe des Benutzers f&uuml;r die KI hinzu, etwa eine Nachricht, eine URL oder ein Bild. Wenn Sie der KI ein Beispiel daf&uuml;r geben, was sie von Nutzern erwarten kann, liefert sie konsistentere Antworten. <\/li>\n<\/ul><p><strong>Definieren Sie unten<\/strong> <\/p><p>Die Option &bdquo;<strong>Weiter unten definieren<\/strong>&ldquo; eignet sich, wenn Sie einen vorformulierten Prompt eingeben m&ouml;chten, den Sie wiederverwenden k&ouml;nnen. Es eignet sich auch ideal zum Weiterleiten dynamischer Daten, da Sie diese mit <a href=\"https:\/\/docs.n8n.io\/code\/expressions\/\" target=\"_blank\" rel=\"noreferrer noopener\">Expressions<\/a> erfassen k&ouml;nnen &ndash; einer JavaScript-Bibliothek, die die Eingabe verarbeitet oder ein bestimmtes Feld ausw&auml;hlt.<\/p><p>Zum Beispiel ruft der vorherige Knoten Daten zur Ressourcennutzung Ihres VPS ab, und Sie m&ouml;chten diese mit KI analysieren. In diesem Fall bleibt der Prompt unver&auml;ndert, aber die Nutzungsmetriken &auml;ndern sich fortlaufend.<\/p><p>Ihr Prompt k&ouml;nnte beispielsweise wie folgt aussehen, wobei <strong>{{ $json.metric }}<\/strong> das Feld ist, das die dynamischen Daten zur Ressourcennutzung Ihres Servers enth&auml;lt:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"raw\" data-enlighter-theme=\"atomic\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">Die aktuelle Auslastung meines Servers betr&auml;gt {{ $json.metric }}. Analysiere diese Daten und vergleiche sie mit dem bisherigen Nutzungsverlauf, um zu pr&uuml;fen, ob dies ungew&ouml;hnlich ist.<\/pre><p>Beachten Sie, dass Sie weiterhin zus&auml;tzliche Prompts wie im vorherigen Modus hinzuf&uuml;gen k&ouml;nnen, um der KI mehr Kontext zu geben.<\/p><h3 class=\"wp-block-heading\" id=\"h-4-send-a-test-prompt\"><strong>4. Senden Sie einen Test-Prompt<\/strong> <\/h3><p>Das Senden eines Test-Prompts best&auml;tigt, dass Ihr Ollama-Modell ordnungsgem&auml;&szlig; funktioniert, wenn es &uuml;ber n8n Eingaben empf&auml;ngt. Am einfachsten geht das, indem Sie anhand der folgenden Schritte eine Beispielnachricht eingeben:<\/p><ol class=\"wp-block-list\">\n<li>Speichern Sie Ihren Workflow, indem Sie auf die Schaltfl&auml;che oben rechts auf Ihrer Arbeitsfl&auml;che klicken. <\/li>\n\n\n\n<li>Bewegen Sie den Mauszeiger &uuml;ber den <strong>Chat<\/strong> trigger-Knoten und klicken Sie auf <strong>Open chat<\/strong>.<\/li>\n\n\n\n<li>Senden Sie in der <strong>Chat-Oberfl&auml;che<\/strong> eine Testnachricht. <\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712e53c9ef\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712e53c9ef\" class=\"aligncenter size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"601\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/die-chat-trigger-oberflache-auf-der-n8n-canvas.png\" alt=\"Die Oberfl&auml;che des Chat-Trigger-Knotens auf dem n8n-Canvas\" class=\"wp-image-11544\" srcset=\"https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/die-chat-trigger-oberflache-auf-der-n8n-canvas.png 1024w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/die-chat-trigger-oberflache-auf-der-n8n-canvas-300x176.png 300w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/die-chat-trigger-oberflache-auf-der-n8n-canvas-768x451.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>Warten Sie, bis der Workflow Ihre Nachricht vollst&auml;ndig verarbeitet hat. W&auml;hrend unserer Tests blieb der Workflow einige Male h&auml;ngen. Wenn Sie auf dasselbe Problem sto&szlig;en, laden Sie n8n einfach neu und senden Sie eine neue Nachricht.<\/p><p>Wenn der Test erfolgreich ist, werden alle Knoten gr&uuml;n. Den JSON-Eingang und -Ausgang jedes Knotens k&ouml;nnen Sie anzeigen, indem Sie auf den jeweiligen Knoten doppelklicken und die Bereiche auf beiden Seiten des Konfigurationsfensters pr&uuml;fen.<\/p><h2 class=\"wp-block-heading\" id=\"h-how-to-create-a-chatbot-workflow-using-ollama-and-n8n\">So erstellen Sie einen Chatbot-Workflow mit Ollama und n8n<\/h2><p>Durch die Integration von Ollama in n8n k&ouml;nnen Sie verschiedene Aufgaben mit LLMs automatisieren, darunter einen KI-gest&uuml;tzten Workflow in n8n erstellen, der auf Benutzeranfragen reagiert, &auml;hnlich wie ein Chatbot. In diesem Abschnitt werden die Schritte zur Entwicklung eines solchen Systems erl&auml;utert.<\/p><p>Wenn Sie ein Automatisierungssystem f&uuml;r andere Aufgaben erstellen m&ouml;chten, finden Sie in unseren <a href=\"\/de\/tutorials\/n8n-workflow-beispiele\/\">n8n-Workflow-Beispielen<\/a> Inspiration.<\/p><h3 class=\"wp-block-heading\" id=\"h-1-add-a-trigger-node\">1. F&uuml;gen Sie einen Trigger-Knoten hinzu<\/h3><p>Der Trigger-Knoten in n8n legt fest, welches Ereignis Ihren Workflow startet. Zu den verschiedenen M&ouml;glichkeiten, einen Chatbot zu erstellen, geh&ouml;ren vor allem diese:<\/p><p><strong>Chat-Trigger<\/strong> <\/p><p>Standardm&auml;&szlig;ig verwendet der Ollama-Chat-Modell-Knoten <strong>Chat message<\/strong> als Ausl&ouml;ser; der Workflow wird gestartet, sobald eine Nachricht eingeht.<\/p><p>Dieser standardm&auml;&szlig;ige <strong>Chat<\/strong> -Knoten eignet sich perfekt, um einen Chatbot zu entwickeln. Damit es funktioniert, m&uuml;ssen Sie nur die Chat-Oberfl&auml;che &ouml;ffentlich zug&auml;nglich machen.<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712e53d2f5\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712e53d2f5\" class=\"aligncenter size-full is-resized wp-lightbox-container\"><img decoding=\"async\" width=\"784\" height=\"830\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/n8n-chat-trigger-offentlich-machen-schalter.png\" alt=\"Der Schalter &bdquo;Make Chat Publicly Available&ldquo; im n8n-Chat-Trigger\" class=\"wp-image-11545\" style=\"width:432px;height:auto\" srcset=\"https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/n8n-chat-trigger-offentlich-machen-schalter.png 784w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/n8n-chat-trigger-offentlich-machen-schalter-283x300.png 283w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/n8n-chat-trigger-offentlich-machen-schalter-768x813.png 768w\" sizes=\"(max-width: 784px) 100vw, 784px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>&Ouml;ffnen Sie dazu den <strong>Chat<\/strong> -Knoten und klicken Sie auf den Schalter <strong>Make Chat Publicly Available<\/strong>. Anschlie&szlig;end k&ouml;nnen Sie diese Chatfunktion mit einer Benutzeroberfl&auml;che in Ihren benutzerdefinierten Chatbot integrieren.<\/p><p><strong>Trigger-Knoten f&uuml;r Messaging-Apps<\/strong> <\/p><p>n8n verf&uuml;gt &uuml;ber Trigger-Knoten, die Eingaben aus beliebten Messaging-Apps wie <strong>Telegram<\/strong> und <strong>WhatsApp<\/strong> empfangen. Sie eignen sich, wenn Sie f&uuml;r solche Anwendungen einen Bot erstellen m&ouml;chten.<\/p><p>Die Konfiguration dieser Knoten ist ziemlich knifflig, weil Sie f&uuml;r die Verbindung mit ihren APIs ein Entwicklerkonto und Authentifizierungsschl&uuml;ssel ben&ouml;tigen. In der entsprechenden Dokumentation erfahren Sie mehr dar&uuml;ber, wie Sie sie konfigurieren.<\/p><p><strong>Webhook-Trigger<\/strong> <\/p><p>Der <strong>Webhook<\/strong> -Trigger startet Ihren Workflow, sobald die zugeh&ouml;rige Endpunkt-URL eine HTTP-Anfrage empf&auml;ngt. Das ist geeignet, wenn Sie Ihren Chatbot &uuml;ber andere Ereignisse als das Senden einer Nachricht starten m&ouml;chten, etwa per Klick.<\/p><p>In den folgenden Schritten verwenden wir diesen Knoten, um unseren Workflow jedes Mal zu starten, wenn ein Discord-Chatbot eine Nachricht empf&auml;ngt. Wenn Sie mitmachen m&ouml;chten, sehen Sie sich zun&auml;chst unser Tutorial n8n mit Discord integrieren an. Dort erfahren Sie, wie Sie einen Discord-Bot erstellen.<\/p><p>\n\n\n<div><p class=\"important\"><strong>Wichtig!<\/strong> Wenn Ihre Webhook-URL mit <strong>localhost<\/strong> beginnt, ersetzen Sie localhost durch die Domain, den Hostnamen oder die IP-Adresse Ihres VPS. Sie k&ouml;nnen dies tun, indem Sie <a href=\"https:\/\/docs.n8n.io\/hosting\/configuration\/environment-variables\/endpoints\/\" target=\"_blank\" rel=\"noopener\">die Umgebungsvariable WEBHOOK_URL von n8n<\/a> in seiner Konfigurationsdatei &auml;ndern.<\/p><\/div>\n\n\n\n<\/p><h3 class=\"wp-block-heading\" id=\"h-2-connect-the-ollama-node\">2. Verbinden Sie den Ollama-Knoten<\/h3><p>Wenn Sie den Ollama-Knoten verbinden, kann der Trigger-Knoten Benutzereingaben zur Verarbeitung weiterleiten.<\/p><p>Der <strong>Ollama Chat Model<\/strong>-Knoten l&auml;sst sich nicht direkt mit Trigger-Knoten verbinden und kann nur mit einem KI-Knoten integriert werden. Standardm&auml;&szlig;ig ist der <strong>Basic LLM Chain<\/strong>-Knoten ausgew&auml;hlt, Sie k&ouml;nnen f&uuml;r komplexere Verarbeitungen aber auch andere <strong>Chain<\/strong> -Knoten verwenden.<\/p><p>Einige <strong>Chain<\/strong> -Knoten unterst&uuml;tzen zus&auml;tzliche Tools zur Verarbeitung Ihrer Daten. Mit dem <strong>AI Agent<\/strong> -Knoten k&ouml;nnen Sie zum Beispiel einen Parser hinzuf&uuml;gen, um die Ausgabe neu zu formatieren, oder einen Speicher einbinden, der die vorherigen Antworten speichert.<\/p><p>F&uuml;r einen Chatbot, der keine komplexe Datenverarbeitung erfordert, wie unseren Discord-Chatbot, reicht die <strong>Basic LLM Chain<\/strong> aus.<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712e53dcdd\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712e53dcdd\" class=\"aligncenter size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"565\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/ollama-einfacher-llm-kettenknoten-cluster-mit-webhook-trigger.png\" alt=\"Ollama und der Cluster aus dem Basic-LLM-Chain-Knoten mit verbundenem Webhook-Trigger\" class=\"wp-image-11546\" srcset=\"https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/ollama-einfacher-llm-kettenknoten-cluster-mit-webhook-trigger.png 1024w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/ollama-einfacher-llm-kettenknoten-cluster-mit-webhook-trigger-300x166.png 300w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/ollama-einfacher-llm-kettenknoten-cluster-mit-webhook-trigger-768x424.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>Verbinden Sie also den Trigger-Knoten mit dem <strong>Basic LLM Chain<\/strong> -Knoten und legen Sie fest, wie die Eingabe &uuml;bergeben wird. Verwenden Sie <strong>Fixed<\/strong>, um die Nachricht als Prompt zu &uuml;bergeben. W&auml;hlen Sie in der Zwischenzeit <strong>Expression<\/strong> aus, um dynamische Daten zu verwenden oder die Eingabe zu bearbeiten, bevor Sie sie an Ollama weiterleiten.<\/p><p>Zum Beispiel verwenden wir den folgenden <strong>Ausdruck<\/strong>, um das JSON-Feld <strong>body.content<\/strong> als Eingabe auszuw&auml;hlen, das sich je nach den Discord-Nachrichten der Benutzer &auml;ndert:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">{{ $json.body.content }}<\/pre><h3 class=\"wp-block-heading\" id=\"h-3-output-the-response\">3. Geben Sie die Antwort aus<\/h3><p>Wenn Sie die Antwort aus dem <strong>KI-Agenten<\/strong> &ndash; oder <strong>Basic LLM Chain<\/strong>-Knoten ausgeben, k&ouml;nnen Nutzer die Antwort Ihres Bots sehen. An dieser Stelle k&ouml;nnen Sie die Ausgabe nur in der Chatoberfl&auml;che oder im Ausgabebereich des Knotens lesen.<\/p><p>Verwenden Sie zum Senden der Antwort denselben Knoten wie f&uuml;r Ihren Trigger. Wenn Sie beispielsweise einen WhatsApp-Chatbot entwickeln, verbinden Sie den Knoten <strong>WhatsApp send message<\/strong>.<\/p><p>Wenn Sie den standardm&auml;&szlig;igen <strong>Chat<\/strong> -Trigger verwenden, k&ouml;nnen Sie den <strong>Webhook<\/strong>-Knoten nutzen, um die Nachricht an Ihren individuell programmierten Bot oder Ihre Chatbot-Oberfl&auml;che weiterzuleiten.<\/p><p>Da der Workflow unseres Discord-Bots den <strong>Webhook<\/strong> -Trigger verwendet, k&ouml;nnen wir f&uuml;r die Ausgabe auch den <strong>Webhook<\/strong> -Knoten nutzen. Alternativ k&ouml;nnen wir denselben Bot verwenden, um die Antwort zu senden, indem wir den Discord <strong>Send a Message<\/strong>-Knoten verbinden und in unseren Chatbot integrieren. Der fertige Workflow sieht so aus:<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712e53e5e7\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712e53e5e7\" class=\"aligncenter size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"374\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/n8n-ollama-discord-bot-Workflow.png\" alt=\"n8ns mit Ollama betriebener Discord-Bot-Workflow\" class=\"wp-image-11547\" srcset=\"https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/n8n-ollama-discord-bot-Workflow.png 1024w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/n8n-ollama-discord-bot-Workflow-300x110.png 300w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/n8n-ollama-discord-bot-Workflow-768x280.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>\n\n<div class=\"protip\">\n                    <p class=\"title\">Sie wissen nicht, wie Sie einen vollst&auml;ndigen Workflow erstellen?<\/p>\n                    <p>n8n stellt verschiedene sofort einsatzbereite Workflows bereit, die Sie ganz einfach in Ihre Canvas importieren k&ouml;nnen. Damit k&ouml;nnen Sie ein KI-gest&uuml;tztes Automatisierungssystem erstellen, ohne den Workflow von Grund auf neu entwickeln zu m&uuml;ssen. In unserem Tutorial zu <a href=\"\/de\/tutorials\/n8n-vorlagen\/\">den besten n8n-Vorlagen<\/a> finden Sie sorgf&auml;ltig ausgew&auml;hlte, sofort einsetzbare Workflows f&uuml;r verschiedene Anwendungsf&auml;lle.<\/p>\n                <\/div>\n\n\n\n<\/p><h2 class=\"wp-block-heading\" id=\"h-what-are-the-best-use-cases-for-n8n-ollama-integration\">Was sind die besten Anwendungsf&auml;lle f&uuml;r die n8n-Ollama-Integration?<\/h2><p>Als eines der leistungsst&auml;rksten KI-Automatisierungstools erm&ouml;glicht Ihnen die Integration von n8n mit Ollamas anpassbaren LLMs, eine Vielzahl von Aufgaben zu automatisieren.<\/p><p>Hier sind Beispiele f&uuml;r Aufgaben, die Sie <a href=\"\/de\/tutorials\/n8n-anwendungsbeispiele-automatisierung\/\">mit n8n automatisieren<\/a> und mit KI erledigen k&ouml;nnen:<\/p><ol class=\"wp-block-list\">\n<li><strong>Automatisierter Workflow f&uuml;r den Kundensupport. <\/strong>Nutzen Sie die LLMs von Ollama, um &uuml;ber n8n Antworten auf Kundenanfragen zu erstellen, Tickets zusammenzufassen oder Anliegen auf Plattformen wie Zendesk und Intercom weiterzuleiten.<\/li>\n\n\n\n<li><strong>Kontextbezogenes Verfassen von E-Mails.<\/strong> E-Mails f&uuml;r unterschiedliche Kontexte oder Aufgaben automatisch mit Ollama entwerfen. So k&ouml;nnen Sie beispielsweise einem neuen Lead eine Willkommensnachricht senden, Kunden an das Auslaufen ihres Abonnements erinnern und Produktaktualisierungen anhand verschiedener Ereignisse ank&uuml;ndigen. <\/li>\n\n\n\n<li><strong>Assistent f&uuml;r die interne Wissensdatenbank.<\/strong> Verwenden Sie n8n, um interne Dokumentation wie Notion, Confluence oder Airtable abzufragen und die Daten an Ollama zu &uuml;bergeben, damit Ollama intelligente Antworten oder Zusammenfassungen f&uuml;r interne Teamanfragen erstellt.<\/li>\n\n\n\n<li><strong>Datenextraktion und Zusammenfassung.<\/strong> Verwenden Sie n8n, um eingehende Textdokumente zu &uuml;berwachen, deren Text zu extrahieren und mit Ollama wichtige Informationen herauszuziehen &ndash; n&uuml;tzlich zum Zusammenfassen von Berichten, Rechnungen oder juristischen Dokumenten.<\/li>\n\n\n\n<li><strong>Automatisierte Pipeline f&uuml;r die Content-Produktion<\/strong>. <a href=\"\/de\/tutorials\/n8n-inhalte-generieren\/\">Erstellen Sie Inhalte mit n8n und Ollama<\/a>, indem Sie einen Workflow erstellen, der die Keyword-Recherche sowie den Schreib- und Bearbeitungsprozess automatisiert.<\/li>\n\n\n\n<li><strong>Sichere Chatbots f&uuml;r den internen Einsatz. <\/strong>Erstellen Sie interne Chatbots, die mit sensiblen internen Daten arbeiten, wobei n8n die Orchestrierung &uuml;bernimmt und Ollama das LLM aus Sicherheits- und Datenschutzgr&uuml;nden vollst&auml;ndig offline ausf&uuml;hrt. <\/li>\n<\/ol><h3 class=\"wp-block-heading\" id=\"h-why-should-you-host-your-n8n-ollama-workflows-with-hostinger\">Warum sollten Sie Ihre n8n-Ollama-Workflows bei Hostinger hosten?<\/h3><p>Wenn Sie Ihre n8n-Ollama-Workflows bei Hostinger hosten, profitieren Sie von verschiedenen Vorteilen gegen&uuml;ber der Nutzung eines eigenen Ger&auml;ts oder des offiziellen Hosting-Tarifs. Hier sind einige der Vorteile:<\/p><ul class=\"wp-block-list\">\n<li><strong>Mehr Kontrolle<\/strong>. Der <a href=\"\/de\/n8n-hosting\">n8n-VPS-Hosting<\/a> -Dienst von Hostinger bietet Benutzern vollen Root-Zugriff auf ihre Servereinstellungen und Daten. Damit k&ouml;nnen Sie Ihre Hosting-Umgebungen f&uuml;r n8n und Ollama an Ihre spezifischen Anforderungen anpassen.<\/li>\n\n\n\n<li><strong>Verbesserter Datenschutz<\/strong>. Da Sie n8n und Ollama auf einem Server hosten, &uuml;ber den Sie die vollst&auml;ndige Kontrolle haben, k&ouml;nnen Sie Zugriffsbeschr&auml;nkungen und Sicherheitseinstellungen frei anpassen.<\/li>\n\n\n\n<li><strong>Skalierbarkeit<\/strong>. Die VPS-Tarife von Hostinger lassen sich ohne Ausfallzeit problemlos upgraden und bieten die n8n-Vorlage f&uuml;r den Queue-Modus, mit der Sie Ihre Aufgaben auf mehrere Worker verteilen k&ouml;nnen. <\/li>\n\n\n\n<li><strong>Optimierte Einrichtung<\/strong>. Mit unseren VPS-Vorlagen installieren Sie n8n oder Ollama mit nur einem Klick und machen den Prozess damit effizienter.<\/li>\n\n\n\n<li><strong>Einfache Verwaltung<\/strong>. Die Verwaltung eines Hostinger-VPS ist mit dem intuitiven hPanel-Kontrollpanel oder dem integrierten Browser-Terminal ganz einfach. Auch Einsteiger k&ouml;nnen unseren KI-Assistenten <strong>Kodee<\/strong> per Chat mit Systemadministrationsaufgaben beauftragen. <\/li>\n<\/ul><figure class=\"wp-block-image size-large\"><a href=\"\/de\/vps-server\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2024\/02\/DE-VPS-hosting_in-text-banner.png\/w=1024,h=1024,fit=scale-down\" alt=\"\" class=\"wp-image-3556\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2024\/02\/DE-VPS-hosting_in-text-banner.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2024\/02\/DE-VPS-hosting_in-text-banner.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/29\/2024\/02\/DE-VPS-hosting_in-text-banner.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><h2 class=\"wp-block-heading\" id=\"h-using-langchain-s-lm-ollama-node-in-n8n\">Den LM Ollama-Knoten von LangChain in n8n verwenden<\/h2><p><strong>LangChain <\/strong>ist ein Framework, das die Integration von LLMs in Anwendungen erleichtert. In n8n umfasst diese Implementierung das Verbinden verschiedener Tool-Knoten und KI-Modelle, um bestimmte Verarbeitungsfunktionen zu erreichen.<\/p><p>In n8n verwendet die LangChain-Funktion <strong>Cluster-Knoten<\/strong> &ndash; eine Gruppe miteinander verbundener Knoten, die in Ihrem Workflow gemeinsam eine Funktion bereitstellen.<\/p><div class=\"wp-block-image\">\n<figure data-wp-context='{\"imageId\":\"6a5712e5402e8\"}' data-wp-interactive=\"core\/image\" data-wp-key=\"6a5712e5402e8\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" width=\"1024\" height=\"914\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/VPS-Cluster-Root-Unterknoten-Illustration.png\" alt=\"Das Konzept von Cluster- Wurzel- und Unterknoten in der LangChain-Implementierung von n8n\" class=\"wp-image-11548\" srcset=\"https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/VPS-Cluster-Root-Unterknoten-Illustration.png 1024w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/VPS-Cluster-Root-Unterknoten-Illustration-300x268.png 300w, https:\/\/www.hostinger.com\/de\/tutorials\/wp-content\/uploads\/sites\/29\/2026\/05\/VPS-Cluster-Root-Unterknoten-Illustration-768x686.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Enlarge\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\"><\/path>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><p>Cluster-Knoten bestehen aus zwei Teilen: <strong>Root-Knoten<\/strong>, die die Hauptfunktionalit&auml;t festlegen, und <strong>Unterknoten<\/strong>, die die LLM-Funktion oder zus&auml;tzliche Features hinzuf&uuml;gen.<\/p><p>Der wichtigste Teil der LangChain-Implementierung in n8n ist die <strong>Chain<\/strong> innerhalb der <strong>Root-Knoten<\/strong>. Es f&uuml;hrt die Logik verschiedener KI-Komponenten wie des Ollama-Modells und des Parser-Knotens zusammen und richtet sie ein, um ein stimmiges Gesamtsystem zu schaffen.<\/p><p>Hier sind die<strong> Chains <\/strong>in n8n und ihre Funktionen:<\/p><ul class=\"wp-block-list\">\n<li><strong>Einfache LLM-Kette<\/strong>. Damit legen Sie den Prompt fest, den das KI-Modell verwendet, sowie optional einen Parser, der die Antwort neu formatiert.<\/li>\n\n\n\n<li><strong>Abruf-Frage-und-Antwort-Kette<\/strong>. Erm&ouml;glicht Ihnen, von KI verarbeitete Daten &uuml;ber Vektorspeicher abzurufen &ndash; Datenbanken, die Informationen in numerischer Form speichern.<\/li>\n\n\n\n<li><strong>Zusammenfassungskette<\/strong>. Fasst die Inhalte mehrerer Dokumente oder Eingaben zusammen. <\/li>\n\n\n\n<li><strong>Sentimentanalyse<\/strong>. Analysiert die Stimmung des Eingabetextes und ordnet sie Kategorien wie positiv, neutral und negativ zu.<\/li>\n\n\n\n<li><strong>Textklassifikator<\/strong>. Sortiert Eingabedaten anhand der angegebenen Kriterien und Parameter in verschiedene benutzerdefinierte Kategorien. <\/li>\n<\/ul><p>Beim Erstellen eines Workflows in n8n k&ouml;nnen Ihnen auch <strong>Agents<\/strong> begegnen &ndash; Untergruppen von <strong>Chains<\/strong>, die Entscheidungen treffen k&ouml;nnen. W&auml;hrend <strong>Chains<\/strong> auf der Grundlage einer Reihe vordefinierter Regeln arbeiten, nutzt der <strong>Agent<\/strong> das verbundene LLM, um die als N&auml;chstes auszuf&uuml;hrenden Aktionen zu bestimmen.<\/p><h2 class=\"wp-block-heading\" id=\"h-what-s-next-after-connecting-n8n-with-ollama\">Wie geht es weiter, nachdem Sie n8n mit Ollama verbunden haben?<\/h2><p>Da sich die Trends in der Automatisierung st&auml;ndig weiterentwickeln, hilft Ihnen die Einf&uuml;hrung eines automatischen Datenverarbeitungssystems dabei, der Konkurrenz einen Schritt voraus zu sein. In Verbindung mit KI k&ouml;nnen Sie ein System schaffen, das die Entwicklung und das Management Ihrer Projekte auf ein neues Niveau hebt.<\/p><p>Die Integration von Ollama in Ihren n8n-Workflow erweitert Ihre KI-gest&uuml;tzte Automatisierung &uuml;ber die M&ouml;glichkeiten des integrierten Knotens hinaus &ndash; und dank der Kompatibilit&auml;t von Ollama mit verschiedenen LLMs k&ouml;nnen Sie unterschiedliche KI-Modelle ausw&auml;hlen und gezielt an Ihre Anforderungen anpassen.<\/p><p>Zu verstehen, wie Sie Ollama in n8n einbinden, ist nur der erste Schritt, um KI-gest&uuml;tzte Automatisierung in Ihrem Projekt umzusetzen. Angesichts der Vielzahl m&ouml;glicher Anwendungsf&auml;lle besteht der n&auml;chste Schritt darin, zu experimentieren und einen Workflow zu entwickeln, der am besten zu Ihrem Projekt passt.<\/p><p>Wenn Sie zum ersten Mal mit n8n oder Ollama arbeiten, ist Hostinger der richtige Ausgangspunkt. Neben leistungsstarken VPS-Tarifen bieten wir Ihnen auch einen umfassenden <a href=\"\/de\/tutorials\/vps\/\">Katalog mit Tutorials<\/a> zu n8n, der Ihnen den Einstieg in die Automatisierung erleichtert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Integration von n8n mit Ollama erm&ouml;glicht es Ihnen, verschiedene KI-Modelle in Ihren Automatisierungs-Workflow einzubinden, sodass dieser komplexe Vorg&auml;nge ausf&uuml;hren kann, die andernfalls nicht m&ouml;glich w&auml;ren. Allerdings kann der Prozess knifflig sein, da Sie in beiden Tools verschiedene Einstellungen konfigurieren m&uuml;ssen, damit sie reibungslos zusammenarbeiten. Sobald n8n und Ollama bereits auf Ihrem Server installiert sind, [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/de\/tutorials\/n8n-mit-ollama-verbinden\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":190,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rank_math_title":"n8n mit Ollama verbinden und Workflows automatisieren","rank_math_description":"n8n mit Ollama verbinden: 1. Ollama-Knoten hinzuf\u00fcgen 2. Modell konfigurieren 3. Prompts anpassen und testen.","rank_math_focus_keyword":"n8n mit Ollama verbinden","footnotes":""},"categories":[25],"tags":[],"class_list":["post-11549","post","type-post","status-publish","format-standard","hentry","category-vps"],"hreflangs":[],"_links":{"self":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts\/11549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/users\/190"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/comments?post=11549"}],"version-history":[{"count":5,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts\/11549\/revisions"}],"predecessor-version":[{"id":11834,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/posts\/11549\/revisions\/11834"}],"wp:attachment":[{"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/media?parent=11549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/categories?post=11549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinger.com\/de\/tutorials\/wp-json\/wp\/v2\/tags?post=11549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}