{"id":6423,"date":"2018-05-25T08:23:03","date_gmt":"2018-05-25T08:23:03","guid":{"rendered":"https:\/\/blog.hostinger.io\/co-tutoriales\/?p=6423"},"modified":"2025-02-05T19:30:48","modified_gmt":"2025-02-05T18:30:48","slug":"conectar-php-mysql","status":"publish","type":"post","link":"\/co\/tutoriales\/conectar-php-mysql\/","title":{"rendered":"C\u00f3mo conectar PHP con bases de datos MySQL"},"content":{"rendered":"<p>Si eres un principiante en el desarrollo de sitios web, puede ser beneficioso saber c&oacute;mo como conectar PHP a <a href=\"https:\/\/www.mysql.com\/\" target=\"_blank\" rel=\"noopener\">MySQL<\/a> con un script. De esta manera, podr&aacute;s modificar, ver o administrar las tablas creadas en la base de datos MySQL. Este art&iacute;culo te mostrar&aacute; las formas m&aacute;s f&aacute;ciles de hacerlo, comencemos.<\/p><figure class=\"wp-block-image size-large\"><a href=\"https:\/\/assets.hostinger.com\/content\/tutorials\/pdf\/Speed-Up-Your-Website-ES.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"283\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/12\/eBook-Speed-Up-your-website-ES.png\/w=1024,h=1024,fit=scale-down\" alt=\"\" class=\"wp-image-25983\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/12\/eBook-Speed-Up-your-website-ES.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/12\/eBook-Speed-Up-your-website-ES.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/12\/eBook-Speed-Up-your-website-ES.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/12\/eBook-Speed-Up-your-website-ES.png\/w=768,fit=scale-down 768w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/12\/eBook-Speed-Up-your-website-ES.png\/w=1536,fit=scale-down 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><h2 class=\"wp-block-heading\" id=\"h-crear-una-base-de-datos-mysql-opcional\">Crear una base de datos MySQL (Opcional)<\/h2><p>Este paso es necesario en caso de que a&uacute;n no tengas una <strong>base de datos MySQL<\/strong> creada.&nbsp;Si eres un usuario de Hostinger, puedes crear f&aacute;cilmente una nueva a trav&eacute;s del hPanel de Hostinger en unos pocos pasos:<\/p><ol class=\"wp-block-list\">\n<li>Busca el men&uacute; <strong>Bases de datos MySQL<\/strong> en la secci&oacute;n <strong>Bases de datos<\/strong>.<\/li>\n\n\n\n<li>Completa los campos necesarios y presiona <strong>Crear<\/strong>.<br><img decoding=\"async\" class=\"aligncenter wp-image-6462 size-full\" src=\"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-content\/uploads\/sites\/40\/2018\/05\/crear-base-de-datos-MySQL.png\" alt=\"crear una nueva base de datos MySQL y un usuario de base de datos en hostingers hpanel, incluida la contrase&ntilde;a del nombre de usuario\" width=\"909\" height=\"363\" srcset=\"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-content\/uploads\/sites\/40\/2018\/05\/crear-base-de-datos-MySQL.png 909w, https:\/\/www.hostinger.com\/co\/tutoriales\/wp-content\/uploads\/sites\/40\/2018\/05\/crear-base-de-datos-MySQL-150x60.png 150w, https:\/\/www.hostinger.com\/co\/tutoriales\/wp-content\/uploads\/sites\/40\/2018\/05\/crear-base-de-datos-MySQL-300x120.png 300w, https:\/\/www.hostinger.com\/co\/tutoriales\/wp-content\/uploads\/sites\/40\/2018\/05\/crear-base-de-datos-MySQL-768x307.png 768w\" sizes=\"(max-width: 909px) 100vw, 909px\" \/><\/li>\n<\/ol><p>Ten en cuenta que al crear una base de datos, esta estar&aacute; en blanco y deber&aacute;s <a href=\"\/co\/tutoriales\/como-usar-php-para-insertar-datos-en-mysql\/\">completar los datos<\/a> antes de poder manipularlos.<\/p><p class=\"important\"><strong>&iexcl;Importante!<\/strong> Toma nota de las credenciales de la base de datos MySQL que acabas de crear para el siguiente paso. &iexcl;No olvides anotar tambi&eacute;n el nombre de usuario y la contrase&ntilde;a de la base de datos!<\/p><h2 class=\"wp-block-heading\" id=\"h-dos-formas-en-que-un-script-php-puede-conectarse-a-mysql\">Dos formas en que un script PHP puede conectarse a MySQL<\/h2><p>Hay dos m&eacute;todos para conectar con PHP a una base de datos MySQL: <strong>MySQLi<\/strong> y <strong>PDO<\/strong>.<\/p><p><strong>MySQLi<\/strong> son las siglas de <strong>MySQL Improved<\/strong>. Es una extensi&oacute;n exclusiva de MySQL que agrega nuevas funciones a la interfaz de una base de datos MySQL. MySQLi es tanto procedimental como orientada a objetos, siendo el primer atributo heredado de la versi&oacute;n anterior de MySQL.<\/p><p>El MySQL original divide una tarea en procedimientos lineales, paso a paso, lo que dificulta la modificaci&oacute;n porque tienes que editar el c&oacute;digo desde la parte superior. Mientras tanto, MySQLi ve los datos como un conjunto de objetos intercambiables con funciones, lo que permite a los usuarios agregar o eliminar datos f&aacute;cilmente.<\/p><p><strong>PDO<\/strong> son las siglas de <strong>PHP Data Object<\/strong>. A diferencia de MySQLi, PDO solo est&aacute; orientado a objetos y admite varios tipos de bases de datos diferentes que usan PHP, como MySQL, MSSQL, Informix y PostgreSQL.<\/p><p class=\"important\"><strong>&iexcl;Importante!<\/strong> Las funciones originales de <strong>mysql_<\/strong> est&aacute;n en <strong>desuso<\/strong> y no deben usarse porque no son seguras y ya no cuentan con mantenimiento ni desarrollo.<\/p><p>Una de las caracter&iacute;sticas m&aacute;s importantes que ambos admiten son las<strong> declaraciones preparadas<\/strong>, lo que acelera el tiempo necesario para que MySQL ejecute la misma consulta varias veces. Tambi&eacute;n se utiliza para prevenir ataques de inyecci&oacute;n de SQL al realizar cambios en la base de datos.<\/p><p>Cualquiera que sea el m&eacute;todo que utilices, necesitar&aacute;s la informaci&oacute;n correcta para poder conectarte a la base de datos MySQL que has creado. Aqu&iacute; es donde los detalles de la base de datos MySQL que has guardado previamente son &uacute;tiles.<\/p><p>Tambi&eacute;n necesitas el <strong>nombre de servidor<\/strong> o <strong>nombre de host<\/strong> correcto para la configuraci&oacute;n. Hostinger usa &ldquo;<strong>localhost<\/strong>&rdquo; como el nombre de host de su servidor MySQL. En general, este es el nombre que querr&aacute;s usar si cargaste tu secuencia de comandos PHP en el mismo servidor que la base de datos.<\/p><p>Por el contrario, si te est&aacute;s conectando a una base de datos desde una ubicaci&oacute;n remota (por ejemplo, su computadora), tendr&aacute;s que usar la <strong>direcci&oacute;n IP<\/strong> del servidor MySQL. Para obtener m&aacute;s detalles, comun&iacute;cate con tu proveedor de alojamiento para que puedan proporcionarte la informaci&oacute;n correcta sobre qu&eacute; usar como nombre de host.<\/p><h2 class=\"wp-block-heading\" id=\"h-uso-de-mysqli-para-conectar-un-script-php-a-mysql\">Uso de MySQLi para conectar un script PHP a MySQL<\/h2><p>Sigue estos pasos para usar MySQLi para conectar un script PHP a MySQL:<\/p><ol class=\"wp-block-list\">\n<li>Ve al <strong>Administrador de archivos -&gt; public_html<\/strong>.<\/li>\n\n\n\n<li>Crea un <strong>Archivo nuevo<\/strong> haciendo clic en el icono del men&uacute; superior.<\/li>\n\n\n\n<li>Gu&aacute;rdalo como <strong>databaseconnect.php<\/strong>. Puedes reemplazar el nombre con lo que quieras, solo aseg&uacute;rate de estar usando php como extensi&oacute;n.<\/li>\n\n\n\n<li>Haz doble clic para abrir el archivo y copia y pega las siguientes l&iacute;neas de c&oacute;digo en &eacute;l. Cambia los primeros cuatro valores debajo de <strong>&lt;?php<\/strong> con las credenciales que anotaste anteriormente.\n<pre class=\"EnlighterJSRAW\" data-enlighter-language=\"null\">&lt;?php\n$servername = \"localhost\";\n$database = \"databasename\";\n$username = \"username\";\n$password = \"password\";\n\/\/ Create connection\n$conn = mysqli_connect($servername, $username, $password, $database);\n\/\/ Check connection\nif (!$conn) {\n    die(\"Connection failed: \" . mysqli_connect_error());\n}\necho \"Connected successfully\";\nmysqli_close($conn);\n?&gt;<\/pre>\n<\/li>\n<\/ol><h3 class=\"wp-block-heading\" id=\"h-explicacion-del-codigo-mysqli\">Explicaci&oacute;n del c&oacute;digo MySQLi<\/h3><p>El m&eacute;todo principal utilizado en este script es <strong>mysqli_connect()<\/strong>. Esta es una funci&oacute;n interna de PHP para establecer una nueva conexi&oacute;n a un servidor MySQL.<\/p><p>Al comienzo de nuestro c&oacute;digo, vemos pocas declaraciones de variables y valores asignados a esas variables. Por lo general, necesitamos cuatro variables para establecer una conexi&oacute;n adecuada: <strong>$servername, $database, $username y $password<\/strong>. En el c&oacute;digo, hemos establecido los datos exactos de nuestra base de datos como valores para esas variables, as&iacute;&nbsp;se pueden pasar a la funci&oacute;n.<\/p><p>Si la conexi&oacute;n no es exitosa, se ejecuta la funci&oacute;n <strong>die()<\/strong>. Esto b&aacute;sicamente termina con el script y arroja el mensaje de error de conexi&oacute;n establecido. De forma predeterminada, el error de conexi&oacute;n de MySQL dir&aacute; <strong>Connection failed<\/strong>&nbsp;seguido de un mensaje de error exacto que describe el problema.<\/p><p>Por otro lado, si la conexi&oacute;n MySQL es exitosa, el c&oacute;digo imprimir&aacute; <strong>Connected successfully<\/strong>.<\/p><p>La &uacute;ltima parte del c&oacute;digo es <strong>mysqli_close<\/strong>, que simplemente permitir&aacute; cerrar la conexi&oacute;n a la base de datos manualmente. Si no se especifica, las conexiones MySQL se cerrar&aacute;n por s&iacute; solas una vez que finalice el script.<\/p><h2 class=\"wp-block-heading\" id=\"h-usar-pdo-para-conectar-un-script-php-a-mysql\">Usar PDO para conectar un script PHP a MySQL<\/h2><p>El otro m&eacute;todo que puedes utilizar para conectar un script PHP a MySQL es PDO. Es similar al m&eacute;todo anterior, pero con una ligera variaci&oacute;n:<\/p><ol class=\"wp-block-list\">\n<li>En <strong>public_html<\/strong>, crea un archivo llamado <strong>pdoconfig.php<\/strong> e inserta el siguiente c&oacute;digo. Como siempre, no olvides reemplazar los valores del marcador de posici&oacute;n con la informaci&oacute;n de tu base de datos. Gu&aacute;rdalo y ci&eacute;rralo una vez que hayas terminado.\n<pre class=\"EnlighterJSRAW\" data-enlighter-language=\"null\">&lt;?php\n    $host = 'localhost';\n    $dbname = 'databasename';\n    $username = 'username';\n    $password = 'password';<\/pre>\n<\/li>\n\n\n\n<li>Crea otro archivo llamado <strong>databaseconnect.php<\/strong> en el mismo directorio, pero con el siguiente c&oacute;digo. Si nombraste el archivo anterior de manera diferente, aseg&uacute;rese de cambiar el valor de <strong>require_once<\/strong>.\n<pre class=\"EnlighterJSRAW\" data-enlighter-language=\"null\">&lt;?php\nrequire_once 'pdoconfig.php';\n \ntry {\n    $conn = new PDO(\"mysql:host=$host;dbname=$dbname\", $username, $password);\n    echo \"Connected to $dbname at $host successfully.\";\n} catch (PDOException $pe) {\n    die(\"Could not connect to the database $dbname :\" . $pe-&gt;getMessage());\n}<\/pre>\n<\/li>\n<\/ol><h3 class=\"wp-block-heading\" id=\"h-explicacion-del-codigo-pdo\">Explicaci&oacute;n del c&oacute;digo PDO<\/h3><p>Una conexi&oacute;n de base de datos PDO requiere que crees un nuevo objeto PDO con un Nombre de origen de datos (<strong>DSN<\/strong> &ndash; <strong>Data Source Name<\/strong>), <strong>nombre de usuario<\/strong> y <strong>contrase&ntilde;a<\/strong>.<\/p><p>El DSN define el tipo de base de datos, el nombre de la base de datos y cualquier otra informaci&oacute;n, si es necesario. Estas son las variables y valores que declaramos dentro del archivo <strong>dbconfig.php<\/strong>, referenciados una vez por la l&iacute;nea <strong>require_once<\/strong> en <strong>databaseconnect.php<\/strong>.<\/p><p>En este &uacute;ltimo, encontrar&aacute;s el c&oacute;digo <strong>try&hellip;catch<\/strong>&hellip; Esto significa que el script intentar&aacute; (<strong>try<\/strong>) conectarse a MySQL utilizando el c&oacute;digo proporcionado, pero si hay un problema, se ejecutar&aacute; el c&oacute;digo de la secci&oacute;n de captura (<strong>catch<\/strong>). Puedes usar el <strong>bloque catch<\/strong> para mostrar mensajes de error de conexi&oacute;n o ejecutar un c&oacute;digo alternativo si falla el <strong>bloque try<\/strong>.<\/p><p>Si la conexi&oacute;n es exitosa, imprimir&aacute; el mensaje &ldquo;<strong>Connected to $dbname at $host successfully<\/strong>&ldquo;. Sin embargo, si el intento falla, el c&oacute;digo de captura mostrar&aacute; un mensaje de error simple y eliminar&aacute; el script.<\/p><h2 class=\"wp-block-heading\" id=\"h-verificar-la-conectividad-y-resolver-los-errores-comunes\">Verificar la conectividad y resolver los errores comunes<\/h2><p>Para verificar si la conexi&oacute;n es exitosa, accede a tu dominio as&iacute;: <strong>tudominio\/databaseconnect.php<\/strong>. Si nombras el archivo PHP de una forma diferente, aseg&uacute;rate de cambiar la direcci&oacute;n anterior en consecuencia.<\/p><p>Ver&aacute;s &ldquo;<strong>Connected<\/strong>&nbsp;<strong>successfully<\/strong>&rdquo; o variantes de este mensaje si todo est&aacute; funcionando sin problemas.<\/p><p>Ahora, si la conexi&oacute;n no fue exitosa, ver&aacute;s algo diferente. Los errores son ligeramente diferentes para MySQLi y PDO.<\/p><h3 class=\"wp-block-heading\" id=\"h-error-contrasena-incorrecta\">Error Contrase&ntilde;a Incorrecta<\/h3><p>Este error ocurre si cambiamos la contrase&ntilde;a o cualquier credencial en el c&oacute;digo PHP (pero no la cambiamos en la base de datos real).<\/p><p>En caso de que veas un mensaje como &ldquo;<strong>Access denied<\/strong>&rdquo; o &ldquo;<strong>Could not connect to database<\/strong>&rdquo; acompa&ntilde;ado de &ldquo;<strong>(using password: YES)<\/strong>&rdquo; al final, lo primero que debes hacer es verificar los detalles de la base de datos. Podr&iacute;a haber un error tipogr&aacute;fico o una parte faltante.<\/p><h3 class=\"wp-block-heading\" id=\"h-no-se-puede-conectar-con-el-servidor-mysql\">No se puede conectar con el servidor MySQL<\/h3><p>Si obtienes el mensaje &ldquo;<strong>Can&rsquo;t connect to MySQL server on &lsquo;server&rsquo; (110)<\/strong>&rdquo; en MySQLi, significa que el script no obtuvo una respuesta de un servidor. Esto sucede cuando configuramos &ldquo;<strong>server<\/strong>&rdquo; en lugar de &ldquo;<strong>localhost<\/strong>&rdquo; como <strong>$servername<\/strong>, y el nombre no es reconocido.<\/p><p>El mensaje de error en PDO se ver&aacute; como &ldquo;<strong>Connection failed: SQLSTATE[Hy000] [2002]<\/strong>&rdquo; seguido de m&aacute;s detalles que indican que no se encontr&oacute; el host My SQL. Pero la forma de solucionarlo es la misma que la anterior.<\/p><p>Y, por supuesto, siempre es importante recordar una regla de oro para solucionar un error: comprobar el registro de errores de su sitio.<\/p><p>El registro se puede encontrar en la misma carpeta donde se ejecuta el script. Por ejemplo, si estamos ejecutando un script en <strong>public_html<\/strong>, encontraremos el registro <strong>error_log<\/strong> en la misma carpeta.<\/p><h2 class=\"wp-block-heading\" id=\"h-conclusion\">Conclusi&oacute;n<\/h2><p>En este tutorial, has aprendido los conocimientos b&aacute;sicos sobre c&oacute;mo conectar un script PHP a una base de datos MySQL usando<strong> MySQLi<\/strong> y <strong>PHP Data Objects (PDO)<\/strong>.<\/p><p>Con suerte, esta gu&iacute;a fue &uacute;til para aquellos que reci&eacute;n est&aacute;n comenzando con el desarrollo web. Despu&eacute;s de todo, conectarse a una base de datos es el primer paso y el m&aacute;s importante cuando se trabaja con configuraciones y scripts m&aacute;s avanzados.<\/p><p>Haznos saber en los comentarios si tienes alg&uacute;n problema al seguir esta gu&iacute;a.<\/p><figure class=\"wp-block-image size-large\"><a href=\"\/co\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=1024,h=1024,fit=scale-down\" alt=\"\" class=\"wp-image-29291\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=768,fit=scale-down 768w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2023\/02\/ES-Web-hosting_in-text-banner.png\/w=1536,fit=scale-down 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Si eres un principiante en el desarrollo de sitios web, puede ser beneficioso saber c&oacute;mo como conectar PHP a MySQL con un script. De esta manera, podr&aacute;s modificar, ver o administrar las tablas creadas en la base de datos MySQL. Este art&iacute;culo te mostrar&aacute; las formas m&aacute;s f&aacute;ciles de hacerlo, comencemos. Crear una base de [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/co\/tutoriales\/conectar-php-mysql\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":85,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_title":"Tutorial para Conectar PHP con Bases de Datos MySQL %page%","rank_math_description":"Nuestra gu\u00eda completa te mostrar\u00e1 c\u00f3mo conectar PHP a uns base de datos MySQL utilizando dos m\u00e9todos diferentes: MySQLi y PDO.","rank_math_focus_keyword":"conectar php con mysql","footnotes":""},"categories":[7497],"tags":[14046],"class_list":["post-6423","post","type-post","status-publish","format-standard","hentry","category-php","tag-conectar-php-con-mysql"],"hreflangs":[{"locale":"en-US","link":"https:\/\/www.hostinger.com\/tutorials\/how-to-connect-php-to-mysql","default":0},{"locale":"pt-BR","link":"https:\/\/www.hostinger.com\/br\/tutoriais\/como-conectar-php-com-mysql","default":0},{"locale":"fr-FR","link":"https:\/\/www.hostinger.com\/fr\/tutoriels\/connecter-php-base-donnees-mysql","default":0},{"locale":"es-ES","link":"https:\/\/www.hostinger.com\/es\/tutoriales\/conectar-php-mysql","default":0},{"locale":"id-ID","link":"https:\/\/www.hostinger.com\/id\/tutorial\/koneksi-database-php","default":0},{"locale":"it-IT","link":"https:\/\/www.hostinger.com\/it\/tutorial\/collegare-php-a-mysql","default":0},{"locale":"en-GB","link":"https:\/\/www.hostinger.com\/uk\/tutorials\/how-to-connect-php-to-mysql","default":0},{"locale":"en-MY","link":"https:\/\/www.hostinger.com\/my\/tutorials\/how-to-connect-php-to-mysql","default":0},{"locale":"en-PH","link":"https:\/\/www.hostinger.com\/ph\/tutorials\/how-to-connect-php-to-mysql","default":0},{"locale":"es-MX","link":"https:\/\/www.hostinger.com\/mx\/tutoriales\/conectar-php-mysql","default":0},{"locale":"es-CO","link":"https:\/\/www.hostinger.com\/co\/tutoriales\/conectar-php-mysql","default":0},{"locale":"es-AR","link":"https:\/\/www.hostinger.com\/ar\/tutoriales\/conectar-php-mysql","default":0},{"locale":"pt-PT","link":"https:\/\/www.hostinger.com\/pt\/tutoriais\/como-conectar-php-com-mysql","default":0},{"locale":"en-IN","link":"https:\/\/www.hostinger.com\/in\/tutorials\/how-to-connect-php-to-mysql","default":0},{"locale":"en-CA","link":"https:\/\/www.hostinger.com\/ca\/tutorials\/how-to-connect-php-to-mysql","default":0},{"locale":"en-AU","link":"https:\/\/www.hostinger.com\/au\/tutorials\/how-to-connect-php-to-mysql","default":0},{"locale":"en-NG","link":"https:\/\/www.hostinger.com\/ng\/tutorials\/how-to-connect-php-to-mysql","default":0}],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/posts\/6423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/users\/85"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/comments?post=6423"}],"version-history":[{"count":15,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/posts\/6423\/revisions"}],"predecessor-version":[{"id":45219,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/posts\/6423\/revisions\/45219"}],"wp:attachment":[{"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/media?parent=6423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/categories?post=6423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/tags?post=6423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}