{"id":4516,"date":"2017-04-18T23:43:53","date_gmt":"2017-04-18T21:43:53","guid":{"rendered":"https:\/\/blog.hostinger.io\/tutoriales\/?p=4516"},"modified":"2025-01-29T09:58:37","modified_gmt":"2025-01-29T08:58:37","slug":"sitemap-en-wordpress","status":"publish","type":"post","link":"\/co\/tutoriales\/sitemap-en-wordpress\/","title":{"rendered":"Sitemap de WordPress: \u00bfQu\u00e9 es y c\u00f3mo crear uno?"},"content":{"rendered":"<p>Crear un mapa del sitio (sitemap en ingl&eacute;s) de WordPress es una de las muchas maneras de <a href=\"\/co\/tutoriales\/seo-en-wordpress\/\">optimizar un sitio web de WordPress para SEO<\/a>. Al utilizar un sitemap de WordPress, los visitantes del sitio web y los robots de los motores de b&uacute;squeda pueden ver mejor la estructura de un sitio. <\/p><p>Los sitemaps de WordPress crean una mejor experiencia de usuario para los visitantes y proporcionan informaci&oacute;n precisa para que los motores de b&uacute;squeda la rastreen.<\/p><p>Este art&iacute;culo te proporcionar&aacute; m&aacute;s detalles sobre los beneficios de generar sitemaps para los sitios web de WordPress. Tambi&eacute;n explicaremos las diferencias entre un sitemap XML y HTML y c&oacute;mo estos ayudan a optimizar un sitio.&nbsp;<\/p><p>Adem&aacute;s, aprender&aacute;s a generar ambos sitemaps para tu sitio de WordPress y a enviar un sitemap tanto a Google, como a Bing.<\/p><p class=\"has-text-align-center\"><a href=\"https:\/\/assets.hostinger.com\/content\/tutorials\/pdf\/Mega-WordPress-Cheat-ES.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Descarga la hoja de trucos de WordPress definitiva<\/a><\/p><h2 class=\"wp-block-heading\" id=\"h-que-es-un-sitemap-wordpress-y-por-que-lo-necesitas\">&iquest;Qu&eacute; es un sitemap WordPress y por qu&eacute; lo necesitas?<\/h2><p>Un sitemap de WordPress es una lista de todas las URL p&uacute;blicas de un sitio web de WordPress. Los sitemaps ayudan a los visitantes y a los motores de b&uacute;squeda a navegar por todas las URL de un sitio de forma m&aacute;s r&aacute;pida y sencilla. Tambi&eacute;n pueden mostrar la relaci&oacute;n entre las diferentes p&aacute;ginas y la importancia de cada una de ellas. Lee nuestra gu&iacute;a si quieres conocer m&aacute;s sobre <a href=\"\/co\/tutoriales\/que-es-un-sitemap\/\">qu&eacute; es un sitemap<\/a> en general.&nbsp;<\/p><p>Un sitemap de WordPress ayuda a los propietarios de sitios web de la siguiente manera:&nbsp;<\/p><ul class=\"wp-block-list\">\n<li><strong>Notificaci&oacute;n a los motores de b&uacute;squeda<\/strong>: avisa a los rastreadores de los motores de b&uacute;squeda y muestra a los visitantes cuando hay nuevas publicaciones en un sitio web. Los sitemaps de WordPress tambi&eacute;n informan a los motores de b&uacute;squeda sobre las p&aacute;ginas de un sitio que no han indexado antes.<\/li>\n\n\n\n<li><strong>F&aacute;cil navegaci&oacute;n<\/strong>: muestra la estructura y jerarqu&iacute;a de las p&aacute;ginas web proporcionando una lista completa de URLs personalizadas.<\/li>\n\n\n\n<li><a href=\"\/co\/tutoriales\/que-es-seo\/\">Optimizaci&oacute;n para motores de b&uacute;squeda<\/a>: ayuda a optimizar un sitio web al notificar a los motores de b&uacute;squeda que el sitio web no tiene contenido duplicado. Los mapas del sitio tambi&eacute;n hacen que un sitio web sea m&aacute;s f&aacute;cil de usar, lo que mejora su clasificaci&oacute;n en los resultados de las p&aacute;ginas de los motores de b&uacute;squeda (SERPs).&nbsp;<\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-diferencias-entre-un-sitemap-xml-y-html-de-wordpress\">Diferencias entre un sitemap XML y HTML de WordPress<\/h2><p>Hay dos tipos diferentes de sitemaps WordPress: un <strong>sitemap XML <\/strong>y <strong>sitemap HTML<\/strong>. Cada tipo juega un papel importante en la optimizaci&oacute;n de una p&aacute;gina web en sus diferentes formas.<\/p><p>Cuando env&iacute;as un sitemap de WordPress a los motores de b&uacute;squeda, utilizas un sitemap en lenguaje de marcado extensible (XML). Con este lenguaje, los robots de los motores de b&uacute;squeda encontrar&aacute;n el contenido y la informaci&oacute;n m&aacute;s f&aacute;cilmente. Los sitemaps XML tambi&eacute;n proporcionan metadatos adicionales y el contexto de cada URL.&nbsp;<\/p><p>Por su parte, los sitemaps HTML proporcionan enlaces que representan todas las p&aacute;ginas web en <a href=\"\/co\/tutoriales\/que-es-html\/\">formato HTML<\/a>. Esta funcionalidad presenta todas las p&aacute;ginas p&uacute;blicas de un sitio de una manera m&aacute;s sencilla de usar, facilitando la navegaci&oacute;n.<\/p><p>La principal diferencia entre los mapas de sitio es que un sitemap&nbsp; XML se encuentra en una URL separada y se centra en <strong>los motores de b&uacute;squeda<\/strong>. Mientras tanto, un sitemap HTML puede incluirse en las p&aacute;ginas web para <strong>los visitantes del sitio<\/strong>.&nbsp;&nbsp;<\/p><p>Te recomendamos tener ambos sitemaps de WordPress para garantizar una experiencia de usuario &oacute;ptima, lo que aumentar&aacute;, como resultado, tu posicionamiento en los motores de b&uacute;squeda.&nbsp;<\/p><h2 class=\"wp-block-heading\" id=\"h-como-generar-un-sitemap-xml-de-wordpress-manualmente\">&iquest;C&oacute;mo generar un sitemap XML de WordPress manualmente?<\/h2><p>Generar un sitemap XML de WordPress manualmente ayudar&aacute; a especificar la informaci&oacute;n exacta que los rastreadores de los motores de b&uacute;squeda obtendr&aacute;n. Sin embargo, se necesitar&aacute; m&aacute;s tiempo para crear un sitemap WordPress manualmente, especialmente para los sitios web con m&aacute;s de 10 URLs.&nbsp;<\/p><p>Para crear manualmente los mapas de sitio de WordPress, abre un editor de texto, como el Bloc de notas de Windows o Nano para los usuarios de Linux y macOS. Ten en cuenta que el archivo debe estar en formato XML. En &eacute;l, incluye la URL de tu sitio web y toda la informaci&oacute;n necesaria que los motores de b&uacute;squeda deben conocer.<\/p><p>Este es un ejemplo de un sitemap XML:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">&lt;?xml version=\"1.0\" encoding=\"UTF-8\"?&gt;\n&lt;urlset xmlns=\"http:\/\/www.sitemaps.org\/schemas\/sitemap\/0.9\"&gt;\n   &lt;url&gt;\n      &lt;loc&gt;http:\/\/www.example.com\/&lt;\/loc&gt;\n      &lt;lastmod&gt;2021-07-18&lt;\/lastmod&gt;\n      &lt;changefreq&gt;monthly&lt;\/changefreq&gt;\n      &lt;priority&gt;0.5&lt;\/priority&gt;\n   &lt;\/url&gt;\n&lt;\/urlset&gt;<\/pre><p>En este sitemap, hay etiquetas obligatorias y opcionales. A continuaci&oacute;n una explicaci&oacute;n de las etiquetas obligatorias:<\/p><ul class=\"wp-block-list\">\n<li><strong>&lt;urlset&gt;<\/strong>: se refiere al protocolo de est&aacute;ndar actual. Mant&eacute;n la URL del ejemplo para tu archivo de sitemap XML.<\/li>\n\n\n\n<li><strong>&lt;url&gt;<\/strong>: etiqueta padre para la URL. El resto de las etiquetas se incluyen dentro de esta etiqueta.<\/li>\n\n\n\n<li><strong>&lt;loc&gt;<\/strong>: es la URL del sitio web. Debes comenzar con el protocolo, como HTTP y terminar con una barra diagonal final si tu servidor web lo utiliza. El valor de esta etiqueta debe ser inferior a 2.048 caracteres.&nbsp;&nbsp;<\/li>\n<\/ul><p>Adem&aacute;s, algunas de las etiquetas opcionales a tener en cuenta son:<\/p><ul class=\"wp-block-list\">\n<li><strong>&lt;lastmod&gt;<\/strong>: muestra la &uacute;ltima hora de modificaci&oacute;n del sitio web. Utiliza el formato AAAA-MM-DD para esta etiqueta.<\/li>\n\n\n\n<li><strong>&lt;changefreq&gt;<\/strong>: revela la frecuencia con la que el sitio web realiza cambios. Los valores v&aacute;lidos son: siempre, cada hora, diariamente, semanalmente, mensualmente, anualmente y nunca.<\/li>\n\n\n\n<li><strong>&lt;priority&gt;<\/strong>: permite a los motores de b&uacute;squeda saber qu&eacute; URLs son m&aacute;s importantes para los rastreadores. Los valores v&aacute;lidos van de 0.0 a 1,0, con el valor predeterminado de 0,5.<\/li>\n<\/ul><p>Una vez que hayas creado un archivo sitemap XML, s&uacute;belo a tu carpeta ra&iacute;z de WordPress. A continuaci&oacute;n, accede a la URL del sitemap para comprobar el mapa del sitio de WordPress. Normalmente, la URL sigue este formato:<\/p><p><a href=\"http:\/\/example.com\/sitemap.xml\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/ejemplo.com\/sitemap.xml<\/a><\/p><p>Despu&eacute;s de encontrar la URL del sitemap, val&iacute;dala con el <a href=\"https:\/\/www.xml-sitemaps.com\/validate-xml-sitemap.html\" target=\"_blank\" rel=\"noreferrer noopener\">validador de sitemaps<\/a>. Los archivos de sitemaps no v&aacute;lidos pueden generar inconvenientes en los sitios web de WordPress. Por lo tanto, es esencial comprobar primero con un validador antes de enviar los sitemaps XML a los motores de b&uacute;squeda.&nbsp;&nbsp;<\/p><p>Para utilizar el validador de sitemaps, introduce la URL del mapa del sitio en el validador y haz clic en el bot&oacute;n <strong>VALIDATE SITEMAP<\/strong>.<\/p><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1007\" height=\"568\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.56.10-p.m.png\/public\" alt=\"Validador de sitemaps\" class=\"wp-image-37433\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.56.10-p.m.png\/w=1007,fit=scale-down 1007w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.56.10-p.m.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.56.10-p.m.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.56.10-p.m.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1007px) 100vw, 1007px\" \/><\/figure><p>Si el sitemap de WordPress es v&aacute;lido, se mostrar&aacute; un banner anunciando &ldquo;<strong>no hay problemas detectados<\/strong>&rdquo;.<\/p><figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Mensaje-de-sitemap-v%C3%A1lido.png\/public\" alt=\"Mensaje de sitemap v&aacute;lido\" class=\"wp-image-37409\"><\/figure><p>Sin embargo, si el mapa del sitio de WordPress no es v&aacute;lido, mostrar&aacute; un mensaje de advertencia, declarando &ldquo;<strong>Problema detectado&rdquo;<\/strong>.<\/p><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"926\" height=\"581\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/problema-detectado-en-sitemap.png\/public\" alt=\"Mensaje de problema detectado en sitemap\" class=\"wp-image-37410\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/problema-detectado-en-sitemap.png\/w=926,fit=scale-down 926w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/problema-detectado-en-sitemap.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/problema-detectado-en-sitemap.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/problema-detectado-en-sitemap.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 926px) 100vw, 926px\" \/><\/figure><h2 class=\"wp-block-heading\" id=\"h-como-generar-un-sitemap-xml-de-wordpress-con-un-plugin\">&iquest;C&oacute;mo generar un sitemap XML de WordPress con un plugin?<\/h2><p>Para crear autom&aacute;ticamente un sitemap en WordPress, utiliza los plugins de sitemaps. Es una forma m&aacute;s r&aacute;pida y fiable de generar un mapa del sitio de WordPress.&nbsp;<\/p><p>Al <a href=\"\/co\/tutoriales\/plugins-en-wordpress-gratis\/\">instalar un plugin de WordPress<\/a>, los usuarios recibir&aacute;n caracter&iacute;sticas y funcionalidades adicionales para ayudar a optimizar su sitio web. Los plugins tambi&eacute;n ayudan a actualizar los sitemaps de WordPress cuando se realiza cualquier cambio de forma autom&aacute;tica.<\/p><p>A continuaci&oacute;n encontrar&aacute;s ayuda sobre c&oacute;mo generar un sitemap XML de WordPress con dos de los mejores plugins de WordPress para esta tarea.&nbsp;<\/p><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"\/co\/hosting-wordpress\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/06\/ES-New-WP_in-text-banner.png\/public\" alt=\"\" class=\"wp-image-40615\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/06\/ES-New-WP_in-text-banner.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/06\/ES-New-WP_in-text-banner.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/06\/ES-New-WP_in-text-banner.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/06\/ES-New-WP_in-text-banner.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div><h3 class=\"wp-block-heading\" id=\"h-generar-un-sitemap-de-wordpress-con-yoast-seo\">Generar un sitemap de WordPress con <a href=\"https:\/\/es.wordpress.org\/plugins\/wordpress-seo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Yoast SEO<\/a><\/h3><p>El plugin Yoast es uno de los <a href=\"\/co\/tutoriales\/mejores-plugins-seo-wordpress\/\">plugins SEO m&aacute;s populares<\/a> para WordPress. Este plugin de SEO se encarga de todos los aspectos t&eacute;cnicos relacionados con la optimizaci&oacute;n del contenido de WordPress, incluyendo la creaci&oacute;n de sitemaps XML.<\/p><p>Sigue estos pasos para crear tu sitemap en WordPress:<\/p><ol class=\"wp-block-list\">\n<li>Dir&iacute;gete al <strong>panel de control<\/strong> de WordPress<strong> -&gt; Plugins -&gt; A&ntilde;adir nuevo <\/strong>y busca el plugin Yoast SEO. Haz clic en <strong>Instalar ahora <\/strong>y <strong>activa <\/strong>la<strong> <\/strong>versi&oacute;n gratuita del plugin.<\/li>\n<\/ol><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"829\" height=\"349\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Yoast.png\/public\" alt=\"Plugin Yoast SEO en WP\" class=\"wp-image-37412\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Yoast.png\/w=829,fit=scale-down 829w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Yoast.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Yoast.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Yoast.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 829px) 100vw, 829px\" \/><\/figure><ol class=\"wp-block-list\" start=\"2\">\n<li>Ve al men&uacute; <strong>Yoast SEO <\/strong>en el tablero de mandos y selecciona <strong>General<\/strong>. A continuaci&oacute;n, entra en la pesta&ntilde;a <strong>Caracter&iacute;sticas <\/strong>para ver la configuraci&oacute;n.<\/li>\n<\/ol><figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Caracter%C3%ADsticas-Yoast-.png\/public\" alt=\"Caracter&iacute;sticas del plugin de Yoast \" class=\"wp-image-37413\"><\/figure><ol class=\"wp-block-list\" start=\"3\">\n<li>En la pesta&ntilde;a de caracter&iacute;sticas, selecciona el bot&oacute;n <strong>Activado <\/strong>debajo de<strong> sitemaps XML <\/strong>y haz clic en el bot&oacute;n <strong>Guardar cambios<\/strong>.<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"672\" height=\"430\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.32.07-p.m.png\/public\" alt=\"Bot&oacute;n de XML Sitemaps en Yoast\" class=\"wp-image-37414\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.32.07-p.m.png\/w=672,fit=scale-down 672w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.32.07-p.m.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.32.07-p.m.png\/w=150,fit=scale-down 150w\" sizes=\"(max-width: 672px) 100vw, 672px\" \/><\/figure>\n<\/div><ol class=\"wp-block-list\" start=\"4\">\n<li>Para comprobar el enlace del sitemap XML, haz clic en el <strong>icono del signo de interrogaci&oacute;n <\/strong>y selecciona la opci&oacute;n <strong>Ver el mapa del sitio XML<\/strong>.&nbsp;<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"581\" height=\"309\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.35.59-p.m.png\/public\" alt=\"Opci&oacute;n de ver el sitemap XML en Yoast\" class=\"wp-image-37415\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.35.59-p.m.png\/w=581,fit=scale-down 581w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.35.59-p.m.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.35.59-p.m.png\/w=150,fit=scale-down 150w\" sizes=\"(max-width: 581px) 100vw, 581px\" \/><\/figure>\n<\/div><ol class=\"wp-block-list\" start=\"5\">\n<li>Yoast SEO te redirigir&aacute; a la URL del mapa del sitio XML. All&iacute; ver&aacute;s m&aacute;s informaci&oacute;n sobre cada URL de tu sitio.<\/li>\n<\/ol><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"708\" height=\"325\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Mapa-del-sitio-XML-.png\/public\" alt=\"Mapa del sitio XML \" class=\"wp-image-37416\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Mapa-del-sitio-XML-.png\/w=708,fit=scale-down 708w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Mapa-del-sitio-XML-.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Mapa-del-sitio-XML-.png\/w=150,fit=scale-down 150w\" sizes=\"(max-width: 708px) 100vw, 708px\" \/><\/figure>\n<\/div><p>Adem&aacute;s, Yoast SEO cuenta con la configuraci&oacute;n de <strong>las Herramientas para webmasters<\/strong>, que permite conectar un sitio web de WordPress con diferentes motores de b&uacute;squeda de inmediato. De este modo, ser&aacute; m&aacute;s f&aacute;cil enviar y notificar las actualizaciones a los distintos motores de b&uacute;squeda.<\/p><figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1160\" height=\"592\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Herramientas-de-webmaster-de-Yoast-SEO-1.png\/w=1024,h=1024,fit=scale-down\" alt=\"Herramientas de webmaster de Yoast SEO\" class=\"wp-image-37418\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Herramientas-de-webmaster-de-Yoast-SEO-1.png\/w=1160,fit=scale-down 1160w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Herramientas-de-webmaster-de-Yoast-SEO-1.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Herramientas-de-webmaster-de-Yoast-SEO-1.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Herramientas-de-webmaster-de-Yoast-SEO-1.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Herramientas-de-webmaster-de-Yoast-SEO-1.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/figure><h3 class=\"wp-block-heading\" id=\"h-google-xml-sitemaps\"><a href=\"https:\/\/es.wordpress.org\/plugins\/google-sitemap-generator\/#installation\" target=\"_blank\" rel=\"noreferrer noopener\">Google XML Sitemaps<\/a><\/h3><p>El plugin Google XML Sitemaps es ideal para aquellos que prefieren una configuraci&oacute;n avanzada de los mapas de sitio y la opci&oacute;n de enviar uno a los motores de b&uacute;squeda de inmediato.<\/p><p>Otra caracter&iacute;stica destacable del sitemap XML son las notificaciones autom&aacute;ticas a los principales motores de b&uacute;squeda cuando se publican nuevos contenidos. Sigue los siguientes pasos para utilizar el plugin:<\/p><ol class=\"wp-block-list\">\n<li>Instala el plugin XML Sitemaps desde el directorio de plugins de WordPress.<img decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/b2fmelMoM728AEwWLxAg9ApqL4O4cHnAGvDJdu80D-Nep-nIQlPN7U88GtmDyot71Y0rPLxxtSF0JV4UqUuzma9lAEr67o3Al7PKo36vj6Z9hlXNFmhSfiVRwq7pYJwkckcfrEkYZCddkZYo5l01JLVyHkm9VdaTqvTR-oK0dyoJQslhsIJoXtsOkYbb\" width=\"624\" height=\"243\"><\/li>\n\n\n\n<li>Abre la p&aacute;gina de configuraci&oacute;n dirigiendote a <strong>Ajustes <\/strong>-&gt; <strong>XML-Sitemap<\/strong>. Como el plugin genera autom&aacute;ticamente un mapa del sitio XML para un sitio de WordPress, ver&aacute;s la URL del sitemap de all&iacute;.<\/li>\n<\/ol><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"374\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.39.48-p.m.png\/public\" alt=\"Ajustes del plugin Google XML Sitemaps\" class=\"wp-image-37421\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.39.48-p.m.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.39.48-p.m.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.39.48-p.m.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.39.48-p.m.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><ol class=\"wp-block-list\" start=\"3\">\n<li>Haz clic en la URL para ver el <strong>&iacute;ndice del mapa del sitio XML<\/strong>.<\/li>\n<\/ol><figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/%C3%8Dndice-del-sitemap-XML.png\/public\" alt=\"&Iacute;ndice del sitemap XML\" class=\"wp-image-37422\"><\/figure><p>Para notificar a los motores de b&uacute;squeda, dir&iacute;gete a <strong>Configuraci&oacute;n <\/strong>-&gt; <strong>Mapa del sitio XML <\/strong>y encuentra la secci&oacute;n <strong>Opciones b&aacute;sicas<\/strong>. Marque las dos primeras casillas para notificar tanto a Google como a Bing y haga clic en el bot&oacute;n <strong>Opciones de actualizaci&oacute;n <\/strong>en la parte inferior de la p&aacute;gina.<\/p><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"799\" height=\"291\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/09\/image-20.png\/public\" alt=\"Opciones para notificar a los motores de b&uacute;squeda del sitemap\" class=\"wp-image-23046\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/09\/image-20.png\/w=799,fit=scale-down 799w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/09\/image-20.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/09\/image-20.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/09\/image-20.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 799px) 100vw, 799px\" \/><\/figure><h2 class=\"wp-block-heading\" id=\"h-como-enviar-un-sitemap-xml-de-wordpress-a-los-motores-de-busqueda\">&iquest;C&oacute;mo enviar un sitemap XML de WordPress a los motores de b&uacute;squeda?<\/h2><p>Despu&eacute;s de generar un sitemap WordPress, env&iacute;alo a motores de b&uacute;squeda como Google y Bing para que lo indexen. Ten en cuenta que, aunque los motores de b&uacute;squeda seguir&aacute;n rastreando los sitios web sin el env&iacute;o manual, el env&iacute;o de sitemaps XML de WordPress a los motores de b&uacute;squeda seguir&aacute; proporcionando beneficios adicionales:&nbsp;&nbsp;<\/p><ul class=\"wp-block-list\">\n<li><strong>SEO<\/strong>: los sitemaps notifican a los motores de b&uacute;squeda cuando hay cambios o nuevos contenidos, lo que ayuda a que tu p&aacute;gina se mantenga actualizada en los resultados de los motores de b&uacute;squeda.<\/li>\n\n\n\n<li><strong>Precisi&oacute;n<\/strong>: con la ayuda de un sitemap de WordPress, un motor de b&uacute;squeda s&oacute;lo indexar&aacute; la informaci&oacute;n m&aacute;s precisa y relevante de un sitio.<\/li>\n\n\n\n<li><strong>Gratis<\/strong>: generar un sitemap de WordPress no tiene ning&uacute;n coste, sea cual sea el m&eacute;todo.<\/li>\n\n\n\n<li><strong>Tr&aacute;fico org&aacute;nico<\/strong>: genera m&aacute;s visitas al posicionarse mejor en las SERPs.&nbsp;&nbsp;<\/li>\n<\/ul><p>\n\n\n\n<div><p class=\"important\"><strong>&iexcl;Importante!<\/strong> Antes de enviar un sitio de WordPress a los motores de b&uacute;squeda, necesitas una URL de mapa del sitio XML.<\/p><\/div>\n\n\n\n<\/p><h3 class=\"wp-block-heading\" id=\"h-enviar-un-sitemap-xml-a-google\">Enviar un sitemap XML a Google<\/h3><p>El env&iacute;o de un sitemap de WordPress a Google <a href=\"\/co\/tutoriales\/como-generar-trafico-web-rapidamente\/\">har&aacute; que aumente el tr&aacute;fico<\/a> y la notoriedad de un sitio web. Los propietarios de sitios web pueden hacerlo utilizando <a href=\"https:\/\/search.google.com\/search-console\/\" target=\"_blank\" rel=\"noreferrer noopener\">Google Search Console<\/a>.<\/p><p>Accede a tu cuenta de Google y sigue los siguientes pasos:<\/p><ol class=\"wp-block-list\">\n<li>Selecciona el tipo de propiedad para empezar. Para obtener informaci&oacute;n sobre todas las URL del dominio, selecciona la opci&oacute;n <strong>Dominio<\/strong>. Introduce tu nombre de dominio y haz clic en el bot&oacute;n <strong>CONTINUAR<\/strong>.<\/li>\n<\/ol><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"928\" height=\"738\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/enviar-URL-en-Google-Search-Console.png\/public\" alt=\"Secci&oacute;n para enviar URL en Google Search Console\" class=\"wp-image-37423\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/enviar-URL-en-Google-Search-Console.png\/w=928,fit=scale-down 928w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/enviar-URL-en-Google-Search-Console.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/enviar-URL-en-Google-Search-Console.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/enviar-URL-en-Google-Search-Console.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 928px) 100vw, 928px\" \/><\/figure><ol class=\"wp-block-list\" start=\"2\">\n<li>Verifica el dominio a&ntilde;adiendo el <strong>registro TXT <\/strong>de Google Search Console a tu servidor de sistema de nombres de dominio (DNS). Si tienes un plan de alojamiento web con Hostinger, dir&iacute;gete a <strong>hPanel -&gt; <\/strong>Editor de zona DNS y a&ntilde;ade el registro en el cuadro <strong>Administrar registros DNS<\/strong>.<\/li>\n<\/ol><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1422\" height=\"483\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Editor-de-Zona-DNS-en-hPanel.png\/public\" alt=\"Editor de Zona DNS en hPanel\" class=\"wp-image-37424\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Editor-de-Zona-DNS-en-hPanel.png\/w=1422,fit=scale-down 1422w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Editor-de-Zona-DNS-en-hPanel.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Editor-de-Zona-DNS-en-hPanel.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Editor-de-Zona-DNS-en-hPanel.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Editor-de-Zona-DNS-en-hPanel.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1422px) 100vw, 1422px\" \/><\/figure><ol class=\"wp-block-list\" start=\"3\">\n<li>Vuelve a la cuenta de Google Search Console y selecciona <strong>Sitemaps <\/strong>en el men&uacute; de la barra lateral izquierda. All&iacute;, inserta la URL de tu mapa del sitio en la secci&oacute;n <strong>A&ntilde;adir un nuevo mapa del sitio <\/strong>y haz clic en <strong>ENVIAR <\/strong>para finalizar el proceso.<\/li>\n<\/ol><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"427\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.42.46-p.m.png\/public\" alt=\"Secci&oacute;n de Sitemaps en Google Search Console\" class=\"wp-image-37425\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.42.46-p.m.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.42.46-p.m.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.42.46-p.m.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.42.46-p.m.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><p>Para comprobar el estado, dir&iacute;gete a <strong>Sitemaps -&gt; Sitemaps enviados<\/strong>. Google Search Console compartir&aacute; el estado y dar&aacute; informaci&oacute;n sobre la optimizaci&oacute;n de tu sitio utilizando <a href=\"https:\/\/developers.google.com\/search\" target=\"_blank\" rel=\"noreferrer noopener\">documentaci&oacute;n<\/a> y recursos.<\/p><h3 class=\"wp-block-heading\" id=\"h-enviar-un-sitemap-xml-de-wordpress-a-bing\"><strong>Enviar un sitemap XML de WordPress a Bing<\/strong><\/h3><p>Bing es <a href=\"https:\/\/financesonline.com\/bing-statistics\/\" target=\"_blank\" rel=\"noreferrer noopener\">otro motor de b&uacute;squeda popular<\/a> para enviar un sitio web, ya que otros motores de b&uacute;squeda, como Yahoo y DuckDuckGo, tambi&eacute;n utilizan su &iacute;ndice de b&uacute;squeda para las clasificaciones. Los propietarios de sitios web pueden utilizar las Herramientas para webmasters de Bing para un rastreo e indexaci&oacute;n inmediatos.<\/p><p>Sigue los siguientes pasos para enviar los mapas de sitio XML de WordPress a Bing:&nbsp;<\/p><ol class=\"wp-block-list\">\n<li>Utiliza las cuentas de Microsoft, Google o Facebook para acceder a <a href=\"https:\/\/www.bing.com\/webmasters\/about\" target=\"_blank\" rel=\"noreferrer noopener\">las Herramientas para webmasters de Bing<\/a>.<\/li>\n<\/ol><figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/inicio-de-sesi%C3%B3n-en-Bing.png\/w=1024,h=1024,fit=scale-down\" alt=\"Interfaz de inicio de sesi&oacute;n en Bing\" class=\"wp-image-37426\"><\/figure><ol class=\"wp-block-list\" start=\"2\">\n<li>En la secci&oacute;n <strong>A&ntilde;adir tu sitio manualmente<\/strong>, a&ntilde;ade la URL de tu sitio web. Si la URL ha sido verificada en Google Search Console, accede con tu cuenta de Google y haz clic en el bot&oacute;n <strong>Importar<\/strong>.<\/li>\n<\/ol><figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/a%C3%B1adir-sitemap-en-Bing.png\/w=1024,h=1024,fit=scale-down\" alt=\"Secci&oacute;n para a&ntilde;adir sitemap en Bing\" class=\"wp-image-37427\"><\/figure><ol class=\"wp-block-list\" start=\"3\">\n<li>Selecciona <strong>Sitemaps -&gt; Submit Sitemaps <\/strong>y a&ntilde;ade la URL del mapa del sitio para notificar a la herramienta que indexe tu sitio.<\/li>\n<\/ol><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"397\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Sitemaps-en-Bing.png\/public\" alt=\"Secci&oacute;n de Sitemaps en Bing\" class=\"wp-image-37428\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Sitemaps-en-Bing.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Sitemaps-en-Bing.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Sitemaps-en-Bing.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Sitemaps-en-Bing.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><p>Para explorar el estado de la indexaci&oacute;n, haz clic en el <strong>Explorador del Sitio <\/strong>en el men&uacute; de la barra lateral izquierda.<\/p><h2 class=\"wp-block-heading\" id=\"h-como-crear-una-pagina-de-sitemap-html-para-wordpress\">&iquest;C&oacute;mo crear una p&aacute;gina de sitemap HTML para WordPress?<\/h2><p>Como mencionamos anteriormente, el sitemap HTML de WordPress es una parte esencial del SEO. Proporciona una navegaci&oacute;n f&aacute;cil de usar para los visitantes del sitio web y establece una estructura clara para las p&aacute;ginas web.<\/p><p>La forma m&aacute;s f&aacute;cil de crear un mapa de sitio HTML para un sitio de WordPress es instalando un plugin. Recomendamos el uso de <a href=\"https:\/\/es.wordpress.org\/plugins\/wp-sitemap-page\/\" target=\"_blank\" rel=\"noreferrer noopener\">WP Sitemap Page<\/a>:<\/p><ol class=\"wp-block-list\">\n<li>Instala WP Sitemap Page y activa el plugin.<img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/Jme3cjHz4UdywBw2IHZvPTLj-KsrUEfCmfp6F4LjWpoYD5Z-oED59_YMSn8bla20_ATyot9ay9T1ybCOQQi8G2xXuihOrt5pNAlzcfsqFKHM7jzsNYKAt6QXeTOhm1Z_KOyJpDfCqkNa0uVMf8GbRbjLzi7F0eAHAIdtiI7JGGLGpSjDyZUn2EemcQCO\" width=\"624\" height=\"228\"><\/li>\n\n\n\n<li>Dir&iacute;gete al <strong>Panel de control -&gt; P&aacute;ginas -&gt; A&ntilde;adir Nueva <\/strong>para crear una nueva p&aacute;gina en un sitio WordPress. Para a&ntilde;adir el mapa del sitio de WordPress a una p&aacute;gina existente, selecciona la p&aacute;gina en la secci&oacute;n <strong>P&aacute;ginas<\/strong>. Dicho esto, recomendamos crear una nueva p&aacute;gina en su lugar.<\/li>\n<\/ol><figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"155\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.53.06-p.m.png\/public\" alt=\"Secci&oacute;n de A&ntilde;adir Nueva p&aacute;gina en WordPress\" class=\"wp-image-37429\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.53.06-p.m.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.53.06-p.m.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.53.06-p.m.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/Captura-de-pantalla-2024-01-25-a-las-1.53.06-p.m.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><ol class=\"wp-block-list\" start=\"3\">\n<li>Inserta el siguiente shortcode de WordPress para a&ntilde;adir el sitemap HTML:<\/li>\n<\/ol><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">[wp_sitemap_page]<\/pre><figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"463\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/nueva-entrada-en-WordPress.png\/w=1024,h=1024,fit=scale-down\" alt=\"Creando una nueva entrada en WordPress\" class=\"wp-image-37430\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/nueva-entrada-en-WordPress.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/nueva-entrada-en-WordPress.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/nueva-entrada-en-WordPress.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/nueva-entrada-en-WordPress.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><ol class=\"wp-block-list\" start=\"4\">\n<li>Haz clic en <strong>Publicar <\/strong>y el mapa del sitio HTML de WordPress estar&aacute; disponible en tu sitio web.<\/li>\n<\/ol><figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"443\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/nueva-entrada-en-WordPress-con-el-Sitemap.png\/w=1024,h=1024,fit=scale-down\" alt=\"Publicaci&oacute;n de nueva entrada en WordPress con el Sitemap\" class=\"wp-image-37431\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/nueva-entrada-en-WordPress-con-el-Sitemap.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/nueva-entrada-en-WordPress-con-el-Sitemap.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/nueva-entrada-en-WordPress-con-el-Sitemap.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/01\/nueva-entrada-en-WordPress-con-el-Sitemap.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><h2 class=\"wp-block-heading\" id=\"h-conclusion\">Conclusi&oacute;n<\/h2><p>En este art&iacute;culo hemos compartido dos formas diferentes de generar sitemaps de WordPress: manualmente y mediante el uso de plugins. Si eliges hacerlo manualmente, podr&aacute;s elegir la informaci&oacute;n exacta a incluir en tu sitemap. Sin embargo, hacerlo requiere m&aacute;s esfuerzo e implica un paso adicional de utilizar una herramienta de validaci&oacute;n para probar tu sitemap.<\/p><p>En su lugar, te recomendamos utilizar uno de los plugins para crear tanto el sitemap HTML, como el XML. Tambi&eacute;n hemos compartido los pasos para enviar un sitemap de WordPress a Google y a Bing.<\/p><p>No dudes en compartir tu experiencia en la generaci&oacute;n y env&iacute;o de un sitemap de WordPress en la secci&oacute;n de comentarios m&aacute;s abajo.<\/p><p>\n\n\n<div class=\"protip\">\n                    <p class=\"title\">Aprende m&aacute;s sobre SEO en WordPress<\/p>\n                    <p> <a>Gu&iacute;a para el Robots.txt de WordPress<\/a><br>\n<a href=\"\/co\/tutoriales\/datos-estructurados-wordpress\/\" target=\"&rdquo;_blank&rdquo;\" rel=\"noopener\">&iquest;C&oacute;mo a&ntilde;adir el Schema Markup en WordPress?<\/a><br>\n<a href=\"\/co\/tutoriales\/agregar-meta-titulo-meta-descripcion-optimizar-seo-wordpress\/\" target=\"&rdquo;_blank&rdquo;\" rel=\"noopener\">&iquest;C&oacute;mo a&ntilde;adir la Meta Descripci&oacute;n y el Meta T&iacute;tulo en WordPress?<\/a><br>\n<a href=\"\/co\/tutoriales\/como-configurar-amp-wordpress\/\" target=\"&rdquo;_blank&rdquo;\" rel=\"noopener\">&iquest;C&oacute;mo configurar AMP (Accelerated Mobile Pages) en WordPress?<\/a><br>\n<\/p>\n                <\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crear un mapa del sitio (sitemap en ingl&eacute;s) de WordPress es una de las muchas maneras de optimizar un sitio web de WordPress para SEO. Al utilizar un sitemap de WordPress, los visitantes del sitio web y los robots de los motores de b&uacute;squeda pueden ver mejor la estructura de un sitio. Los sitemaps de [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/co\/tutoriales\/sitemap-en-wordpress\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":138,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_title":"\u00bfC\u00f3mo crear un sitemap en WordPress?: Gu\u00eda para principiantes","rank_math_description":"\u00bfQuieres mejorar la visibilidad de tu sitio web en los motores de b\u00fasqueda? Aprende a crear un sitemap de WordPress en este art\u00edculo.","rank_math_focus_keyword":"sitemap wordpress","footnotes":""},"categories":[4747],"tags":[14131],"class_list":["post-4516","post","type-post","status-publish","format-standard","hentry","category-wordpress","tag-sitemap-wordpress"],"hreflangs":[{"locale":"en-US","link":"https:\/\/www.hostinger.com\/tutorials\/how-to-create-wordpress-sitemap","default":0},{"locale":"pt-BR","link":"https:\/\/www.hostinger.com\/br\/tutoriais\/como-criar-sitemap-para-wordpress","default":0},{"locale":"fr-FR","link":"https:\/\/www.hostinger.com\/fr\/tutoriels\/sitemap-wordpress","default":0},{"locale":"es-ES","link":"https:\/\/www.hostinger.com\/es\/tutoriales\/sitemap-en-wordpress","default":0},{"locale":"id-ID","link":"https:\/\/www.hostinger.com\/id\/tutorial\/cara-membuat-sitemap-wordpress\/","default":0},{"locale":"de-DE","link":"https:\/\/www.hostinger.com\/de\/tutorials\/wordpress-sitemap-erstellen","default":0},{"locale":"nl-NL","link":"https:\/\/www.hostinger.com\/nl\/tutorials\/wordpress-sitemap","default":0},{"locale":"ja-JP","link":"https:\/\/www.hostinger.com\/jp\/tutorials\/how-to-create-wordpress-sitemap\/","default":0},{"locale":"en-GB","link":"https:\/\/www.hostinger.com\/uk\/tutorials\/how-to-create-wordpress-sitemap","default":0},{"locale":"en-MY","link":"https:\/\/www.hostinger.com\/my\/tutorials\/create-wordpress-sitemap","default":0},{"locale":"en-PH","link":"https:\/\/www.hostinger.com\/ph\/tutorials\/create-wordpress-sitemap","default":0},{"locale":"pt-PT","link":"https:\/\/www.hostinger.com\/pt\/tutoriais\/como-criar-sitemap-para-wordpress","default":0},{"locale":"en-IN","link":"https:\/\/www.hostinger.com\/in\/tutorials\/how-to-create-wordpress-sitemap","default":0},{"locale":"en-CA","link":"https:\/\/www.hostinger.com\/ca\/tutorials\/how-to-create-wordpress-sitemap","default":0},{"locale":"es-AR","link":"https:\/\/www.hostinger.com\/ar\/tutoriales\/sitemap-en-wordpress","default":0},{"locale":"es-MX","link":"https:\/\/www.hostinger.com\/mx\/tutoriales\/sitemap-en-wordpress","default":0},{"locale":"es-CO","link":"https:\/\/www.hostinger.com\/co\/tutoriales\/sitemap-en-wordpress","default":0},{"locale":"en-AU","link":"https:\/\/www.hostinger.com\/au\/tutorials\/how-to-create-wordpress-sitemap","default":0},{"locale":"en-NG","link":"https:\/\/www.hostinger.com\/ng\/tutorials\/how-to-create-wordpress-sitemap","default":0}],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/posts\/4516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/users\/138"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/comments?post=4516"}],"version-history":[{"count":26,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/posts\/4516\/revisions"}],"predecessor-version":[{"id":37434,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/posts\/4516\/revisions\/37434"}],"wp:attachment":[{"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/media?parent=4516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/categories?post=4516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/tags?post=4516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}