{"id":21732,"date":"2022-08-08T20:38:07","date_gmt":"2022-08-08T18:38:07","guid":{"rendered":"https:\/\/blog.hostinger.io\/co-tutoriales\/?p=21732"},"modified":"2026-03-10T16:43:53","modified_gmt":"2026-03-10T15:43:53","slug":"wp-nav-menu","status":"publish","type":"post","link":"\/co\/tutoriales\/wp-nav-menu\/","title":{"rendered":"\u00bfC\u00f3mo crear un men\u00fa personalizado utilizando la funci\u00f3n wp_nav_menu de WordPress?"},"content":{"rendered":"<p>Los men&uacute;s son algunos de los elementos m&aacute;s comunes en los sitios web. Con <a href=\"\/co\/hosting-wordpress\">WordPress<\/a>, puedes personalizar f&aacute;cilmente los men&uacute;s y elegir entre m&uacute;ltiples opciones de visualizaci&oacute;n si tu tema lo admite. Sin embargo, si quieres utilizar men&uacute;s en una ubicaci&oacute;n personalizada, tendr&aacute;s que editar los archivos de tu tema y a&ntilde;adir la funci&oacute;n <a href=\"https:\/\/developer.wordpress.org\/reference\/functions\/wp_nav_menu\/\" target=\"_blank\" rel=\"noreferrer noopener\">wp_nav_menu<\/a>.<\/p><p>Combinando esta funci&oacute;n con <strong>register_nav_menu<\/strong>, podr&aacute;s crear y colocar men&uacute;s en cualquier lugar de tu sitio web. A&ntilde;adir y configurar estas funciones es relativamente sencillo, incluso si no eres un desarrollador. Adem&aacute;s, puedes editar los men&uacute;s directamente desde tu panel de control de WordPress.<\/p><p>En este art&iacute;culo, hablaremos de c&oacute;mo funciona la funci&oacute;n wp_nav_menu de <a href=\"\/co\/tutoriales\/que-es-wordpress\/\">WordPress<\/a>. Te mostraremos qu&eacute; argumentos y clases funcionan con wp_nav_menu y luego te explicaremos c&oacute;mo usar la funci&oacute;n con tu tema. &iexcl;Vamos a ello!<\/p><p class=\"has-text-align-center\"><a href=\"https:\/\/assets.hostinger.com\/content\/tutorials\/pdf\/Mega-WordPress-Cheat-ES.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Descarga la hoja de trucos de WordPress definitiva<\/a><\/p><h2 class=\"wp-block-heading\" id=\"h-que-es-la-funcion-wp-nav-menu-de-wordpress\">&iquest;Qu&eacute; es la funci&oacute;n wp_nav_menu de WordPress?<\/h2><p>wp_nav_menu es una funci&oacute;n que puede mostrar men&uacute;s personalizados en WordPress. A diferencia de <a href=\"https:\/\/developer.wordpress.org\/reference\/functions\/wp_page_menu\/\" target=\"_blank\" rel=\"noreferrer noopener\">wp_page_menu<\/a>, que muestra una lista de p&aacute;ginas existentes, wp_nav_menu solo funciona con men&uacute;s personalizados.<\/p><p>Puedes a&ntilde;adir la funci&oacute;n a cualquiera de los archivos de plantilla de tu tema para controlar d&oacute;nde quieres que aparezca el men&uacute;. Aqu&iacute; hay un ejemplo r&aacute;pido de c&oacute;mo se ve la funci&oacute;n sin ning&uacute;n par&aacute;metro espec&iacute;fico:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">wp_nav_menu( array $args = array() )<\/pre><p>Tendr&aacute;s que especificar qu&eacute; men&uacute; quieres mostrar para que el c&oacute;digo funcione. En la pr&aacute;ctica, una funci&oacute;n wp_nav_menu de ejemplo en una plantilla de p&aacute;gina tendr&iacute;a este aspecto:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">wp_nav_menu( array( \n    'theme_location' =&gt; 'custom-menu') );<\/pre><p>Una funci&oacute;n wp_nav_menu puede incluir m&uacute;ltiples par&aacute;metros. En ese ejemplo, utilizamos theme_location para especificar el nombre del men&uacute; personalizado que queremos utilizar.<\/p><p>Si no te sientes c&oacute;modo a&ntilde;adiendo c&oacute;digo a tu sitio web, puedes optar por <a href=\"\/co\/tutoriales\/plugin-menu-wordpress\/\">los plugins de men&uacute; de WordPress<\/a> en su lugar. Algunas herramientas te permitir&aacute;n crear y colocar men&uacute;s personalizados, igual que si usaras wp_nav_menu.<\/p><p>Tambi&eacute;n puedes utilizar algunos <a href=\"\/co\/tutoriales\/page-builders-wordpress\/\">constructores de p&aacute;ginas de WordPress<\/a>. Si ya utilizas una de estas herramientas, comprueba si ofrece la funci&oacute;n de men&uacute; personalizado.<\/p><h2 class=\"wp-block-heading\" id=\"h-parametros-del-wp_nav_menu-de-wordpress-y-clases-css\">Par&aacute;metros del wp_nav_menu de WordPress y clases CSS<\/h2><p>La mayor&iacute;a de las funciones de WordPress ofrecen varios par&aacute;metros predeterminados para modificar sus efectos. En el caso de wp_nav_menu, tienes tanto par&aacute;metros como clases CSS. Empecemos por los primeros.<\/p><h2 class=\"wp-block-heading\" id=\"h-parametros-wp_nav_menu\">Par&aacute;metros wp_nav_menu&nbsp;<\/h2><p>Puedes personalizar la funci&oacute;n wp_nav_menu utilizando uno o m&aacute;s par&aacute;metros. Aqu&iacute; est&aacute;n las opciones disponibles:<\/p><ul class=\"wp-block-list\">\n<li><strong>&lsquo;menu&rsquo;<\/strong>:<strong> <\/strong>indica qu&eacute; men&uacute; est&aacute;s utilizando. Puedes especificar un men&uacute; utilizando un ID, un slug, un nombre o un objeto.<\/li>\n\n\n\n<li><strong>&lsquo;menu_class&rsquo;<\/strong>: configura la clase CSS para tu men&uacute;. Por defecto, la funci&oacute;n utilizar&aacute; la clase<strong> men&uacute;<\/strong>.<\/li>\n\n\n\n<li><strong>&lsquo;menu_id&rsquo;<\/strong>: especifica el ID del men&uacute;. El valor o ID por defecto es el slug del men&uacute; con un n&uacute;mero a&ntilde;adido o incrementado.<\/li>\n\n\n\n<li><strong>&lsquo;container&rsquo;<\/strong>: elige el tipo de contenedor a utilizar para el men&uacute;. Por defecto, la funci&oacute;n utiliza contenedores <strong>div<\/strong>.<\/li>\n\n\n\n<li><strong>&lsquo;container_class&rsquo;<\/strong>: establece una clase CSS que se aplica directamente al contenedor del men&uacute;. Por defecto, esa clase de men&uacute; ser&aacute; <strong>menu-{menu slug}-container<\/strong>.<\/li>\n\n\n\n<li><strong>&lsquo;container_id&rsquo;<\/strong>: establece un ID para el contenedor del men&uacute;. Al igual que con el ID del men&uacute;, el contenedor utilizar&aacute; su slug incrementado por defecto.<\/li>\n\n\n\n<li><strong>&lsquo;fallback_cb<\/strong>&lsquo;: si WordPress no encuentra el men&uacute; que quiere mostrar, este par&aacute;metro le indica qu&eacute; otro elemento debe mostrar.<\/li>\n\n\n\n<li><strong>&lsquo;theme_location<\/strong>&lsquo;: si registras un men&uacute; personalizado usando <strong>register_nav_menu<\/strong>, este par&aacute;metro lo mostrar&aacute;.<\/li>\n\n\n\n<li><strong>items_wrap<\/strong>&lsquo;: por defecto, tu men&uacute; se mostrar&aacute; en formato de <strong>lista desordenada (ul)<\/strong>. Este par&aacute;metro te permite configurar c&oacute;mo envolver los elementos del men&uacute;.<\/li>\n\n\n\n<li><strong>&lsquo;item_spacing<\/strong>&lsquo;: la mayor&iacute;a de los men&uacute;s utilizan espacios en blanco para separar los elementos. Si quieres desactivar ese espacio en blanco, puedes establecer este par&aacute;metro para <strong>descartarlo<\/strong>.&nbsp;<\/li>\n<\/ul><p>Hay algunos <a href=\"https:\/\/developer.wordpress.org\/reference\/functions\/wp_nav_menu\/\" target=\"_blank\" rel=\"noreferrer noopener\">par&aacute;metros de wp_nav_menu<\/a> adicionales que no mencionamos, incluyendo opciones para a&ntilde;adir texto al men&uacute;. Sin embargo, los par&aacute;metros mencionados anteriormente son los elementos principales que utilizar&aacute;s al a&ntilde;adir men&uacute;s personalizados a un tema.<\/p><p>Este es un ejemplo de una funci&oacute;n que utiliza m&uacute;ltiples par&aacute;metros:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">&lt;?php\nwp_nav_menu( array( \n    'theme_location' =&gt; 'custom-menu', \n    'container_class' =&gt; 'menu-class'\n    'fallback_cb' =&gt; &lsquo;wp_page_menu&rsquo; ) ); \n?&gt;<\/pre><p>Si el n&uacute;mero de par&aacute;metros disponibles parece abrumador, no te preocupes. En la mayor&iacute;a de los casos, s&oacute;lo utilizar&aacute;s los par&aacute;metros <strong>theme_location <\/strong>y <strong>container_class<\/strong>. Eso hace que la configuraci&oacute;n de la funci&oacute;n sea notablemente sencilla.&nbsp;<\/p><h2 class=\"wp-block-heading\" id=\"h-clases-css-de-wp_nav_menu\">Clases CSS de wp_nav_menu<\/h2><p>Cuando utilizas la funci&oacute;n wp_nav_menu, &eacute;sta aplica autom&aacute;ticamente una serie de clases CSS a cada elemento del men&uacute; mostrado.<\/p><p>Aqu&iacute; est&aacute;n las <a href=\"https:\/\/developer.wordpress.org\/reference\/functions\/wp_nav_menu\/\" target=\"_blank\" rel=\"noreferrer noopener\">clases CSS m&aacute;s importantes de wp_nav_menu<\/a>:<\/p><ul class=\"wp-block-list\">\n<li><strong>.menu-item<\/strong>: esta clase se aplica autom&aacute;ticamente a cada elemento del men&uacute;.<\/li>\n\n\n\n<li><strong>.menu-item-has-children<\/strong>: se aplica s&oacute;lo a los elementos de men&uacute; con subelementos.<\/li>\n\n\n\n<li><strong>.menu-item-object-{object}<\/strong>: se aplica a todos los elementos del men&uacute;. El marcador de posici&oacute;n del <strong>objeto<\/strong> puede ser un post_type o una taxonom&iacute;a.<\/li>\n\n\n\n<li><strong>.menu-item-object-category<\/strong>: estos elementos de men&uacute; corresponden a una categor&iacute;a espec&iacute;fica de WordPress.<\/li>\n\n\n\n<li><strong>.menu-item-object-tag<\/strong>: elementos de men&uacute; que corresponden a una etiqueta de WordPress.<\/li>\n\n\n\n<li><strong>.menu-item-object-page<\/strong>: elementos de men&uacute; dentro de p&aacute;ginas est&aacute;ticas.<\/li>\n\n\n\n<li><strong>.menu-item-object-{custom}<\/strong>: elementos que corresponden a <a href=\"\/co\/tutoriales\/custom-post-types-wordpress\/\">tipos de post personalizados<\/a>.<\/li>\n\n\n\n<li><strong>.menu-item-type-{type}<\/strong>: se aplica a cada elemento del men&uacute;. El marcador de posici&oacute;n de <strong>tipo <\/strong>puede ser post_type o taxonom&iacute;a.<\/li>\n\n\n\n<li><strong>.menu-item-type-post_type<\/strong>: elementos que corresponden a cualquier post_type.<\/li>\n\n\n\n<li><strong>.menu-item-type-taxonomy<\/strong>: elementos que corresponden a cualquier taxonom&iacute;a.<\/li>\n<\/ul><p>Como puedes ver, hay mucha superposici&oacute;n con las clases CSS de wp_nav_menu. El amplio n&uacute;mero de opciones a tu disposici&oacute;n significa que puedes ser hiperespec&iacute;fico cuando uses CSS para configurar men&uacute;s personalizados.<\/p><p>Recuerda que tambi&eacute;n puedes utilizar clases CSS personalizadas con los par&aacute;metros de wp_nav_menu. Este enfoque puede ser una gran opci&oacute;n si ninguna de las clases predeterminadas se dirige al men&uacute; o a los elementos exactos que quieres estilizar.<\/p><h2 class=\"wp-block-heading\" id=\"h-como-crear-y-personalizar-un-menu-utilizando-la-funcion-wp_nav_menu-de-wordpress\">&iquest;C&oacute;mo crear y personalizar un men&uacute; utilizando la funci&oacute;n wp_nav_menu de WordPress?<\/h2><p>Ahora que sabes c&oacute;mo funciona la funci&oacute;n wp_nav_menu, es el momento de aprender a utilizarla dentro de tu tema. Vamos a empezar hablando de wp_nav_register.<\/p><h3 class=\"wp-block-heading\">Paso 1: crea un men&uacute; personalizado utilizando la funci&oacute;n wp_nav_register<\/h3><p>Como mencionamos anteriormente, wp_nav_menu no permite crear men&uacute;s personalizados, sino que permite colocarlos. Eso significa que tienes que hacer los men&uacute;s manualmente antes de usar esa funci&oacute;n.<\/p><p>wp_nav_register te permite crear o &ldquo;registrar&rdquo; men&uacute;s para un tema espec&iacute;fico. Tendr&aacute;s que editar el archivo <strong>functions.php <\/strong>del tema<strong> <\/strong>para utilizarlo.<\/p><p>Antes de ponerte a trabajar, te recomendamos que configures un tema hijo si a&uacute;n no lo est&aacute;s utilizando. Trabajar con un tema hijo evitar&aacute; que cualquier cambio en el c&oacute;digo del tema desaparezca cuando lo actualices. Tambi&eacute;n es aconsejable hacer una copia de seguridad completa de tu sitio web antes de cambiar los archivos esenciales.<\/p><p>Una vez resuelto esto, tendr&aacute;s que acceder al archivo functions.php de tu tema. La forma m&aacute;s f&aacute;cil de hacerlo es navegando a la p&aacute;gina <strong>Apariencia -&gt; Editor de archivos de temas <\/strong>en el panel de control.<\/p><p>El editor de temas deber&iacute;a abrir tu tema activo y puedes seleccionar el archivo functions.php utilizando el men&uacute; de la derecha.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"475\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-15.png\/w=1024,h=1024,fit=scale-down\" alt=\"Editor de temas de WP\" class=\"wp-image-22225\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-15.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-15.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-15.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-15.png\/w=768,fit=scale-down 768w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-15.png\/w=1536,fit=scale-down 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><p>Alternativamente, puedes acceder a functions.php utilizando <strong>el Protocolo de Transferencia de Archivos (FTP)<\/strong>. Te recomendamos este m&eacute;todo si prefieres utilizar un editor de texto completo. S&oacute;lo vas a a&ntilde;adir un &uacute;nico fragmento de c&oacute;digo, por lo que el editor de c&oacute;digo integrado de WordPress deber&iacute;a ser suficiente.<\/p><p>Navega hasta el final del archivo y a&ntilde;ade el siguiente c&oacute;digo:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">function wpb_custom_new_menu() {\n  register_nav_menu('custom-menu',__( 'Custom Menu' ));\n}\nadd_action( 'init', 'wpb_custom_new_menu' );<\/pre><p>Tendr&aacute;s que modificar el slug del<strong> men&uacute; personalizado <\/strong>y el nombre del men&uacute;, que ser&iacute;a el campo <strong>Men&uacute; personalizado<\/strong>. Sin embargo, puedes establecer cualquier nombre para el men&uacute; personalizado.<\/p><p>Guarda los cambios en el archivo functions.php. Ahora es el momento de editar qu&eacute; elementos se incluir&aacute;n en el nuevo men&uacute;.<\/p><h3 class=\"wp-block-heading\">Paso 2: edita tu men&uacute; personalizado de WordPress<\/h3><p>Para editar el men&uacute; personalizado que acabas de configurar, dir&iacute;gete a <strong>Apariencia -&gt; Men&uacute;s<\/strong>. Busca la secci&oacute;n <strong>Ajustes del men&uacute; <\/strong>en la parte inferior derecha de la pantalla.<\/p><p>Esa secci&oacute;n debe incluir la nueva ubicaci&oacute;n del men&uacute; que registraste en el primer paso.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1283\" height=\"662\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-17.png\/w=1024,h=1024,fit=scale-down\" alt=\"Secci&oacute;n del men&uacute; personalizado en WP\" class=\"wp-image-22227\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-17.png\/w=1283,fit=scale-down 1283w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-17.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-17.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-17.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-17.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1283px) 100vw, 1283px\" \/><\/figure><\/div><p>Para editar los elementos que mostrar&aacute; esa ubicaci&oacute;n, elige un men&uacute; mediante la opci&oacute;n <strong>Seleccionar un men&uacute; para editar: <\/strong>o crea uno nuevo.<\/p><p>A continuaci&oacute;n, escoge los elementos que deseas incluir en el men&uacute;, utilizando la lista de la izquierda y reorgan&iacute;zalos en la secci&oacute;n <strong>Estructura del men&uacute;<\/strong>.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1668\" height=\"717\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-18.png\/w=1024,h=1024,fit=scale-down\" alt=\"Secci&oacute;n de estructura del men&uacute; en WP \" class=\"wp-image-22228\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-18.png\/w=1668,fit=scale-down 1668w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-18.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-18.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-18.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-18.png\/w=768,fit=scale-down 768w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-18.png\/w=1536,fit=scale-down 1536w\" sizes=\"(max-width: 1668px) 100vw, 1668px\" \/><\/figure><\/div><p>Cada elemento del men&uacute; incluye un nombre para mostrar y un enlace. Cuando est&eacute;s satisfecho con tus selecciones, recuerda verificar si tu nuevo men&uacute; personalizado est&aacute; activo en la configuraci&oacute;n del men&uacute;. Si lo est&aacute;, guarda los cambios en el men&uacute;.<\/p><h3 class=\"wp-block-heading\">Paso 3: utiliza la funci&oacute;n wp_nav_menu para mostrar el nuevo men&uacute;<\/h3><p>En esta etapa, deber&iacute;as tener un men&uacute; listo para ser registrado en tu tema. Sin embargo, aunque el men&uacute; existe, no aparecer&aacute; en ning&uacute;n sitio hasta que uses la funci&oacute;n wp_nav_menu para especificar su ubicaci&oacute;n.<\/p><p>Necesitas a&ntilde;adir la funci&oacute;n wp_nav_menu dentro de una plantilla de p&aacute;gina para colocar el men&uacute; personalizado. Los archivos de la plantilla de p&aacute;gina a los que tienes acceso depender&aacute;n del tema que est&eacute;s utilizando.<\/p><p>Ve a <strong>Apariencia -&gt; Editor de archivos de temas <\/strong>para acceder a estos archivos en el panel de control. La secci&oacute;n de <strong>Archivos de Tema<\/strong> a la derecha contiene una lista de todos los archivos que puedes editar desde esta pantalla.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"414\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-19.png\/w=1024,h=1024,fit=scale-down\" alt=\"Editor de temas de WP\" class=\"wp-image-22229\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-19.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-19.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-19.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-19.png\/w=768,fit=scale-down 768w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2022\/08\/image-19.png\/w=1536,fit=scale-down 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><p>En nuestro ejemplo, hemos seleccionado la plantilla de una sola p&aacute;gina de nuestro tema. El c&oacute;digo que necesitas a&ntilde;adir a la plantilla debe ser algo parecido a esto:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">&lt;?php\nwp_nav_menu( array( \n    'theme_location' =&gt; 'custom-menu', \n    'container_class' =&gt; 'menu-class'\n    'fallback_cb' =&gt; &lsquo;wp_page_menu&rsquo; ) ); \n?&gt;<\/pre><p>Antes de guardar los cambios en el archivo de la plantilla, recuerda actualizar los marcadores de posici&oacute;n con el slug de tu tema personalizado y los dem&aacute;s par&aacute;metros que desees utilizar. En nuestro ejemplo incluimos los par&aacute;metros <em>container_class <\/em>y <em>fallback_cb<\/em>.<\/p><p>Sin embargo, el c&oacute;digo que se utiliza puede ser tan simple como:<\/p><pre class=\"EnlighterJSRAW\" data-enlighter-language=\"generic\" data-enlighter-theme=\"\" data-enlighter-highlight=\"\" data-enlighter-linenumbers=\"\" data-enlighter-lineoffset=\"\" data-enlighter-title=\"\" data-enlighter-group=\"\">&lt;?php\nwp_nav_menu( array( \n    'theme_location' =&gt; 'custom-menu' ) ); \n?&gt;<\/pre><p>La posici&oacute;n de ese c&oacute;digo determinar&aacute; la ubicaci&oacute;n del men&uacute; en la p&aacute;gina. Si no est&aacute;s seguro de c&oacute;mo funciona esa ubicaci&oacute;n, puedes experimentar con diferentes ubicaciones dentro del archivo de la plantilla.&nbsp;<\/p><p>No recomendamos cambiar ninguna otra parte del c&oacute;digo al editar los archivos de la plantilla, a menos que sepas lo que hace. Como s&oacute;lo est&aacute;s a&ntilde;adiendo unas pocas l&iacute;neas de c&oacute;digo, puedes eliminarlas si hay alg&uacute;n error.<\/p><p>Despu&eacute;s de la edici&oacute;n, comprueba si el men&uacute; se carga visitando una de las p&aacute;ginas que utilizan la plantilla en la que estabas trabajando. Si el men&uacute; no se muestra, es posible que haya un error con el slug para el par&aacute;metro theme_location, as&iacute; que sigue adelante y vuelve a comprobarlo.<\/p><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"\/co\/hosting-wordpress\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/06\/ES-New-WP_in-text-banner.png\/public\" alt=\"\" class=\"wp-image-40615\" srcset=\"https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/06\/ES-New-WP_in-text-banner.png\/w=1024,fit=scale-down 1024w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/06\/ES-New-WP_in-text-banner.png\/w=300,fit=scale-down 300w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/06\/ES-New-WP_in-text-banner.png\/w=150,fit=scale-down 150w, https:\/\/imagedelivery.net\/LqiWLm-3MGbYHtFuUbcBtA\/wp-content\/uploads\/sites\/40\/2024\/06\/ES-New-WP_in-text-banner.png\/w=768,fit=scale-down 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div><h2 class=\"wp-block-heading\" id=\"h-conclusion\">Conclusi&oacute;n<\/h2><p>Aunque WordPress te permite crear men&uacute;s personalizados f&aacute;cilmente, no te permite a&ntilde;adir <strong>ubicaciones <\/strong>de<strong> <\/strong>men&uacute; personalizadas. Ah&iacute; es donde entra la funci&oacute;n <strong>wp_nav_menu<\/strong>. Con esta funci&oacute;n, puedes mostrar los men&uacute;s personalizados creados con <strong>register_nav_menu <\/strong>en cualquier parte de tu sitio web.<\/p><p>A continuaci&oacute;n, un resumen r&aacute;pido de c&oacute;mo utilizar la funci&oacute;n wp_nav_menu de WordPress:<\/p><ol class=\"wp-block-list\">\n<li>Crea un men&uacute; personalizado utilizando la funci&oacute;n register_nav_menu.<\/li>\n\n\n\n<li>Edita tu men&uacute; personalizado de WordPress.<\/li>\n\n\n\n<li>Utiliza la funci&oacute;n wp_nav_menu para mostrar el nuevo men&uacute;.<\/li>\n<\/ol><p>&iquest;Tienes alguna pregunta sobre el uso de la funci&oacute;n wp_nav_menu en WordPress? &iexcl;Escr&iacute;bela en la secci&oacute;n de comentarios m&aacute;s abajo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los men&uacute;s son algunos de los elementos m&aacute;s comunes en los sitios web. Con WordPress, puedes personalizar f&aacute;cilmente los men&uacute;s y elegir entre m&uacute;ltiples opciones de visualizaci&oacute;n si tu tema lo admite. Sin embargo, si quieres utilizar men&uacute;s en una ubicaci&oacute;n personalizada, tendr&aacute;s que editar los archivos de tu tema y a&ntilde;adir la funci&oacute;n wp_nav_menu. [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/co\/tutoriales\/wp-nav-menu\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":353,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_title":"Crear un men\u00fa personalizado con la funci\u00f3n wp_nav_menu","rank_math_description":"Aprende qu\u00e9 es y en qu\u00e9 consiste la funci\u00f3n wp_nav_menu de WordPress. Sus funciones, par\u00e1metros y c\u00f3mo crear un men\u00fa utilizando esta funci\u00f3n.","rank_math_focus_keyword":"wp_nav_menu","footnotes":""},"categories":[4747,14348],"tags":[],"class_list":["post-21732","post","type-post","status-publish","format-standard","hentry","category-wordpress","category-experto"],"hreflangs":[{"locale":"es-ES","link":"https:\/\/www.hostinger.com\/es\/tutoriales\/wp-nav-menu","default":0},{"locale":"es-AR","link":"https:\/\/www.hostinger.com\/ar\/tutoriales\/wp-nav-menu","default":0},{"locale":"es-MX","link":"https:\/\/www.hostinger.com\/mx\/tutoriales\/wp-nav-menu","default":0},{"locale":"es-CO","link":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-nav-menu","default":0}],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/posts\/21732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/users\/353"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/comments?post=21732"}],"version-history":[{"count":14,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/posts\/21732\/revisions"}],"predecessor-version":[{"id":36392,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/posts\/21732\/revisions\/36392"}],"wp:attachment":[{"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/media?parent=21732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/categories?post=21732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinger.com\/co\/tutoriales\/wp-json\/wp\/v2\/tags?post=21732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}